{"id":7676,"date":"2020-05-03T00:08:56","date_gmt":"2020-05-03T06:08:56","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=7676"},"modified":"2020-05-02T20:36:05","modified_gmt":"2020-05-03T02:36:05","slug":"hora-de-reactivar","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/hora-de-reactivar\/","title":{"rendered":"\u00bfHora de reactivar?"},"content":{"rendered":"<p>El <span class=\"scayt-misspell-word\" data-scayt-word=\"covid\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfyjk4d22a3s3rp\">covid<\/span>-19 mantiene actualmente bajo medidas de confinamiento a una cuarta parte de la poblaci\u00f3n mundial. La pandemia ha superado los 3 millones de casos confirmados, ha costado decenas de miles de vidas, y ha borrado a\u00f1os de crecimiento econ\u00f3mico.<\/p>\n<p>Por la alta virulencia de esta enfermedad, la principal medida de prevenci\u00f3n es el aislamiento: millones de personas permanecen en sus casas por orden de sus respectivos gobiernos, en un intento desesperado por frenar la propagaci\u00f3n de este nuevo tipo de <span class=\"scayt-misspell-word\" data-scayt-word=\"coronavirus\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfyoy5g3ppsej5l\">coronavirus<\/span>.<\/p>\n<p>Como consecuencia, buena parte de la actividad econ\u00f3mica ha parado, y algunas industrias, como la aeron\u00e1utica y el petr\u00f3leo, se han llevado la peor parte. Con aeropuertos cerrados y nadie viajando, las aerol\u00edneas han frenado sus operaciones, y con una poblaci\u00f3n mundial que se transporta poco, el petr\u00f3leo lleg\u00f3 en abril a negociarse a precios negativos, es decir, los productores llegaron a pagar porque se retirara el producto de sus almacenes.<\/p>\n<p>Paralelamente, la Organizaci\u00f3n Internacional del Trabajo calcula que se perder\u00e1n unos 50 millones de empleos, y que el mayor impacto -un 80 % en el caso de Am\u00e9rica Latina- se lo llevar\u00e1n los trabajadores independientes. La poblaci\u00f3n m\u00e1s pobre no ha podido salir a ganarse el sustento y la previsi\u00f3n global es que la desaceleraci\u00f3n econ\u00f3mica supera a la que se tuvo para la crisis de 2008.<\/p>\n<p>Entre el temor natural por la enfermedad, y la crisis econ\u00f3mica que han ya generado el <span class=\"scayt-misspell-word\" data-scayt-word=\"covid\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfypq0x8gny90kx\">covid<\/span>-19 y las medidas de confinamiento asociadas al mismo, la gran pregunta es cu\u00e1ndo reabrir las econom\u00edas. En Estados Unidos, el pa\u00eds con mayor impacto por el <span class=\"scayt-misspell-word\" data-scayt-word=\"coronavirus\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfyqhkgpx6tst6m\">coronavirus<\/span>, este proceso ya inici\u00f3, en medio de cr\u00edticas por una posible segunda ola de contagios al permitir que m\u00e1s gente salga a las calles para retomar las labores en industrias y comercios que, durante las \u00faltimas semanas, permanecieron cerrados.<\/p>\n<p>El economista Ricardo <span class=\"scayt-misspell-word\" data-scayt-word=\"Hausmann\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfykc1wwdlff2az\">Hausmann<\/span>, director del Centro para el Desarrollo Internacional y profesor en la <span class=\"scayt-misspell-word\" data-scayt-word=\"Kennedy\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfykbzqzibq7q10\">Kennedy<\/span> <span class=\"scayt-misspell-word\" data-scayt-word=\"School\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfykbxn7rzhu09k\">School<\/span> of <span class=\"scayt-misspell-word\" data-scayt-word=\"Government\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfykbv4jot9wc6y\">Government<\/span> de la Universidad de <span class=\"scayt-misspell-word\" data-scayt-word=\"Harvard\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfykbtke6qqvrfp\">Harvard<\/span>, fue uno de los primeros en <span class=\"scayt-misspell-word\" data-scayt-word=\"advirtir\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfykbqplefv29ex\">advirtir<\/span> que la pandemia tendr\u00e1 serias implicaciones <span class=\"scayt-misspell-word\" data-scayt-word=\"macroecon\u00f3micas\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfykbmyhsb6zuak\">macroecon\u00f3micas<\/span> para la mayor\u00eda de loa pa\u00edses. <span class=\"scayt-misspell-word\" data-scayt-word=\"Hausmann\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfyl37n1gz95k6c\">Hausmann<\/span> est\u00e1 a favor de las medidas que lleven a aplanar la curva de contagios, como el confinamiento, pero aclara que para reducir los efectos de estas medidas sobre las empresas y el empleo, como aplicar medidas de alivio a negocios y personas.<\/p>\n<p>Un punto clave, y en el que se centra actualmente el debate en el pa\u00eds, es c\u00f3mo volver a retomar la actividad normal despu\u00e9s de una cuarentena como la aplicada en El Salvador. El experto aboga por mantener aislados a los adultos mayores antes de levantar la cuarentena, y retomar de forma gradual las diferentes actividades econ\u00f3micas, y ajustar el ritmo de <span class=\"scayt-misspell-word\" data-scayt-word=\"reapertura\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfyluu674zg479g\">reapertura<\/span> de las empresas a medida que se cuente con mayor informaci\u00f3n sobre la evoluci\u00f3n de la enfermedad.<\/p>\n<p>El experto sugiere movilizar todos los recursos que sean posibles hacia la lucha contra la enfermedad, aun cuando esto implique adquirir nueva deuda. La prioridad del gasto debe ser el rubro de salud, seguido por la protecci\u00f3n de los individuos y, en tercer lugar, de las empresas.<\/p>\n<p>El plan de alivio econ\u00f3mico presentado por el Gobierno, que requiere una inversi\u00f3n de $1,000 millones, no aborda la <span class=\"scayt-misspell-word\" data-scayt-word=\"reapertura\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfymmpttxdv11yy\">reapertura<\/span> de la actividad econ\u00f3mica, sino m\u00e1s bien medidas para dar liquidez a las empresas, como una pr\u00f3rroga de plazos fiscales, pr\u00e9stamos a bajo inter\u00e9s, y un subsidio a las planillas.<\/p>\n<p>El c\u00f3mo y cu\u00e1ndo retomar la actividad econ\u00f3mica est\u00e1, por el momento, fuera de la discusi\u00f3n oficial, pese a que el mismo Ministerio de Trabajo ha trabajado ya, junto a gremiales como la de los industriales, protocolos para retomar los procesos productivos de forma m\u00e1s segura.<\/p>\n<p>El <span class=\"scayt-misspell-word\" data-scayt-word=\"covid\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfynepu0w1sxmcy\">covid<\/span>-19 cambi\u00f3 la forma en la que debemos hacer las cosas. Empresas y gobiernos deben pensar en maneras creativas de reabrir las econom\u00edas, sin que esto implique volver a dar <span class=\"scayt-misspell-word\" data-scayt-word=\"especio\" data-wsc-lang=\"es_ES\" data-wsc-id=\"k9qfyo6nmt824tqfc\">especio<\/span> a la pandemia.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La desaceleraci\u00f3n econ\u00f3mica supera a la que se tuvo para la crisis de 2008.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":14,"featured_media":13,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-opinion.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[16],"tags":[225],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u00bfHora de reactivar? - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u00bfHora de reactivar?\" \/>\n<meta property=\"og:description\" content=\"La desaceleraci\u00f3n econ\u00f3mica supera a la que se tuvo para la crisis de 2008.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2020-05-03T06:08:56+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-05-03T02:36:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/mariana-belloso.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"500\" \/>\n\t<meta property=\"og:image:height\" content=\"500\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mariana Belloso\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/mariana-belloso.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/mariana-belloso.jpg\",\"width\":500,\"height\":500},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/\",\"name\":\"[:es]\u00bfHora de reactivar?[:] - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/#primaryimage\"},\"datePublished\":\"2020-05-03T06:08:56+00:00\",\"dateModified\":\"2020-05-03T02:36:05+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/39c1c5eeb45d3e784abfbd1f18d5c307\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u00bfHora de reactivar?\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/39c1c5eeb45d3e784abfbd1f18d5c307\",\"name\":\"Mariana Belloso\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/40658c596a06775e7334f465ab09877a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/40658c596a06775e7334f465ab09877a?s=96&d=mm&r=g\",\"caption\":\"Mariana Belloso\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/mbelloso\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u00bfHora de reactivar? - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/","og_locale":"en_US","og_type":"article","og_title":"[:es]\u00bfHora de reactivar?[:] - S\u00e9ptimo Sentido","og_description":"[:es]La desaceleraci\u00f3n econ\u00f3mica supera a la que se tuvo para la crisis de 2008.[:]","og_url":"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2020-05-03T06:08:56+00:00","article_modified_time":"2020-05-03T02:36:05+00:00","og_image":[{"width":500,"height":500,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/mariana-belloso.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"Mariana Belloso","Est. reading time":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/mariana-belloso.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/mariana-belloso.jpg","width":500,"height":500},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/","name":"[:es]\u00bfHora de reactivar?[:] - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/#primaryimage"},"datePublished":"2020-05-03T06:08:56+00:00","dateModified":"2020-05-03T02:36:05+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/39c1c5eeb45d3e784abfbd1f18d5c307"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/hora-de-reactivar\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"\u00bfHora de reactivar?"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/39c1c5eeb45d3e784abfbd1f18d5c307","name":"Mariana Belloso","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/40658c596a06775e7334f465ab09877a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/40658c596a06775e7334f465ab09877a?s=96&d=mm&r=g","caption":"Mariana Belloso"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/mbelloso\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/mariana-belloso.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-1ZO","jetpack-related-posts":[{"id":7822,"url":"https:\/\/7s.laprensagrafica.com\/en\/cierres-intermitentes\/","url_meta":{"origin":7676,"position":0},"title":"Cierres intermitentes","date":"31 May, 2020","format":false,"excerpt":"[:es]Junto a la crisis sanitaria y humana, avanzaba tambi\u00e9n la econ\u00f3mica. Potencias mundiales reportan ya decrecimiento, hay millones de desempleados.[:]","rel":"","context":"In &quot;Opini\u00f3n desde ac\u00e1&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/mariana-belloso.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7519,"url":"https:\/\/7s.laprensagrafica.com\/en\/quedemonos-en-casa\/","url_meta":{"origin":7676,"position":1},"title":"Qued\u00e9monos en casa","date":"5 April, 2020","format":false,"excerpt":"[:es]M\u00e1s all\u00e1 de estar pensando en que un decreto va a dejar de estar vigente para irme para la calle, todos deber\u00edamos estar pensando en forma para reducir nuestras salidas al m\u00ednimo posible.[:]","rel":"","context":"In &quot;Opini\u00f3n desde ac\u00e1&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/mariana-belloso.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3457,"url":"https:\/\/7s.laprensagrafica.com\/en\/una-generacion-dormida\/","url_meta":{"origin":7676,"position":2},"title":"Una generaci\u00f3n dormida","date":"29 April, 2018","format":false,"excerpt":"Ninguna de esas dos encrucijadas ha llevado a los salvadore\u00f1os a las calles. Ni saber que los recursos naturales se nos acaban ni que la \u00faltima \u201creforma\u201d a los ahorros previsionales no conlleva cambios sustanciales.","rel":"","context":"In &quot;Opini\u00f3n desde ac\u00e1&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/Sigfredo-Ram\u00edrez.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7871,"url":"https:\/\/7s.laprensagrafica.com\/en\/conversaciones-urgentes\/","url_meta":{"origin":7676,"position":3},"title":"Conversaciones urgentes","date":"7 June, 2020","format":false,"excerpt":"[:es]Atender el flagelo de la desigualdad econ\u00f3mica ha sido continuamente postergado por diferentes administraciones que han beneficiado solo a un n\u00famero reducido de la poblaci\u00f3n.[:]","rel":"","context":"In &quot;Opini\u00f3n desde ac\u00e1&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/06\/gabriel_zura_zamora.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7009,"url":"https:\/\/7s.laprensagrafica.com\/en\/a-que-jugamos\/","url_meta":{"origin":7676,"position":4},"title":"\u00bfA qu\u00e9 jugamos?","date":"12 January, 2020","format":false,"excerpt":"A seis meses de iniciada la administraci\u00f3n de Nayib Bukele, el tema estrella ha sido la seguridad. Reci\u00e9n esta semana se comenz\u00f3 a hablar oficialmente de la pol\u00edtica econ\u00f3mica que se impulsar\u00e1: el fomento a las inversiones.","rel":"","context":"In &quot;Opini\u00f3n desde ac\u00e1&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/mariana-belloso.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7666,"url":"https:\/\/7s.laprensagrafica.com\/en\/los-paises-pobres-deben-pensarse-dos-veces-las-estrategias-de-distanciamiento-dicen-economistas-de-yale\/","url_meta":{"origin":7676,"position":5},"title":"\u00abLos pa\u00edses pobres deben pensarse dos veces las estrategias de distanciamiento\u00bb, dicen economistas de Yale","date":"3 May, 2020","format":false,"excerpt":"[:es]La disponibilidad de recursos tiene que incidir en las medidas que se tomen en torno a la pandemia por covid-19. Lo que funciona para un pa\u00eds, no necesariamente funciona para todos. La universidad de Yale ha publicado un estudio en el que analiza los frutos de las principales medidas tomadas\u2026","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/05\/fsep03052020Efe9639180.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/7676"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/14"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=7676"}],"version-history":[{"count":1,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/7676\/revisions"}],"predecessor-version":[{"id":7677,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/7676\/revisions\/7677"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/13"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=7676"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=7676"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=7676"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}