{"id":6105,"date":"2019-08-04T00:05:17","date_gmt":"2019-08-04T06:05:17","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=6105"},"modified":"2019-08-03T18:15:28","modified_gmt":"2019-08-04T00:15:28","slug":"tenes-que-aprender-a-ser-autonomo-con-tu-hacer","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/","title":{"rendered":"&#8220;Ten\u00e9s que aprender a ser aut\u00f3nomo con tu hacer&#8221;"},"content":{"rendered":"<h4>\u200b\u200b\u200b\u200b\u200b\u200b\u200b\u00bfQu\u00e9 es lo que necesita en este momento?<\/h4>\n<p>Un deseo. Que el ser humano aprenda del ser humano.<\/p>\n<h4>Actualmente, \u00bfcu\u00e1l considera que es la virtud m\u00e1s sobrevalorada?<\/h4>\n<p>La honestidad.<\/p>\n<h4>\u00bfQu\u00e9 obst\u00e1culos ha encontrado en su camino?<\/h4>\n<p>Conocerme a m\u00ed, descubrir c\u00f3mo soy y seguir intentando descubrir qui\u00e9n soy.<\/p>\n<h4>\u00bfQu\u00e9 consejo se dar\u00eda?<\/h4>\n<p>&#8220;Ten\u00e9s que aprender a ser aut\u00f3nomo con tu hacer, desprenderte de comportamientos conformistas, con pobreza mental y emocional, para seguir construyendo tu camino&#8221;.<\/p>\n<h4>\u00bfCu\u00e1l ha sido su mayor atrevimiento en la vida?<\/h4>\n<p>Sigue siendo cada d\u00eda apostar por lo que anhelo realizar, arte.<\/p>\n<h4>\u00bfCu\u00e1l es su posesi\u00f3n m\u00e1s preciada?<\/h4>\n<p>El conocimiento que d\u00eda a d\u00eda voy adquiriendo de mi realidad y la realidad que me rodea.<\/p>\n<h4>\u00bfCu\u00e1l es su miedo m\u00e1s grande?<\/h4>\n<p>Que mi mente y cuerpo me falten.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Gabriel Galego es bailar\u00edn de danza cl\u00e1sica y de contempor\u00e1nea. A sus 24 a\u00f1os se ha especializado en la carrera de Bellas Artes, en la Universidad de Murcia, Espa\u00f1a. Esto lo llev\u00f3, en 2017, a presentarse por primera vez con su perfomance &#8220;En lo distinto de la permanencia&#8221;, en el Museo Molinos del R\u00edo, en Espa\u00f1a. Actualmente, Galego forma parte del Ballet Academy Alicia de Rusconi y Pole Dance Peace and Pole by Nina.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":6106,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-preguntas.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[6],"tags":[34],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Ten\u00e9s que aprender a ser aut\u00f3nomo con tu hacer&quot; - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Ten\u00e9s que aprender a ser aut\u00f3nomo con tu hacer&quot; - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Gabriel Galego es bailar\u00edn de danza cl\u00e1sica y de contempor\u00e1nea. A sus 24 a\u00f1os se ha especializado en la carrera de Bellas Artes, en la Universidad de Murcia, Espa\u00f1a. Esto lo llev\u00f3, en 2017, a presentarse por primera vez con su perfomance &quot;En lo distinto de la permanencia&quot;, en el Museo Molinos del R\u00edo, en Espa\u00f1a. Actualmente, Galego forma parte del Ballet Academy Alicia de Rusconi y Pole Dance Peace and Pole by Nina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2019-08-04T06:05:17+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2019-08-04T00:15:28+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/08\/fsep04082019corcuestionario1.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1023\" \/>\n\t<meta property=\"og:image:height\" content=\"682\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9ptimo Sentido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/08\/fsep04082019corcuestionario1.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/08\/fsep04082019corcuestionario1.jpg\",\"width\":1023,\"height\":682},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/\",\"name\":\"\\\"Ten\u00e9s que aprender a ser aut\u00f3nomo con tu hacer\\\" - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/#primaryimage\"},\"datePublished\":\"2019-08-04T06:05:17+00:00\",\"dateModified\":\"2019-08-04T00:15:28+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Ten\u00e9s que aprender a ser aut\u00f3nomo con tu hacer&#8221;\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\",\"name\":\"S\u00e9ptimo Sentido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"caption\":\"S\u00e9ptimo Sentido\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Ten\u00e9s que aprender a ser aut\u00f3nomo con tu hacer\" - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/","og_locale":"en_US","og_type":"article","og_title":"\"Ten\u00e9s que aprender a ser aut\u00f3nomo con tu hacer\" - S\u00e9ptimo Sentido","og_description":"Gabriel Galego es bailar\u00edn de danza cl\u00e1sica y de contempor\u00e1nea. A sus 24 a\u00f1os se ha especializado en la carrera de Bellas Artes, en la Universidad de Murcia, Espa\u00f1a. Esto lo llev\u00f3, en 2017, a presentarse por primera vez con su perfomance \"En lo distinto de la permanencia\", en el Museo Molinos del R\u00edo, en Espa\u00f1a. Actualmente, Galego forma parte del Ballet Academy Alicia de Rusconi y Pole Dance Peace and Pole by Nina.","og_url":"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2019-08-04T06:05:17+00:00","article_modified_time":"2019-08-04T00:15:28+00:00","og_image":[{"width":1023,"height":682,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/08\/fsep04082019corcuestionario1.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"S\u00e9ptimo Sentido","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/08\/fsep04082019corcuestionario1.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/08\/fsep04082019corcuestionario1.jpg","width":1023,"height":682},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/","name":"\"Ten\u00e9s que aprender a ser aut\u00f3nomo con tu hacer\" - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/#primaryimage"},"datePublished":"2019-08-04T06:05:17+00:00","dateModified":"2019-08-04T00:15:28+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/en\/tenes-que-aprender-a-ser-autonomo-con-tu-hacer\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"&#8220;Ten\u00e9s que aprender a ser aut\u00f3nomo con tu hacer&#8221;"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b","name":"S\u00e9ptimo Sentido","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","caption":"S\u00e9ptimo Sentido"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/08\/fsep04082019corcuestionario1.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-1At","jetpack-related-posts":[{"id":8506,"url":"https:\/\/7s.laprensagrafica.com\/en\/si-eres-feliz-has-encontrado-el-exito\/","url_meta":{"origin":6105,"position":0},"title":"&#8220;Si eres feliz, has encontrado el \u00e9xito&#8221;","date":"22 November, 2020","format":false,"excerpt":"[:es]Sa\u00fal Hern\u00e1ndez es licenciado en Ciencia Pol\u00edtica por la Universidad de Buenos Aires, Argentina, y tiene un M\u00e1ster en Gesti\u00f3n P\u00fablica por la Universidad Aut\u00f3noma de Barcelona, Espa\u00f1a. Ha ejercido el periodismo en televisi\u00f3n, como coordinador editorial y conductor de entrevistas y noticieros. Actualmente, es director ejecutivo de Canal 33,\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/11\/fsep22112020corsaulhernandez1ca.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7306,"url":"https:\/\/7s.laprensagrafica.com\/en\/la-felicidad-nunca-es-absoluta-y-permanente\/","url_meta":{"origin":6105,"position":1},"title":"&#8220;La felicidad nunca es absoluta y permanente&#8221;","date":"23 February, 2020","format":false,"excerpt":"[:es]Lidia Servell\u00f3n es una joven fot\u00f3grafa de productos y gastronom\u00eda. Desde el 2016, la artista se ha dedicado a crear historias m\u00e1gicas con objetos cotidianos. Tambi\u00e9n, se encarga de generar contenido fotogr\u00e1fico para el sector de bebidas y alimentos.[:]","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/02\/fsep23022020corcues0222.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8355,"url":"https:\/\/7s.laprensagrafica.com\/en\/no-hay-nada-mas-ofensivo-que-asumir-la-inexistencia-de-una-persona\/","url_meta":{"origin":6105,"position":2},"title":"&#8220;No hay nada m\u00e1s ofensivo que asumir la inexistencia de una persona&#8221;","date":"11 October, 2020","format":false,"excerpt":"[:es]Armando Castillo (Arcevedo) tiene 23 a\u00f1os. Es licenciado en Ciencias Jur\u00eddicas y cantautor. Ha participado en conciertos como \"Cantos de Mi Pueblo: Un homenaje a Pancho Lara\". Desde 2019, es miembro de Errantes cantautores, con quienes ha trabajado para visibilizar la m\u00fasica de autor nacional. Actualmente, se encuentra produciendo su\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/10\/fsep11102020corarcevedo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5139,"url":"https:\/\/7s.laprensagrafica.com\/en\/todo-pasa-y-todo-es-aprendizaje\/","url_meta":{"origin":6105,"position":3},"title":"\u201cTodo pasa y todo es aprendizaje\u201d","date":"20 January, 2019","format":false,"excerpt":"Rodrigo Pira es un m\u00fasico salvadore\u00f1o de la banda Camelo. Su primer instrumento, a los siete a\u00f1os, fue el piano. Aprendi\u00f3 a tocar la guitarra de manera autodid\u00e1ctica a los 13 a\u00f1os. Cuando cumpli\u00f3 14, aprendi\u00f3 a tocar el bajo el\u00e9ctrico y luego, el violoncelo con la maestra Memena Garc\u00eda.\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/01\/fsep20012019arccues93.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1162,"url":"https:\/\/7s.laprensagrafica.com\/en\/la-paz-esta-respeto-los-derechos-humanos\/","url_meta":{"origin":6105,"position":4},"title":"\u201cLa paz est\u00e1 en el respeto a los derechos humanos\u201d","date":"20 August, 2017","format":false,"excerpt":"Alejandro D\u00edaz es un abogado que trabaja en el acompa\u00f1amiento a v\u00edctimas en casos de graves violaciones a los derechos humanos, desde la oficina de Tutela Legal Doctora Mar\u00eda Julia Hern\u00e1ndez. Labora en el tema desde 2001. Dos de los casos en los que actualmente participa son la reapertura del\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/08\/sietepreguntas-alejandro-diaz.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7963,"url":"https:\/\/7s.laprensagrafica.com\/en\/me-habria-gustado-vivir-muchas-de-las-experiencias-de-vida-de-quincy-jones\/","url_meta":{"origin":6105,"position":5},"title":"&#8220;Me habr\u00eda gustado vivir muchas de las experiencias de vida de Quincy Jones&#8221;","date":"5 July, 2020","format":false,"excerpt":"[:es]Mateo Sorto es bajista de la banda salvadore\u00f1a de rock mel\u00f3dico progresivo: Pvzzles. Actualmente, el m\u00fasico de 27 a\u00f1os aprende producci\u00f3n m\u00fasical y t\u00e9cnicas de grabaci\u00f3n de manera autodidacta. Tambi\u00e9n es graduado de la carrera de Ingenier\u00eda Qu\u00edmica en la Universidad de El Salvador y cursa un t\u00e9cnico en multimedia\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/07\/fsep05072020corcuestiona1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/6105"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=6105"}],"version-history":[{"count":2,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/6105\/revisions"}],"predecessor-version":[{"id":6108,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/6105\/revisions\/6108"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/6106"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=6105"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=6105"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=6105"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}