{"id":4792,"date":"2018-11-18T00:02:18","date_gmt":"2018-11-18T06:02:18","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=4792"},"modified":"2018-11-17T19:33:27","modified_gmt":"2018-11-18T01:33:27","slug":"yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/","title":{"rendered":"&#8220;Yo ten\u00eda que compartir el instrumento con otros 20 violinistas&#8221;"},"content":{"rendered":"<figure id=\"attachment_4793\" style=\"width: 1743px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"4793\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/fsep18112018xxdud1\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxdud1.jpg\" data-orig-size=\"1743,980\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep18112018xxdud1\" data-image-description=\"&lt;p&gt;Dirigiendo la orquesta&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Dirigiendo la orquesta&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxdud1-300x169.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxdud1-1024x576.jpg\" loading=\"lazy\" class=\"size-full wp-image-4793\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxdud1.jpg\" alt=\"\" width=\"1743\" height=\"980\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxdud1.jpg 1743w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxdud1-300x169.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxdud1-768x432.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxdud1-1024x576.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxdud1-1200x675.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxdud1-500x281.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxdud1-1000x562.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxdud1-700x394.jpg 700w\" sizes=\"(max-width: 1743px) 100vw, 1743px\" \/><figcaption class=\"wp-caption-text\">Dirigiendo la orquesta<\/figcaption><\/figure>\n<p>El director de orquesta venezolano Gustavo Dudamel tiene muy presente en todo momento sus or\u00edgenes, a pesar de su fama internacional y de haber logrado uno de sus sue\u00f1os: dirigir la Filarm\u00f3nica de Berl\u00edn, con la que actualmente est\u00e1 de gira por Asia.<\/p>\n<p>En esta entrevista, habla de las diferencias entre las orquestas, la importancia de acercar la m\u00fasica cl\u00e1sica a los j\u00f3venes, su pasi\u00f3n por romper barreras, los problemas actuales de su pa\u00eds y del Sistema Nacional de Orquestas y Coros Juveniles e Infantiles de Venezuela, donde se form\u00f3.<\/p>\n<p><strong>\u00bfQu\u00e9 significa para usted dirigir la Filarm\u00f3nica de Berlin?<\/strong><br \/>\nUn sue\u00f1o hecho realidad. Conversaba el otro d\u00eda con un amigo y le dec\u00eda que para m\u00ed, ha sido lo m\u00e1s natural del mundo. Yo nunca me he presionado para lograrlo. Pero mi primer sue\u00f1o musical est\u00e1 relacionado con esta orquesta. Me acuerdo que iba a los conciertos en Barquisimeto de la Orquesta Sinf\u00f3nica Juvenil de Lara y me sentaba en la primera fila del Teatro Ju\u00e1rez, un teatro de principios del siglo XX. Y ya entonces so\u00f1aba con estar aqu\u00ed, en Berl\u00edn.<\/p>\n<p><strong>\u00bfSe tiene que pellizcar a veces?<\/strong><br \/>\nS\u00ed, porque uno no debe perder la inocencia. Cuando pierdes la inocencia, todo se vuelve rutinario.<\/p>\n<p><strong>Usted es el director musical de la Filarm\u00f3nica de Los \u00c1ngeles. \u00bfPuede definir en qu\u00e9 se diferencia una orquesta norteamericana de una europea?<\/strong><br \/>\nDudamel: Con Los \u00c1ngeles, donde ya dirijo desde hace 10 a\u00f1os, hemos construido un discurso sonoro juntos. Es una orquesta maravillosa, a la que dirigieron desde Zubin Mehta hasta el gran Otto Klemperer. Pero cuando llegas a una orquesta como invitado, como es el caso de Berl\u00edn, llegas como el invitado a una casa. Si es tu casa, tratas de disfrutarlo. As\u00ed es con una orquesta. Toda orquesta tiene una tradici\u00f3n, un sonido, una forma de tocar que t\u00fa, antes de imponer algo, tienes que escuchar. Es como bailar: vas ense\u00f1ando y aprendiendo un poco el movimiento de tu pareja y te vas adaptando. O como manejar un coche: no es lo mismo manejar un Ferrari que un Aston Martin. Son dos carros r\u00e1pidos pero los dos son muy distintos.<\/p>\n<p><strong>\u00bfYa manej\u00f3 uno?<\/strong><br \/>\nAlguna vez, por diversi\u00f3n. Me encantan los coches, desde que era ni\u00f1o, por la tecnolog\u00eda. Pero volviendo al tema, no puedo hacer sonar a la Filarm\u00f3nica de Los \u00c1ngeles como la Filarm\u00f3nica de Berl\u00edn.<\/p>\n<p><strong>Lleg\u00f3 a Los \u00c1ngeles con un proyecto de aproximaci\u00f3n a la comunidad, sobre todo latina, de la ciudad.<\/strong><br \/>\nS\u00ed. La primera propuesta fue crear una orquesta con ni\u00f1os. La Filarm\u00f3nica de Los \u00c1ngeles tiene que participar en moldear el futuro de la sociedad. Yo provengo de una iniciativa similar, pero de mucha m\u00e1s larga data: el Sistema de Coros y Orquestas juveniles de Venezuela, creado por el maestro Jos\u00e9 Antonio Abreu. La filarm\u00f3nica asumi\u00f3 la propuesta inmediatamente. Y en estos 10 a\u00f1os que existe YOLA, la orquesta juvenil, ya vamos por el s\u00e9ptimo centro. Ahora el arquitecto Frank Gehry esta dise\u00f1ando un centro en Inglewood, una zona de escasos recursos, complicada, d\u00f3nde hay un banco que se reestructur\u00f3 y se va a convertir en un escenario y en un espacio musical.<\/p>\n<p><strong>Su figura hasta hoy, con sus 38 a\u00f1os, est\u00e1 asociada a la juventud&#8230;.<\/strong><br \/>\nA pesar de las canas que me est\u00e1n saliendo.<\/p>\n<p><strong>\u00bfCu\u00e1l es la importancia de ganar un p\u00fablico nuevo, m\u00e1s joven?<\/strong><br \/>\nEs fundamental, y eso no es una fantas\u00eda, sino una realidad con mucha base. Yo crec\u00ed en un proyecto as\u00ed, el sistema, y por eso s\u00e9 que funciona. El objetivo no es que esos ni\u00f1os luego sean m\u00fasicos profesionales, sino que tengan un aprendizaje musical. Algunos despu\u00e9s deciden ser m\u00fasicos, otros no. De los compa\u00f1eros de mi generaci\u00f3n, han salido ingenieros, emprendedores, m\u00e9dicos. Pero nunca dejan de estar en contacto con la orquesta y nunca dejan de escuchar conciertos. De esta forma han aprendido a desarrollarse como espectadores y atraen a su vez a gente que no tiene nada que ver con la m\u00fasica. Por eso no podemos quedarnos sentados en un trono. Tenemos que ir hacia la gente y hacer entender lo que hacemos. Porque tampoco es llegar y tocar, sino mostrar la posibilidad transformadora que tiene la m\u00fasica.<\/p>\n<h4>En los ensayos para el show del Super Bowl en 2016, actuamos con Beyonc\u00e9, Bruno Mars y Chris Martin de Coldplay. Ensayamos cada detalle, cada movimiento, el sonido. Es un trabajo y eso se respeta. Por eso yo no pongo muros entre la m\u00fasica, el arte. Incluso hay un video de la Filarm\u00f3nica de Berl\u00edn tocando con los Scorpions. Todo eso crea un puente hacia un p\u00fablico que no est\u00e1 acostumbrado a escuchar m\u00fasica cl\u00e1sica. Hay una frase de Miguel de Unamuno: \u201cLa libertad que hay que darle al pueblo es la cultura\u201d.<\/h4>\n<p><strong>A diferencia de Europa, en Estados Unidos las orquestas no tienen problemas en trabajar con m\u00fasicos pop.<\/strong><br \/>\nNo, y est\u00e1 bien que as\u00ed sea. Estas superestrellas, en algunos casos verdaderas leyendas, son artistas maravillosos. No te imaginas el nivel de perfecci\u00f3n en los ensayos, c\u00f3mo aprecian cada detalle. En los ensayos para el show del Super Bowl en 2016, actuamos con Beyonc\u00e9, Bruno Mars y Chris Martin de Coldplay. Ensayamos cada detalle, cada movimiento, el sonido. Es un trabajo y eso se respeta. Por eso yo no pongo muros entre la m\u00fasica, el arte. Incluso hay un video de la Filarm\u00f3nica de Berl\u00edn tocando con los Scorpions. Todo eso crea un puente hacia un p\u00fablico que no est\u00e1 acostumbrado a escuchar m\u00fasica cl\u00e1sica. Hay una frase de Miguel de Unamuno: \u201cLa libertad que hay que darle al pueblo es la cultura\u201d.<\/p>\n<p><strong>\u00bfEs una experiencia que llev\u00f3 de Venezuela a Los \u00c1ngeles?<\/strong><br \/>\nS\u00ed, la de romper barreras. Cuando comenc\u00e9 a dirigir en Los \u00c1ngeles, nos embarcamos en proyectos maravillosos. Nunca me hubiera imaginado hacer una \u00f3pera con Frank Gehry, pero as\u00ed fue. Me ayud\u00f3 a que hici\u00e9ramos la trilog\u00eda de las \u00f3peras de Mozart con los libretos de Da Ponte con tres arquitectos: Jean Nouvel, que hizo \u201cLas bodas de F\u00edgaro\u201d, Zaha Hadid, que hizo \u201cCosi Fan Tutte\u201d y Gehry con \u201cDon Juan\u201d. Ahora acabo de hacer con el core\u00f3grafo Benjamin Millepied, el esposo de Natalie Portman, una versi\u00f3n de \u201cRomeo y Julieta\u201d con una filmaci\u00f3n en vivo de ciertas partes del ballet. Todo lo que estaba sucediendo alrededor del hall aparec\u00eda en una pantalla en el escenario simult\u00e1neamente con la danza.<\/p>\n<p><strong>\u00bfEn qu\u00e9 situaci\u00f3n est\u00e1 el Sistema Nacional de Orquestas y Coros Juveniles e Infantiles de Venezuela?<\/strong><br \/>\nEl sistema sigue adelante a pesar de la complej\u00edsima situaci\u00f3n que estamos viviendo en Venezuela -econ\u00f3mica, social, espiritual. Hoy es un emblema de esperanza. Esto no lo digo como una frase hecha, porque a pesar de todo, el sistema no se ha detenido. Estamos viviendo un momento muy complejo debido a la salida de muchos talentos del pa\u00eds. Pero de alguna manera tambi\u00e9n, a pesar de la compleja situaci\u00f3n, de lo dif\u00edcil que puede ser para un m\u00fasico, para cualquier tipo de profesional, salir del pa\u00eds, veo muchos de ellos en todo el mundo y no pierdo la fe en que volver\u00e1n y que se est\u00e1n enriqueciendo y est\u00e1n siempre en contacto con sus compa\u00f1eros en Venezuela.<\/p>\n<p><strong>\u00bfEs decir que el sistema tendr\u00e1 en el futuro un papel que ahora ya no puede tener?<\/strong><br \/>\nMientras haya un ni\u00f1o en los n\u00facleos, el Sistema est\u00e1 vivo. Un solo ni\u00f1o, un maestro. Aun hoy, en la situaci\u00f3n actual, eso genera un efecto multiplicador. El sistema se ha hecho de adversidades. Cuando el maestro (Jos\u00e9 Antonio) Abreu lo cre\u00f3, nadie cre\u00eda en \u00e9l. Le cost\u00f3 much\u00edsimo abrirse camino. Cuando estaba en Barquisimeto, no ten\u00edamos un sitio d\u00f3nde tocar, no hab\u00eda instrumentos. Yo ten\u00eda que compartir el instrumento con otros 20 violinistas, uno tocaba una hora, despu\u00e9s el otro. Nos dec\u00edan \u201cla orquesta de los sin techo\u201d. Y a pesar de todas las crisis que hemos estado viviendo en los ochenta, en los noventa, todav\u00eda estamos.<\/p>\n<figure id=\"attachment_4794\" style=\"width: 700px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"4794\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/fsep18112018xxduda01\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxduda01.jpg\" data-orig-size=\"700,941\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep18112018xxduda01\" data-image-description=\"&lt;p&gt;Gustavo Dudamel&lt;br \/&gt;\nDirector de la Orquesta Filarm\u00f3nica de Los \u00c1ngeles&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Gustavo Dudamel&lt;br \/&gt;\nDirector de la Orquesta Filarm\u00f3nica de Los \u00c1ngeles&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxduda01-223x300.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxduda01.jpg\" loading=\"lazy\" class=\"size-full wp-image-4794\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxduda01.jpg\" alt=\"\" width=\"700\" height=\"941\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxduda01.jpg 700w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxduda01-223x300.jpg 223w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxduda01-500x672.jpg 500w\" sizes=\"(max-width: 700px) 100vw, 700px\" \/><figcaption class=\"wp-caption-text\"><strong>Gustavo Dudamel<\/strong>. Director de la Orquesta Filarm\u00f3nica de Los \u00c1ngeles<\/figcaption><\/figure>\n<p><strong>\u00bfEs una situaci\u00f3n terminal?<\/strong><br \/>\nEl fil\u00f3sofo franc\u00e9s (Jean-Jacques) Rousseau le preguntaba a Dios en \u201cLas confesiones\u201d por qu\u00e9 le hab\u00eda hecho pasar tantas situaciones adversas. La respuesta: te he hecho d\u00e9bil para caer en el hueco, porque te he hecho lo suficientemente fuerte para salir de \u00e9l. Yo podr\u00eda hablarte de todo lo terrible que est\u00e1 sucediendo en mi pa\u00eds, que es triste y doloroso. Cada vez que veo salir a un joven, me duele. Cuando veo que la gente no tiene la posibilidad de comprar los bienes b\u00e1sicos, me duele, tambi\u00e9n porque all\u00e1 vive mi familia, de la que nunca me he desconectado. Pero al mismo tiempo debemos seguir luchando porque al final del t\u00fanel hay una luz, y esa luz significa uni\u00f3n. Porque la polarizaci\u00f3n ha calado hondo hasta en las mismas familias.<\/p>\n<p><strong>Para que la uni\u00f3n suceda, \u00bfNicol\u00e1s Maduro deber\u00e1 dejar el poder?<\/strong><br \/>\nYo creo que el pueblo es sabio y sabr\u00e1 decidir cu\u00e1l es su futuro. El problema es hoy la sobrepolitizaci\u00f3n, y de eso tenemos que proteger a nuestros ni\u00f1os. No podemos enfermarlos con esta diatriba pol\u00edtica y esta pelea permanente de que si t\u00fa eres culpable. Cada uno tiene que asumir su responsabilidad y su culpa. Nosotros, desde las peque\u00f1as posiciones en que estamos, tenemos que construir el pa\u00eds.<\/p>\n<p><strong>\u00bfPero existe hoy ese margen en Venezuela?<\/strong><br \/>\nAbsolutamente. Creo que ahora es el momento. Pero los tiempos de un pa\u00eds son distintos a los tiempos de un individuo. Nosotros podemos desesperarnos, pero un pa\u00eds necesita mucho tiempo para transformarse. Basta con ver lo que vivi\u00f3 Alemania: dos guerras mundiales, reg\u00edmenes dictatoriales, un muro que los separ\u00f3. Tantos a\u00f1os de sufrimiento y tantas equivocaciones. Nosotros tambi\u00e9n hemos sido muy golpeados, tambi\u00e9n por nosotros mismos, por no tener la disciplina suficiente. Pero no es momento de achacarnos culpa. Es el momento para que cada quien asuma la responsabilidad que tiene.<\/p>\n<p><strong>\u00bfSe siente como protector del sistema desde el exterior?<\/strong><br \/>\nCompletamente. Yo soy un pap\u00e1.<\/p>\n<p><strong>\u00bfY esa posici\u00f3n tambi\u00e9n le ha llevado a mantenerle en silencio durante mucho tiempo?<\/strong><br \/>\nPero es que yo nunca he estado en silencio. La gente sabe solo el 0.1 % del trabajo que hago. Yo muchas veces he estado en Venezuela y nadie sabe que estoy ah\u00ed. Viajamos por el pa\u00eds viendo c\u00f3mo est\u00e1n los n\u00facleos, pero yo no hago alarde de eso o me tomo una selfie. He estado metido en s\u00f3tanos viendo ensayos de orquestas, nunca en la sala grande; me he reunido con los muchachos, estoy en contacto con ellos a trav\u00e9s de Skype&#8230;<\/p>\n<p><strong>\u00bfCu\u00e1l es su papel como ciudadano de Venezuela?<\/strong><br \/>\nMi papel es de unir y no dividir. Porque para m\u00ed, es muy dif\u00edcil tener un p\u00fablico que est\u00e1 completamente dividido y yo dividirlo m\u00e1s. Mi funci\u00f3n es que el publico sienta que cuando est\u00e1 escuchando m\u00fasica, se est\u00e1 uniendo. Habr\u00e1 otros que hacen discursos pol\u00edticos, pero esa no es mi funci\u00f3n. El resto es trabajar, no por un lado o por un color, sino por toda Venezuela.<\/p>\n<p><strong>\u00bfCu\u00e1l es la base de su optimismo?<\/strong><br \/>\nCuando me pasan los videos de todo lo que est\u00e1 sucediendo en Venezuela y veo toda la cacofon\u00eda que se vive, y al mismo tiempo veo ni\u00f1os en un curso de oboe -ahora vas a pensar que estoy loco-, es que eso es lo que brinda esperanza, tal cual lo concibi\u00f3 el maestro Abreu con el sistema. Por eso tengo fe en que vendr\u00e1 el momento en que Venezuela se desarrolle, porque ahora estamos en el hueco, pero nos han hecho lo suficientemente fuertes para salir de \u00e9l.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Naci\u00f3 el 26 de enero de 1981, en Barquisimeto, Venezuela. Gustavo Dudamel se form\u00f3 en el Sistema de Orquestas Juveniles de Venezuela que dirigi\u00f3 despu\u00e9s en diferentes lugares del mundo. Hoy es el director de la Orquesta Filarm\u00f3nica de Los \u00c1ngeles y de la Orquesta Sinf\u00f3nica Sim\u00f3n Bol\u00edvar, de Venezuela. En enero de 2017, se convirti\u00f3 en el maestro m\u00e1s joven en dirigir el legendario concierto de A\u00f1o Nuevo al frente de la Orquesta Filarm\u00f3nica de Viena. Actualmente est\u00e1 de gira por Asia con la Filarm\u00f3nica de Berl\u00edn.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":4794,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;Yo ten\u00eda que compartir el instrumento con otros 20 violinistas&quot; - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;Yo ten\u00eda que compartir el instrumento con otros 20 violinistas&quot; - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Naci\u00f3 el 26 de enero de 1981, en Barquisimeto, Venezuela. Gustavo Dudamel se form\u00f3 en el Sistema de Orquestas Juveniles de Venezuela que dirigi\u00f3 despu\u00e9s en diferentes lugares del mundo. Hoy es el director de la Orquesta Filarm\u00f3nica de Los \u00c1ngeles y de la Orquesta Sinf\u00f3nica Sim\u00f3n Bol\u00edvar, de Venezuela. En enero de 2017, se convirti\u00f3 en el maestro m\u00e1s joven en dirigir el legendario concierto de A\u00f1o Nuevo al frente de la Orquesta Filarm\u00f3nica de Viena. Actualmente est\u00e1 de gira por Asia con la Filarm\u00f3nica de Berl\u00edn.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-11-18T06:02:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-11-18T01:33:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxduda01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"700\" \/>\n\t<meta property=\"og:image:height\" content=\"941\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9ptimo Sentido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"10 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxduda01.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxduda01.jpg\",\"width\":700,\"height\":941,\"caption\":\"Gustavo Dudamel Director de la Orquesta Filarm\u00f3nica de Los \u00c1ngeles\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/\",\"name\":\"\\\"Yo ten\u00eda que compartir el instrumento con otros 20 violinistas\\\" - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/#primaryimage\"},\"datePublished\":\"2018-11-18T06:02:18+00:00\",\"dateModified\":\"2018-11-18T01:33:27+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;Yo ten\u00eda que compartir el instrumento con otros 20 violinistas&#8221;\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\",\"name\":\"S\u00e9ptimo Sentido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"caption\":\"S\u00e9ptimo Sentido\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"Yo ten\u00eda que compartir el instrumento con otros 20 violinistas\" - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/","og_locale":"en_US","og_type":"article","og_title":"\"Yo ten\u00eda que compartir el instrumento con otros 20 violinistas\" - S\u00e9ptimo Sentido","og_description":"Naci\u00f3 el 26 de enero de 1981, en Barquisimeto, Venezuela. Gustavo Dudamel se form\u00f3 en el Sistema de Orquestas Juveniles de Venezuela que dirigi\u00f3 despu\u00e9s en diferentes lugares del mundo. Hoy es el director de la Orquesta Filarm\u00f3nica de Los \u00c1ngeles y de la Orquesta Sinf\u00f3nica Sim\u00f3n Bol\u00edvar, de Venezuela. En enero de 2017, se convirti\u00f3 en el maestro m\u00e1s joven en dirigir el legendario concierto de A\u00f1o Nuevo al frente de la Orquesta Filarm\u00f3nica de Viena. Actualmente est\u00e1 de gira por Asia con la Filarm\u00f3nica de Berl\u00edn.","og_url":"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-11-18T06:02:18+00:00","article_modified_time":"2018-11-18T01:33:27+00:00","og_image":[{"width":700,"height":941,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxduda01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"S\u00e9ptimo Sentido","Est. reading time":"10 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxduda01.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxduda01.jpg","width":700,"height":941,"caption":"Gustavo Dudamel Director de la Orquesta Filarm\u00f3nica de Los \u00c1ngeles"},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/","name":"\"Yo ten\u00eda que compartir el instrumento con otros 20 violinistas\" - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/#primaryimage"},"datePublished":"2018-11-18T06:02:18+00:00","dateModified":"2018-11-18T01:33:27+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/en\/yo-tenia-que-compartir-el-instrumento-con-otros-20-violinistas\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"&#8220;Yo ten\u00eda que compartir el instrumento con otros 20 violinistas&#8221;"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b","name":"S\u00e9ptimo Sentido","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","caption":"S\u00e9ptimo Sentido"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep18112018xxduda01.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-1fi","jetpack-related-posts":[{"id":6078,"url":"https:\/\/7s.laprensagrafica.com\/en\/liderar-una-orquesta-no-habia-estado-en-mi-lista-de-propositos-para-el-futuro\/","url_meta":{"origin":4792,"position":0},"title":"&#8220;Liderar una orquesta no hab\u00eda estado en mi lista de prop\u00f3sitos para el futuro&#8221;","date":"28 July, 2019","format":false,"excerpt":"Es el coordinador general de la Orquesta Mar\u00eda de Baratta y exintegrante de la Orquesta Sinf\u00f3nica Juvenil de El Salvador, donde por ocho a\u00f1os interpret\u00f3 la viola. Este a\u00f1o viaj\u00f3 a Costa Rica para ser parte del Primer Simposio de Maestros, M\u00fasicos y Gestores Culturales de Iberoam\u00e9rica, coordinado por la\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/07\/fsep27072019xxfabricio1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4736,"url":"https:\/\/7s.laprensagrafica.com\/en\/hay-futuro-para-la-musica-en-el-salvador\/","url_meta":{"origin":4792,"position":1},"title":"&#8220;Hay futuro para la m\u00fasica en El Salvador&#8221;","date":"11 November, 2018","format":false,"excerpt":"Irving Ram\u00edrez es el director adjunto de la Orquesta Sinf\u00f3nica de El Salvador desde 2002. Realiz\u00f3 sus estudios formales de m\u00fasica en Rusia, en el Conservatorio I. Tchaikovsky, y en Venezuela. Parte de sus labores ha estado inclinada a la ense\u00f1anza, desde la academia y el Gobierno.","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/fsep25112018xxirving550.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5817,"url":"https:\/\/7s.laprensagrafica.com\/en\/una-utopia-llamada-reinsercion\/","url_meta":{"origin":4792,"position":2},"title":"Una utop\u00eda llamada reinserci\u00f3n","date":"9 June, 2019","format":false,"excerpt":"Sin una l\u00ednea presupuestaria y con al menos 12 mil privados de libertad sin participar, el modelo Yo Cambio intenta ser una herramienta de reinserci\u00f3n para un sistema penitenciario saturado. De 28 centros penales, 15 no cuentan con el modelo penitenciario en su totalidad. Actualmente, los reos que est\u00e1n en\u2026","rel":"","context":"In &quot;Reportaje Nacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/06\/fsep09062019fzcamb77.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5029,"url":"https:\/\/7s.laprensagrafica.com\/en\/ninas-de-pandillas-enemigas-se-juntan-en-una-cancion-2\/","url_meta":{"origin":4792,"position":3},"title":"Ni\u00f1as de pandillas enemigas se juntan en una canci\u00f3n","date":"30 December, 2018","format":false,"excerpt":"Esta orquesta est\u00e1 formada por j\u00f3venes que, antes de ser condenadas por alg\u00fan tribunal salvadore\u00f1o, nunca tuvieron oportunidad de tener un instrumento musical en sus manos. El 5 de agosto de este a\u00f1o conocimos la historia de estas ni\u00f1as a las que la m\u00fasica les marc\u00f3 un nuevo camino.","rel":"","context":"In &quot;Reportaje&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/08\/fsep05082018mrcri07ca.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4199,"url":"https:\/\/7s.laprensagrafica.com\/en\/ninas-de-pandillas-enemigas-se-juntan-en-una-cancion\/","url_meta":{"origin":4792,"position":4},"title":"Ni\u00f1as de pandillas enemigas se juntan en una canci\u00f3n","date":"5 August, 2018","format":false,"excerpt":"Antes podr\u00edan haberse enfrentado con armas, pero ahora tocan juntas y en sincron\u00eda. En Ilopango hay una orquesta de cuerdas formada por j\u00f3venes que han sido condenadas por los tribunales salvadore\u00f1os. La particularidad de este grupo art\u00edstico es que en \u00e9l conviven en paz ni\u00f1as y adolescentes con afinidad a\u2026","rel":"","context":"In &quot;Reportaje&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/08\/fsep05082018mrcri07ca.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1618,"url":"https:\/\/7s.laprensagrafica.com\/en\/miedo-mas-grande-desarrollar-ego\/","url_meta":{"origin":4792,"position":5},"title":"\u201cMi miedo m\u00e1s grande es desarrollar ego\u201d","date":"8 October, 2017","format":false,"excerpt":"Chepito Paiz es un baterista salvadore\u00f1o de 48 a\u00f1os; treinta y cinco de ellos los ha dedicado a su carrera musical. Ha pasado por agrupaciones de variados g\u00e9neros, como la Orquesta de Lito Barrientos, S\u00faper Combo 12 y Proyecto Ac\u00fastico. Actualmente milita en el grupo de jazz fusi\u00f3n LOS. Es\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/7preguntas-min.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4792"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=4792"}],"version-history":[{"count":1,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4792\/revisions"}],"predecessor-version":[{"id":4795,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4792\/revisions\/4795"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/4794"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=4792"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=4792"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=4792"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}