{"id":4459,"date":"2018-09-16T00:02:23","date_gmt":"2018-09-16T06:02:23","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=4459"},"modified":"2018-09-16T05:23:06","modified_gmt":"2018-09-16T11:23:06","slug":"caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/","title":{"rendered":"Caimanera,  la frontera m\u00e1s cercana entre Cuba y Estados Unidos"},"content":{"rendered":"<figure id=\"attachment_4460\" style=\"width: 1920px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"4460\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/fsep16092018gdanue01\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01.jpg\" data-orig-size=\"1920,1473\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep16092018gdanue01\" data-image-description=\"&lt;p&gt;De cerca.  Este poblado comparte paisaje con la c\u00e1rcel de Guant\u00e1namo. Aqu\u00ed, Cuba y Estados Unidos comparten una lengua de tierra y una playa.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;De cerca.  Este poblado comparte paisaje con la c\u00e1rcel de Guant\u00e1namo. Aqu\u00ed, Cuba y Estados Unidos comparten una lengua de tierra y una playa.&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01-300x230.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01-1024x786.jpg\" loading=\"lazy\" class=\"size-full wp-image-4460\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01.jpg\" alt=\"\" width=\"1920\" height=\"1473\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01.jpg 1920w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01-300x230.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01-768x589.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01-1024x786.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01-1900x1458.jpg 1900w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01-1200x921.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01-500x384.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01-1000x767.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01-700x537.jpg 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-caption-text\"><strong>De cerca.<\/strong> Este poblado comparte paisaje con la c\u00e1rcel de Guant\u00e1namo. Aqu\u00ed, Cuba y Estados Unidos comparten una lengua de tierra y una playa.<\/figcaption><\/figure>\n<p>El punto m\u00e1s cercano entre Cuba y Estados Unidos no se encuentra a 90 millas en una zona entre el noroeste de la isla y los Cayos de Florida. En la provincia de Guant\u00e1namo existe, cara a cara, una frontera que recuerda que la presencia estadounidense est\u00e1 muy cerca, o como se dice en el Caribe, \u201cen la sala de la casa\u201d.<\/p>\n<p>Esa zona, donde est\u00e1 localizada la base naval de Guant\u00e1namo, representa una espina clavada en el orgullo de los cubanos, quienes piden que los terrenos ocupados por la Marina de Estados Unidos, que se ubic\u00f3 all\u00ed desde principios del siglo XX y ha desistido de marcharse, sean devueltos a sus manos por ser parte del territorio nacional.<\/p>\n<p>Estados Unidos posee 45 millas cuadradas de tierra en Cuba con una frontera que se extiende por una longitud de 17 millas. No es un cayo cercano a la costa del territorio principal, ni una isla aleda\u00f1a del archipi\u00e9lago, como fueron los casos de Vieques y Culebra en Puerto Rico. No, se trata de un enclave estadounidense en pleno suelo cubano, en los dos extremos de una de las mejores bah\u00edas de bolsa del mundo, perfecta, por ejemplo, para la construcci\u00f3n de un muelle de trasbordo o un punto vital para la industria pesquera.<\/p>\n<p>All\u00ed impera el estilo de vida t\u00edpico de las bases militares estadounidenses, con sus tiendas libres de impuestos, establecimientos de comida r\u00e1pida, dispensarios m\u00e9dicos, entre otras comodidades b\u00e1sicas. Cerca de 5,000 personas permanecen all\u00ed entre personal civil y militar.<\/p>\n<p>Su estatus legal es confuso, pues t\u00e9cnicamente es territorio soberano de Cuba, pero con jurisdicci\u00f3n de Estados Unidos, lo cual crea un vac\u00edo legal que fue usado como excusa en su momento para establecer el centro de detenci\u00f3n de personas calificadas como terroristas que todav\u00eda operan las autoridades estadounidenses.<\/p>\n<p>La presencia de Estados Unidos en esta zona del oriente cubano tiene mucha historia y data de la invasi\u00f3n de 1898, provocada por la guerra hispanoamericana contra Espa\u00f1a. Lo que hoy es la base naval de Guant\u00e1namo comenz\u00f3 a gestarse a trav\u00e9s de un convenio en 1903, el cual se vali\u00f3 de la llamada Enmienda Platt, un recurso mediante el cual se reconoc\u00eda la independencia de Cuba, pero que daba a Estados Unidos, tras su triunfo en la guerra contra Espa\u00f1a, la autoridad de intervenir en los asuntos de Cuba y controlar parte de su territorio.<\/p>\n<p>Estados Unidos paga a Cuba la cantidad de $4,085 al a\u00f1o por concepto de arrendamiento, un dinero que, tras el triunfo de la revoluci\u00f3n de Fidel Castro Ruz, el Gobierno cubano solo cobr\u00f3 \u201cpor error\u201d en 1959 y que desde entonces el cheque, depositado a trav\u00e9s de la embajada de Suiza como mediador, nunca ha sido cambiado. Los fondos caducan al a\u00f1o y son devueltos a la cuenta de la Marina de Guerra de Estados Unidos, entidad que paga a nombre del Tesoro de Cuba, un organismo que ni siquiera existe en la isla.<\/p>\n<p>La presencia estadounidense en esa zona de Cuba constituye, junto con el embargo o bloqueo econ\u00f3mico, la principal fuente de resentimiento entre ambos vecinos. Si bien nunca se han registrado enfrentamientos oficiales entre tropas, en esas 17 millas de frontera se han registrado diversos hechos muy particulares.<\/p>\n<p>Por ejemplo, Cuba decidi\u00f3 dejar una especie de espacio muerto entre ambos lados, algo parecido a la franja del paralelo que divide las dos Coreas, un territorio divisorio que por d\u00e9cadas, por ejemplo, estuvo repleto de minas.<\/p>\n<p>Ya libre de peligro, ese espacio ha servido para escaramuzas entre soldados de los dos lados o bromas de mal gusto, como saltarse al lado del otro y dejar excremento, o enviar buzos a pasar las fronteras mutuas para dejarse \u201cregalitos\u201d que indiquen que estuvieron por all\u00ed sin ser detectados.<\/p>\n<p>Por esos lares tambi\u00e9n se han registrado serios incidentes que Cuba imputa a los militares estadounidenses.<\/p>\n<p>Entre ellos est\u00e1 el lanzamientos de materiales inflamables desde aviones procedentes de la base; presuntas provocaciones de soldados norteamericanos, incluyendo insultos, lanzamientos de piedras, de latas con material inflamable y disparos con pistolas y armas autom\u00e1ticas; violaciones de las aguas jurisdiccionales de Cuba, y la muerte de ciudadanos cubanos a manos de fuerzas de Estados Unidos.<\/p>\n<p>El Gobierno cubano reclama que el 6 de enero de 1961 fue torturado por soldados de la base naval el obrero Manuel Prieto G\u00f3mez, quien laboraba all\u00ed hac\u00eda m\u00e1s de tres a\u00f1os, por delito de \u201cser revolucionario\u201d.<\/p>\n<p>El 15 de octubre de ese a\u00f1o, Cuba sostiene que fue torturado y luego asesinado el obrero cubano Rub\u00e9n L\u00f3pez Sabariego, mientras que el 24 de junio de 1962 mataron con disparos desde la base a Rodolfo Rosell Salas, pescador del poblado de Caimanera.<\/p>\n<p>El 19 de julio de 1964, los cubanos afirman que tiros de militares estadounidenses provocaron la muerte al guardafrontera de 17 a\u00f1os Ram\u00f3n L\u00f3pez Pe\u00f1a, en el puesto donde cumpl\u00eda con su turno, y el 21 de mayo de 1966 le ocurri\u00f3 lo mismo al soldado Luis Ram\u00edrez L\u00f3pez.<\/p>\n<p>En octubre de 1991, Estados Unidos le jug\u00f3 una broma pesada al Gobierno cubano cuando aviones y helic\u00f3pteros procedentes de la base naval violaron el espacio a\u00e9reo y sobrevolaron la ciudad de Santiago de Cuba, donde Castro Ruz comandaba el IV Congreso del Partido Comunista.<\/p>\n<p>Estados Unidos no ha esclarecido oficialmente los incidentes y Cuba aspira a que se haga justicia en alg\u00fan momento.<\/p>\n<h1 style=\"text-align: center;\">***<\/h1>\n<p><strong>CORDIALIDAD PESE A TENSI\u00d3N<\/strong><\/p>\n<p>Las relaciones, sin embargo, han sido m\u00e1s de cordialidad que de hostilidad. Por ejemplo, por a\u00f1os, ciudadanos cubanos entraban a trabajar a la base a diario.<br \/>\nAll\u00ed llegaron a laborar 5,000 cubanos, los cuales fueron reducidos a 700 por Estados Unidos en 1964 tras triunfar la revoluci\u00f3n. Con el paso del tiempo, esos empleos, en su mayor\u00eda de mantenimiento, no se repusieron y los \u00faltimos dos cubanos empleados por la base naval se jubilaron en 2013.<\/p>\n<p>Algunos de ellos decidieron quedarse dentro de la base y 23 todav\u00eda viven retirados en las instalaciones militares. Cuba les ha permitido entrar a territorio nacional en varias ocasiones por \u201crazones humanitarias\u201d.<\/p>\n<p>Cerca de 40 familiares o extrabajadores cubanos todav\u00eda cobran pensiones del Gobierno estadounidense por sus labores all\u00ed.<br \/>\nEsos trabajadores pasaban a la base naval a trav\u00e9s de unos puntos fronterizos habilitados para esos fines. Esas postas todav\u00eda existen y son usadas para contactos peri\u00f3dicos que se dan entre ambos lados, pues hay temas log\u00edsticos que tratar y los encuentros entre las autoridades cubanas y las estadounidenses no son anormales.<br \/>\nA la base naval es imposible acceder desde suelo cubano. La zona est\u00e1 completamente militarizada. Solo dos pueblos est\u00e1n enclavados en el \u00e1rea de seguridad que Cuba ha delimitado en torno de la instalaci\u00f3n estadounidense, Boquer\u00f3n y Caimanera.<\/p>\n<p>Para llegar a ellos se requiere de un permiso especial muy complicado de obtener. Ambos pueblos son considerados zonas de seguridad nacional, por lo que para poder residir all\u00ed hay que pasar un proceso de verificaci\u00f3n extremo, incluso para quien quiere establecer una relaci\u00f3n marital o simplemente visitar la familia.<\/p>\n<h4>Su estatus legal es confuso, pues t\u00e9cnicamente es territorio soberano de Cuba, pero con jurisdicci\u00f3n de Estados Unidos, lo cual crea un vac\u00edo legal que fue usado como excusa en su momento para establecer el centro de detenci\u00f3n de personas calificadas como terroristas que todav\u00eda operan las autoridades estadounidenses.<\/h4>\n<p>El Nuevo D\u00eda visit\u00f3 Caimanera como parte de un grupo de periodistas internacionales a los cuales se les permiti\u00f3 acceso al municipio fronterizo con la base naval.<br \/>\nEl pueblo recibe a sus visitantes con un control militar y un pancarta que lee: \u201cCaimanera, primera trinchera antiimperialista\u201d.<\/p>\n<p>Ese mensaje no es casual. Caimanera, junto con Boquer\u00f3n, est\u00e1 considerado como el primer punto de respuesta en el caso de que Estados Unidos decidiera intervenir militarmente en Cuba usando la base naval como centro de operaciones, por lo que no es casual\u00a0que muchos de sus 9,000 residentes sean militares con sus familias.<br \/>\nDentro de sus l\u00edmites, el pueblito es pintoresco, muy a la cubana, con su plaza p\u00fablica, tiendas estatales muy bien surtidas (mejor que muchas de La Habana) y calles repletas de transe\u00fantes que van y vienen por la carretera central o la v\u00eda que bordea todo el pueblo de frente al mar, de cara a la bah\u00eda, desde donde pueden apreciarse las turbinas e\u00f3licas que Estados Unidos mont\u00f3 para alimentar de energ\u00eda la base.<\/p>\n<p>Desde Caimanera se ve poco de la base naval. En el muelle de los pescadores se aprecian las boyas anaranjadas y una barda flotante colocadas por el Ej\u00e9rcito cubano para marcar el peligro y la cercan\u00eda al \u00e1rea controlada por los estadounidenses, que est\u00e1 a los dos lados de la boca de la bah\u00eda.<\/p>\n<p>Los pescadores del pueblo, que son cerca de 60, solo pueden ejercer su oficio en la parte adentro de la bah\u00eda, ya que les est\u00e1 vetado usar la rica embocadura de zona o salir a mar abierto por el control estadounidense en la entrada del \u00e1rea.<\/p>\n<p>Sus residentes viven orgullosos de encontrarse en la primera l\u00ednea de fuego de lo que cada d\u00eda es menos probable, un enfrentamiento militar entre los dos pa\u00edses.<\/p>\n<p>\u201cHemos tenido que soportar una falta de respeto, es como soportar a un vecino indeseable, que te molesta con su himno, con su pr\u00e1ctica militar. Sencillamente, han creado un sentimiento de rechazo, sentimos odio porque ellos est\u00e1n ah\u00ed. No hemos podido disfrutar de las bondades de nuestra bah\u00eda. Yo tengo 66 a\u00f1os y nunca he disfrutado de una acampada ah\u00ed, de sus playas\u201d, dijo a El Nuevo D\u00eda el historiador del pueblo, Pedro Batista, quien es presidente de la Direcci\u00f3n Cultural Jos\u00e9 Mart\u00ed en Caimanera y jubilado del sector de la cultura.<\/p>\n<p>\u201cEl mejor coto de pesca est\u00e1 ah\u00ed, es la tercera bah\u00eda de bolsa del mundo y no hemos podido explotarla, ni desarrollar la industria de la pesca, el comercio de cabotaje. Caimanera y Guant\u00e1namo tuvieran un desarrollo socioecon\u00f3mico m\u00e1s floreciente de contar con la bah\u00eda, y hubiera ayudado al desarrollo del pa\u00eds\u201d, agreg\u00f3.<\/p>\n<p>Los cubanos reclaman que la ocupaci\u00f3n estadounidense en ese territorio \u2013el cual puede ser devuelto a Cuba de manera unilateral por Estados Unidos, mediante un pacto entre los dos pa\u00edses, siempre y cuando haya un Gobierno reconocido como democr\u00e1tico en la isla\u2013 ha afectado severamente el desarrollo econ\u00f3mico de Guant\u00e1namo.<\/p>\n<p>\u201cQue este territorio est\u00e9 ocupado por una base norteamericana ilegal exige un esfuerzo superior. Esta base naval ilegal provoca muchas limitaciones en el desarrollo econ\u00f3mico y social de nuestro territorio, a partir de que Caimanera est\u00e1 ubicada en la parte interior de la bah\u00eda, zona cenagosa, y la base naval est\u00e1 ubicada en la parte de la entrada, donde est\u00e1n creadas las mejores condiciones de playa y econ\u00f3micas para el desarrollo de nuestro territorio\u201d, explic\u00f3 a El Nuevo D\u00eda el presidente de la Asamblea Municipal del Poder Popular de Caimanera, Jos\u00e9 \u00c1ngel Calvi\u00f1o P\u00e9rez.<\/p>\n<p>\u00bfQu\u00e9 quiere la gente de Caimanera, que los americanos se vayan?<br \/>\n\u2014Que se vayan y que nos acaben de entregar nuestra tierra, que es nuestra, que es de los cubanos, y que los cubanos la queremos y la estamos guapeando, para seguir desarrollando nuestro territorio.<\/p>\n<p>M\u00e1s all\u00e1 de los problemas econ\u00f3micos e ideol\u00f3gicos que causa la presencia militar estadounidense en la zona, los residentes de Caimanera sufren de temas pr\u00e1cticos que no se dan en otras partes de Cuba y que solo se configuran aqu\u00ed por la particularidad de la necesidad de seguridad extrema.<\/p>\n<p>Los residentes, que reciben trato especial en compensaci\u00f3n y suministros por parte del Estado, se cantan felices de vivir en un pueblo costero, bello, tranquilo y libre de delincuencia, pero pagan un precio que llega a ser alto.<\/p>\n<p>\u201c\u00a1Aqu\u00ed somos felices!\u201d, exclam\u00f3 en voz alta la maestra Olga P\u00e9rez Guerra, quien, rodeada de sus alumnos, paseaba por la zona del muelle del pueblo.<br \/>\n\u201c\u00bfSomos felices aqu\u00ed?\u201d, pregunt\u00f3 a su alumnos, quienes a coro respondieron con un \u201c\u00a1s\u00ed!\u201d largo y sonoro.<\/p>\n<p>Pero no todo es color de rosa. La maestra adora el pueblo por su calma, por su belleza natural, por el acceso a un mar tranquilo a cualquier hora. Reconoce, sin embargo, que hay limitaciones importantes por la presencia, al sur del pueblo, de soldados de Estados Unidos.<\/p>\n<p>\u201cPudi\u00e9ramos ser mejores. Si no tuvi\u00e9semos limitaciones, cu\u00e1nto pudi\u00e9ramos aprovechar las bellezas naturales que tiene ese lado de nuestro suelo y recibir visitas a cualquier hora, de cualquier parte, como ocurre en otras partes del pa\u00eds, sin limitaciones por seguridad\u201d, manifest\u00f3 P\u00e9rez Guerra.<\/p>\n<h4>En octubre de 1991, Estados Unidos le jug\u00f3 una broma pesada al Gobierno cubano cuando aviones y helic\u00f3pteros procedentes de la base naval violaron el espacio a\u00e9reo y sobrevolaron la ciudad de Santiago de Cuba, donde Castro Ruz comandaba el IV Congreso del Partido Comunista.<\/h4>\n<p>\u00bfNos puede hablar de esas limitaciones?<br \/>\n\u2014Una limitaci\u00f3n por seguridad es que yo, como joven, para tener una pareja no caimanerense tengo que pedir varios documentos para que pueda establecerse ac\u00e1. Estamos privados de visitas de personas de otras provincias y pa\u00edses, eso no ocurre en ninguna otra parte del pa\u00eds. Del lado all\u00e1 hay bellas playas, que no podemos disfrutar, que nos tocan a nosotros y hoy no podemos beneficiarnos de ellas. Nos afecta psicol\u00f3gicamente, socialmente, nos impide el desarrollo normal y las relaciones con j\u00f3venes de todas las provincias y del mundo. Ellos solo buscan una justificaci\u00f3n para provocar una agresi\u00f3n militar a nuestro suelo y en Cuba va a seguir ondeando la bandera bella y hermosa, y presente estar\u00e1 la sonrisa de nuestros ni\u00f1os.<br \/>\nEl deseo de los cubanos de recibir de vuelta los terrenos de la base naval de Guant\u00e1namo no se cumplir\u00e1 a corto plazo. Ni siquiera los avances en las relaciones entre Cuba y Estados Unidos dados bajo las administraciones de Barack Obama y Ra\u00fal Castro Ruz lograron mover un \u00e1pice en el tema.<\/p>\n<p>Mucho menos lo har\u00e1 bajo la presencia de Donald Trump en la Casa Blanca, sobre todo porque la intenci\u00f3n del mandatario es sostener el centro de detenci\u00f3n para presuntos terroristas que opera en la base naval, que representa el \u00fanico motivo determinante para que Estados Unidos mantenga en operaciones ese recinto militar.<br \/>\nEsa es la creencia del profesor del Centro de Estudios Caribe\u00f1os de la Universidad de Puerto Rico (UPR) Don E. Walicek, quien recientemente present\u00f3 en la Universidad de Ciencias M\u00e9dicas de Guant\u00e1namo su libro \u201cGuant\u00e1namo y el imperio estadounidense: las humanidades responden\u201d.<\/p>\n<p>\u201cEstados Unidos mantiene la base como un s\u00edmbolo para mantener su posici\u00f3n estrat\u00e9gica y poder en el mundo, para controlar varias poblaciones caribe\u00f1as, los cubanos, los haitianos, los jamaicanos, entre otros\u201d, dijo Walicek, quien es estadounidense y lleva 15 a\u00f1os trabajando en la UPR, a El Nuevo D\u00eda en Guant\u00e1namo.<\/p>\n<p>\u201cSi se estudia la historia de la base, hay varias opciones a corto plazo para devolver los terrenos a Cuba. Un primer paso ser\u00eda cerrar la prisi\u00f3n, que es ilegal, pues han ocurrido cosas que ni el gobierno federal de Estados Unidos puede controlar. Ese ser\u00eda un paso bien \u00fatil para analizar c\u00f3mo utilizar el espacio y despu\u00e9s devolver el territorio a Cuba\u201d, agreg\u00f3.<br \/>\nEn teor\u00eda, el proceso para devolver la base naval es complejo. Si Estados Unidos decide cerrar las operaciones militares all\u00ed, eso no significa que renunciar\u00e1 al control sobre el terreno. De hacerlo, tendr\u00eda que acordar con Cuba qu\u00e9 pasar\u00e1 con las instalaciones all\u00ed construidas, como el aeropuerto, los muelles, las residencias, edificios de trabajo y la c\u00e1rcel. El Gobierno estadounidense podr\u00eda destruirlos, venderlos a Cuba o simplemente cederlos.<\/p>\n<p>Ese escenario, no obstante, pinta lejos de concretarse, por lo que la \u00fanica certeza a corto plazo es que Caimanera seguir\u00e1 de vecino de los marines de Estados Unidos, con las tensiones que un escenario como ese crea, sea para un lado o para el otro de la verja que hoy divide ambos mundos<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Estados Unidos posee 45 millas cuadradas de tierra en Cuba. Es en esta regi\u00f3n en donde est\u00e1 localizada la base naval de Guant\u00e1namo. Cuba ha pedido en varias ocasiones que sean devueltos los terrenos ocupados por la Marina de Estados Unidos, que se ubic\u00f3 all\u00ed desde principios del siglo XX.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":4460,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Caimanera, la frontera m\u00e1s cercana entre Cuba y Estados Unidos - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Caimanera, la frontera m\u00e1s cercana entre Cuba y Estados Unidos - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Estados Unidos posee 45 millas cuadradas de tierra en Cuba. Es en esta regi\u00f3n en donde est\u00e1 localizada la base naval de Guant\u00e1namo. Cuba ha pedido en varias ocasiones que sean devueltos los terrenos ocupados por la Marina de Estados Unidos, que se ubic\u00f3 all\u00ed desde principios del siglo XX.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-09-16T06:02:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-09-16T11:23:06+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1473\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Benjam\u00edn Morales Mel\u00e9ndez\/El Nuevo D\u00eda\/Puerto Rico\/GDA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"14 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01.jpg\",\"width\":1920,\"height\":1473,\"caption\":\"De cerca. Este poblado comparte paisaje con la c\u00e1rcel de Guant\u00e1namo. Aqu\u00ed, Cuba y Estados Unidos comparten una lengua de tierra y una playa.\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/\",\"name\":\"Caimanera, la frontera m\u00e1s cercana entre Cuba y Estados Unidos - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/#primaryimage\"},\"datePublished\":\"2018-09-16T06:02:23+00:00\",\"dateModified\":\"2018-09-16T11:23:06+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Caimanera, la frontera m\u00e1s cercana entre Cuba y Estados Unidos\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\",\"name\":\"S\u00e9ptimo Sentido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"caption\":\"S\u00e9ptimo Sentido\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Caimanera, la frontera m\u00e1s cercana entre Cuba y Estados Unidos - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/","og_locale":"en_US","og_type":"article","og_title":"Caimanera, la frontera m\u00e1s cercana entre Cuba y Estados Unidos - S\u00e9ptimo Sentido","og_description":"Estados Unidos posee 45 millas cuadradas de tierra en Cuba. Es en esta regi\u00f3n en donde est\u00e1 localizada la base naval de Guant\u00e1namo. Cuba ha pedido en varias ocasiones que sean devueltos los terrenos ocupados por la Marina de Estados Unidos, que se ubic\u00f3 all\u00ed desde principios del siglo XX.","og_url":"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-09-16T06:02:23+00:00","article_modified_time":"2018-09-16T11:23:06+00:00","og_image":[{"width":1920,"height":1473,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"Benjam\u00edn Morales Mel\u00e9ndez\/El Nuevo D\u00eda\/Puerto Rico\/GDA","Est. reading time":"14 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01.jpg","width":1920,"height":1473,"caption":"De cerca. Este poblado comparte paisaje con la c\u00e1rcel de Guant\u00e1namo. Aqu\u00ed, Cuba y Estados Unidos comparten una lengua de tierra y una playa."},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/","name":"Caimanera, la frontera m\u00e1s cercana entre Cuba y Estados Unidos - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/#primaryimage"},"datePublished":"2018-09-16T06:02:23+00:00","dateModified":"2018-09-16T11:23:06+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/caimanera-la-frontera-mas-cercana-entre-cuba-y-estados-unidos\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Caimanera, la frontera m\u00e1s cercana entre Cuba y Estados Unidos"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b","name":"S\u00e9ptimo Sentido","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","caption":"S\u00e9ptimo Sentido"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":""}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep16092018gdanue01.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-19V","jetpack-related-posts":[{"id":5329,"url":"https:\/\/7s.laprensagrafica.com\/en\/el-servicio-de-datos-cambia-el-escenario-tecnologico-de-cuba\/","url_meta":{"origin":4459,"position":0},"title":"El servicio de datos cambia el escenario tecnol\u00f3gico de Cuba","date":"3 March, 2019","format":false,"excerpt":"La apertura de puntos wifi ha comenzado a hacer que la poblaci\u00f3n descubra los servicios y las infinitas posibilidades que ofrece internet. Sin embargo, el servicio domiciliar sigue ausente.","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/03\/fsep02032019arccuba43.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8340,"url":"https:\/\/7s.laprensagrafica.com\/en\/duelo-de-narrativas-en-cuba\/","url_meta":{"origin":4459,"position":1},"title":"Duelo de narrativas en Cuba","date":"11 October, 2020","format":false,"excerpt":"[:es]Youtube se convirti\u00f3 en la mejor plataforma para contrarrestar la verdad oficial por parte de los ciudadanos. Cada vez m\u00e1s j\u00f3venes usan este canal para contar lo que el gobierno no quiere que se sepa. Los segudores crecen y el acecho de los polic\u00edas, tambi\u00e9n.[:]","rel":"","context":"In &quot;Reportaje&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/10\/duelo-de-narrativas-en-cuba.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5872,"url":"https:\/\/7s.laprensagrafica.com\/en\/feminicidios-los-crimenes-que-oculta-el-socialismo\/","url_meta":{"origin":4459,"position":2},"title":"Feminicidios: los cr\u00edmenes que oculta el socialismo","date":"16 June, 2019","format":false,"excerpt":"Secretismo en las estad\u00edsticas, investigaciones laxas, silencio c\u00f3mplice e impunidad, rondan los asesinatos de mujeres en Cuba. Mientras que las v\u00edctimas de violencia intrafamiliar se enfrentan a una nula protecci\u00f3n policial y cero opciones de refugio.","rel":"","context":"In &quot;Reportaje&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/06\/fsep16062019xxilus04.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6015,"url":"https:\/\/7s.laprensagrafica.com\/en\/rizos-y-espendrus-para-reivindicar-la-cultura-afrocubana\/","url_meta":{"origin":4459,"position":3},"title":"Rizos y &#8220;espendr\u00fas&#8221; para reivindicar la cultura afrocubana","date":"14 July, 2019","format":false,"excerpt":"Trabajar el cabello ha sido una de las formas como las nuevas generaciones en Cuba han comenzado a reivindicar la cultura afrocubana. De esta forma diferentes emprendedores, como Adriana Heredia, coordinadora del proyecto \"Beyond Roots\", crean productos para este grupo, que es relegado en la isla caribe\u00f1a.","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/07\/fsep14072019Efe8755688.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7635,"url":"https:\/\/7s.laprensagrafica.com\/en\/ser-indigente-en-cuba-en-tiempos-del-coronavirus\/","url_meta":{"origin":4459,"position":4},"title":"Ser indigente en Cuba en tiempos del coronavirus","date":"26 April, 2020","format":false,"excerpt":"[:es]Ante el creciente n\u00famero de infectados, el gobierno cubano ha insistido en que \"nadie quedar\u00e1 desamparado\". Sin embargo, las alarmas est\u00e1n puestas en una poblaci\u00f3n que parece invisible a todos: los habitantes de la calle.[:]","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/04\/sep26042020f2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4227,"url":"https:\/\/7s.laprensagrafica.com\/en\/aumentan-cruces-ilegales-en-la-frontera-mexico-arizona\/","url_meta":{"origin":4459,"position":5},"title":"Aumentan cruces ilegales en la frontera M\u00e9xico-Arizona","date":"12 August, 2018","format":false,"excerpt":"El endurecimiento de medidas en contra de la migraci\u00f3n sin documentos hacia Estados Unidos no logra persuadir a salvadore\u00f1os, hondure\u00f1os o guatemaltecos de emprender este viaje. Lo que s\u00ed ha provocado es el descubrimiento de nuevas rutas o el uso de otras que hab\u00edan sido consideradas demasiado riesgosas.","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/08\/fsep12082018Ap7808179.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4459"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=4459"}],"version-history":[{"count":3,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4459\/revisions"}],"predecessor-version":[{"id":4464,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4459\/revisions\/4464"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/4460"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=4459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=4459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=4459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}