{"id":434,"date":"2017-06-11T00:06:53","date_gmt":"2017-06-11T06:06:53","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=434"},"modified":"2017-06-09T20:41:59","modified_gmt":"2017-06-10T02:41:59","slug":"carta-editorial-8","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-8\/","title":{"rendered":"Carta Editorial"},"content":{"rendered":"<p>El dilema acerca de c\u00f3mo equilibrar subsistencia y conservaci\u00f3n del medio ambiente ya alcanz\u00f3 al Parque Nacional Montecristo. La primera disputa es por el agua.<\/p>\n<p>De las m\u00e1s de 7,000 hect\u00e1reas, solo unas 2,000 est\u00e1n protegidas por ley. El resto es la zona de amortiguamiento, que es indispensable para poder mantener en buenas condiciones la zona protegida.<\/p>\n<p>La constante deforestaci\u00f3n de la zona de amortiguamiento hace que cada vez se capte menos agua. Si en la \u00e9poca sin lluvia es esperable que se reduzca el caudal los riachuelos y las quebradas, lo que no es normal ni sano es que se sequen.<\/p>\n<p>En la zona de amortiguamiento hay comunidades. Las comunidades obtienen ingresos de la agricultura de subsistencia. Extensiones que antes eran bosque ahora se usan para cosechar lechugas. La eterna lucha va acerca de c\u00f3mo resolver las necesidades inmediatas sin llevarse por delante las necesidades m\u00e1s integrales, esas que implican conservar el bosque, aunque a corto plazo esto no d\u00e9 ingresos econ\u00f3micos.<\/p>\n<p>En esto hay mucho de conciencia, de educaci\u00f3n, como se relata en el texto. Pero tambi\u00e9n caben la desigualdad y la injusticia. A estas poblaciones cercanas a la invaluable zona de Montecristo, \u00bfqu\u00e9 otras opciones se les han dado? \u00bfSon estas otras de las poblaciones aisladas y marginadas a las que al final de cuentas no les queda m\u00e1s que hacer parir la tierra para comer?<\/p>\n<p>Un ecosistema no es otra cosa que algo que funciona con base en conexiones entre todos los que lo integran. No tiene caso no involucrar a los habitantes cercanos como parte del bosque. No se les puede poner en una situaci\u00f3n en la que lo \u00fanico que les quede es ir a la contra y hacer da\u00f1o.<\/p>\n<p>Las consecuencias vistas hacen evidente que urgen nuevos planteamientos, otras maneras de hacerle frente a esta realidad. No se puede alargar m\u00e1s el drama.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La eterna lucha va acerca de c\u00f3mo resolver las necesidades inmediatas sin llevarse por delante las necesidades m\u00e1s integrales.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":435,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-carta.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[4],"tags":[155],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carta Editorial - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta Editorial - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"La eterna lucha va acerca de c\u00f3mo resolver las necesidades inmediatas sin llevarse por delante las necesidades m\u00e1s integrales.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-06-11T06:06:53+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-06-10T02:41:59+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/portada-2.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"828\" \/>\n\t<meta property=\"og:image:height\" content=\"651\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Glenda Gir\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/portada-2.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/portada-2.jpg\",\"width\":828,\"height\":651},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/\",\"name\":\"Carta Editorial - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/#primaryimage\"},\"datePublished\":\"2017-06-11T06:06:53+00:00\",\"dateModified\":\"2017-06-10T02:41:59+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta Editorial\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\",\"name\":\"Glenda Gir\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"caption\":\"Glenda Gir\u00f3n\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta Editorial - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/","og_locale":"en_US","og_type":"article","og_title":"Carta Editorial - S\u00e9ptimo Sentido","og_description":"La eterna lucha va acerca de c\u00f3mo resolver las necesidades inmediatas sin llevarse por delante las necesidades m\u00e1s integrales.","og_url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2017-06-11T06:06:53+00:00","article_modified_time":"2017-06-10T02:41:59+00:00","og_image":[{"width":828,"height":651,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/portada-2.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"Glenda Gir\u00f3n","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/portada-2.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/portada-2.jpg","width":828,"height":651},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/","name":"Carta Editorial - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/#primaryimage"},"datePublished":"2017-06-11T06:06:53+00:00","dateModified":"2017-06-10T02:41:59+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-8\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Carta Editorial"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c","name":"Glenda Gir\u00f3n","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","caption":"Glenda Gir\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/portada-2.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-70","jetpack-related-posts":[{"id":447,"url":"https:\/\/7s.laprensagrafica.com\/en\/el-desgaste-de-montecristo\/","url_meta":{"origin":434,"position":0},"title":"El desgaste de Montecristo","date":"11 June, 2017","format":false,"excerpt":"Las comunidades y los ecosistemas alrededor del Parque Nacional Montecristo comparten la necesidad del agua. Aunque ambos necesitan coexistir para perdurar, la subsistencia impulsa al desequilibrio. Los bosques perdidos en las laderas han llevado la situaci\u00f3n a un punto cr\u00edtico.","rel":"","context":"In &quot;Reportaje Nacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/Foto-principal.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3373,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-15-abril-2018\/","url_meta":{"origin":434,"position":1},"title":"Carta editorial","date":"15 April, 2018","format":false,"excerpt":"Que ahora el agua fluya por las tuber\u00edas deber\u00eda ser un ep\u00edlogo feliz; pero esto es El Salvador. Y ac\u00e1, el acceso a los derechos b\u00e1sicos est\u00e1 atravesado por las violencias.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/04\/Ssen_001.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7619,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-26-abril-2020\/","url_meta":{"origin":434,"position":2},"title":"Carta Editorial","date":"26 April, 2020","format":false,"excerpt":"[:es]La ERC que se sufre en las comunidades agr\u00edcolas viene desnudando inequidades e injusticias sociales desde hace d\u00e9cadas.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/04\/montaje2018portaditaca-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4439,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-09-septiembre-2018-2\/","url_meta":{"origin":434,"position":3},"title":"Carta Editorial","date":"16 September, 2018","format":false,"excerpt":"Hacer una intervenci\u00f3n en favor del \u00e1rea de conservaci\u00f3n siempre ha tra\u00eddo a cuenta la relaci\u00f3n que los pobladores tienen con el medio ambiente. No se les puede pedir que cuiden algo y pasar por alto el hambre.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/Ssen09162018001.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7198,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-02-febrero-2020\/","url_meta":{"origin":434,"position":4},"title":"Carta Editorial","date":"2 February, 2020","format":false,"excerpt":"[:es]En los 21 mil kil\u00f3metros que forman El Salvador, hay zonas a las que el sistema p\u00fablico de salud no se ha podido instalar.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/02\/montaje2018portaditaca.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7867,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-07-junio-2020\/","url_meta":{"origin":434,"position":5},"title":"Carta Editorial","date":"7 June, 2020","format":false,"excerpt":"[:es]No se presupuest\u00f3 el hambre que Rosa y sus hijos iban a comenzar a sufrir tan pronto ella ya no pudiera sacar su carret\u00f3n de minutas.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/06\/montaje2018portaditaca.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/434"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=434"}],"version-history":[{"count":2,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/434\/revisions"}],"predecessor-version":[{"id":437,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/434\/revisions\/437"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/435"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=434"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=434"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=434"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}