{"id":4316,"date":"2018-08-26T00:05:02","date_gmt":"2018-08-26T06:05:02","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=4316"},"modified":"2018-08-27T07:21:32","modified_gmt":"2018-08-27T13:21:32","slug":"el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/","title":{"rendered":"\u201cEl acto m\u00e1s grande de amor en mi vida es hacer las cosas con pasi\u00f3n\u201d"},"content":{"rendered":"<h4>\u00bfCu\u00e1l es tu miedo m\u00e1s grande?<\/h4>\n<p>No poder ayudar a mi pa\u00eds desde lo que hago: comunicar, hacer teatro, ense\u00f1ar, conectar.<\/p>\n<h4>\u00bfCu\u00e1l superpoder quisieras tener?<\/h4>\n<p>\u00a1Definitivamente quisiera poder multiplicarme! As\u00ed podr\u00eda tener m\u00e1s tiempo para hacer m\u00e1s cosas. M\u00e1s en mis clases, instructor\u00edas, talleres e investigaciones.<\/p>\n<h4>\u00bfCree que es importante tener un empleo estable?<\/h4>\n<p>Es importante sentirse estable. Y eso tiene que ver mucho con conocerse a uno mismo, estar dispuesto a aprender y desaprender, ser parte de proyectos que enamoren, vivir con un prop\u00f3sito y luchar por lo que uno quiere y cree.<\/p>\n<h4>\u00bfQu\u00e9 o qui\u00e9n es el m\u00e1s grande amor en su vida?<\/h4>\n<p>El acto m\u00e1s grande de amor en mi vida es hacer las cosas con pasi\u00f3n.<\/p>\n<h4>\u00bfC\u00f3mo reacciona a las cr\u00edticas si cree que son injustificadas?<\/h4>\n<p>Todos tenemos algo valioso que aportar ante cualquier situaci\u00f3n. Y frente a diferencias de pensamiento, el di\u00e1logo y el sano debate son puentes para encontrar puntos en com\u00fan.<\/p>\n<h4>\u00bfC\u00f3mo imagina su vida dentro de 10 a\u00f1os?<\/h4>\n<p>Me veo trabajando en el desarrollo de la industria art\u00edstica y creativa de nuestro pa\u00eds, facilitando experiencias para que otras personas se acerquen al teatro y comunicando lo que pienso, siempre al servicio de los dem\u00e1s.<\/p>\n<h4>\u00bfQu\u00e9 no perdonar\u00eda?<\/h4>\n<p>No cambiar, el conformismo, el no ver las cosas de otra manera, la injusticia, la desigualdad y la falta de empat\u00eda.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Es graduado del diplomado en Actuaci\u00f3n del Centro Nacional de Artes (CENAR) y estudiante de Comunicaciones Integradas de Marketing en la Escuela M\u00f3nica Herrera. Trabaj\u00f3 en el equipo de recaudaci\u00f3n de fondos para la pel\u00edcula salvadore\u00f1a \u201cVolar\u201d y tambi\u00e9n en la campa\u00f1a La Cachada Teatro. Desde 2017 es miembro del movimiento De Estudiantes para Estudiantes, un programa experimental de formaci\u00f3n para futuros docentes universitarios del Laboratorio de Dise\u00f1o Estrat\u00e9gico, Syncros.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":4351,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-preguntas.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201cEl acto m\u00e1s grande de amor en mi vida es hacer las cosas con pasi\u00f3n\u201d - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cEl acto m\u00e1s grande de amor en mi vida es hacer las cosas con pasi\u00f3n\u201d - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Es graduado del diplomado en Actuaci\u00f3n del Centro Nacional de Artes (CENAR) y estudiante de Comunicaciones Integradas de Marketing en la Escuela M\u00f3nica Herrera. Trabaj\u00f3 en el equipo de recaudaci\u00f3n de fondos para la pel\u00edcula salvadore\u00f1a \u201cVolar\u201d y tambi\u00e9n en la campa\u00f1a La Cachada Teatro. Desde 2017 es miembro del movimiento De Estudiantes para Estudiantes, un programa experimental de formaci\u00f3n para futuros docentes universitarios del Laboratorio de Dise\u00f1o Estrat\u00e9gico, Syncros.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-08-26T06:05:02+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-08-27T13:21:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/08\/IMG_4117.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"640\" \/>\n\t<meta property=\"og:image:height\" content=\"960\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9ptimo Sentido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/08\/IMG_4117.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/08\/IMG_4117.jpg\",\"width\":640,\"height\":960},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/\",\"name\":\"\u201cEl acto m\u00e1s grande de amor en mi vida es hacer las cosas con pasi\u00f3n\u201d - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/#primaryimage\"},\"datePublished\":\"2018-08-26T06:05:02+00:00\",\"dateModified\":\"2018-08-27T13:21:32+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cEl acto m\u00e1s grande de amor en mi vida es hacer las cosas con pasi\u00f3n\u201d\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\",\"name\":\"S\u00e9ptimo Sentido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"caption\":\"S\u00e9ptimo Sentido\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cEl acto m\u00e1s grande de amor en mi vida es hacer las cosas con pasi\u00f3n\u201d - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/","og_locale":"en_US","og_type":"article","og_title":"\u201cEl acto m\u00e1s grande de amor en mi vida es hacer las cosas con pasi\u00f3n\u201d - S\u00e9ptimo Sentido","og_description":"Es graduado del diplomado en Actuaci\u00f3n del Centro Nacional de Artes (CENAR) y estudiante de Comunicaciones Integradas de Marketing en la Escuela M\u00f3nica Herrera. Trabaj\u00f3 en el equipo de recaudaci\u00f3n de fondos para la pel\u00edcula salvadore\u00f1a \u201cVolar\u201d y tambi\u00e9n en la campa\u00f1a La Cachada Teatro. Desde 2017 es miembro del movimiento De Estudiantes para Estudiantes, un programa experimental de formaci\u00f3n para futuros docentes universitarios del Laboratorio de Dise\u00f1o Estrat\u00e9gico, Syncros.","og_url":"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-08-26T06:05:02+00:00","article_modified_time":"2018-08-27T13:21:32+00:00","og_image":[{"width":640,"height":960,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/08\/IMG_4117.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"S\u00e9ptimo Sentido","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/08\/IMG_4117.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/08\/IMG_4117.jpg","width":640,"height":960},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/","name":"\u201cEl acto m\u00e1s grande de amor en mi vida es hacer las cosas con pasi\u00f3n\u201d - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/#primaryimage"},"datePublished":"2018-08-26T06:05:02+00:00","dateModified":"2018-08-27T13:21:32+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/en\/el-acto-mas-grande-de-amor-en-mi-vida-es-hacer-las-cosas-con-pasion\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"\u201cEl acto m\u00e1s grande de amor en mi vida es hacer las cosas con pasi\u00f3n\u201d"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b","name":"S\u00e9ptimo Sentido","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","caption":"S\u00e9ptimo Sentido"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/08\/IMG_4117.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-17C","jetpack-related-posts":[{"id":1796,"url":"https:\/\/7s.laprensagrafica.com\/en\/importante-lo-uno-le-apasiona-la-vida\/","url_meta":{"origin":4316,"position":0},"title":"\u201cEs importante hacer lo que a uno le apasiona en la vida\u201d","date":"29 October, 2017","format":false,"excerpt":"Mario Guardado es un actor salvadore\u00f1o de 36 a\u00f1os. Desde 2006 se ha formado en proyectos de teatro universitario y teatro independiente. Es egresado del T\u00e9cnico en Artes Dram\u00e1ticas de la Universidad Jos\u00e9 Mat\u00edas Delgado. Actualmente forma parte del elenco de la obra \u201cPor delante y por detr\u00e1s\u201d del Teatro\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/mario-guardado.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2738,"url":"https:\/\/7s.laprensagrafica.com\/en\/los-secretos-esconde-la-vida-circo\/","url_meta":{"origin":4316,"position":1},"title":"Los secretos que esconde la vida en el circo","date":"28 January, 2018","format":false,"excerpt":"Dejarlo todo por seguir una pasi\u00f3n es el factor com\u00fan de los trabajadores del Circo Ruso sobre Hielo. Estas son las historias de algunos de estos n\u00f3madas contempor\u00e1neos.","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/fsep28012018corcosta06.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6378,"url":"https:\/\/7s.laprensagrafica.com\/en\/toda-mi-personalidad-es-una-extravagancia\/","url_meta":{"origin":4316,"position":2},"title":"&#8220;Toda mi personalidad es una extravagancia&#8221;","date":"22 September, 2019","format":false,"excerpt":"Rafael Figueroa es un artista visual que basa su trabajo en la b\u00fasqueda de un funcionamiento org\u00e1nico entre distintas t\u00e9cnicas como: el dibujo, la pintura y medios contempor\u00e1neos. Adem\u00e1s, le interesa abordar problem\u00e1ticas sobre la convivencia social y las relaciones personales en vinculaci\u00f3n con el entorno. Su obra se ha\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/09\/fsep22092019xxcues39.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5608,"url":"https:\/\/7s.laprensagrafica.com\/en\/ya-tengo-el-mejor-superpoder-el-cafe\/","url_meta":{"origin":4316,"position":3},"title":"\u201cYa tengo el mejor superpoder: \u00a1el caf\u00e9!\u201d","date":"28 April, 2019","format":false,"excerpt":"Es un salvadore\u00f1o entrenador de baristas. Ha preparado a profesionales del caf\u00e9 para ganar o llegar a las finales de Campeonato Mundial de Baristas. As\u00ed ha estado detr\u00e1s del triunfo de dos campeones, dos finalistas y cinco semifinalistas.","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/04\/fsep27042019corbolanos234ca.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7831,"url":"https:\/\/7s.laprensagrafica.com\/en\/la-vida-no-es-una-dicotomia\/","url_meta":{"origin":4316,"position":4},"title":"&#8220;La vida no es una dicotom\u00eda&#8221;","date":"31 May, 2020","format":false,"excerpt":"[:es]Eduardo Salazar es un comunicador salvadore\u00f1o. Actualmente trabaja como gestor de campa\u00f1as publicitarias de compra program\u00e1tica en AKQA, una agencia digital internacional con presencia en El Salvador. Es graduado de la licenciatura en Ciencias de la Comunicaci\u00f3n de la Universidad Dr. Jos\u00e9 Mat\u00edas Delgado.[:]","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/05\/fsep31052020corcuest92.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1687,"url":"https:\/\/7s.laprensagrafica.com\/en\/no-me-falta-nada\/","url_meta":{"origin":4316,"position":5},"title":"\u201cNo me hace falta nada\u201d","date":"15 October, 2017","format":false,"excerpt":"Argelia Quintana ha dedicado los \u00faltimos 25 a\u00f1os de su vida a recolectar la poes\u00eda de su hija, Leyla Quintana. Leyla era poeta y muri\u00f3 a los 21 a\u00f1os en el contexto de la guerra civil. Desde la muerte de su hija, Argelia, quien ahora tiene 72 a\u00f1os, se ha\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/7-preguntas.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4316"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=4316"}],"version-history":[{"count":2,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4316\/revisions"}],"predecessor-version":[{"id":4352,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4316\/revisions\/4352"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/4351"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=4316"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=4316"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=4316"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}