{"id":4157,"date":"2018-07-29T00:06:32","date_gmt":"2018-07-29T06:06:32","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=4157"},"modified":"2018-07-28T21:12:54","modified_gmt":"2018-07-29T03:12:54","slug":"carta-editorial-29-julio-2018","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-29-julio-2018\/","title":{"rendered":"Carta Editorial"},"content":{"rendered":"<p>Rub\u00e9n Mart\u00ednez es el arquitecto que dise\u00f1\u00f3 y ayud\u00f3 a construir la iglesia El Rosario. Tambi\u00e9n es el cerebro detr\u00e1s del Cristo de la Paz y del Monumento a la Constituci\u00f3n. Hizo bustos: desde Roberto d&#8217;Aubuisson hasta Mauricio Funes. En una iglesia de Costa Rica hay una m\u00e1s de sus obras, una de 4 metros. Su carrera est\u00e1 llena de esos que ahora son referencia f\u00edsica de la ciudad, ha recibido encargos desde fuera del pa\u00eds y hasta ha sido imitado. Su queja, sin embargo, es la misma que la de otros artistas que han sido entrevistados en este espacio: el reconocimiento de este pa\u00eds que lo vio nacer ha tardado demasiado en llegar.<\/p>\n<p>No es una queja hueca. No es algo que se pueda dejar pasar solo porque todos lo dicen. De hecho, deber\u00eda ser motivo de mucha verg\u00fcenza que este sea el sentimiento que uniforma a quienes aqu\u00ed han buscado mantener una carrera relacionada con el arte y la cultura. Dice mucho, para mal, de qui\u00e9nes somos y c\u00f3mo nos recibimos.<br \/>\nLa forma en la que se construye la memoria hist\u00f3rica de un pa\u00eds est\u00e1 influenciada por los personajes que toman por asalto las coyunturas. As\u00ed, un texto de esta edici\u00f3n narra c\u00f3mo la ciudad de Medell\u00edn, en Colombia, lucha por descartar del ideario colectivo la imagen rom\u00e1ntica de Pablo Escobar como un Robin Hood y busca que ning\u00fan narcotraficante sanguinario pueda limpiar su imagen y soslayar sus cr\u00edmenes entre la sed de h\u00e9roes de una sociedad de posguerra.<\/p>\n<p>En El Salvador nos falta dar su lugar a personajes que sean referentes con m\u00edstica de disciplina y dedicaci\u00f3n. Nos falta entregar a las nuevas generaciones informaci\u00f3n suficiente de esos personajes que, al margen de sus imperfecciones y de la ingratitud del entorno, supieron formarse, crear y dejar huella. Urge ser m\u00e1s justos para encontrar la ruta a la reconciliaci\u00f3n.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>En El Salvador nos falta dar su lugar a personajes que sean referentes con m\u00edstica de disciplina y dedicaci\u00f3n.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":4155,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-carta.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carta Editorial - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta Editorial - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"En El Salvador nos falta dar su lugar a personajes que sean referentes con m\u00edstica de disciplina y dedicaci\u00f3n.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-29T06:06:32+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-29T03:12:54+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/montaje2018portaditaca28.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"575\" \/>\n\t<meta property=\"og:image:height\" content=\"719\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Glenda Gir\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/montaje2018portaditaca28.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/montaje2018portaditaca28.jpg\",\"width\":575,\"height\":719},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/\",\"name\":\"Carta Editorial - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/#primaryimage\"},\"datePublished\":\"2018-07-29T06:06:32+00:00\",\"dateModified\":\"2018-07-29T03:12:54+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta Editorial\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\",\"name\":\"Glenda Gir\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"caption\":\"Glenda Gir\u00f3n\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta Editorial - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/","og_locale":"en_US","og_type":"article","og_title":"Carta Editorial - S\u00e9ptimo Sentido","og_description":"En El Salvador nos falta dar su lugar a personajes que sean referentes con m\u00edstica de disciplina y dedicaci\u00f3n.","og_url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-07-29T06:06:32+00:00","article_modified_time":"2018-07-29T03:12:54+00:00","og_image":[{"width":575,"height":719,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/montaje2018portaditaca28.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"Glenda Gir\u00f3n","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/montaje2018portaditaca28.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/montaje2018portaditaca28.jpg","width":575,"height":719},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/","name":"Carta Editorial - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/#primaryimage"},"datePublished":"2018-07-29T06:06:32+00:00","dateModified":"2018-07-29T03:12:54+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-29-julio-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Carta Editorial"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c","name":"Glenda Gir\u00f3n","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","caption":"Glenda Gir\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/montaje2018portaditaca28.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-153","jetpack-related-posts":[{"id":8118,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-23-agosto-2020\/","url_meta":{"origin":4157,"position":0},"title":"Carta Editorial","date":"23 August, 2020","format":false,"excerpt":"[:es]Garc\u00eda es parte de un movimiento de escritores que van creando sus propias escaleras para avanzar en un pa\u00eds con una industria muy cruda y muy afectada por todas las otras crisis.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/08\/montaje2018portaditaca-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4478,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-23-septiembre-2018\/","url_meta":{"origin":4157,"position":1},"title":"Carta Editorial","date":"23 September, 2018","format":false,"excerpt":"Si las leyes que nos definen a todos como iguales fueran palabra viva, una discapacidad f\u00edsica no deber\u00eda ser raz\u00f3n para la exclusi\u00f3n educativa o social.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/montaje2018portadsep23f.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":511,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-9\/","url_meta":{"origin":4157,"position":2},"title":"Carta Editorial","date":"18 June, 2017","format":false,"excerpt":"Bajo su cargo, como rese\u00f1a el personal de la instituci\u00f3n, el complejo ha crecido en infraestructura y tambi\u00e9n en la calidad de la ense\u00f1anza que se imparte.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/portada-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6191,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-18-agosto-2019\/","url_meta":{"origin":4157,"position":3},"title":"Carta Editorial","date":"18 August, 2019","format":false,"excerpt":"La laguna de Alegr\u00eda, como se lee en el reportaje realizado por el periodista Stanley Luna, es el coraz\u00f3n de una poblaci\u00f3n. De ella emanan historias que se han hecho eternas en la tradici\u00f3n oral de los residentes de la zona.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/08\/montaje2018portaditaca-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8096,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-16-agosto-2020\/","url_meta":{"origin":4157,"position":4},"title":"Carta Editorial","date":"16 August, 2020","format":false,"excerpt":"[:es]El gremio art\u00edstico ya era vulnerable antes de que el virus llegara a imponer normas de distanciamiento social. Ahora, necesita reinventarse. Necesita encontrar el camino para salvarse y salvarnos a todos.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/08\/montaje2018portaditaca-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3875,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-24-junio-2018\/","url_meta":{"origin":4157,"position":5},"title":"Carta Editorial","date":"24 June, 2018","format":false,"excerpt":"A menor edad de la v\u00edctima, mayor es el porcentaje de violencias sexuales que se comenten en entornos cercanos, como la casa, la escuela, la iglesia, la comunidad.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/portada_septimo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4157"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=4157"}],"version-history":[{"count":1,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4157\/revisions"}],"predecessor-version":[{"id":4158,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4157\/revisions\/4158"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/4155"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=4157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=4157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=4157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}