{"id":4097,"date":"2018-07-15T00:06:44","date_gmt":"2018-07-15T06:06:44","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=4097"},"modified":"2018-07-14T14:04:20","modified_gmt":"2018-07-14T20:04:20","slug":"carta-editorial-15-julio-2018","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-15-julio-2018\/","title":{"rendered":"Carta Editorial"},"content":{"rendered":"<p>Esta edici\u00f3n podr\u00eda ser un resumen a luz y sombra de qu\u00e9 sucede a los ni\u00f1os que migran a Estados Unidos. Por un lado, podr\u00edan encontrar una brillante oportunidad para desarrollar sus peculiares talentos; aunque, por el otro, podr\u00edan acabar separados de sus padres, encerrados y solos ante un juez que, en el mejor de los casos, los despachar\u00e1 con una orden de salida voluntaria. En cualquiera de los casos lo que uniforma es un trauma que dif\u00edcilmente ser\u00e1 superado.<\/p>\n<p>Javier Zamora es un salvadore\u00f1o que, a los 28 a\u00f1os, ya ha estudiado en varias de las mejores universidades de Estados Unidos. Cuando ten\u00eda solo nueve a\u00f1os, sali\u00f3 de San Luis La Herradura para recorrer una ruta del migrante que se le qued\u00f3 grabada como una herida de las que nunca se curan del todo.<\/p>\n<p>Estudi\u00f3 con becas. Esas que se ganan al demostrar habilidades extraordinarias. Ese tipo de habilidades que obligan a hacer la pregunta de qu\u00e9 habr\u00eda sido de \u00e9l en el San Luis La Herradura.<br \/>\nEsta edici\u00f3n podr\u00eda ser un resumen de lo que sucede a los ni\u00f1os migrantes. Pero, en realidad, los textos incluidos llevan a pensar m\u00e1s en lo que nos concierne como pa\u00eds: \u00bfpor qu\u00e9 los ni\u00f1os son obligados a migrar para poder superar las enormes barreras que les impone la desigualdad?<\/p>\n<p>Zamora tuvo que huir de una posguerra que ya daba avisos de ser una etapa no de reconciliaci\u00f3n, sino que de profundizaci\u00f3n de las lesiones sociales m\u00e1s graves. En su reciente regreso al pa\u00eds, el joven se ha venido a encontrar con la descendiente de aquel proceso mal hecho: la violencia, esa por la que desde la casa de sus abuelos escuch\u00f3 las balas que pusieron fin a la vida de alguien. Esa es la que lo tiene desesperado por irse a Estados Unidos. Un sentimiento que provoca buena parte de las migraciones actuales y que, para el pa\u00eds receptor, ya no viene siendo motivo suficiente para dar asilo.<\/p>\n<p>Muchos de los ni\u00f1os que est\u00e1n llegando ahora ante un juez de Migraci\u00f3n en Estados Unidos, solos, son menores que Zamora cuando emprendi\u00f3 el camino. Pero son el rostro del gran fracaso de la educaci\u00f3n p\u00fablica, de la salud p\u00fablica, de la seguridad. Esas que, pese a ser conocidas como \u201cp\u00fablicas\u201d, no alcanzan a llegar a todos. Algo que, en su momento, tambi\u00e9n Zamora represent\u00f3.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Cuando ten\u00eda solo nueve a\u00f1os, sali\u00f3 de San Luis La Herradura para recorrer una ruta del migrante que se le qued\u00f3 grabada como una herida de las que nunca se curan del todo.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":4098,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-carta.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carta Editorial - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta Editorial - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Cuando ten\u00eda solo nueve a\u00f1os, sali\u00f3 de San Luis La Herradura para recorrer una ruta del migrante que se le qued\u00f3 grabada como una herida de las que nunca se curan del todo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-15T06:06:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-14T20:04:20+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/07_15_2018-Ssen07152018001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"737\" \/>\n\t<meta property=\"og:image:height\" content=\"922\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Glenda Gir\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/07_15_2018-Ssen07152018001.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/07_15_2018-Ssen07152018001.jpg\",\"width\":737,\"height\":922},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/\",\"name\":\"Carta Editorial - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/#primaryimage\"},\"datePublished\":\"2018-07-15T06:06:44+00:00\",\"dateModified\":\"2018-07-14T20:04:20+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta Editorial\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\",\"name\":\"Glenda Gir\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"caption\":\"Glenda Gir\u00f3n\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta Editorial - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/","og_locale":"en_US","og_type":"article","og_title":"Carta Editorial - S\u00e9ptimo Sentido","og_description":"Cuando ten\u00eda solo nueve a\u00f1os, sali\u00f3 de San Luis La Herradura para recorrer una ruta del migrante que se le qued\u00f3 grabada como una herida de las que nunca se curan del todo.","og_url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-07-15T06:06:44+00:00","article_modified_time":"2018-07-14T20:04:20+00:00","og_image":[{"width":737,"height":922,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/07_15_2018-Ssen07152018001.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"Glenda Gir\u00f3n","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/07_15_2018-Ssen07152018001.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/07_15_2018-Ssen07152018001.jpg","width":737,"height":922},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/","name":"Carta Editorial - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/#primaryimage"},"datePublished":"2018-07-15T06:06:44+00:00","dateModified":"2018-07-14T20:04:20+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-15-julio-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Carta Editorial"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c","name":"Glenda Gir\u00f3n","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","caption":"Glenda Gir\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/07_15_2018-Ssen07152018001.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-145","jetpack-related-posts":[{"id":5671,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-12-mayo-2019\/","url_meta":{"origin":4097,"position":0},"title":"Carta Editorial","date":"12 May, 2019","format":false,"excerpt":"La necesidad de esta informaci\u00f3n oficial tambi\u00e9n reside en la importancia que tiene para la elaboraci\u00f3n de estudios, investigaciones o encuestas para que sus resultados sean coherentes con la realidad.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/05\/portada.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5641,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-05-mayo-2019\/","url_meta":{"origin":4097,"position":1},"title":"Carta Editorial","date":"5 May, 2019","format":false,"excerpt":"Ma\u00f1ana, otros cientos se van a tener que ir por razones casi id\u00e9nticas a las que, hace 10 a\u00f1os, dieron los que en ese momento se fueron.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/05\/montaje2018portaditaca.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8066,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-02-agosto-2020\/","url_meta":{"origin":4097,"position":2},"title":"Carta Editorial","date":"2 August, 2020","format":false,"excerpt":"[:es]Lo que Attali recomienda a los gobiernos es aplicar medidas de econom\u00eda de guerra[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/08\/montaje2018portaditaca.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6239,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-25-agosto-2019\/","url_meta":{"origin":4097,"position":3},"title":"Carta Editorial","date":"25 August, 2019","format":false,"excerpt":"Y ac\u00e1 estamos otra vez, compungidos, sin saber qu\u00e9 tiempo usar para contar esto. \u00bfPasado? Cuando no lo hemos superado. \u00bfPresente? Cuando hablamos de ausencias. \u00bfFuturo? Ojal\u00e1 que no.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/08\/ortada-7s.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4122,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-22-julio-2018\/","url_meta":{"origin":4097,"position":4},"title":"Carta Editorial","date":"22 July, 2018","format":false,"excerpt":"Este reportaje es un recordatorio m\u00e1s de que es indispensable ver hacia las escuelas si lo que se busca es una soluci\u00f3n eficaz a los principales problemas sociales.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/portada_septimo_22-julio-2018.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8320,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-04-octubre-2020\/","url_meta":{"origin":4097,"position":5},"title":"Carta Editorial","date":"4 October, 2020","format":false,"excerpt":"[:es]Este es un relato de las tribulaciones por las cuales han tenido que pasar dos mujeres, dos madres, en su camino hacia un territorio que, creen, puede ofrecerles m\u00e1s oportunidades de sobrevivir que este.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/10\/montaje2018portaditaca.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4097"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=4097"}],"version-history":[{"count":1,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4097\/revisions"}],"predecessor-version":[{"id":4099,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4097\/revisions\/4099"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/4098"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=4097"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=4097"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=4097"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}