{"id":4048,"date":"2018-07-08T00:01:24","date_gmt":"2018-07-08T06:01:24","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=4048"},"modified":"2018-07-07T18:17:38","modified_gmt":"2018-07-08T00:17:38","slug":"alma-guillermoprieto-maestra-del-periodismo","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/alma-guillermoprieto-maestra-del-periodismo\/","title":{"rendered":"Alma Guillermoprieto, maestra del periodismo"},"content":{"rendered":"<figure id=\"attachment_4049\" style=\"width: 1920px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"4049\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/alma-guillermoprieto-maestra-del-periodismo\/fsep08072018coralma03ca\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca.jpg\" data-orig-size=\"1920,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep08072018coralma03ca\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Nombre&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca-300x169.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca-1024x576.jpg\" loading=\"lazy\" class=\"wp-image-4049 size-full\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca.jpg\" alt=\"\" width=\"1920\" height=\"1080\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca.jpg 1920w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca-300x169.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca-768x432.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca-1024x576.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca-1900x1069.jpg 1900w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca-1200x675.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca-500x281.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca-1000x563.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca-700x394.jpg 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-caption-text\">Alma Estela Guillermoprieto Panigua<\/figcaption><\/figure>\n<p>En su cocina est\u00e1n las huellas de sus experimentos. Lo que ahora tiene en la cabeza es c\u00f3mo lograr una buena masa para hacer pizza. No quiere que le quede muy delgada, tampoco muy gruesa: intenta encontrar el t\u00e9rmino preciso y est\u00e1 dispuesta a dedicar las horas que sean necesarias para conseguirlo. Alma Guillermoprieto es perseverante tambi\u00e9n en eso. Lo ha sido durante sus 40 a\u00f1os de vida period\u00edstica, a\u00f1os en los que ha perseguido historias por toda Am\u00e9rica Latina y o\u00eddo a sus protagonistas con la atenci\u00f3n y la paciencia del que sabe que al otro lado hay una vida que importa. A\u00f1os en los que ha escrito los mejores art\u00edculos sobre la realidad de estos pa\u00edses \u2013sus revoluciones, sus conflictos\u2013 y que ha publicado en medios como The New Yorker, The New York Review of Books, The Guardian o The Washington Post.<\/p>\n<p>Mucho de lo que los lectores de habla inglesa conocen del conflicto colombiano, y del latinoamericano en general, se debe precisamente a los textos de esta escritora y periodista que se ha dedicado a investigar, entender y traducir nuestra realidad, con la profundidad y la sensibilidad necesarias para transmitir lo que significa un territorio tan complejo. Sus reportajes est\u00e1n reunidos en libros como \u201cAl pie de un volc\u00e1n te escribo\u201d, \u201cLos a\u00f1os en que no fuimos felices\u201d, \u201cDesde el pa\u00eds de nunca jam\u00e1s\u201d, \u201cHistoria escrita\u201d y \u201cLas guerras en Colombia\u201d (que este mes tendr\u00e1 una nueva edici\u00f3n). Tambi\u00e9n es autora de \u201cSamba\u201d, su primer libro, en el que relata la vida cotidiana de una escuela de samba en una favela de R\u00edo de Janeiro; de \u201cLa Habana en un espejo\u201d, que describe los meses que vivi\u00f3 en la capital cubana como profesora de danza; y de \u201cLos placeres y los d\u00edas\u201d, donde re\u00fane, entre otros, su texto sobre el tango y sobre Celia Cruz. Ning\u00fan tema le es ajeno. Durante dos a\u00f1os escribi\u00f3 una columna de gastronom\u00eda en la revista mexicana Nexos y ah\u00ed daba rienda suelta a una de las cosas que m\u00e1s le apasionan: la comida.<\/p>\n<p>Ya es conocido que lleg\u00f3 al oficio del periodismo por accidente, que su sue\u00f1o era ser bailarina y termin\u00f3 siendo cronista estrella de The New Yorker; que naci\u00f3 en Ciudad de M\u00e9xico, hija de padre mexicano y madre guatemalteca; que su nombre completo es Alma Estela Guillermoprieto Paniagua y que ese Guillermoprieto \u2013as\u00ed, unido\u2013 viene de muchas generaciones atr\u00e1s y si se escarba, llegamos a dar con el poeta y pol\u00edtico mexicano de comienzos del siglo XIX Guillermo Prieto; que en 1995, Gabriel Garc\u00eda M\u00e1rquez la busc\u00f3 porque quer\u00eda que formara parte de lo que en ese momento era un sue\u00f1o: la Fundaci\u00f3n Nuevo Periodismo. Alma inaugur\u00f3 el taller de cr\u00f3nica en Cartagena y continu\u00f3 dict\u00e1ndolo durante muchos a\u00f1os. Por ese taller han pasado decenas de reporteros latinoamericanos que se quedaron con sus ense\u00f1anzas en la memoria. Sus ense\u00f1anzas y su ejemplo. Porque de lo que ella se aprende no es solo teor\u00eda del oficio, es una forma de ser periodista. Sabemos tambi\u00e9n que le gusta leer novelas largas \u2013aunque hoy prefiere la no ficci\u00f3n, sobre todo la ciencia\u2013 y que disfruta el tiempo junto a las plantas que est\u00e1n en su balc\u00f3n. Alma tiene un nombre que le encaja muy bien.<\/p>\n<p>El mes pasado recibi\u00f3 el Premio Princesa de Asturias de Comunicaci\u00f3n y Humanidades, y as\u00ed se une a un prestigioso listado de ganadores en la misma categor\u00eda, en el que aparecen personajes como Umberto Eco, George Steiner, Annie Leibovitz, Zygmunt Bauman o Ryszard Kapuscinski. Ya tiene en su haber el Mar\u00eda Moors Cabot \u2013el reconocimiento internacional m\u00e1s antiguo en el periodismo\u2013 y el Ortega y Gasset, que le entregaron el a\u00f1o pasado por su trayectoria profesional, para citar solo dos m\u00e1s de los premios que ha recibido. Desde que anunciaron que el Princesa de Asturias hab\u00eda llegado a sus manos, Alma Guillermoprieto ha tenido que responder decenas de entrevistas. Y no hay que conocerla tanto para entender que ella prefiere estar del otro lado de la libreta: en el lugar del que toma notas y pregunta.<\/p>\n<p><strong>Suele decir que en su carrera result\u00f3 esencial la presencia del editor. \u00bfCu\u00e1l de todos la marc\u00f3 m\u00e1s y qu\u00e9 ense\u00f1anzas recuerda?<\/strong><br \/>\nJohn Bennet, sin duda. \u00c9l edit\u00f3 todos mis textos en The New Yorker. Y es curioso porque, cuando trabaj\u00e1bamos juntos, era la intimidad absoluta. Fuera de eso, nada. Se jubil\u00f3 hace dos a\u00f1os y no le he mandado ni una notita. Incre\u00edble. Despu\u00e9s de 20 a\u00f1os de trabajo. \u00bfQu\u00e9 me ense\u00f1\u00f3? Si es aburrido, no va. Quita lo m\u00e1s que pueda los entrecomillados porque es dif\u00edcil que alguien hable de manera m\u00e1s interesante que t\u00fa, y vuelven lento el texto. Me acuerdo cuando estaba trabajando en el reportaje sobre Lima, durante el fujimorazo, que yo buscaba una palabra para el p\u00e1rrafo en el que dec\u00eda que todo estaba tan caro que la gente escuchaba hablar de un guiso y se mor\u00eda de la risa. Pero lo que hab\u00eda o\u00eddo que produc\u00eda risa no era una palabra chistosa en ingl\u00e9s. Era espagueti. Y no funcionaba. John y yo nos pusimos a buscar la palabra precisa. Hablamos una hora a larga distancia, cuando esas llamadas costaban plata, sobre esa pendejada. Ri\u00e9ndonos. Hasta que de repente dije: \u00a1Noodles! Y claro: esa era. La chispa de una frase depend\u00eda de eso; para que cuando yo dijera que la gente se re\u00eda, el lector se riera tambi\u00e9n. Ya no quedan editores as\u00ed. Y bueno, est\u00e1 su lecci\u00f3n de \u00e9tica: trata a todos tus entrevistados como si tuvieran $5 millones para meterte una demanda con el mejor abogado.<\/p>\n<figure id=\"attachment_4050\" style=\"width: 1600px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"4050\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/alma-guillermoprieto-maestra-del-periodismo\/fsep08072018coralma02\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma02.jpg\" data-orig-size=\"1600,900\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep08072018coralma02\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Imagen&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma02-300x169.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma02-1024x576.jpg\" loading=\"lazy\" class=\"size-full wp-image-4050\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma02.jpg\" alt=\"\" width=\"1600\" height=\"900\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma02.jpg 1600w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma02-300x169.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma02-768x432.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma02-1024x576.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma02-1200x675.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma02-500x281.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma02-1000x563.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma02-700x394.jpg 700w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><figcaption class=\"wp-caption-text\">Imagen<\/figcaption><\/figure>\n<p><strong>Buena lecci\u00f3n. Con frecuencia a la gente sin recursos, a los desconocidos, a los humildes, se les pasa por encima.<\/strong><br \/>\nClaro, porque los pobres no tienen abogados. Entonces muchos escriben de ellos lo que se les ocurre. Y se meten a su cuarto, hasta adentro, sin pedir permiso.<\/p>\n<p><strong>Empez\u00f3 en el periodismo a finales de los a\u00f1os setenta, cubriendo la insurrecci\u00f3n sandinista en Nicaragua. \u00bfPor qu\u00e9 result\u00f3 tan importante para usted en ese momento la compa\u00f1\u00eda de la fot\u00f3grafa estadounidense Susan Meiselas?<\/strong><br \/>\nYo tuve la ventaja de no saber nada de periodismo cuando inici\u00e9 mi vida como reportera. No ten\u00eda idea. No sab\u00eda cu\u00e1les eran los grandes medios. Escrib\u00eda para The Guardian y pensaba que era un pasqu\u00edn. Y c\u00f3mo no iba a serlo, si me hab\u00edan contratado a m\u00ed. Adem\u00e1s, pagaban una miseria. Susan era de mi edad y nos hicimos amigas r\u00e1pidamente. Ella llevaba varios meses en Nicaragua y era como la gu\u00eda. Yo dorm\u00eda en el piso de su habitaci\u00f3n porque el dinero no me daba para pagar un cuarto de hotel. Sal\u00edamos juntas a trabajar. Como todos los buenos fot\u00f3grafos, ella es muy buena reportera. Vi\u00e9ndola trabajar fue como aprend\u00ed a reportear. Aprend\u00ed que si no te acercas, no tomas la foto. Si no te acercas, no tienes el art\u00edculo. Y me extra\u00f1aba que otras personas se quedaran en Managua y salieran luego con unas notas preciosas. Porque iban a hablar con los embajadores, iban a las conferencias de prensa y reporteaban muy bien otro mundo que a m\u00ed nunca me interes\u00f3. Si yo me hubiera tenido que dedicar a ruedas de prensa y charlas con ministros, no duro un mes en este oficio. A m\u00ed lo que me emocionaba era la vida. La posibilidad de acceder al mundo, de vivir una vida grandota. Eso fue lo que me sedujo. Lo otro, jam\u00e1s.<\/p>\n<p><strong>Sus primeros textos aparecieron como freelance en Latin American Newsletters y The Guardian. Pero despu\u00e9s tuvo puestos fijos en las salas de redacci\u00f3n de The Washington Post y de The Newsweek. \u00bfQu\u00e9 fue lo que no le gust\u00f3 de esos cargos?<\/strong><br \/>\nQue no me gusta estar en una oficina. Eso. La conformaci\u00f3n del espacio f\u00edsico de las oficinas me pone de mal humor. Y mira que la que tuve en R\u00edo de Janeiro era divina, y yo ten\u00eda libertad absoluta. En el fondo, creo que no me gust\u00f3 porque soy escritora. En ese momento todav\u00eda no lo sab\u00eda. Aunque, para impaciencia eterna de mis editores de The Washington Post, lo que hac\u00eda era escribir reportajes y no escribir lo que hab\u00eda reporteado.<\/p>\n<p><strong>Que es algo bien diferente. \u00bfY le desbarataban los reportajes?<\/strong><br \/>\nNo, lo que hac\u00eda Karen DeYoung, mi gran amiga y editora, la que me llev\u00f3 a The Washington Post, era agarrar unas tijeras y cortarle toda la primera mitad. Y lo hac\u00eda de una manera mucho m\u00e1s civilizada que los de The Guardian. Se quedaba con el final, con la segunda parte, que era donde yo dejaba de echar mi rollo literario, de echar el cuento.<\/p>\n<p><strong>\u00bfEso la frustraba?<\/strong><br \/>\nNo le daba mucho valor. Yo escrib\u00eda lo que me parec\u00eda que era interesante y ellos se quedaban con lo que les parec\u00eda \u00fatil. Tampoco era que yo pensara en algo como \u201cvoy a desplegar mi arte\u201d. No, para nada. Hac\u00eda lo que se me ocurr\u00eda y no era un pleito cuando me lo cortaban. Nunca he sido muy teatrera en ese sentido.<\/p>\n<p><strong>Fue en The New Yorker, entonces, donde sus historias empezaron a salir completas. <\/strong><br \/>\nS\u00ed, aunque yo ya acababa de entregar el manuscrito de \u201cSamba\u201d, mi primer libro.<\/p>\n<p><strong>\u00bfPor qu\u00e9 ese libro no est\u00e1 traducido al espa\u00f1ol?<\/strong><br \/>\nNunca he encontrado una traducci\u00f3n en la que sienta que se escucha mi voz. De alguna manera, \u201cSamba\u201d es mi libro m\u00e1s personal. Es en el que m\u00e1s he buscado la calidad de la escritura. Y no me imagino c\u00f3mo quedar\u00eda traducido. Adem\u00e1s, qued\u00e9 curada de espanto porque lo tradujeron al franc\u00e9s y result\u00f3 tan horripilante que dije \u201cnunca m\u00e1s\u201d.<\/p>\n<h4>En la revoluci\u00f3n cubana se hab\u00eda impuesto mucho la ortodoxia sovi\u00e9tica, y dec\u00eda que efectivamente el arte era una cosa secundaria. Y que o serv\u00eda a las masas o no ten\u00eda valor. Esa es una diferencia muy importante: si el arte no tiene valor en s\u00ed, un artista no puede existir.<\/h4>\n<p><strong>\u00bfC\u00f3mo es su relaci\u00f3n hoy con \u201cSamba\u201d?<\/strong><br \/>\nQuiero mucho ese libro. Le veo errores. Es muy largo, la estructura no es la mejor. Me hubiera gustado tener una editora m\u00e1s exigente, que le hubiera cambiado algo. Pero les gust\u00f3, y le pusieron ese t\u00edtulo espantoso. Lo quiero por lo que fue la experiencia de reportear y por lo que representa. Fue un a\u00f1o de trabajo. Viviendo en la favela un mes. Pero yendo todos los d\u00edas, desde muy temprano y hasta las 4 de la ma\u00f1ana, un a\u00f1o entero. Renunci\u00e9 a Newsweek y para ir a reportearlo. Despu\u00e9s me vine a Bogot\u00e1, con mi trasteo, en 1988, a escribirlo.<\/p>\n<p><strong>Vivi\u00f3 aqu\u00ed de 1988 a 1992. Pleno narcoterrorismo, Pablo Escobar, carteles. \u00bfEsto le interes\u00f3 como tema? \u00bfPor eso eligi\u00f3 Bogot\u00e1?<\/strong><br \/>\nNo, no fue por nada de eso. Me he dado cuenta de que a m\u00ed me gustan los lugares altos. Como asomaditos al mundo y aislados al mismo tiempo. Y en ese momento no se paraba ni una mosca por ac\u00e1. No hab\u00eda extranjeros. Conoc\u00eda a dos: Joe Broderick y Penny Lernoux, que fue quien realmente me entusiasm\u00f3 para venir aqu\u00ed. Mi gran amiga Penny. Ella escribi\u00f3 dos libros muy importantes: uno sobre la Iglesia colombiana, L\u00f3pez Trujillo y compa\u00f1\u00eda (\u00e9l le dio una cachetada una vez), y otro sobre los bancos y el Vaticano. Una mujer fant\u00e1stica.<\/p>\n<p><strong>Hab\u00eda pocos extranjeros, pero mucha rumba. <\/strong><br \/>\nS\u00ed, c\u00f3mo no. Eso era muy rico. Estaba La Teja Corrida, El Goce Pagano, Salom\u00e9, Caf\u00e9 Libro. Unos rumbeaderos deliciosos, de DJ, antes de que existiera ese t\u00e9rmino propiamente. Pistas atiborradas de gente echando pasito. Me imagino que todav\u00eda hay, lo que pasa es que ya no voy a eso.<\/p>\n<p><strong>\u00bfHizo buenos amigos en Bogot\u00e1?<\/strong><br \/>\nMuy buenos. Cuando llegu\u00e9 era f\u00e1cil hacer buenos amigos, hoy creo que no tanto. En esa \u00e9poca, si llegaba una extranjera, la gente te miraba con asombro y con agradecimiento. Te abr\u00eda las puertas de su casa f\u00e1cilmente, lo que hoy ya no ocurre. Adem\u00e1s, era un tiempo en que tocaba compartir durezas, y eso hace que las amistades sean muy fuertes. Cuando compartes duelo. Eso marca mucho.<\/p>\n<p><strong>Entre sus amigas estaba Silvia Duz\u00e1n, la periodista asesinada por paramilitares en 1990&#8230; <\/strong><br \/>\nS\u00ed, fuimos amigas. Silvia era una muchacha de una vitalidad, una alegr\u00eda de vivir y una curiosidad por el mundo excepcionales. Yo estaba en Managua, durante la derrota del Frente Sandinista en las elecciones, cuando me llam\u00f3 el director de The New Yorker y me dijo que me estaban buscando de Bogot\u00e1 para informarme que Silvia hab\u00eda muerto.<\/p>\n<p><strong>Como casi todos nosotros, ha tenido amigos muertos por la guerra\u2026<\/strong><br \/>\nS\u00ed. Y eso me hizo tambi\u00e9n parte de este pa\u00eds.<\/p>\n<p><strong>La primera vez que vivi\u00f3 en Bogot\u00e1 fue en 1988, pero usted ya hab\u00eda pasado por aqu\u00ed en 1973. \u00bfC\u00f3mo recuerda ese viaje?<\/strong><br \/>\nFue cuando iba rumbo a Chile, a estudiar por fin en la universidad. Me sub\u00ed al avi\u00f3n el 11 de septiembre. Aterrizamos en Buenos Aires. No pudimos hacerlo en Santiago. Fue muy duro. En ese trayecto pas\u00e9 por Colombia. Tom\u00e9 un tren de Santa Marta a Bogot\u00e1. Lo \u00fanico que me acuerdo de ese viaje es que era un tren infame, con asientos de madera, lento, lent\u00edsimo, con los vidrios empa\u00f1ados y sucios. Y en esa modorra tremenda del calor, paramos y vi a trav\u00e9s del vidrio un letrerito que dec\u00eda Aracataca. Era una estacioncita en medio de la nada.<\/p>\n<p><strong>\u00bfYa hab\u00eda le\u00eddo a Garc\u00eda M\u00e1rquez?<\/strong><br \/>\nAh, claro. De memoria me lo sab\u00eda. Le\u00ed \u201cCien a\u00f1os de soledad\u201d en una sola noche. Estaba en Nueva York viviendo con mi mam\u00e1 y una amiga de ella lleg\u00f3 de M\u00e9xico y nos dijo: les traje este libro que lo tienen que leer porque es maravilloso. Eso fue en 1967. Amanec\u00ed ley\u00e9ndolo, despacito para que no se acabara. Entonces pasar por Aracataca fue maravilloso. Y una cosa m\u00e1s incre\u00edble todav\u00eda, absolutamente absurda: a la salida se nubl\u00f3 much\u00edsimo, se puso negro, como que iba a caer un aguacero, y cuando me di cuenta hab\u00eda en la ventana una nube de mariposas amarillas.<\/p>\n<p><strong>Puro realismo m\u00e1gico. Podr\u00eda pensarse que no fue verdad.<\/strong><br \/>\nS\u00ed, uno puede decir que no fue verdad. Pero pas\u00f3. Porque adem\u00e1s antes hab\u00eda muchos m\u00e1s insectos en el mundo. Ahora me doy cuenta, manejando por la carretera, que no se te queda en el parabrisas ni un solo insecto. Se est\u00e1n acabando. Y las mariposas m\u00e1s.<\/p>\n<p><strong>\u00bfC\u00f3mo fue esa primera imagen de Bogot\u00e1?<\/strong><br \/>\nEn esa ocasi\u00f3n solo estuve de paso, pero s\u00ed me acuerdo que era una ciudad pacata, gris, donde se com\u00eda tan mal que yo, que soy de tan buen apetito, no com\u00eda. Bastante sin gracia. Perd\u00f3n.<br \/>\nAlgo ha cambiado&#8230; C\u00f3mo no. No s\u00e9 por qu\u00e9, pero es una ciudad vital, interesante. Y hoy se come muy bien.<\/p>\n<p><strong>Cuenta que en Nueva York viv\u00eda con su mam\u00e1. \u00bfC\u00f3mo fue su relaci\u00f3n con ella?<\/strong><br \/>\nFue una influencia enorme en mi vida. Una mujer brillante. Gran lectora. Ten\u00eda mucho talento para escribir. Era secretaria y durante muchos a\u00f1os tuvo una columna en una revista mexicana. Era biling\u00fce y se preocup\u00f3 mucho porque yo no perdiera el espa\u00f1ol. Una mujer con mucha chispa y sentido del humor. Muy vital. Creo que fue un golpe para ella que yo no quisiera ir a la escuela ni a la universidad. Si de pronto se le ocurri\u00f3 que no era lo mejor para m\u00ed seguir una carrera en la danza, nunca me lo dijo. Si tem\u00eda por mi vida cuando yo estaba en Centroam\u00e9rica, jam\u00e1s me lo dijo. Despu\u00e9s me enter\u00e9 por su mejor amiga que, por supuesto, se preocupaba. Pero nunca me habl\u00f3 de eso. Era una mujer de una gran libertad. Y que respet\u00f3 siempre mi libertad.<\/p>\n<p><strong>\u00bfPor qu\u00e9 quiso ser bailarina? \u00bfAlguien bailaba en su familia?<\/strong><br \/>\nCreo que, hasta la fecha, somos much\u00edsimas las ni\u00f1as que hemos visto \u201cLas zapatillas rojas\u201d a los seis, siete, ocho a\u00f1os. Y algo que para m\u00ed s\u00ed es un misterio: por qu\u00e9 las ni\u00f1as vemos una pel\u00edcula en la que la protagonista se muere bailando, literalmente, y decimos \u201cquiero ser bailarina\u201d. Y a partir de ah\u00ed nadie nos quita eso de la cabeza. Esa pel\u00edcula fue una influencia enorme. Una amiga tiene una hija de 10 a\u00f1os que est\u00e1 fascinada con el ballet y le dijo algo incre\u00edble como \u201cyo s\u00e9 que para bailar hay que sufrir\u201d. Y es una ni\u00f1a feliz, con un hogar feliz. Me parece que con esa idea, con esa emoci\u00f3n, entramos todas a la danza. Hay algo muy poderoso en eso para las mujeres.<\/p>\n<p><strong>\u00bfLa dificultad que implicaba le llamaba la atenci\u00f3n?<\/strong><br \/>\nT\u00fa sabes que los delfines, por ejemplo, cuando los tienen en cautiverio y les ense\u00f1an cosas, llegan a su pr\u00e1ctica muertos de la emoci\u00f3n. Es maravilloso que te reten, que superes obst\u00e1culos, que aprendas una cosa nueva todos los d\u00edas, que avances. Eso est\u00e1 no solo en la mente humana, sino en la naturaleza de todo ser vivo con inteligencia.<\/p>\n<p><strong>A los 16 a\u00f1os deja Ciudad de M\u00e9xico para irse a Nueva York, tras el sue\u00f1o de la danza&#8230;<\/strong><br \/>\nS\u00ed, precisamente porque mi madre estaba viviendo all\u00e1 y me dijo que fuera, con la idea de que siguiera mi formaci\u00f3n en el estudio de Martha Graham. Yo estaba bailando con una compa\u00f1\u00eda mexicana, el Ballet Nacional de M\u00e9xico, donde us\u00e1bamos la t\u00e9cnica Graham como m\u00e9todo de entrenamiento. As\u00ed que ir a su estudio me llam\u00f3 much\u00edsimo la atenci\u00f3n.<\/p>\n<p><strong>Tuvo maestros muy reconocidos. No solo Graham, sino Merce Cunningham o Twyla Tharp.<\/strong><br \/>\n<strong>\u00bfCu\u00e1l de todos ellos fue el que le dio el no a su carrera en la danza? <\/strong><br \/>\nTwyla Tharp. Aunque despu\u00e9s, cuando regres\u00e9 de Cuba y estaba sumamente desnutrida y flaca, Merce vino un d\u00eda y a su manera me dijo que le gustar\u00eda que yo volviera a un ensayo. Yo en ese momento ya estaba con la Revoluci\u00f3n. Y le dije que no.<\/p>\n<p><strong>O sea que qued\u00f3 una puerta abierta en la danza\u2026<\/strong><br \/>\nS\u00ed.<\/p>\n<p><strong>El per\u00edodo que vivi\u00f3 en La Habana, como profesora de un grupo de bailarines cubanos, fue dif\u00edcil para usted. Incluso dice que esa temporada le cambi\u00f3 la vida. \u00bfPor qu\u00e9?<\/strong><br \/>\nPorque me sac\u00f3 de la danza, que era mi universo. Me qued\u00e9 en el limbo.<\/p>\n<p><strong>Hubo un momento, durante ese per\u00edodo, en el que se plante\u00f3 si en realidad el arte serv\u00eda para algo&#8230; <\/strong><br \/>\nEs que en la revoluci\u00f3n cubana se hab\u00eda impuesto mucho la ortodoxia sovi\u00e9tica, y dec\u00eda que efectivamente el arte era una cosa secundaria. Y que o serv\u00eda a las masas o no ten\u00eda valor. Esa es una diferencia muy importante: si el arte no tiene valor en s\u00ed, un artista no puede existir.<\/p>\n<p>A los seis meses de irme de Cuba fue el esc\u00e1ndalo de Heberto Padilla, que tuvo que retractarse p\u00fablicamente de sus poemas porque a alguien se le ocurri\u00f3 que eran antirrevolucionarios. Seis a\u00f1os antes de que yo llegara, el arquitecto de las escuelas nacionales de arte donde di clases hab\u00eda tenido que irse del pa\u00eds y qued\u00f3 en la ignominia, porque su arquitectura era contrarrevolucionaria.<\/p>\n<p>O sea, una vez que estableces ese criterio, cualquier cosa puede ser contrarrevolucionaria, que es lo que sucedi\u00f3 con el estalinismo. En Cuba nunca hubo estalinismo, pero s\u00ed la posibilidad de que gente envidiosa destruyera las carreras de otras personas con ese argumento. Y yo me lo cre\u00ed. Cre\u00ed que, efectivamente, el arte que no serv\u00eda para algo iba en contra de la revoluci\u00f3n. Y como no pude con esa contradicci\u00f3n interior, me sal\u00ed de la danza.<\/p>\n<h4>En The New Yorker el texto tiene calidad literaria o no. Aunque eso era antes. Creo que ahora lo que importa es la informaci\u00f3n. Antes pod\u00edas escribir sobre un se\u00f1or que criaba verduras miniatura y, si ten\u00eda calidad literaria, funcionaba. Ya no. Son los tiempos.<\/h4>\n<p><strong>Es incre\u00edble c\u00f3mo lleg\u00f3 a estar de involucrada con el esp\u00edritu revolucionario. <\/strong><br \/>\nNo hay nadie que tenga un temperamento menos partidario y de masa y de fervor ideol\u00f3gico que yo. Pero es que tener 20 a\u00f1os y estar sola, desconectada absolutamente de todas tus relaciones, todas, tu familia, tus amistades, tu actividad, todo, te produce eso.<\/p>\n<p><strong>En ese tiempo usted se deprimi\u00f3 y lleg\u00f3 a pelearse con la vida&#8230; <\/strong><br \/>\nS\u00ed, fue una depresi\u00f3n muy fuerte. Hay una cosa de la que se habla poco y son los suicidios dentro de los reg\u00edmenes revolucionarios. Porque obligatoriamente mucha gente, y no solo los artistas, entran en contradicci\u00f3n con s\u00ed mismos, con lo que desean y con lo que se tolera. \u00bfQu\u00e9 dice Shakespeare? El infierno que puede haber entre el momento en que se te ocurre algo y lo llevas a cabo.<\/p>\n<p><strong>Usted relata todo lo que vivi\u00f3 durante esos meses en La Habana en un espejo, el \u00fanico libro en el que habla de su vida personal de forma tan directa. \u00bfC\u00f3mo se sinti\u00f3 al escribirlo?<\/strong><br \/>\nFue interesante. Ese libro me permiti\u00f3 ver muchas mentiras que yo ten\u00eda acerca de m\u00ed misma. En ese sentido fue muy saludable. Escribir sobre uno mismo es muy sanador. Yo me hab\u00eda tenido una cierta autocompasi\u00f3n antes y hab\u00eda pensado que la vida me hab\u00eda tratado mal y de repente entend\u00ed que lo que en realidad sucedi\u00f3 fue que mi vida hab\u00eda sido maravillosa en muchos sentidos. El regalo del arte, de la danza, de tantos mundos que he podido conocer.<\/p>\n<p><strong>Despu\u00e9s de La Habana viaj\u00f3 a Nueva York y luego a Nicaragua. \u00bfTambi\u00e9n por el tema revolucionario?<\/strong><br \/>\nClaro. Pero antes yo hab\u00eda regresado a M\u00e9xico. Y trabaj\u00e9 primero como profesora de ingl\u00e9s, luego como profesora de espa\u00f1ol con unos becarios japoneses, y despu\u00e9s como int\u00e9rprete simult\u00e1nea, que es lo mejor que me ha salido en la vida. Era buen\u00edsima en eso, buen\u00edsima. Empec\u00e9 traduciendo congresos m\u00e9dicos y ah\u00ed segu\u00ed. De veras, era excepcional. Jam\u00e1s tom\u00e9 un curso y no me costaba ning\u00fan esfuerzo. Ese ha sido mi talento mayor, realmente. Fue una \u00e9poca bonita. Y en esas estaba cuando me fui a Nicaragua.<\/p>\n<p><strong>En un momento en el que pod\u00eda poner en riesgo su vida\u2026<\/strong><br \/>\nCuando eres joven, no piensas en esas cosas. Jam\u00e1s. Yo ven\u00eda de la derrota de Salvador Allende y ese horror que fue Chile. Y de repente aparece una cosa que, no s\u00e9 c\u00f3mo, pero se sent\u00eda que iba a triunfar. Desde la primera imagen que vi en la televisi\u00f3n, que era la secuela de la toma del Congreso por los sandinistas, la gente que sali\u00f3 a las calles masivamente, era claro que iban a triunfar. Y dije: quiero ver eso.<\/p>\n<p><strong>La terquedad, que es una de sus caracter\u00edsticas.<\/strong><br \/>\nNo cabe duda. Si yo me reconozco alg\u00fan m\u00e9rito, es ser terca. Y alg\u00fan defecto tambi\u00e9n.<\/p>\n<p><strong>Esa terquedad, enfocada en el trabajo period\u00edstico, \u00bftiene alg\u00fan l\u00edmite? \u00bfO llega un momento en el que desiste? <\/strong><br \/>\nHay un momento en que reconozco una imposibilidad. Pero mientras haya una opci\u00f3n, contin\u00fao. Como con el papa Francisco, que no me dio la entrevista para el perfil que escrib\u00ed, pero hasta el \u00faltimo d\u00eda estuve haciendo el intento por todos los medios posibles. O cuando me fui a parar en frente de la c\u00e1rcel de Bello, en Antioquia. Estaba haciendo un texto sobre la masacre de Segovia. Fue mi primer art\u00edculo para The New Yorker, aunque nunca sali\u00f3. Le dimos 20 vueltas y no logramos armarlo. Pero le trabaj\u00e9. Y me hab\u00edan dicho que uno de los que hab\u00eda participado en la masacre estaba en esa c\u00e1rcel. Tom\u00e9 mi camioncito y me fui. Al llegar, me dijeron que no pod\u00eda entrar. Yo iba vestida con mi ropa brasile\u00f1a, tan chic, no te imaginas. Una falda negra hasta los tobillos, divina. Unos pliegues, un lino fin\u00edsimo. Y una blusita blanca, de lino tambi\u00e9n. Y dije pues me voy a quedar aqu\u00ed al rayo del sol hasta que algo pase. Como a la hora, me abrieron la puerta y me dijeron: \u201cHermana, venga\u201d.<\/p>\n<p><strong>\u00a1Pensaron que era una religiosa!<\/strong><br \/>\n\u00a1Claro! Una evang\u00e9lica. Fue buen\u00edsimo. Y la entrevista estuvo de parar los pelos. \u00c9l no confes\u00f3 que hab\u00eda participado, pero me cont\u00f3 su vida.<\/p>\n<p><strong>\u00bfY el texto nunca sali\u00f3?<\/strong><br \/>\nNo, no lo logramos. En The New Yorker el texto tiene calidad literaria o no. Aunque eso era antes. Creo que ahora lo que importa es la informaci\u00f3n. Antes pod\u00edas escribir sobre un se\u00f1or que criaba verduras miniatura y, si ten\u00eda calidad literaria, funcionaba. Ya no. Son los tiempos.<\/p>\n<p><strong>Los reportajes que conocemos en todos sus libros fueron originalmente escritos en ingl\u00e9s. \u00bfSe siente mejor escribiendo en ese idioma?<\/strong><br \/>\nTodos excepto \u201cLa Habana en un espejo\u201d y las columnas de comida. Lo que pasa es que yo me hice escritora en ingl\u00e9s y en The New Yorker. Cuando escrib\u00ed \u201cLa Habana en un espejo\u201d \u2013que lo hice en espa\u00f1ol para sacarlo de un contexto gringo porque yo viv\u00ed esa experiencia como una muchacha de 20 a\u00f1os mexicana\u2013, me di cuenta de que no soy tan buena escritora en espa\u00f1ol, y adem\u00e1s me da\u00f1\u00f3 el ingl\u00e9s. Entonces, dije \u201cno lo vuelvo a hacer\u201d. Llevaba a\u00f1os perfeccionando un instrumento y tuve que desmontarlo y montar otro aparato, y fue dif\u00edcil retomarlo despu\u00e9s.<\/p>\n<p><strong>En ingl\u00e9s se le nota, adem\u00e1s, una iron\u00eda que a veces no alcanza a percibirse en las traducciones al espa\u00f1ol&#8230; <\/strong><br \/>\nS\u00ed, el ingl\u00e9s tiene metido eso. El wit, esa cosa tan particular con las palabras, con la iron\u00eda, con la distancia. Me gusta y me ha servido mucho para escribir. En espa\u00f1ol no es tan f\u00e1cil el juego de palabras. Es menos juguet\u00f3n. Por eso hay tan pocos escritores c\u00f3micos en este idioma. Si te pones a ver, \u00bfqui\u00e9n? Ibarg\u00fcengoitia, que se merece estatua, \u00bfy qui\u00e9n m\u00e1s? Bioy Casares, de pronto, Osvaldo Soriano. Son muy pocos. Como que escribir en espa\u00f1ol es una actividad seria, \u00bfno? Zafarme de eso tambi\u00e9n fue muy importante. Todos los escritores del Boom te contaban que pon\u00edan a Tchaikovsky para escribir, a Prok\u00f3fiev. Y yo dec\u00eda: \u00f3rale.<\/p>\n<p><strong>Este oficio del periodismo puede tambi\u00e9n ser una especie de autobiograf\u00eda, \u00bfno le parece? <\/strong><br \/>\nTotalmente.<\/p>\n<p><strong>\u00bfHa buscado, quiz\u00e1s, una respuesta sobre usted?<\/strong><br \/>\nDurante toda esa \u00e9poca en Centroam\u00e9rica seguramente estaba tratando de procesar todav\u00eda el a\u00f1o que viv\u00ed en Cuba. Aunque no me diera cuenta de eso. Pero, por otro lado, tambi\u00e9n estaba descubrir Am\u00e9rica Latina. Los mexicanos somos muy orgullosos, con mucha raz\u00f3n, adem\u00e1s, de nuestro pa\u00eds. Pero descubrir Latinoam\u00e9rica fue una aventura maravillosa. Un pa\u00eds fascinante como Colombia, por ejemplo, o como Brasil, aunque nunca me enamor\u00f3 de la misma manera. O Argentina. O Per\u00fa. Fue maravilloso haber convivido con cada pa\u00eds. Qui\u00e9n me iba a decir que iba a pasar un total de seis meses reporteando en Bolivia.<\/p>\n<p><strong>Despu\u00e9s de recorrer estos pa\u00edses y de ese conocimiento profundo de Latinoam\u00e9rica, \u00bfpor qu\u00e9 cree que parecemos condenados al conflicto, a la violencia?<\/strong><br \/>\nNo s\u00e9. En \u00e9pocas en que la violencia era revolucionaria, que era una cosa light si lo miramos en comparaci\u00f3n con lo que es la violencia hoy, yo me preguntaba por qu\u00e9 no hemos tenido un movimiento revolucionario pol\u00edtico pacifista, por qu\u00e9 ac\u00e1 nunca ha habido un Martin Luther King o un Gandhi. Esa es la gran pregunta para m\u00ed. Adem\u00e1s, si lo hubiera, no tendr\u00eda ni cinco de posibilidades. Y en parte creo que se debe a la religi\u00f3n cat\u00f3lica y su \u00e9nfasis sobre los m\u00e1rtires. El martirologio lo traemos como parte de nuestra concepci\u00f3n del mundo. El Che Guevara, de alguna manera, encarn\u00f3 todo ese deseo de martirio y muerte.<\/p>\n<p>Y tambi\u00e9n est\u00e1 la voluntad tremenda de los reg\u00edmenes de derecha de crear m\u00e1rtires a mansalva. Cuando yo hac\u00eda la pregunta, me dec\u00edan es que aqu\u00ed t\u00fa no puedes protestar pac\u00edficamente. No, pero en la India tampoco. Y en Estados Unidos tampoco, en \u00e9pocas de Martin Luther King. Eso es una parte. Tambi\u00e9n creo \u2013comprobadamente en el caso de Brasil\u2013 que la guerrilla que estuvo presa dej\u00f3 una ense\u00f1anza de la violencia a los presos comunes. Eso se transmiti\u00f3. Y viceversa, en Colombia: la guerrilla se volvi\u00f3 criminal. Ese juego entre violencia y crimen no ha ayudado. Y en eso se mont\u00f3 el narcotr\u00e1fico. El gran culpable de la violencia en Am\u00e9rica Latina es Estados Unidos y la prohibici\u00f3n de las drogas.<\/p>\n<p>Porque eso ha dado para alimentar generaciones de criminales. Tampoco entiendo mucho por qu\u00e9 la gente mete coca\u00edna, por ejemplo, si se pone a pensar de d\u00f3nde viene. Cu\u00e1nta gente ha muerto o ha sido explotada brutalmente en el proceso.<\/p>\n<p><strong>\u00bfC\u00f3mo ha visto el acuerdo de paz en Colombia?<\/strong><br \/>\nAccidentado, pero fundamentalmente glorioso. Un pa\u00eds sin guerra es mejor que un pa\u00eds con guerra. Pero creo que aqu\u00ed hay una especie de estr\u00e9s postraum\u00e1tico que hace que a la gente le parezca normal vivir con violencia. Todas las dificultades que ha tenido el proceso de paz surgen de esa incapacidad para voltear la p\u00e1gina y decir esto ya pas\u00f3, esto ya termin\u00f3 y ahora hay que hacer un intercambio de cosas que uno cede para que eso que nos ha atormentado tanto tiempo \u2013que es la violencia y la criminalidad de los grupos armados\u2013 se acabe. Y es tr\u00e1gico lo que ha sucedido. Porque Colombia es un pa\u00eds que cuando mira al futuro, es glorioso, y cuando se queda trabado en el pasado, no se abre puertas.<\/p>\n<p><strong>M\u00e9xico tambi\u00e9n est\u00e1 pasando por un momento complicado\u2026 <\/strong><br \/>\nNo creo que lo de M\u00e9xico sea un momento, es una condici\u00f3n de la que nos vamos a tardar a\u00f1os en salir. Quiz\u00e1 sea por los temblores, pero M\u00e9xico es un pa\u00eds que s\u00ed sabe darle la vuelta a la hoja. Esto pas\u00f3 y ya, ma\u00f1ana a otro cuento. Pero la corrupci\u00f3n que foment\u00f3 y aup\u00f3 el PRI durante 72 a\u00f1os es absolutamente general. Y es la que ha permitido que la violencia sea tan desbordante. El narcotr\u00e1fico se mont\u00f3 en la corrupci\u00f3n y hoy es el que manda. All\u00e1 tenemos un problema que no me imagino c\u00f3mo resolver. Es m\u00e1s grave que el de Colombia porque finalmente, aunque fr\u00e1giles, aqu\u00ed est\u00e1n los acuerdos de paz. Se hicieron. Lo de M\u00e9xico no veo por d\u00f3nde empezar a resolverlo porque no hay dos partes que se sienten a platicar.<\/p>\n<p><strong>Usted vivi\u00f3 un a\u00f1o en Europa. \u00bfC\u00f3mo le fue en ese continente? <\/strong><br \/>\nViv\u00ed en Madrid, Londres y Par\u00eds. Pero Par\u00eds es un lugar al que vuelvo siempre. Me gusta, a pesar de que se ha vuelto una especie de Disneylandia para turistas. Pobres parisinos. Entiendo por qu\u00e9 son tan malhumorados. Y mira que el \u00fanico pa\u00eds donde he sido v\u00edctima de racismo es Francia. Un tipo se neg\u00f3 a venderme un boleto de tren. Eso pas\u00f3 hace tiempo, pero no creo que haya cambiado. La migraci\u00f3n va a ser un problema grave en el mundo porque no va a parar. El cambio clim\u00e1tico va a provocar una migraci\u00f3n nunca vista. De hecho, ya la est\u00e1 provocando. La crisis del medio ambiente es una crisis pol\u00edtica.<\/p>\n<p><strong>Ha escrito temas alejados de la violencia y los conflictos, como el reportaje sobre el tango o sobre Celia Cruz. \u00bfC\u00f3mo se siente cuando hace estos textos?<\/strong><br \/>\nSi t\u00fa ves, en mi primera \u00e9poca de The New Yorker, no hay textos sobre violencia. \u201cAl pie de un volc\u00e1n te escribo\u201d no es un libro sobre violencia. Pero la verdad es que s\u00ed le agradezco much\u00edsimo a National Geographic que me haya dado la oportunidad de escribir las notas m\u00e1s divertidas de mi vida. Que me mand\u00f3 a Buenos Aires a escribir sobre el tango. O me pidi\u00f3 que fuera a Bolivia a escribir sobre las cholitas. Qu\u00e9 delicia. Como las columnas de gastronom\u00eda, el texto sobre la canci\u00f3n ranchera o el de Celia Cruz. Siempre he sentido m\u00e1s urgencia de escribir sobre las injusticias que padece la gente de este hemisferio, pero cuando puedo hacerlo sobre otra cosa, soy feliz. Qu\u00e9 dicha escribir sobre las infinitas maneras que tiene la gente, esa misma gente, de sobrevivir y gozar.<\/p>\n<p><strong>Le gusta mucho la cocina. \u00bfPor qu\u00e9?<\/strong><br \/>\nPor la satisfacci\u00f3n de compartir. Yo no cocino para m\u00ed. Me fascina ofrecerles a los dem\u00e1s. Me encanta una mesa rodeada de gente feliz con lo que est\u00e1 comiendo. No lo hago mucho, pero cuando puedo me muero de la felicidad. Justamente ahorita estoy haciendo masa tras masa de pizza para encontrar la que me quede como quiero. El pan es algo m\u00e1gico: harina, agua, sal y unos bichitos vivos que se llaman levadura. Y con eso haces qu\u00e9 cantidad de cosas incre\u00edbles. El pan me fascina. Hacerlo. Y transformar.<\/p>\n<p><strong>La m\u00fasica es otra de sus aficiones\u2026<\/strong><br \/>\nTodas las m\u00fasicas afro me mueven mucho. Desde el blues de Chicago hasta no tanto la bossa nova, sino la samba propiamente. Pasando por la salsa cubana y neoyorquina. Y la cl\u00e1sica, claro. Pero hoy escucho mucho menos m\u00fasica que antes. No s\u00e9 si es porque no tengo un equipo bueno ac\u00e1, pero la verdad es que no escucho ni remotamente lo mismo. Creo que es un asunto log\u00edstico. A todos nos fue dando jartera eso de sacar un disco compacto y ponerlo. Y lo digital no es lo mismo. A veces ni siquiera oyes las canciones completas.<\/p>\n<p><strong>\u00bfToca alg\u00fan instrumento?<\/strong><br \/>\nNo, no tengo mucha coordinaci\u00f3n manual. Siempre me preguntaban que si tocaba guitarra. Supongo que tengo cara de hacerlo. En Centroam\u00e9rica me confund\u00edan con Joan B\u00e1ez. As\u00ed que las preguntas eran: \u00bfTocas guitarra? \u00bfEres Joan B\u00e1ez? Ser\u00eda por la idea de un look, algo, no s\u00e9. Yo me sent\u00eda mal de no tener mi guitarra.<\/p>\n<p><strong>En respuestas anteriores habla del periodismo en pasado. \u00bfYa no lo est\u00e1 ejerciendo de la misma forma?<\/strong><br \/>\nCada vez hago menos. Esa es la realidad. Supongo que estoy en la edad en que participo en juntas asesoras. Ten\u00eda la idea de un libro que se me fue a pique. Pero hago otras cosas que me distraen. Cuarenta a\u00f1os es mucho.<\/p>\n<p><strong>Sol\u00eda definirse como exbailarina. \u00bfTodav\u00eda?<\/strong><br \/>\nCreo que si rascas, hasta la fecha de hoy. Porque no es una cosa de superficie. Es de m\u00e9dula. Es algo que te forma y te marca de una manera que no se te borra.<\/p>\n<p><strong>\u00bfPiensa volver a vivir en M\u00e9xico?<\/strong><br \/>\nVoy con frecuencia. No s\u00e9 si vuelva a vivir. Quiz\u00e1s. O talvez no. La vida no es lo que uno pronostica, ya lo dijo John Lennon, es lo que ocurre cuando est\u00e1s entretenido haciendo otros planes. Uno controla mucho menos de lo que piensa. Si algo he aprendido es que la vida es un largo accidente.<\/p>\n<img data-attachment-id=\"4051\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/alma-guillermoprieto-maestra-del-periodismo\/fsep08072018arcprie82\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018arcprie82.jpg\" data-orig-size=\"600,841\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep08072018arcprie82\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018arcprie82-214x300.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018arcprie82.jpg\" loading=\"lazy\" class=\"aligncenter size-full wp-image-4051\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018arcprie82.jpg\" alt=\"\" width=\"600\" height=\"841\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018arcprie82.jpg 600w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018arcprie82-214x300.jpg 214w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018arcprie82-500x701.jpg 500w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Alma Estela Guillermoprieto Panigua naci\u00f3 en 1949, en Ciudad de M\u00e9xico. Esta entrevista se enmarca en el anuncio que la da como la ganadora del Premio Princesa de Asturias de Comunicaci\u00f3n y Humanidades. Es un repaso por las grandes lecciones que a ella le dejaron 40 a\u00f1os en periodismo, aunque a\u00fan se defina como exbailarina.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":4049,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Alma Guillermoprieto, maestra del periodismo - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Alma Guillermoprieto, maestra del periodismo - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Alma Estela Guillermoprieto Panigua naci\u00f3 en 1949, en Ciudad de M\u00e9xico. Esta entrevista se enmarca en el anuncio que la da como la ganadora del Premio Princesa de Asturias de Comunicaci\u00f3n y Humanidades. Es un repaso por las grandes lecciones que a ella le dejaron 40 a\u00f1os en periodismo, aunque a\u00fan se defina como exbailarina.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-08T06:01:24+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-08T00:17:38+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Mar\u00eda Paulina Ortiz\/Revista Bocas\/El Tiempo\/Colombia\/GDA\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"31 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Nombre\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/\",\"name\":\"Alma Guillermoprieto, maestra del periodismo - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/#primaryimage\"},\"datePublished\":\"2018-07-08T06:01:24+00:00\",\"dateModified\":\"2018-07-08T00:17:38+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Alma Guillermoprieto, maestra del periodismo\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\",\"name\":\"S\u00e9ptimo Sentido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"caption\":\"S\u00e9ptimo Sentido\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Alma Guillermoprieto, maestra del periodismo - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/","og_locale":"en_US","og_type":"article","og_title":"Alma Guillermoprieto, maestra del periodismo - S\u00e9ptimo Sentido","og_description":"Alma Estela Guillermoprieto Panigua naci\u00f3 en 1949, en Ciudad de M\u00e9xico. Esta entrevista se enmarca en el anuncio que la da como la ganadora del Premio Princesa de Asturias de Comunicaci\u00f3n y Humanidades. Es un repaso por las grandes lecciones que a ella le dejaron 40 a\u00f1os en periodismo, aunque a\u00fan se defina como exbailarina.","og_url":"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-07-08T06:01:24+00:00","article_modified_time":"2018-07-08T00:17:38+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"Mar\u00eda Paulina Ortiz\/Revista Bocas\/El Tiempo\/Colombia\/GDA","Est. reading time":"31 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca.jpg","width":1920,"height":1080,"caption":"Nombre"},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/","name":"Alma Guillermoprieto, maestra del periodismo - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/#primaryimage"},"datePublished":"2018-07-08T06:01:24+00:00","dateModified":"2018-07-08T00:17:38+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/alma-guillermoprieto-maestra-del-periodismo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Alma Guillermoprieto, maestra del periodismo"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b","name":"S\u00e9ptimo Sentido","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","caption":"S\u00e9ptimo Sentido"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":""}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018coralma03ca.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-13i","jetpack-related-posts":[{"id":7448,"url":"https:\/\/7s.laprensagrafica.com\/en\/el-alma-se-ve-reflejada-en-el-legado-que-dejas\/","url_meta":{"origin":4048,"position":0},"title":"&#8220;El alma se ve reflejada en el legado que dejas&#8221;","date":"22 March, 2020","format":false,"excerpt":"[:es]Alejandra Segovia es una salvadore\u00f1a que se ha especializado en la producci\u00f3n audiovisual. En los \u00faltimos tres a\u00f1os, la joven permaneci\u00f3 en la ciudad de New York, Estados Unidos, donde trabaj\u00f3 como productora freelance. Segovia tambi\u00e9n ha participado en proyectos salvadore\u00f1os con \"Focal Photo\". Actualmente, se encuentra trabajando en producciones\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/03\/fsep22032020coralesegovia1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8395,"url":"https:\/\/7s.laprensagrafica.com\/en\/quiero-creer-que-el-alma-es-inmortal\/","url_meta":{"origin":4048,"position":1},"title":"&#8220;Quiero creer que el alma es inmortal&#8221;","date":"25 October, 2020","format":false,"excerpt":"[:es]Dennis Morales tiene 26 a\u00f1os. Es Licenciado en Letras por la Universidad de El Salvador. Fue miembro del taller literario El Perro Muerto. En 2015, obtuvo el primer lugar en el V Certamen Centroamericano de Poes\u00eda Ipso Facto, convocado por Editorial Equizzero, con el poemario Exhum aci\u00f3n de la vida.\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/10\/fsep24102020xxsiete34.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1687,"url":"https:\/\/7s.laprensagrafica.com\/en\/no-me-falta-nada\/","url_meta":{"origin":4048,"position":2},"title":"\u201cNo me hace falta nada\u201d","date":"15 October, 2017","format":false,"excerpt":"Argelia Quintana ha dedicado los \u00faltimos 25 a\u00f1os de su vida a recolectar la poes\u00eda de su hija, Leyla Quintana. Leyla era poeta y muri\u00f3 a los 21 a\u00f1os en el contexto de la guerra civil. Desde la muerte de su hija, Argelia, quien ahora tiene 72 a\u00f1os, se ha\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/7-preguntas.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7878,"url":"https:\/\/7s.laprensagrafica.com\/en\/el-triunfo-o-el-fracaso-realmente-es-hipotetico\/","url_meta":{"origin":4048,"position":3},"title":"&#8220;El triunfo o el fracaso realmente es hipot\u00e9tico&#8221;","date":"14 June, 2020","format":false,"excerpt":"[:es]Adileth Villatoro es una salvadore\u00f1a que se especializa en el dise\u00f1o de prendas b\u00e1sicas y vers\u00e1tiles con su emprendimiento ALMA. Indumentaria hecha para mujeres bajo un concepto \"multiusos\". Villatoro es abogada graduada de la Universidad Centroamericana \"Jos\u00e9 Sime\u00f3n Ca\u00f1as\" (UCA). Tambi\u00e9n cuenta con una certificaci\u00f3n en dise\u00f1o textil en la\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/06\/fsep14062020xxcuest322.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8518,"url":"https:\/\/7s.laprensagrafica.com\/en\/estamos-siempre-en-el-filo-del-alma\/","url_meta":{"origin":4048,"position":4},"title":"ESTAMOS SIEMPRE EN EL FILO DEL ALMA","date":"22 November, 2020","format":false,"excerpt":"[:es]Inundan nuestro jornada, y al final del d\u00eda todo lo que anhelamos al comienzo se nos convierte en espesura almacenada.[:]","rel":"","context":"In &quot;Historias sin Cuento&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/pluma.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8456,"url":"https:\/\/7s.laprensagrafica.com\/en\/la-muerte-significa-el-final-de-mi-mision-en-la-vida\/","url_meta":{"origin":4048,"position":5},"title":"&#8220;La muerte significa el final de mi misi\u00f3n en la vida&#8221;","date":"8 November, 2020","format":false,"excerpt":"[:es]Carol Hills naci\u00f3 en San Salvador, tiene 28 a\u00f1os. Es traductora e int\u00e9rprete de profesi\u00f3n, pero se dedica a la composici\u00f3n musical. Es fundadora del colectivo Errantes Cantautores, que busca abrir espacios para la m\u00fasica de autor contempor\u00e1nea y apoyar al talento emergente. En 2017, fue telonera de la banda\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/11\/carol-hill.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4048"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=4048"}],"version-history":[{"count":1,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4048\/revisions"}],"predecessor-version":[{"id":4052,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4048\/revisions\/4052"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/4049"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=4048"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=4048"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=4048"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}