{"id":4039,"date":"2018-07-08T00:10:55","date_gmt":"2018-07-08T06:10:55","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=4039"},"modified":"2018-07-07T17:45:11","modified_gmt":"2018-07-07T23:45:11","slug":"la-masacre-de-ninos-durante-la-represion-orteguista","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/la-masacre-de-ninos-durante-la-represion-orteguista\/","title":{"rendered":"La masacre de ni\u00f1os durante la represi\u00f3n orteguista"},"content":{"rendered":"<figure id=\"attachment_4040\" style=\"width: 1920px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"4040\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/la-masacre-de-ninos-durante-la-represion-orteguista\/fsep08072018efe7702088\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088.jpg\" data-orig-size=\"1920,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep08072018Efe7702088\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Entierro&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088-300x169.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088-1024x576.jpg\" loading=\"lazy\" class=\"size-full wp-image-4040\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088.jpg\" alt=\"\" width=\"1920\" height=\"1080\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088.jpg 1920w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088-300x169.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088-768x432.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088-1024x576.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088-1900x1069.jpg 1900w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088-1200x675.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088-500x281.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088-1000x563.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088-700x394.jpg 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-caption-text\">Entierro<\/figcaption><\/figure>\n<p>El beb\u00e9 no llor\u00f3. No grit\u00f3. No habl\u00f3. Nelson Lor\u00edo, su pap\u00e1, mir\u00f3 c\u00f3mo se le hundi\u00f3 la mollera. La sangre corr\u00eda por sus manos. La camisa, el trapo con que lo tapaba, su ropita, todo estaba rojo. Fueron segundos que pasaron r\u00e1pido y a la vez lentos. Entr\u00f3 a la casa de una se\u00f1ora que no conoc\u00eda. Ella le lav\u00f3 la cabecita. Lo \u00faltimo que mir\u00f3 de su ni\u00f1o fueron unos gestos de querer hablar, unas gesticulaciones que cree eran las de: \u201cmam\u00e1\u201d o \u201cpap\u00e1\u201d.<\/p>\n<p>Teyler Leonardo Lor\u00edo Navarrete muri\u00f3 el 23 de junio de un disparo a la cabeza. Ten\u00eda apenas 14 meses y 16 d\u00edas de haber nacido. \u201cNo ten\u00eda color ni partido pol\u00edtico, estaba en estado angelical. Jam\u00e1s se imagin\u00f3 que le iban a disparar\u201d, dice Nelson Lor\u00edo, su padre, quien lo llevaba en los brazos cuando recibi\u00f3 el impacto de parte de \u201cpolic\u00edas y paramilitares\u201d que realizaban \u201clabores de limpieza\u201d en el barrio Am\u00e9ricas Uno, de Managua.<\/p>\n<p>La muerte del beb\u00e9 Lor\u00edo Navarrete es uno de los \u00faltimos asesinatos de ni\u00f1os por parte de la represi\u00f3n orteguista. La Asociaci\u00f3n Nicarag\u00fcense de Derechos Humanos (ANPDH) revel\u00f3 que 21 menores, de 18 a\u00f1os o menos, han muerto entre el 18 de abril y el 25 de junio en los hechos violentos de la crisis pol\u00edtica que vive el pa\u00eds.<\/p>\n<p>La Prensa (Nicaragua) contabiliza 15 casos de j\u00f3venes que han muerto de las formas m\u00e1s crueles: de impactos de bala en la cabeza, pecho o cuello. Mientras que hay algunos que murieron calcinados junto con sus padres, suplicando por sus vidas o atropellados cruel e intencionalmente por un bus.<\/p>\n<p>Seg\u00fan el informe de la ANPDH, ocho de los menores de edad ten\u00edan 17 a\u00f1os, cuatro ten\u00edan 16 a\u00f1os, cinco 15 a\u00f1os, una ni\u00f1a de 11 a\u00f1os y una de dos a\u00f1os, y dos beb\u00e9s: uno de 14 meses y otro de cinco meses de edad.<\/p>\n<h1 style=\"text-align: center;\">***<\/h1>\n<p><strong>\u201cHERODES NICARAG\u00dcENSE\u201d<\/strong><br \/>\nLa presidenta del Centro Nicarag\u00fcense de Derechos Humanos (CENIDH), Vilma N\u00fa\u00f1ez, dijo que el presidente inconstitucional Daniel Ortega se est\u00e1 convirtiendo en el Herodes nicarag\u00fcense. \u201cHerodes fue aquel que mand\u00f3 a matar a todos los ni\u00f1os de determinadas edades para que no le hicieran competencia. Entonces, Daniel Ortega est\u00e1 matando a la ni\u00f1ez nicarag\u00fcense\u201d, afirm\u00f3 N\u00fa\u00f1ez.<\/p>\n<p>El Movimiento Mundial por la Infancia (MMI) Cap\u00edtulo Nicaragua conden\u00f3 el \u201cuso de la fuerza letal\u201d del gobierno de Daniel Ortega contra los ni\u00f1os en la crisis sociopol\u00edtica local, que ha dejado saldo de m\u00e1s de 218 muertos, seg\u00fan sus datos, de los cuales al menos 17 son menores de edad.<\/p>\n<p>\u201cCondenamos rotundamente el uso de la fuerza letal contra la poblaci\u00f3n civil, especialmente ni\u00f1os y adolescentes\u201d, se\u00f1al\u00f3 el MMI Nicaragua, que exigi\u00f3 al Estado nicarag\u00fcense asumir \u201csu rol como garante de derechos con mayor cuidado y responsabilidad por tratarse de un ni\u00f1o o adolescente, y debe, adem\u00e1s, tomar medidas especiales fundamentadas en el principio del inter\u00e9s superior de la ni\u00f1ez\u201d.<\/p>\n<figure id=\"attachment_4043\" style=\"width: 1920px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"4043\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/la-masacre-de-ninos-durante-la-represion-orteguista\/fsep08072018efe7702080\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702080.jpg\" data-orig-size=\"1920,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep08072018Efe7702080\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Rechazo.  Personas caminan frente a un mural con mensajes en contra de Daniel Ortega en el barrio ind\u00edgena de Monimbo, en Masaya, ciudad que hace 39 a\u00f1os fue crucial en la victoria sandinista.  &lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702080-300x169.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702080-1024x576.jpg\" loading=\"lazy\" class=\"size-full wp-image-4043\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702080.jpg\" alt=\"\" width=\"1920\" height=\"1080\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702080.jpg 1920w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702080-300x169.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702080-768x432.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702080-1024x576.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702080-1900x1069.jpg 1900w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702080-1200x675.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702080-500x281.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702080-1000x563.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702080-700x394.jpg 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-caption-text\"><strong>Rechazo<\/strong>. Personas caminan frente a un mural con mensajes en contra de Daniel Ortega en el barrio ind\u00edgena de Monimbo, en Masaya, ciudad que hace 39 a\u00f1os fue crucial en la victoria sandinista.<\/figcaption><\/figure>\n<h1 style=\"text-align: center;\">***<\/h1>\n<p><strong>DISPARO CONTRA DIOS<\/strong><br \/>\nEl domingo 24 de junio, durante la homil\u00eda en la catedral de Managua, el cardenal Leopoldo Brenes, presidente de la Conferencia Episcopal de Nicaragua, elev\u00f3 una oraci\u00f3n especial por la memoria de Teyler Leonardo Lor\u00edo Navarrete, beb\u00e9 de 14 meses.<\/p>\n<p>Ese mismo d\u00eda el obispo auxiliar de la Arquidi\u00f3cesis de Managua, monse\u00f1or Silvio B\u00e1ez, calific\u00f3 el asesinato de Lor\u00edo como \u201cotro signo de inhumanidad\u201d. Monse\u00f1or Rolando \u00c1lvarez, obispo de la Di\u00f3cesis de Matagalpa, dijo que \u201cla bala contra inocentes es un disparo contra Dios\u201d. Y agreg\u00f3: \u201cEn la bala asesina disparada contra los ni\u00f1os tambi\u00e9n se ha disparado contra Dios, se ha profanado contra \u00c9l, quitando la vida contra los inocentes\u201d.<\/p>\n<h1 style=\"text-align: center;\">***<\/h1>\n<p><strong>EL BEB\u00c9 DE LOS COLOCHOS<\/strong><br \/>\nLos colochos de Teyler son lo que m\u00e1s recuerda su padre, Nelson Lor\u00edo. \u201cSiempre quise un ni\u00f1o as\u00ed, con ese tipo de pelo\u201d, dice el padre. \u201cNunca se lo cort\u00e9 porque quer\u00edamos dej\u00e1rselo crecer\u201d.<br \/>\nNelson Lor\u00edo y Karina Navarrete se conocieron hace ocho a\u00f1os. Un a\u00f1o despu\u00e9s naci\u00f3 Joshuara, su primera ni\u00f1a, quien ahora tiene siete a\u00f1os de edad. Estuvieron separados durante dos a\u00f1os y regresaron desde hace cinco. Ambos planificaron tener un ni\u00f1o durante ese tiempo, hasta que el 7 de abril de 2017, a las 7 de la ma\u00f1ana, naci\u00f3 Teyler Leonardo en el Hospital Monte Espa\u00f1a.<\/p>\n<p>\u201cMi orgullo de var\u00f3n\u201d, dice el padre, quien fue el primero en cargarlo, sin poder imaginarse que tambi\u00e9n ser\u00eda el \u00faltimo. \u201cNo lo pod\u00eda dejar de ver. Nunca me lo despegaba\u201d, dice Nelson, quien a partir de ese d\u00eda empez\u00f3 a trabajar en supermercados o gasolineras para que a Teyler \u201cno le faltara nada\u201d.<\/p>\n<p>Karina Navarrete, la madre, tambi\u00e9n empez\u00f3 a trabajar como dom\u00e9stica. Ambos compraron un terrenito que todav\u00eda est\u00e1n pagando. Es por eso que todos los d\u00edas iban a dejar a Teyler a la casa de su abuelo paterno, Jaime Lor\u00edo, en el barrio Am\u00e9ricas Uno.<\/p>\n<h4>Monse\u00f1or Rolando \u00c1lvarez, obispo de la Di\u00f3cesis de Matagalpa, dijo que \u201cla bala contra inocentes es un disparo contra Dios\u201d. Y agreg\u00f3: \u201cEn la bala asesina disparada contra los ni\u00f1os tambi\u00e9n se ha disparado contra Dios, se ha profanado contra \u00c9l, quitando la vida contra los inocentes\u201d.<\/h4>\n<p>El abuelo se encari\u00f1\u00f3 tanto con el ni\u00f1o que se lo ped\u00eda a su hijo. \u201cMi esposa se enojaba porque mi pap\u00e1 se lo quer\u00eda quedar\u201d, dice Nelson, apenas sonriendo. \u201cYo no hallaba c\u00f3mo decirle a mi pap\u00e1 que el ni\u00f1o hab\u00eda muerto porque me daba miedo que tambi\u00e9n se muriera\u201d.<\/p>\n<p>El abuelo se desmay\u00f3 con la noticia. En el sepelio tambi\u00e9n se desmay\u00f3, despu\u00e9s de que abri\u00f3 el ata\u00fad de su nieto y le deposit\u00f3 el peluche con el que jugaban. Ahora, Jaime Lor\u00edo llega todos los d\u00edas a visitar a su hijo para no sentirse solo. Llega en la ma\u00f1ana, siempre con un vaso de leche agria y una tortilla. Trata de verse fuerte, sereno. \u201cPero talvez solo me meto un momento al cuarto y cuando regreso, lo encuentro llorando\u201d, dice Nelson.<\/p>\n<figure id=\"attachment_4042\" style=\"width: 1600px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"4042\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/la-masacre-de-ninos-durante-la-represion-orteguista\/fsep07082018efe7694038\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep07082018Efe7694038.jpg\" data-orig-size=\"1600,900\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep07082018Efe7694038\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Impunidad.  Las investigaciones por los asesinatos de estos ni\u00f1os y de todas las v\u00edctimas de los cuerpos de seguridad est\u00e1n estancadas en Nicaragua.&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep07082018Efe7694038-300x169.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep07082018Efe7694038-1024x576.jpg\" loading=\"lazy\" class=\"size-full wp-image-4042\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep07082018Efe7694038.jpg\" alt=\"\" width=\"1600\" height=\"900\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep07082018Efe7694038.jpg 1600w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep07082018Efe7694038-300x169.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep07082018Efe7694038-768x432.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep07082018Efe7694038-1024x576.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep07082018Efe7694038-1200x675.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep07082018Efe7694038-500x281.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep07082018Efe7694038-1000x563.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep07082018Efe7694038-700x394.jpg 700w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><figcaption class=\"wp-caption-text\"><strong>Impunidad<\/strong>. Las investigaciones por los asesinatos de estos ni\u00f1os y de todas las v\u00edctimas de los cuerpos de seguridad est\u00e1n estancadas en Nicaragua.<\/figcaption><\/figure>\n<p>Teyler se dorm\u00eda a las 9 de la noche y se despertaba a las 4 de la ma\u00f1ana. \u201cEra mi alarma para ir a trabajar\u201d, dice Karina. Desde esa hora, Teyler le gritaba a su abuela o a sus t\u00edos para \u201cque supieran que estaba despierto y lo cargaran\u201d, dice la madre.<\/p>\n<p>Joshuara, la ni\u00f1a de siete a\u00f1os, tambi\u00e9n pregunta por su hermanito: \u201c\u00bfY el negrito, d\u00f3nde est\u00e1, mama?\u201d Karina Navarrete trata de no llorar delante de su hija. Le responde que el negrito est\u00e1 en el cielo, que est\u00e1 jugando, que le desee buenas noches y que le diga que hoy se porte bien.<\/p>\n<p>Durante el d\u00eda, Karina se distrae platicando, viendo televisi\u00f3n, dando entrevistas. Pero cuando llega la noche se quiebra. No aguanta. Duerme a la ni\u00f1a y se va a otro cuarto. Cierra la puerta. Llora. No le importa lo que piensen los dem\u00e1s que solo escuchan sus gritos. \u201cEn ese cuarto solo yo s\u00e9 c\u00f3mo me pongo a llorar\u201d.<\/p>\n<h1 style=\"text-align: center;\">***<\/h1>\n<p><strong>NI\u00d1OS CALCINADOS<\/strong><br \/>\nMath\u00edas Vel\u00e1squez Raudez, de cinco meses, y Daryeli Vel\u00e1squez Raudez, de dos a\u00f1os de edad, murieron calcinados en su casa el s\u00e1bado 15 de junio, d\u00eda en que la polic\u00eda y paramilitares hac\u00edan \u201clabores de limpieza\u201d en el barrio Carlos Marx, donde los protestantes de la zona hab\u00edan levantado barricadas desde los primeros d\u00edas de protesta.<\/p>\n<p>En la tragedia murieron de la misma forma sus abuelos, \u00d3scar Vel\u00e1squez Pav\u00f3n y Maritza L\u00f3pez. Y tambi\u00e9n sus padres, Alfredo Vel\u00e1squez L\u00f3pez y Mercedes Raudez. Un d\u00eda antes de que murieran en el incendio, su madre hab\u00eda subido una foto en la que aparec\u00edan los ni\u00f1os con trapos sobre el rostro, como una especie de pasamonta\u00f1as, y unos morteros de juguete que llevaban el grabado de Nicaragua. \u201cMis beb\u00e9s vand\u00e1licos\u201d, hab\u00eda escrito en su publicaci\u00f3n.<\/p>\n<figure id=\"attachment_4044\" style=\"width: 1600px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"4044\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/la-masacre-de-ninos-durante-la-represion-orteguista\/fsep08072018efe7687642\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7687642.jpg\" data-orig-size=\"1600,900\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep08072018Efe7687642\" data-image-description=\"&lt;p&gt;Demandas.  Un hombre sostiene un cartel con fotograf\u00edas de detenido por el Gobierno de Daniel Ortega, durante una protesta realizada al exterior de El Chipote, una c\u00e1rcel de m\u00e1xima seguridad.  &lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Demandas.  Un hombre sostiene un cartel con fotograf\u00edas de detenido por el Gobierno de Daniel Ortega, durante una protesta realizada al exterior de El Chipote, una c\u00e1rcel de m\u00e1xima seguridad.  &lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7687642-300x169.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7687642-1024x576.jpg\" loading=\"lazy\" class=\"size-full wp-image-4044\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7687642.jpg\" alt=\"\" width=\"1600\" height=\"900\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7687642.jpg 1600w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7687642-300x169.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7687642-768x432.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7687642-1024x576.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7687642-1200x675.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7687642-500x281.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7687642-1000x563.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7687642-700x394.jpg 700w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><figcaption class=\"wp-caption-text\"><strong>Demandas<\/strong>. Un hombre sostiene un cartel con fotograf\u00edas de detenido por el Gobierno de Daniel Ortega, durante una protesta realizada al exterior de El Chipote, una c\u00e1rcel de m\u00e1xima seguridad.<\/figcaption><\/figure>\n<h3 style=\"text-align: center;\">Ni\u00f1o y adolescentes asesinados<\/h3>\n<p><strong>\u00c1lvaro Conrado, de 15 a\u00f1os de edad:<\/strong><\/p>\n<p>Fue el primer ni\u00f1o asesinado durante las protestas. Muri\u00f3 el 20 de abril despu\u00e9s de mediod\u00eda. Fue asesinado cuando llevaba a escondidas agua a los universitarios que recog\u00edan v\u00edveres en la catedral de Managua. Era m\u00fasico, atleta y quer\u00eda ser abogado. Recibi\u00f3 un impacto de bala que le da\u00f1\u00f3 la tr\u00e1quea y el es\u00f3fago.<\/p>\n<p><strong>Orlando C\u00f3rdoba, 15 a\u00f1os de edad:<\/strong><\/p>\n<p>Asesinado el 30 de mayo, D\u00eda de las Madres. Orlandito nunca hab\u00eda participado en ninguna marcha. Aquel d\u00eda, frente a la UNI, una bala penetr\u00f3 su t\u00f3rax. Su pasatiempo era mirar videos en YouTube para aprender a tocar mejor la bater\u00eda, su instrumento de todos los viernes en el culto de su iglesia evang\u00e9lica. Era fan\u00e1tico del Barcelona, equipo espa\u00f1ol de f\u00fatbol. Cursaba el sexto grado de primaria en el Centro Escolar Espa\u00f1a, en Managua.<\/p>\n<p><strong>J\u00fanior Gait\u00e1n, de 15 a\u00f1os de edad:<\/strong><\/p>\n<p>Fue asesinado el 2 de junio, de rodillas ante un polic\u00eda, seg\u00fan familiares y testigos. \u201cLe suplic\u00f3 por su vida\u201d, dijo su madre, Aura Lila L\u00f3pez. \u201cLe dispar\u00f3 a quemarropa en el pecho\u201d. Le encantaba jugar f\u00fatbol. Le dec\u00edan \u201cel Pollo\u201d o \u201cPollito\u201d, de cari\u00f1o. Fue una vecina la que le \u201cencaj\u00f3\u201d ese apodo, supuestamente porque com\u00eda mucho pollo frito. Era buen alumno, le llamaban la atenci\u00f3n los bomberos y los grafitis.<\/p>\n<p><strong>S\u00e1ndor Dolmus, 15 a\u00f1os de edad:<\/strong><\/p>\n<p>Muri\u00f3 el 14 de junio. Un balazo certero lo tumb\u00f3 parti\u00e9ndole el pecho, a unos metros de la puerta de su casa, en el barrio San Juan. Casi no sal\u00eda de casa. No hab\u00eda salido en los \u00faltimos dos meses. Le gustaba mirar videos en YouTube de cantos a la Virgen Mar\u00eda. Era muy cat\u00f3lico y seguidor de monse\u00f1or Silvio Jos\u00e9 B\u00e1ez, obispo auxiliar de Managua. Estaba en cuarto a\u00f1o del colegio de secundaria Sagrado Coraz\u00f3n de Jes\u00fas.<\/p>\n<p><strong>Francisco Rivera Narv\u00e1ez, de 16 a\u00f1os de edad:<\/strong><\/p>\n<p>Falleci\u00f3 el s\u00e1bado 23 de junio. El informe m\u00e9dico legal indica que la causa de la muerte fue herida por proyectil de arma de fuego, con entrada y salida en el cr\u00e1neo. El joven habitaba en el barrio Santa Elena, de Managua. Ese d\u00eda regresaba de jugar f\u00fatbol en el parque del barrio Monte Fresco cuando fue atacado.<\/p>\n<p><strong>Samuel Reyes, de 16 a\u00f1os de edad:<\/strong><\/p>\n<p>Asesinado el s\u00e1bado 23 de junio. Muri\u00f3 al ser herido por arma de fuego y arma blanca en el cr\u00e1neo. Viv\u00eda en el barrio Reparto Schick de Managua.<\/p>\n<p><strong>J\u00e9sner Josu\u00e9 Rivas, de 16 a\u00f1os de edad:<\/strong><\/p>\n<p>Asesinado el 22 de abril. Su madre cont\u00f3 que ese d\u00eda, al escuchar que un grupo de v\u00e1ndalos pretend\u00eda asaltar un supermercado en la entrada del barrio La Fuente, de Managua, J\u00e9sner tom\u00f3 su tiradora y sali\u00f3 de su casa. Minutos despu\u00e9s una bala lo impact\u00f3 casi a la altura del cuello, en la parte izquierda. Le gustaba jugar f\u00fatbol y su familia conserva los trofeos que hab\u00eda obtenido.<\/p>\n<p><strong>Abraham Antonio Castro Jarqu\u00edn, de 17 a\u00f1os de edad:<\/strong><\/p>\n<p>Asesinado el 8 de junio durante un ataque de turbas paramilitares orteguistas en la salida norte del municipio de Jinotega. Sus familiares le llamaban \u201cPatito\u201d. Se dedicaba a la reparaci\u00f3n de motos, pero llevaba d\u00edas en las trincheras. Viv\u00eda en el barrio Carlos Rizo.<\/p>\n<p><strong>\u00c1ngel Reyes, de 17 a\u00f1os de edad:<\/strong><\/p>\n<p>Muri\u00f3 el 17 de mayo, despu\u00e9s de que una ruta lo atropell\u00f3 intencionalmente. Estaba en una barricada cuando un bus, conducido por un paramilitar, le pas\u00f3 encima y le caus\u00f3 la muerte casi inmediata. Reyes era estudiante del Colegio Rigoberto L\u00f3pez P\u00e9rez y estaba apoyando a los universitarios atrincherados en la UPOLI.<\/p>\n<p><strong>Carlos Bonilla L\u00f3pez, de 17 a\u00f1os de edad:<\/strong><\/p>\n<p>Muri\u00f3 el 20 de abril tras recibir un balazo. Fue un disparo en la frente. Estaba en Ciudad Sandino y lo trasladaron al hospital local y luego fue remitido al Hospital Len\u00edn Fonseca, donde muri\u00f3. Hab\u00eda salido a un ensayo de la banda r\u00edtmica a la que pertenec\u00eda. Se acababa de bachillerar, en 2017, y estudiaba cursos libres de caja e ingl\u00e9s.<\/p>\n<p><strong>Jos\u00e9 Abraham Amador, de 17 a\u00f1os:<\/strong><\/p>\n<p>Asesinado el 20 de abril, cuando recibi\u00f3 el impacto de bala que le perfor\u00f3 los pulmones, cerca del mercado de Artesan\u00edas, de Masaya. Era estudiante de cuarto a\u00f1o de secundaria del centro Rafaela Herrera y pretend\u00eda estudiar veterinaria.<\/p>\n<p><strong>R\u00edchard Eduardo Berm\u00fadez Pav\u00f3n, de 17 a\u00f1os:<\/strong><\/p>\n<p>Fue uno de los primeros muertos del 19 de abril. Cay\u00f3 de una r\u00e1faga en el t\u00f3rax. Era estudiante de secundaria y viv\u00eda en Tipitapa, donde formaba parte de una comparsa r\u00edtmica.<\/p>\n<figure id=\"attachment_4045\" style=\"width: 1920px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"4045\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/la-masacre-de-ninos-durante-la-represion-orteguista\/sep080718arteca\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/sep080718arteca.jpg\" data-orig-size=\"1920,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"sep080718arteca\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Imagen&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/sep080718arteca-300x169.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/sep080718arteca-1024x576.jpg\" loading=\"lazy\" class=\"size-full wp-image-4045\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/sep080718arteca.jpg\" alt=\"\" width=\"1920\" height=\"1080\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/sep080718arteca.jpg 1920w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/sep080718arteca-300x169.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/sep080718arteca-768x432.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/sep080718arteca-1024x576.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/sep080718arteca-1900x1069.jpg 1900w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/sep080718arteca-1200x675.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/sep080718arteca-500x281.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/sep080718arteca-1000x563.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/sep080718arteca-700x394.jpg 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-caption-text\">Imagen<\/figcaption><\/figure>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Como si Herodes hubiese vuelto a las suyas, entre los 285 muertos de la represi\u00f3n orteguista, ANPDH contabiliza 21 menores de edad. Estas son las historias de los adolescentes, ni\u00f1os y beb\u00e9s asesinados.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":4040,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>La masacre de ni\u00f1os durante la represi\u00f3n orteguista - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"La masacre de ni\u00f1os durante la represi\u00f3n orteguista - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Como si Herodes hubiese vuelto a las suyas, entre los 285 muertos de la represi\u00f3n orteguista, ANPDH contabiliza 21 menores de edad. Estas son las historias de los adolescentes, ni\u00f1os y beb\u00e9s asesinados.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-07-08T06:10:55+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-07-07T23:45:11+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Juli\u00e1n Navarrete \/ La Prensa \/ Nicaragua\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"12 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Entierro\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/\",\"name\":\"La masacre de ni\u00f1os durante la represi\u00f3n orteguista - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/#primaryimage\"},\"datePublished\":\"2018-07-08T06:10:55+00:00\",\"dateModified\":\"2018-07-07T23:45:11+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La masacre de ni\u00f1os durante la represi\u00f3n orteguista\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\",\"name\":\"S\u00e9ptimo Sentido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"caption\":\"S\u00e9ptimo Sentido\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"La masacre de ni\u00f1os durante la represi\u00f3n orteguista - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/","og_locale":"en_US","og_type":"article","og_title":"La masacre de ni\u00f1os durante la represi\u00f3n orteguista - S\u00e9ptimo Sentido","og_description":"Como si Herodes hubiese vuelto a las suyas, entre los 285 muertos de la represi\u00f3n orteguista, ANPDH contabiliza 21 menores de edad. Estas son las historias de los adolescentes, ni\u00f1os y beb\u00e9s asesinados.","og_url":"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-07-08T06:10:55+00:00","article_modified_time":"2018-07-07T23:45:11+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"Juli\u00e1n Navarrete \/ La Prensa \/ Nicaragua","Est. reading time":"12 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088.jpg","width":1920,"height":1080,"caption":"Entierro"},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/","name":"La masacre de ni\u00f1os durante la represi\u00f3n orteguista - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/#primaryimage"},"datePublished":"2018-07-08T06:10:55+00:00","dateModified":"2018-07-07T23:45:11+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/la-masacre-de-ninos-durante-la-represion-orteguista\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"La masacre de ni\u00f1os durante la represi\u00f3n orteguista"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b","name":"S\u00e9ptimo Sentido","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","caption":"S\u00e9ptimo Sentido"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":""}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep08072018Efe7702088.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-139","jetpack-related-posts":[{"id":6436,"url":"https:\/\/7s.laprensagrafica.com\/en\/ser-nino-en-el-triangulo-norte-y-desaparecer\/","url_meta":{"origin":4039,"position":0},"title":"Ser ni\u00f1o en el Tri\u00e1ngulo Norte y desaparecer","date":"29 September, 2019","format":false,"excerpt":"En el Tri\u00e1ngulo Norte desaparecen ni\u00f1os sin dejar ning\u00fan registro. La regi\u00f3n, compuesta por El Salvador, Honduras y Guatemala es un corredor de migraciones forzadas y violencia en donde todav\u00eda no se tipifica como delito la desaparici\u00f3n por causas actuales. En el marco del D\u00eda del Ni\u00f1o y a pocas\u2026","rel":"","context":"In &quot;Reportaje Nacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/09\/septimo09092019desa1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5179,"url":"https:\/\/7s.laprensagrafica.com\/en\/la-soledad-de-la-busqueda\/","url_meta":{"origin":4039,"position":1},"title":"La soledad de la b\u00fasqueda","date":"27 January, 2019","format":false,"excerpt":"Cuando una persona desaparece, su localizaci\u00f3n depende \u2013casi en exclusiva\u2013 del ah\u00ednco con el que sus seres queridos presionen a las autoridades estatales y de la repercusi\u00f3n medi\u00e1tica del caso. En este reportaje, los familiares de las personas desaparecidas reclaman que las investigaciones no generan resultados; no los encuentran vivos\u2026","rel":"","context":"In &quot;Reportaje Nacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/01\/fsep27012019propuestax.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9734,"url":"https:\/\/7s.laprensagrafica.com\/en\/las-madres-con-las-que-nadie-habla\/","url_meta":{"origin":4039,"position":2},"title":"Las madres con las que nadie habla","date":"15 August, 2021","format":false,"excerpt":"[:es]Los acusados no son los \u00fanicos que enfrentan las consecuencias de una investigaci\u00f3n poco robusta. En sus casas, madres y esposas esperan, algunas en la miseria, que alguien les lleve alguna noticia sobre sus familiares.[:]","rel":"","context":"In &quot;Reportaje&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2021\/08\/fsep01082021juchalchua06min.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8468,"url":"https:\/\/7s.laprensagrafica.com\/en\/los-maestros-estamos-haciendo-la-lucha-por-un-lado-y-por-el-otro\/","url_meta":{"origin":4039,"position":3},"title":"&#8220;Los maestros estamos haciendo la lucha por un lado y por el otro&#8221;","date":"15 November, 2020","format":false,"excerpt":"[:es]Carmen Garc\u00eda es maestra desde hace 37 a\u00f1os. Desde que comenz\u00f3 su carrera, ha trabajado con ni\u00f1os que viven en extrema pobreza. Ha ense\u00f1ado en tiempos de guerra, terremotos y tormentas tropicales. Pero, para ella, la ense\u00f1anza nunca se hab\u00eda complicado tanto como en los tiempos de la Covid-19.\u00a0[:]","rel":"","context":"In &quot;Reportaje Nacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/11\/fsep15112020wumae001.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2799,"url":"https:\/\/7s.laprensagrafica.com\/en\/calabozo-retorno-una-denuncia-26-anos-despues\/","url_meta":{"origin":4039,"position":4},"title":"El Calabozo: El retorno de una denuncia 26 a\u00f1os despu\u00e9s","date":"4 February, 2018","format":false,"excerpt":"El viernes 26 de enero se realiz\u00f3 una inspecci\u00f3n de los lugares en los que, de acuerdo con testigos, ocurri\u00f3 la masacre de El Calabozo en 1982. El reci\u00e9n reconocimiento de este lugar llega casi 26 a\u00f1os despu\u00e9s de que el caso fue denunciado ante las autoridades. La lista de\u2026","rel":"","context":"In &quot;Reportaje&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/02\/fsep04022017fmcala26.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4892,"url":"https:\/\/7s.laprensagrafica.com\/en\/testimonios-y-huesos-las-primeras-pruebas-de-la-masacre-de-el-calabozo\/","url_meta":{"origin":4039,"position":5},"title":"Testimonios y huesos: las primeras pruebas de la masacre de El Calabozo","date":"2 December, 2018","format":false,"excerpt":"Al menos 200 personas de la poblaci\u00f3n civil fueron asesinadas por militares en la masacre de El Calabozo en 1982, de acuerdo con la denuncia de supervivientes. La evidencia f\u00edsica de esta masacre, ocurrida en los alrededores de San Esteban Catarina (San Vicente), escasea. Los pobladores cuentan que sus familiares\u2026","rel":"","context":"In &quot;Reportaje Nacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/12\/fsep02112018agcala441.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4039"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=4039"}],"version-history":[{"count":2,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4039\/revisions"}],"predecessor-version":[{"id":4047,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/4039\/revisions\/4047"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/4040"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=4039"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=4039"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=4039"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}