{"id":3780,"date":"2018-06-10T00:02:41","date_gmt":"2018-06-10T06:02:41","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=3780"},"modified":"2018-06-10T04:16:44","modified_gmt":"2018-06-10T10:16:44","slug":"el-tiempo-detenido-en-un-paisaje-blanco-y-negro","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/","title":{"rendered":"El tiempo detenido en un paisaje blanco y negro"},"content":{"rendered":"<figure id=\"attachment_3785\" style=\"width: 1920px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"3785\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/fsep10062018corguatemala07ca\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca.jpg\" data-orig-size=\"1920,1080\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep10062018corguatemala07ca\" data-image-description=\"&lt;p&gt;Cenizas&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Cenizas&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca-300x169.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca-1024x576.jpg\" loading=\"lazy\" class=\"size-full wp-image-3785\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca.jpg\" alt=\"\" width=\"1920\" height=\"1080\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca.jpg 1920w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca-300x169.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca-768x432.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca-1024x576.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca-1900x1069.jpg 1900w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca-1200x675.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca-500x281.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca-1000x563.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca-700x394.jpg 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-caption-text\">Cenizas<\/figcaption><\/figure>\n<p>La aldea de San Miguel Los Lotes perdi\u00f3 su color. Parece una fotograf\u00eda en blanco y negro de lo que alg\u00fan d\u00eda fue un lugar habitable. Ahora es un desierto de ceniza, apagado, triste. Debajo, est\u00e1n todav\u00eda los cad\u00e1veres de decenas de personas.<\/p>\n<p>La maquinaria fue abriendo paso estos d\u00edas hasta hacer reaparecer la carretera principal, la Ruta Nacional 14, una calzada de asfalto que ahora simula un camino de terracer\u00eda m\u00e1s. Unos metros antes, detr\u00e1s de un cord\u00f3n rojo, un bombero voluntario da instrucciones a periodistas. \u201cSi quieren entrar, tenemos que ir juntos. No nos separemos por favor. Y no se salgan de los caminamientos\u201d. Comienza el recorrido. Una excursi\u00f3n de 50 personas que pasean por una zona devastada.<\/p>\n<p>Despu\u00e9s de las primeras casas, las menos afectadas, permanece intacto un puente del que el d\u00eda anterior los rescatistas sacaron un cad\u00e1ver sin pies. Algunos de los que vieron la escena desde abajo, a una distancia prudencial, hoy caminan a pocos metros del guardarrail donde se encontraba el cad\u00e1ver.<\/p>\n<p>Dos rescatistas colocan trapos al suelo para aliviar el calor de un perro que sobrevivi\u00f3 a la erupci\u00f3n volc\u00e1nica y que lleva dos d\u00edas manteni\u00e9ndose cerca de su casa.<br \/>\nUn poco m\u00e1s adelante, las casas m\u00e1s cercanas a la carretera aguantan de pie, a\u00fan no se sabe c\u00f3mo. La primera imagen es la de dos veh\u00edculos. Ni siquiera se distingue su color. Est\u00e1n casi verticales, incrustados en un mont\u00edculo de ceniza, cubiertos de polvo. Una gr\u00faa arrastra un picop marr\u00f3n, no se sabe si por el \u00f3xido o por la costra de la tierra h\u00fameda, mojada a\u00fan por la lluvia de la tarde anterior. Pareciera la escena de un desguace.<\/p>\n<p>En la entrada de una vivienda algunos socorristas levantaron un improvisado puente por el que caminan bomberos, polic\u00edas, miembros del Ej\u00e9rcito, vecinos de la aldea\u2026 Es una casa especialmente sencilla. Contrasta con las de block de cemento a sus lados; piso de tierra, techo de l\u00e1mina. Y a pesar de su sencillez, no se ve tan perjudicada por la avalancha de ceniza. Sobre la mesa de madera, una canasta con granos de ma\u00edz pareciera esperar por alguien que los cocine. En la cocina, tazas perfectamente colocadas, ollas, sartenes. Todo en su lugar.<br \/>\nAl fondo de la casa, la salida es un angosto espacio de un 1.50 metro de altura. Es la puerta al horror.<\/p>\n<p>Del otro lado est\u00e1n las viviendas que quedaron soterradas por la ceniza; algunas completamente. Otras est\u00e1n cubiertas con una peque\u00f1a capa gris. El tiempo parece haberse detenido en ellas. Tres costales de naranjas ennegrecidas aguardan en una esquina a alguien que debi\u00f3 comenzar la venta el lunes, temprano. A unos metros, una hilera de palos de madera gris\u00e1ceos est\u00e1n listos para calentar una estufa de le\u00f1a ahora inservible.<\/p>\n<h4>Tres costales de naranjas ennegrecidas aguardan en una esquina a alguien que debi\u00f3 comenzar la venta el lunes, temprano. A unos metros, una hilera de palos de madera gris\u00e1ceos est\u00e1n listos para calentar una estufa de le\u00f1a ahora inservible. En una de las viviendas hay trastes que nadie lav\u00f3 despu\u00e9s del almuerzo. Hay ropa en el tendedero, seca, polvorienta, r\u00edgida. La fruta fresca preparada en un canasto para que los ni\u00f1os la comieran est\u00e1 hecha harina. Una bicicleta, completamente pintada<\/h4>\n<p>En una de las viviendas hay trastes que nadie lav\u00f3 despu\u00e9s del almuerzo. Hay ropa en el tendedero, seca, polvorienta, r\u00edgida. La fruta fresca preparada en un canasto para que los ni\u00f1os la comieran est\u00e1 hecha harina. Una bicicleta, completamente pintada de blanco. Un triciclo ahogado en ceniza.<br \/>\nLuego de un peque\u00f1o callej\u00f3n, una casa de block de dos niveles ayuda a entender un poco la situaci\u00f3n en la que se encuentran muchas viviendas. Estamos de pie, sobre lo que se supone que antes era una calle. Sin embargo, un letrero de cobre en el que se lee apartamento A, que deber\u00eda estar encima de la puerta de entrada, se encuentra ahora a poco m\u00e1s de un palmo del suelo. A su lado, las esquinas superiores de la puerta y de una ventana asoman entre la tierra. Estamos en la calle, s\u00ed, pero a unos 2.5 metros de altura.<\/p>\n<p>El callej\u00f3n contin\u00faa, alej\u00e1ndose de la carretera principal. Al nivel del piso, un grupo de seis bomberos se turna para agujerear el tejado de una casa. Se mantienen con equilibrio sobre unos listones de madera. El ruido de palas, arados y grandes martillos se escucha con golpes secos sobre un techo de cemento y metal. \u201cCambio\u201d, grita el superior. Los seis bomberos regresan y unos compa\u00f1eros toman su lugar. Buscan cad\u00e1veres dentro de las casas. Por ahora no han logrado retirar ninguno. La cifra de 70 personas fallecidas lleva inmutable todo el d\u00eda.<br \/>\nLos cad\u00e1veres enterrados<br \/>\nHace calor. El suelo es ceniza, ceniza y m\u00e1s ceniza. Cada paso hacia arriba, hacia dentro de la aldea, se siente en la suela de los zapatos. Las calienta, las desprende de las botas hasta abrasar los pies de quien camina por la zona. Entender esta sensaci\u00f3n de malestar, de inseguridad y de peligro es crucial para comprender por qu\u00e9 hoy no se ha rescatado ning\u00fan cad\u00e1ver de San Miguel Los Lotes.<br \/>\nEn la entrada de la aldea, los grupos de rescatistas esperan la orden. Algunos se recuestan en el pasto ceniciento. Comen, beben agua y suero, reponen fuerzas. Cada poco tiempo un grupo de 20 se forma frente al cord\u00f3n rojo. Hacen un r\u00e1pido recuento. \u201c\u00a1Uno, dos, tres, cuatro, cinco, seis!&#8230;\u201d. El oficial a cargo pregunta qui\u00e9n necesita lentes, guantes y m\u00e1scaras. \u201cCon conciencia, que no hay para todos\u201d. Algunos levantan la mano. Otros se quedan callados, con la vista en el suelo. No tienen lentes ni guantes. \u201cLo siento por los que no, much\u00e1\u201d, termina el oficial.<\/p>\n<p>Al final de la fila est\u00e1 V\u00edctor \u00c1lvarez. Lleva ocho a\u00f1os colaborando como bombero voluntario. V\u00edctor trabaja vendiendo peri\u00f3dicos en las calles de Guatemala. Pidi\u00f3 un par de d\u00edas libres para poder ayudar. Est\u00e1n a punto de salir hacia un \u00e1rea en la que creen que hay al menos 10 cad\u00e1veres. \u201cEst\u00e1 dif\u00edcil\u201d, resume V\u00edctor. Hace tres a\u00f1os estuvo en la tragedia del Cambray, el deslizamiento de tierra en Santa Catarina Pinula el que fallecieron m\u00e1s de 260 v\u00edctimas. \u00c9l sac\u00f3 ocho fallecidos con sus manos. Cuando cierra los ojos todav\u00eda recuerda sus rostros. \u201cAqu\u00ed es m\u00e1s dif\u00edcil\u201d, repite. La tierra no est\u00e1 h\u00fameda como en el Cambray. Aqu\u00ed est\u00e1 seca y arde. Bajo la capa superficial llega a los 300 grados cent\u00edgrados.<br \/>\nCuando consiguen abrirse paso y entrar en una casa, la situaci\u00f3n es peor. En las viviendas, cerradas, herm\u00e9ticas, la temperatura del ambiente puede llegar a los 100 grados cent\u00edgrados. El d\u00eda anterior alcanzaban los 120.<br \/>\nLos 20 bomberos aguardan a que baje el grupo anterior. Toman el relevo y avanzan a paso ligero. Los que llegan est\u00e1n destrozados. Sus trajes est\u00e1n te\u00f1idos de gris, los rostros desencajados, desesperanzados. Desesperanza. Es la palabra que utiliza H\u00e9ctor Chac\u00f3n Cuellas, mayor de los Bomberos Municipales. Chac\u00f3n lleva 50 de sus 72 a\u00f1os trabajando como bombero. Lleva la delantera de su grupo, y al bajar de la aldea contin\u00faa su camino, casi por inercia, hacia el inicio de la Ruta Nacional 14. Una de las personas a su cargo le detiene. \u201cMayor, por aqu\u00ed\u201d, le gu\u00eda a tomar un poco de agua.<\/p>\n<figure id=\"attachment_3786\" style=\"width: 1548px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"3786\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/fsep10062018corguatemala02\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala02.jpg\" data-orig-size=\"1548,1032\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep10062018corguatemala02\" data-image-description=\"&lt;p&gt;Fieles. Dos rescatistas colocan trapos al suelo para aliviar el calor de un perro que sobrevivi\u00f3 a la erupci\u00f3n volc\u00e1nica y que lleva dos d\u00edas manteni\u00e9ndose cerca de su casa.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Fieles. Dos rescatistas colocan trapos al suelo para aliviar el calor de un perro que sobrevivi\u00f3 a la erupci\u00f3n volc\u00e1nica y que lleva dos d\u00edas manteni\u00e9ndose cerca de su casa.&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala02-300x200.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala02-1024x683.jpg\" loading=\"lazy\" class=\"wp-image-3786 size-full\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala02.jpg\" alt=\"\" width=\"1548\" height=\"1032\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala02.jpg 1548w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala02-300x200.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala02-768x512.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala02-1024x683.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala02-1200x800.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala02-500x333.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala02-1000x667.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala02-700x467.jpg 700w\" sizes=\"(max-width: 1548px) 100vw, 1548px\" \/><figcaption class=\"wp-caption-text\"><strong>Fieles<\/strong>. Dos rescatistas colocan trapos al suelo para aliviar el calor de un perro que sobrevivi\u00f3 a la erupci\u00f3n volc\u00e1nica y que lleva dos d\u00edas manteni\u00e9ndose cerca de su casa.<\/figcaption><\/figure>\n<p>\u201cCada vez hay m\u00e1s desesperanza. Hay mucha tierra. Hay mucha tierra\u201d, dice Chac\u00f3n, con la mirada perdida. \u201cCada vez se vuelve m\u00e1s dif\u00edcil\u201d.<br \/>\nMynor Ruano, oficial de Informaci\u00f3n de los Bomberos Municipales, ofrece algunas luces acerca de las labores de rescate. Mientras da la informaci\u00f3n es interrumpido por llamadas, consultas de los dem\u00e1s bomberos y avisos. \u201cEl avance est\u00e1 siendo m\u00e1s lento. Ahora se est\u00e1 haciendo un rastreo paralelo para acercarnos a partes m\u00e1s lejanas\u201d, explica.<br \/>\nRuano completa lo que ya adelantaron los otros bomberos. Que cada vez se vuelve m\u00e1s complicado encontrar cad\u00e1veres enteros, como fueron apareciendo a lo largo del domingo y del lunes.<\/p>\n<p>Est\u00e1n calcinados, y el calor y la aridez del ambiente solo complican m\u00e1s los trabajos de b\u00fasqueda. \u201cEs probable que ahora salgan mutilados\u201d, concluye.<br \/>\nCerca del list\u00f3n rojo hay varios hombres que se acercaron con palas, cubiertos \u00fanicamente por mascarillas de papel. Esperan pacientemente a que les den permiso para entrar en el terreno. Quieren ayudar. Se\u00f1alar los lugares en los que estaban sus casas o las casas de sus familiares. Ver si todav\u00eda se pueden rescatar los cad\u00e1veres.<\/p>\n<p>Un hombre aguarda de pie, acompa\u00f1ado de un amigo que explica su situaci\u00f3n. \u201cBuscamos a una cu\u00f1ada y a una sobrina de \u00e9l. Solo sabe Dios si siguen ah\u00ed\u201d. Una hora m\u00e1s tarde, los bomberos se acercan a los dos j\u00f3venes. Comparten unas palabras, asienten, y los muchachos les acompa\u00f1an al interior de la aldea.<br \/>\nLas esperanzas de encontrar personas con vida van menguando a cada hora que pasa. De vez en cuando aparecen perros cojeando, gallinas picoteando el suelo, o patos desorientados. Los rescatadores no se explican c\u00f3mo pueden seguir con vida.<\/p>\n<p>Carretera abajo, en el primer ret\u00e9n, Melisa Mar Charro, brigadier de la Direcci\u00f3n General de Protecci\u00f3n y Seguridad Vial (PROVIAL) lleva todo el d\u00eda dando indicaciones a las personas que se acercan al lugar. \u201cSi quieren entrar pueden hacerlo, pero de una manera ordenada. Tienen que ir al centro de comando\u201d, les explica pacientemente a cada grupo que se presenta con ansias de subir caminando hacia la aldea.<\/p>\n<p>La mayor\u00eda solo quiere volver a sus casas, al inicio de San Miguel, para recoger algunos objetos personales. As\u00ed lo explican Melvin Montes de Oca, de 24 a\u00f1os, y Paola Hern\u00e1ndez, de 20, una pareja que viv\u00eda con su hija en una casa rentada. \u201cLa idea es entrar a sacar algo, por lo menos, para no empezar otra vez de cero. Aqu\u00ed no podemos seguir viviendo. Es imposible\u201d, dice Melvin.<br \/>\nCharro explica que este control de las personas que suben y bajan se hace como medida de precauci\u00f3n. Para saber qui\u00e9n entra, a d\u00f3nde va y cu\u00e1ndo regresa. Sin embargo, a lo largo del d\u00eda el caos, la tensi\u00f3n y el hast\u00edo hacen que hombres y mujeres se internen en el \u00e1rea sin dar sus nombres.<\/p>\n<p>de blanco. Un triciclo ahogado en ceniza.<\/p>\n<h4>Las esperanzas de encontrar personas con vida van menguando a cada hora que pasa. De vez en cuando aparecen perros cojeando, gallinas picoteando el suelo o patos desorientados. Los rescatadores no se explican c\u00f3mo pueden seguir con vida.<\/h4>\n<p>Este descontrol es muestra de los problemas de informaci\u00f3n. Sergio Caba\u00f1as, secretario ejecutivo de la Coordinadora Nacional para la Reducci\u00f3n de Desastres (CONRED) dec\u00eda ayer en conferencia de prensa que hay 192 personas desaparecidas. \u201cYa tenemos los nombres y de qu\u00e9 comunidad eran; con los datos del Instituto Nacional de Estad\u00edstica (INE) y una foto a\u00e9rea estamos haciendo una comparaci\u00f3n\u201d, explic\u00f3.<\/p>\n<p>Pero hay dos vac\u00edos. Primero, las personas fallecidas que no han sido identificadas. El segundo, las que no han sido reportadas.<br \/>\nLa jornada de trabajo cerraba ese d\u00eda abruptamente con una explosi\u00f3n que suspendi\u00f3 las labores de rescate y obligaba al cierre de la autopista desde Ciudad de Guatemala en direcci\u00f3n a Escuintla.<\/p>\n<p>A las 8 de la tarde, el Instituto Nacional de Sismolog\u00eda, Vulcanolog\u00eda, Meteorolog\u00eda e Hidrolog\u00eda (INSIVUMEH) emit\u00eda un bolet\u00edn en el que indicaba que el volc\u00e1n de Fuego hab\u00eda aumentado su actividad y como consecuencia de esto, a las 7:30 se hab\u00eda generado un nuevo flujo pirocl\u00e1stico. Por el clima, nublado, no se pod\u00eda observar bien su desplazamiento, alertaba.<br \/>\nPor ahora tocar\u00e1 esperar a ver si el mi\u00e9rcoles se retoman los trabajos. Se cumplir\u00e1n entonces 72 horas de la tragedia, tiempo l\u00edmite para tomar una decisi\u00f3n clave: la revisi\u00f3n minuciosa que se ha hecho hasta ahora podr\u00eda detenerse. La maquinaria pesada entrar\u00eda entonces para desescombrar la aldea.<\/p>\n<hr \/>\n<p>*Este art\u00edculo es una colaboraci\u00f3n period\u00edstica de Plaza P\u00fablica. Puede ver la publicaci\u00f3n original en: <a href=\"https:\/\/www.plazapublica.com.gt\/content\/el-tiempo-detenido-en-un-paisaje-en-blanco-y-negro\" target=\"_blank\" rel=\"noopener\">https:\/\/www.plazapublica.com.gt\/content\/el-tiempo-detenido-en-un-paisaje-en-blanco-y-negro<\/a>.<\/p>\n<figure id=\"attachment_3787\" style=\"width: 1920px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"3787\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/fsep10062018corguatemala04\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala04.jpg\" data-orig-size=\"1920,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep10062018corguatemala04\" data-image-description=\"\" data-image-caption=\"\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala04-300x200.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala04-1024x683.jpg\" loading=\"lazy\" class=\"wp-image-3787 size-full\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala04.jpg\" alt=\"\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala04.jpg 1920w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala04-300x200.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala04-768x512.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala04-1024x683.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala04-1900x1267.jpg 1900w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala04-1200x800.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala04-500x333.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala04-1000x667.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala04-700x467.jpg 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-caption-text\"><strong>Sin explicaci\u00f3n<\/strong>. Una gallina cruza el patio de la casa. Sorprendentemente, varios pollos, unos perros y unos gatos lograron sobrevivir a la erupci\u00f3n volc\u00e1nica.<\/figcaption><\/figure>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Dos d\u00edas despu\u00e9s de la cat\u00e1strofe del volc\u00e1n de Fuego, los rescatistas contin\u00faan su trabajo en una aldea que perdi\u00f3 su color. El interior de las casas que no est\u00e1n enterradas muestra c\u00f3mo el tiempo se detuvo. Casi todo qued\u00f3 en su lugar, cubierto de un manto de cenizas gris\u00e1ceo.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":3785,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El tiempo detenido en un paisaje blanco y negro - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El tiempo detenido en un paisaje blanco y negro - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Dos d\u00edas despu\u00e9s de la cat\u00e1strofe del volc\u00e1n de Fuego, los rescatistas contin\u00faan su trabajo en una aldea que perdi\u00f3 su color. El interior de las casas que no est\u00e1n enterradas muestra c\u00f3mo el tiempo se detuvo. Casi todo qued\u00f3 en su lugar, cubierto de un manto de cenizas gris\u00e1ceo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-06-10T06:02:41+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-06-10T10:16:44+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1080\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Carmen Quintela \/ Plaza P\u00fablica \/ Guatemala\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"11 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca.jpg\",\"width\":1920,\"height\":1080,\"caption\":\"Cenizas\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/\",\"name\":\"El tiempo detenido en un paisaje blanco y negro - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/#primaryimage\"},\"datePublished\":\"2018-06-10T06:02:41+00:00\",\"dateModified\":\"2018-06-10T10:16:44+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El tiempo detenido en un paisaje blanco y negro\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\",\"name\":\"S\u00e9ptimo Sentido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"caption\":\"S\u00e9ptimo Sentido\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El tiempo detenido en un paisaje blanco y negro - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/","og_locale":"en_US","og_type":"article","og_title":"El tiempo detenido en un paisaje blanco y negro - S\u00e9ptimo Sentido","og_description":"Dos d\u00edas despu\u00e9s de la cat\u00e1strofe del volc\u00e1n de Fuego, los rescatistas contin\u00faan su trabajo en una aldea que perdi\u00f3 su color. El interior de las casas que no est\u00e1n enterradas muestra c\u00f3mo el tiempo se detuvo. Casi todo qued\u00f3 en su lugar, cubierto de un manto de cenizas gris\u00e1ceo.","og_url":"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-06-10T06:02:41+00:00","article_modified_time":"2018-06-10T10:16:44+00:00","og_image":[{"width":1920,"height":1080,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"Carmen Quintela \/ Plaza P\u00fablica \/ Guatemala","Est. reading time":"11 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca.jpg","width":1920,"height":1080,"caption":"Cenizas"},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/","name":"El tiempo detenido en un paisaje blanco y negro - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/#primaryimage"},"datePublished":"2018-06-10T06:02:41+00:00","dateModified":"2018-06-10T10:16:44+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/en\/el-tiempo-detenido-en-un-paisaje-blanco-y-negro\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"El tiempo detenido en un paisaje blanco y negro"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b","name":"S\u00e9ptimo Sentido","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","caption":"S\u00e9ptimo Sentido"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":""}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep10062018corguatemala07ca.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-YY","jetpack-related-posts":[{"id":467,"url":"https:\/\/7s.laprensagrafica.com\/en\/sobrevivir-entre-ceniza\/","url_meta":{"origin":3780,"position":0},"title":"(Sobre)Vivir entre ceniza","date":"11 June, 2017","format":false,"excerpt":"En las faldas del Volc\u00e1n Turrialba, la cotidianidad se confunde con la alerta. No hace falta que se declare una emergencia; aqu\u00ed, el d\u00eda a d\u00eda es un recordatorio perenne de los riesgos del coloso.","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/Principal-ceniza.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6796,"url":"https:\/\/7s.laprensagrafica.com\/en\/en-esta-casa-no-hay-nadie\/","url_meta":{"origin":3780,"position":1},"title":"En esta casa no hay nadie","date":"8 December, 2019","format":false,"excerpt":"En esta casa no hay nadie es una historia que forma parte de D\u00edas del Olimpo, el libro con el que el escritor y poeta salvadore\u00f1o Miguel Huezo Mixco completa la trilog\u00eda que comenz\u00f3 con Camino de hormigas y la Casa de Moravia, todas publicadas por la editorial Alfaguara, de\u2026","rel":"","context":"In &quot;Reportaje&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/12\/fsep08102019cuento4.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6333,"url":"https:\/\/7s.laprensagrafica.com\/en\/la-historia-no-escuchada\/","url_meta":{"origin":3780,"position":2},"title":"La historia no escuchada","date":"15 September, 2019","format":false,"excerpt":"En su libro Literatura en las cenizas de la historia, Cathy Caruth analiza las experiencias traum\u00e1ticas y c\u00f3mo \u00e9stas siempre traen una p\u00e9rdida secundaria; el de desaparecer del registro hist\u00f3rico. Son historias no escuchadas.","rel":"","context":"In &quot;Opini\u00f3n desde all\u00e1&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/\u00c9velyn-Galindo-Doucette.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6925,"url":"https:\/\/7s.laprensagrafica.com\/en\/condenados-al-racismo-perpetuo-en-brasil\/","url_meta":{"origin":3780,"position":3},"title":"Condenados al racismo perpetuo en Brasil","date":"29 December, 2019","format":false,"excerpt":"Los indicadores de asesinatos son mayores entre la poblaci\u00f3n de color. Son las personas de raza negra la mayor\u00eda en las c\u00e1rceles. Brasil tiene una deuda grande para eliminar la discriminaci\u00f3n racial que, con el nuevo gobierno, ha crecido.","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/12\/fsep29122019eferacismo2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5469,"url":"https:\/\/7s.laprensagrafica.com\/en\/que-no-haya-guerra-es-la-paz-es-asi-de-simple\/","url_meta":{"origin":3780,"position":4},"title":"\u00bfQue no haya guerra es la paz? \u00bfEs as\u00ed de simple?","date":"31 March, 2019","format":false,"excerpt":"Hiroko Kishida estaba a 1.5 kil\u00f3metros de donde explot\u00f3 la bomba at\u00f3mica en Hiroshima, en 1945. Ahora se dedica a contar c\u00f3mo sobrevivi\u00f3 y a apelar para que los gobiernos firmen el tratado en contra de las armas nucleares.","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/03\/fsep28032019corinter53.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7906,"url":"https:\/\/7s.laprensagrafica.com\/en\/los-signos-y-simbolos-luego-de-george-floyd\/","url_meta":{"origin":3780,"position":5},"title":"Los signos y s\u00edmbolos luego de George Floyd","date":"21 June, 2020","format":false,"excerpt":"[:es]Hasta hace poco \"Karen\" y \"Becky\" eran nombres comunes con connotaciones neutrales, pero ahora m\u00e1s que nunca se usan de manera peyorativa para referirse a las mujeres blancas de mediana edad.[:]","rel":"","context":"In &quot;Opini\u00f3n desde all\u00e1&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/\u00c9velyn-Galindo-Doucette.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3780"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=3780"}],"version-history":[{"count":1,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3780\/revisions"}],"predecessor-version":[{"id":3788,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3780\/revisions\/3788"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/3785"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=3780"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=3780"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=3780"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}