{"id":3709,"date":"2018-05-27T00:06:10","date_gmt":"2018-05-27T06:06:10","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=3709"},"modified":"2018-05-26T20:51:32","modified_gmt":"2018-05-27T02:51:32","slug":"carta-editorial-27-mayo-2018","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-27-mayo-2018\/","title":{"rendered":"Carta Editorial"},"content":{"rendered":"<p>La \u00f3pera en El Salvador se hace a punta de sacrificios personales, como trabajar turnos de 3 de la tarde a 7 de la ma\u00f1ana para poder asistir a los ensayos. S\u00ed, hay \u00f3pera en este pa\u00eds, pero cuesta mucho. Es un apostolado que sobrevive a medias entre la pasi\u00f3n, la entrega, la terquedad y las ganas de desarrollar un talento. Que la \u00d3pera de El Salvador (OPES) recibe una partida de fondos p\u00fablicos, dir\u00e1n, pero esto es apenas una parte de lo que hay que pagar en salarios para mantener las puertas abiertas. Todo el talento que los fundadores de la instituci\u00f3n han encontrado merece mucho m\u00e1s.<\/p>\n<p>La forma en que ha venido funcionando la OPES ha facilitado que la educaci\u00f3n l\u00edrica llegue sin restricciones de estrato social. Habr\u00e1 entre los estudiantes, como se explica en el texto de la periodista Valeria Guzm\u00e1n, quienes sin drama pueden pagar hasta $75 al mes por las clases; y tambi\u00e9n quienes est\u00e1n obligados a hacer doble jornada laboral, no para pagar $10 al mes, sino para hacerle trampas al reloj y generar ingresos al mismo tiempo que se adquieren conocimientos.<\/p>\n<p>A la OPES le sobra gallard\u00eda. Es de valientes no rendirse ante el poco apoyo que recibe el arte en un pa\u00eds que, ir\u00f3nicamente, lo necesita tanto. Y a\u00fan as\u00ed, no se puede dejar de apuntar a que lo que deber\u00eda abundar en esta historia, que cuenta la periodista Valeria Guzm\u00e1n sobre \u00f3pera y talento, no es la valent\u00eda. Deber\u00edan abundar las sedes, los estudiantes, los profesores, los conciertos, los p\u00fablicos. La de este tipo de proyectos no puede seguir siendo una historia de angustias y de la existencia al borde los n\u00fameros rojos.<\/p>\n<p>Las revoluciones no se arman solo de protestas en la calle. Revoluci\u00f3n tambi\u00e9n es que una joven rompa con los estereotipos sociales y las limitaciones econ\u00f3micas para, con disciplina, educar la voz hasta convertirla en ese argumento que puede dejar en silencio a todo un teatro. Cuando alguien quiera ayudar a mejorar el pa\u00eds y se pregunt\u00e9 qu\u00e9 puede hacer, ad\u00f3nde puede colocar el dinero para que se convierta en desarrollo, transformarlo en m\u00fasica es una opci\u00f3n.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Es de valientes no rendirse ante el poco apoyo que recibe el arte en un pa\u00eds que, ir\u00f3nicamente, lo necesita tanto.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":3710,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-carta.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carta Editorial - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta Editorial - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Es de valientes no rendirse ante el poco apoyo que recibe el arte en un pa\u00eds que, ir\u00f3nicamente, lo necesita tanto.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-27T06:06:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-27T02:51:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/portada_7s_27mayo_2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"743\" \/>\n\t<meta property=\"og:image:height\" content=\"985\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Glenda Gir\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/portada_7s_27mayo_2018.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/portada_7s_27mayo_2018.jpg\",\"width\":743,\"height\":985},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/\",\"name\":\"Carta Editorial - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/#primaryimage\"},\"datePublished\":\"2018-05-27T06:06:10+00:00\",\"dateModified\":\"2018-05-27T02:51:32+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta Editorial\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\",\"name\":\"Glenda Gir\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"caption\":\"Glenda Gir\u00f3n\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta Editorial - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/","og_locale":"en_US","og_type":"article","og_title":"Carta Editorial - S\u00e9ptimo Sentido","og_description":"Es de valientes no rendirse ante el poco apoyo que recibe el arte en un pa\u00eds que, ir\u00f3nicamente, lo necesita tanto.","og_url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-05-27T06:06:10+00:00","article_modified_time":"2018-05-27T02:51:32+00:00","og_image":[{"width":743,"height":985,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/portada_7s_27mayo_2018.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"Glenda Gir\u00f3n","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/portada_7s_27mayo_2018.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/portada_7s_27mayo_2018.jpg","width":743,"height":985},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/","name":"Carta Editorial - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/#primaryimage"},"datePublished":"2018-05-27T06:06:10+00:00","dateModified":"2018-05-27T02:51:32+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-27-mayo-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Carta Editorial"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c","name":"Glenda Gir\u00f3n","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","caption":"Glenda Gir\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/portada_7s_27mayo_2018.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-XP","jetpack-related-posts":[{"id":5005,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-23-diciembre-2018\/","url_meta":{"origin":3709,"position":0},"title":"Carta Editorial","date":"23 December, 2018","format":false,"excerpt":"Con historias como las de ellos, los adultos nos asomamos al pa\u00eds que hemos construido: uno que secuestra infancias.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/12\/montaje231218portadita.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5797,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-02-junio-2019\/","url_meta":{"origin":3709,"position":1},"title":"Carta Editorial","date":"2 June, 2019","format":false,"excerpt":"Barrera es una figura desde donde se pueden hacer dos lecturas. Habla como exfuncionario de los gobiernos de Salvador S\u00e1nchez Cer\u00e9n y de Mauricio Funes, y tambi\u00e9n como creador.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/06\/Ssen0206219001.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5202,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-03-febrero-2019\/","url_meta":{"origin":3709,"position":2},"title":"Carta Editorial","date":"3 February, 2019","format":false,"excerpt":"Por estos lados, el gran problema de la literatura es que sigue buscando c\u00f3mo sobrevivir.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/02\/montaje2018portaditaca.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3258,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-01-abril-de-2018\/","url_meta":{"origin":3709,"position":3},"title":"Carta Editorial","date":"1 April, 2018","format":false,"excerpt":"En esta edici\u00f3n el periodista Mois\u00e9s Alvarado nos lleva a conocer las vueltas que ha dado Antonio Corrales para hoy erguirse como de los compositores salvadore\u00f1os m\u00e1s exitosos.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/04\/7s-portada-01-abril-2018.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4361,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-02-septiembre-2018\/","url_meta":{"origin":3709,"position":4},"title":"Carta Editorial","date":"2 September, 2018","format":false,"excerpt":"Aqu\u00ed hay talento, se\u00f1ala este ganador de un \u00d3scar. Eso, sin embargo, no basta si no hay, a la par, un proceso formativo.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/Septimo-Sentido_001.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8393,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-25-octubre-2020\/","url_meta":{"origin":3709,"position":5},"title":"Carta Editorial","date":"25 October, 2020","format":false,"excerpt":"[:es]Ella, su trabajo sin aspavientos, se han convertido en inspiraci\u00f3n y modelo a seguir.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/10\/montaje2018portaditaca-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3709"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=3709"}],"version-history":[{"count":2,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3709\/revisions"}],"predecessor-version":[{"id":3712,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3709\/revisions\/3712"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/3710"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=3709"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=3709"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=3709"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}