{"id":3654,"date":"2018-05-20T00:04:36","date_gmt":"2018-05-20T06:04:36","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=3654"},"modified":"2018-05-20T11:55:41","modified_gmt":"2018-05-20T17:55:41","slug":"buzon-9","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/","title":{"rendered":"Buz\u00f3n"},"content":{"rendered":"<figure id=\"attachment_3655\" style=\"width: 1537px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"3655\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/buzon-20-mayo-2018\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018.jpg\" data-orig-size=\"1537,933\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"buzon-20-mayo-2018\" data-image-description=\"&lt;p&gt;Buz\u00f3n&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Buz\u00f3n&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018-300x182.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018-1024x622.jpg\" loading=\"lazy\" class=\"size-full wp-image-3655\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018.jpg\" alt=\"\" width=\"1537\" height=\"933\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018.jpg 1537w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018-300x182.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018-768x466.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018-1024x622.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018-1200x728.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018-500x304.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018-1000x607.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018-700x425.jpg 700w\" sizes=\"(max-width: 1537px) 100vw, 1537px\" \/><figcaption class=\"wp-caption-text\">Buz\u00f3n<\/figcaption><\/figure>\n<h1>No crecemos<\/h1>\n<p>El domingo sacaron un buen art\u00edculo sobre la realidad de la comunidad rural. Debido a mi profesi\u00f3n y a que tengo ra\u00edces familiares que a\u00fan viven en la zona rural considero que no solo debe conocerse el problema, sino que tambi\u00e9n sus causas hist\u00f3ricas. Cuando se ha querido potenciar la organizaci\u00f3n de productores, los aprovechados de siempre enarbolan la bandera del mercado y bombardean las asociaciones de productores. Si los productores estuvieran organizados, tuvieran acceso a informaci\u00f3n de mercado y a mejores condiciones de financiamiento. En los pa\u00edses desarrollados todos los productores est\u00e1n organizados, por lo tanto, tienen capacidad de exigir. Han llegado a tecnificar el sector agropecuario y dar valor agregado a la producci\u00f3n. En el caso del ma\u00edz y frijol, parece raro pero es una realidad, a\u00fan se trabaja con t\u00e9cnicas ancestrales. Lo \u00fanico que ha cambiado es que nuestros ancestros utilizaban una vara con una punta de barro endurecida, y actualmente esa punta es de metal. No podemos crecer.<\/p>\n<p><strong>Manny Nagula,<\/strong><br \/>\nmjlaguna59@hotmail.com<\/p>\n<hr \/>\n<h1>Crisis agroalimentaria<\/h1>\n<p>La juventud se niega a seguir con la tradici\u00f3n de trabajar la tierra debido a la \u201cterritorializaci\u00f3n\u201d de los grupos il\u00edcitos, as\u00ed lo sugiere el reportaje de Mois\u00e9s Alvarado, \u201cEl campo se queda sin j\u00f3venes\u201d. La agricultura familiar contribuye en m\u00e1s del 70 % a la producci\u00f3n de alimentos, a pesar de que esa poblaci\u00f3n campesina es la que m\u00e1s de cerca enfrenta la inseguridad que se vive. Es parad\u00f3jico que los cultivadores de nuestros alimentos sean los m\u00e1s vulnerables. Vemos c\u00f3mo \u00faltimamente la producci\u00f3n de granos b\u00e1sicos ha bajado y no se tienen alternativas innovadoras como propuestas para los agricultores. El sistema actual de mercadeo de granos b\u00e1sicos no favorece al productor, ya que por necesidad vende en el momento de la cosecha cuando el precio est\u00e1 en su menor punto, y este solo se queda con el sudor sin ganancia para otros menesteres.<\/p>\n<p><strong>Julio Roberto Maga\u00f1a,<\/strong><br \/>\njrobertomasa@hotmail.com<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El domingo sacaron un buen art\u00edculo sobre la realidad de la comunidad rural. Debido a mi profesi\u00f3n y a que tengo ra\u00edces familiares que a\u00fan viven en la zona rural considero que no solo debe conocerse el problema&#8230;<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":3655,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-opinion.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Buz\u00f3n - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buz\u00f3n - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"El domingo sacaron un buen art\u00edculo sobre la realidad de la comunidad rural. Debido a mi profesi\u00f3n y a que tengo ra\u00edces familiares que a\u00fan viven en la zona rural considero que no solo debe conocerse el problema...\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-20T06:04:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-20T17:55:41+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1537\" \/>\n\t<meta property=\"og:image:height\" content=\"933\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9ptimo Sentido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018.jpg\",\"width\":1537,\"height\":933,\"caption\":\"Buz\u00f3n\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/\",\"name\":\"Buz\u00f3n - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/#primaryimage\"},\"datePublished\":\"2018-05-20T06:04:36+00:00\",\"dateModified\":\"2018-05-20T17:55:41+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buz\u00f3n\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\",\"name\":\"S\u00e9ptimo Sentido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"caption\":\"S\u00e9ptimo Sentido\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buz\u00f3n - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/","og_locale":"en_US","og_type":"article","og_title":"Buz\u00f3n - S\u00e9ptimo Sentido","og_description":"El domingo sacaron un buen art\u00edculo sobre la realidad de la comunidad rural. Debido a mi profesi\u00f3n y a que tengo ra\u00edces familiares que a\u00fan viven en la zona rural considero que no solo debe conocerse el problema...","og_url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-05-20T06:04:36+00:00","article_modified_time":"2018-05-20T17:55:41+00:00","og_image":[{"width":1537,"height":933,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"S\u00e9ptimo Sentido","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018.jpg","width":1537,"height":933,"caption":"Buz\u00f3n"},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/","name":"Buz\u00f3n - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/#primaryimage"},"datePublished":"2018-05-20T06:04:36+00:00","dateModified":"2018-05-20T17:55:41+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-9\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Buz\u00f3n"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b","name":"S\u00e9ptimo Sentido","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","caption":"S\u00e9ptimo Sentido"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon-20-mayo-2018.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-WW","jetpack-related-posts":[{"id":1106,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-13-agosto-2017\/","url_meta":{"origin":3654,"position":0},"title":"Buz\u00f3n","date":"13 August, 2017","format":false,"excerpt":"Innovaci\u00f3n La agricultura deber\u00eda ser una actividad prioridad desde la \u00f3ptica de cualquier Gobierno, pues de su impulso depende que todos tengamos la alimentaci\u00f3n a tiempo y con precios razonables; importar lo que se puede producir ac\u00e1 resulta inusitado para un pa\u00eds que aunque peque\u00f1o en territorio es explosivo en\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/08\/buzon.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4014,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-1-de-julio-2018\/","url_meta":{"origin":3654,"position":1},"title":"Buz\u00f3n","date":"1 July, 2018","format":false,"excerpt":"La opini\u00f3n de Sigfredo Ram\u00edrez y el seguir escuchando de hermanos salvadore\u00f1os que sufren por falta de agua me ha hecho reflexionar sobre la importancia de implementar en nuestro pa\u00eds el programa \u201cAgua para siempre\u201d.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/buzon.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1027,"url":"https:\/\/7s.laprensagrafica.com\/en\/una-canasta-la-desigualdad\/","url_meta":{"origin":3654,"position":2},"title":"Una canasta contra la desigualdad","date":"6 August, 2017","format":false,"excerpt":"La Canasta Campesina es un proyecto que transporta hortalizas org\u00e1nicas sembradas en Comasagua hacia San Salvador. Quienes producen estas frutas y verduras son mujeres agricultoras y hombres j\u00f3venes que han probado que s\u00ed es posible tener una vida digna trabajando la tierra. En este modelo de venta no hay intermediarios\u2026","rel":"","context":"In &quot;Reportaje Nacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/08\/principal-reportaje.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3401,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-abril-2018\/","url_meta":{"origin":3654,"position":3},"title":"Buz\u00f3n","date":"22 April, 2018","format":false,"excerpt":"Si de verdad los gobiernos que ha tenido este pa\u00eds hubieran querido sacar adelante un proyecto a largo plazo (\u201cAgua para todos\u201d) y evitar as\u00ed acercarnos a una crisis estructural severa, no estar\u00edamos en los afanes de protestar con c\u00e1ntaros y cumbos para que llegue el agua.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/04\/agua-izalco.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3475,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-abril-2018\/","url_meta":{"origin":3654,"position":4},"title":"Buz\u00f3n","date":"29 April, 2018","format":false,"excerpt":"Antes y despu\u00e9s La valent\u00eda de decir \u201cno m\u00e1s, he decidido hacer este cambio\u201d para enfatizar el giro radical en modos de pensar requiere de buena dosis de coraje. La ruptura de conductas, sufrimientos innecesarios y hasta de relaciones enfermizas es una decisi\u00f3n inteligente. Valeria Guzm\u00e1n, en su audiencia con\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/04\/buzon_29_abril_2018.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1953,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-05-nov-2017\/","url_meta":{"origin":3654,"position":5},"title":"Buz\u00f3n","date":"5 November, 2017","format":false,"excerpt":"Mis felicitaciones a Mois\u00e9s Alvarado por ese reportaje donde se refleja el esp\u00edritu de lucha de muchas mujeres salvadore\u00f1as rurales y de las que vivimos en el \u00e1rea urbana por sacar a nuestros hijos adelante siendo jefas de hogar.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"Buz\u00f3n","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/buzon-5-nov-2017.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3654"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=3654"}],"version-history":[{"count":1,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3654\/revisions"}],"predecessor-version":[{"id":3656,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3654\/revisions\/3656"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/3655"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=3654"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=3654"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=3654"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}