{"id":3606,"date":"2018-05-13T00:02:36","date_gmt":"2018-05-13T06:02:36","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=3606"},"modified":"2018-05-13T01:20:01","modified_gmt":"2018-05-13T07:20:01","slug":"aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/","title":{"rendered":"Aldana, la fiscal que apres\u00f3 a un presidente en Guatemala"},"content":{"rendered":"<figure id=\"attachment_3607\" style=\"width: 1920px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"3607\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/fsep13052018ap7453322ca\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca.jpg\" data-orig-size=\"1920,930\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep13052018Ap7453322ca\" data-image-description=\"&lt;p&gt;Fiscal Aldana&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Fiscal Aldana&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca-300x145.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca-1024x496.jpg\" loading=\"lazy\" class=\"size-full wp-image-3607\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca.jpg\" alt=\"\" width=\"1920\" height=\"930\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca.jpg 1920w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca-300x145.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca-768x372.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca-1024x496.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca-1900x920.jpg 1900w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca-1200x581.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca-500x242.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca-1000x484.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca-700x339.jpg 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-caption-text\">Fiscal Aldana<\/figcaption><\/figure>\n<p>Thelma Aldana no puede salir sola a la calle de su pa\u00eds y quiz\u00e1 nunca podr\u00e1 hacerlo de nuevo.<br \/>\nSer la fiscal general que envi\u00f3 a un presidente a la c\u00e1rcel y desarticul\u00f3 varias estructuras criminales en Guatemala le vali\u00f3 el reconocimiento internacional, pero eso tuvo un costo: su seguridad.<\/p>\n<p>Tan solo en 2016, el Ministerio de Gobernaci\u00f3n confirm\u00f3 que una estructura criminal hab\u00eda planeado y pagado un atentado contra ella, por lo que hoy cuenta con medidas de protecci\u00f3n de la Comisi\u00f3n Interamericana de Derechos Humanos (CIDH).<\/p>\n<p>La guatemalteca de 62 a\u00f1os dejar\u00e1 su cargo el pr\u00f3ximo 16 de mayo y ser\u00e1 reemplazada por Mar\u00eda Consuelo Porras, actual magistrada suplente de la Corte de Constitucionalidad y reci\u00e9n elegida por el presidente de entre seis candidatos.<\/p>\n<p>En los cuatro a\u00f1os que mantuvo el puesto, en colaboraci\u00f3n con la Comisi\u00f3n Contra la Impunidad en Guatemala (CICIG), Aldana encabez\u00f3 una lucha anticorrupci\u00f3n que alcanz\u00f3 a la agrupaci\u00f3n que habr\u00eda liderado el expresidente Otto P\u00e9rez Molina, acusado de defraudar al Estado por varios millones de d\u00f3lares y hoy preso junto con su entonces vicepresidenta, Roxana Baldetti, y otros funcionarios cercanos.<\/p>\n<p>P\u00e9rez Molina no era cualquier presidente: antes de ocupar el cargo fue general de uno de los ej\u00e9rcitos m\u00e1s temidos durante los a\u00f1os de la guerra civil de Guatemala (1960-1996), un hombre que quiz\u00e1 no imagin\u00f3 que su peor pesadilla no lo confrontar\u00eda en un campo de batalla, sino en una sala de justicia y llevar\u00eda el nombre de Thelma Aldana.<\/p>\n<p>Aldana es \u201cla Jefa\u201d. Sus colaboradores m\u00e1s cercanos la llaman as\u00ed por distintos motivos. Es puntual y, como toda buena abogada, lee todo lo que cae en sus manos. La expresi\u00f3n de su rostro es dura y no es f\u00e1cil descifrar lo que piensa al mirarla: cuando aparec\u00eda ante las c\u00e1maras de la prensa y pon\u00eda al descubierto una nueva red de corrupci\u00f3n en el pa\u00eds, manten\u00eda su temple y la mirada imp\u00e1vida.<\/p>\n<p>Parecer\u00eda que el \u00fanico que puede \u201cdominarla\u201d es Toby, su peque\u00f1o perro Shih Tzu de cinco a\u00f1os. Cuando habla de \u00e9l, la cara de Aldana s\u00ed se transforma. La fiscal sonr\u00ede cuando lo menciona y cuenta que, cuando necesita llevarse trabajo a casa, transporta sus archivos en una caja de cart\u00f3n en la que a Toby le gusta echarse. Y as\u00ed, con su mascota recostada sobre los documentos que podr\u00edan enviar a criminales y pol\u00edticos tras las rejas, una de las fiscales m\u00e1s renombradas de Am\u00e9rica Latina se sienta a leer.<\/p>\n<p>Su nombre no solo se ha impreso en los titulares de diarios regionales: en 2017, la revista Time la nombr\u00f3 como una de las 100 personas m\u00e1s influyentes del mundo junto a figuras como Neymar, Colin Kaepernick o Viola Davis.<\/p>\n<p>Para ella tampoco es poca cosa haber revisado m\u00e1s de 450 casos durante su gesti\u00f3n. \u201cLuchar contra la corrupci\u00f3n es un proceso y no es f\u00e1cil\u201d, dice.<\/p>\n<p>Solo en 2017 el organismo que lideraba obtuvo 9,358 sentencias condenatorias y aunque a\u00fan falta mucho por hacer, en 2014 la fiscal\u00eda ten\u00eda 1,280,378 expedientes por resolver, cifra que a la fecha se redujo m\u00e1s del 50 %.<\/p>\n<h1 style=\"text-align: center;\">***<\/h1>\n<p><strong>La ruta<\/strong><br \/>\nEl camino que sigui\u00f3 para convertirse en fiscal general fue largo. Inici\u00f3 en 1981 en uno de los puestos m\u00e1s bajos de la administraci\u00f3n de justicia como conserje de juzgado, y escal\u00f3 poco a poco hasta convertirse en presidenta de la Corte Suprema en 2011. Una vez como fiscal, quiz\u00e1 ni sus colaboradores m\u00e1s cercanos imaginaban lo que podr\u00eda alcanzar en el puesto. El mismo P\u00e9rez Molina, que fue a la c\u00e1rcel por ella, la eligi\u00f3 para el puesto en mayo de 2014 entre rumores de v\u00ednculos y cercan\u00eda, que en su momento \u00e9l neg\u00f3.<\/p>\n<p>Algunos guatemaltecos pensaban que al ser electa por el expresidente, las acusaciones por corrupci\u00f3n en su contra no se investigar\u00edan y que no habr\u00eda justicia, pero sucedi\u00f3 justo lo contrario. Ahora ella dice que eso le hace sentir muy orgullosa y asegura que nadie se acerc\u00f3 a ofrecerle sobornos.<\/p>\n<p>\u201cUna parte de la Biblia dice: por sus obras los conocer\u00e9is, y yo hice mi mejor esfuerzo\u201d, dijo la fiscal. \u201cCon toda humildad, me voy con la frente en alto\u201d, asegur\u00f3 al cuestion\u00e1rsele si alguna vez consider\u00f3 no tomar medidas contra el entonces presidente.<\/p>\n<p>Iv\u00e1n Vel\u00e1squez, el titular de la CICIG, cuenta que trabajar con ella tiene un balance positivo y que la considera una mujer fuerte y valiente. Y aunque la confianza entre ambos no surgi\u00f3 desde el primer momento, dice Vel\u00e1squez, el trabajo en com\u00fan le parece una experiencia satisfactoria que con todo y sus diferencias siempre lleg\u00f3 a consensos en armon\u00eda.<\/p>\n<p>El caso que afianz\u00f3 sus coincidencias fue justamente el de P\u00e9rez Molina. Seg\u00fan el abogado colombiano que desde 2013 lidera la CICIG, el caso contra el exmandatario fue \u201cde un momento muy cr\u00edtico\u201d, pero Aldana no dud\u00f3 en tomar las acciones pertinentes.<\/p>\n<p>Durante su gesti\u00f3n, Aldana ha sido v\u00edctima de amenazas, persecuciones y difamaciones. Aunque pod\u00eda, decidi\u00f3 no volver a postularse como fiscal para evitar m\u00e1s riesgos, y est\u00e1 convencida de que el actual presidente, Jimmy Morales \u2013se\u00f1alado por la fiscal\u00eda y la CICIG por hechos de corrupci\u00f3n\u2013, nunca la hubiera elegido para volver a ocupar el cargo.<\/p>\n<p>Al hacer un balance de su trabajo, la fiscal califica estos \u00faltimos cuatro a\u00f1os como los m\u00e1s dif\u00edciles de los 37 que ha dedicado al sistema de justicia de su pa\u00eds, e incluye su paso como expresidenta de la Corte Suprema de Justicia.<br \/>\nUno de los momentos m\u00e1s duros de su gesti\u00f3n, dice Aldana, lleg\u00f3 el d\u00eda en que el presidente Morales \u2013a qui\u00e9n ella y Vel\u00e1squez intentaron investigar por financiamiento electoral il\u00edcito\u2013 intent\u00f3 expulsar al comisionado del pa\u00eds. \u201cHasta anunci\u00e9 que si se iba, yo renunciaba\u201d, dijo.<\/p>\n<p>La fiscal, adem\u00e1s, recuerda con tristeza cuando se enter\u00f3 de la muerte de 41 ni\u00f1as en un hogar de acogida estatal el 8 de marzo de 2017, cuando estas intentaron fugarse y al no conseguirlo incendiaron la habitaci\u00f3n donde las hab\u00edan encerrado bajo llave. El fuego tambi\u00e9n dej\u00f3 quemadas gravemente a otras 15 menores. Los fiscales bajo su mando lograron que 10 exfuncionarios fueran detenidos por el caso.<\/p>\n<p>Casi al t\u00e9rmino de su gesti\u00f3n, \u201cla Jefa\u201d confes\u00f3 tener una deuda con su familia, pues al dejar el cargo deber\u00e1 tratar de recuperar el tiempo que perdi\u00f3 con sus dos hijos, de 21 y 24 a\u00f1os.<br \/>\nAldana asegura que el costo personal de haber sido fiscal general ha sido grande, ya que para cuidar su seguridad, tuvo que dejar de hacer cosas cotidianas.<\/p>\n<p>\u201cNo voy pr\u00e1cticamente a lugares p\u00fablicos y no puedo caminar en las calles. Siempre tengo que estar con un aparato de seguridad; mi estilo de vida cambi\u00f3 bastante\u201d, dice, y a\u00f1ade que una de sus preocupaciones ahora que finaliza su gesti\u00f3n es garantizar su seguridad y la de su familia. \u201cEntonces, ser\u00e1 responsabilidad del Estado guatemalteco la vida m\u00eda, protegerla, y la de mi familia\u201d, sentencia.<\/p>\n<p>De cara a esta situaci\u00f3n, Guatemala deber\u00e1 acatar la orden de la Comisi\u00f3n Interamericana de Derechos Humanos, que orden\u00f3 medidas cautelares de protecci\u00f3n para Aldana y sus familiares. \u201cS\u00e9 que hemos investigado estructuras criminales poderosas y, en consecuencia, debo conducirme con mucha cautela\u201d, explica.<\/p>\n<p>En el futuro cercano, \u201cla Jefa\u201d quisiera pasar sus d\u00edas en un aula frente a estudiantes. Dice que le apuesta a la docencia porque con la experiencia de haber llevado a prisi\u00f3n a m\u00e1s de 100 estructuras vinculadas al crimen y la corrupci\u00f3n en el pa\u00eds, sus ense\u00f1anzas ser\u00e1n de utilidad para los j\u00f3venes.<\/p>\n<h4>La fiscal sonr\u00ede cuando lo menciona y cuenta que, cuando necesita llevarse trabajo a casa, transporta sus archivos en una caja de cart\u00f3n en la que a Toby le gusta echarse. Y as\u00ed, con su mascota recostada sobre los documentos que podr\u00edan enviar a criminales y pol\u00edticos tras las rejas, una de las fiscales m\u00e1s renombradas de Am\u00e9rica Latina se sienta a leer.<\/h4>\n<p>Aldana no saldr\u00e1 de su oficina con las manos vac\u00edas. Entre los documentos que seguramente conservar\u00e1 hay decenas de premios y reconocimientos que le han entregado por su trabajo; entre ellos, el de Mujeres Valientes del Departamento de Estado, el Premio Internacional de Catar Excelencia Anticorrupci\u00f3n \u2013ambos otorgados en 2016\u2013 y la vara de autoridad que le fue entregada por l\u00edderes ind\u00edgenas guatemaltecos, uno de sus favoritos.<\/p>\n<p>Al preguntarle c\u00f3mo le gustar\u00eda que la recuerden, Aldana muestra su orgullo por los esfuerzos que encabez\u00f3 para mejorar la atenci\u00f3n a nivel nacional de los casos de violencia hacia la mujer y dice que espera haber dejado en la mente de los guatemaltecos que la independencia de la fiscal\u00eda general s\u00ed es posible. \u201cEs un bien preciado\u201d, asegura.<\/p>\n<p>Los d\u00edas que vendr\u00e1n ser\u00e1n menos complicados. Tras su salida de la fiscal\u00eda, que coincide con el inicio de la copa del mundo en Rusia, \u201cla Jefa\u201d tratar\u00e1 de disfrutar momentos m\u00e1s mundanos: ver el mundial completo en televisi\u00f3n y en tiempo real.<\/p>\n<p>\u201cSiempre he tenido que verlo en la noche, en diferido, pero ahora tengo el deseo de verlo en directo, y luego ver\u00e9 qu\u00e9 hago con mi vida profesional\u201d, dice.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Pocos creyeron en ella en un principio. Su cercan\u00eda con el presidente Otto P\u00e9rez Molina hac\u00eda pensar en que no llevar\u00eda adelante las investigaciones en contra de \u00e9l. Pero, como ella misma destaca, hablaron las acciones. P\u00e9rez Molina acab\u00f3 tras las rejas y Aldana dejar\u00e1 su cargo el pr\u00f3ximo mi\u00e9rcoles entre elogios por su compromiso con la justicia.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":3607,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Aldana, la fiscal que apres\u00f3 a un presidente en Guatemala - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Aldana, la fiscal que apres\u00f3 a un presidente en Guatemala - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Pocos creyeron en ella en un principio. Su cercan\u00eda con el presidente Otto P\u00e9rez Molina hac\u00eda pensar en que no llevar\u00eda adelante las investigaciones en contra de \u00e9l. Pero, como ella misma destaca, hablaron las acciones. P\u00e9rez Molina acab\u00f3 tras las rejas y Aldana dejar\u00e1 su cargo el pr\u00f3ximo mi\u00e9rcoles entre elogios por su compromiso con la justicia.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-13T06:02:36+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-13T07:20:01+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"930\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7s\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"8 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca.jpg\",\"width\":1920,\"height\":930,\"caption\":\"Fiscal Aldana\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/\",\"name\":\"Aldana, la fiscal que apres\u00f3 a un presidente en Guatemala - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/#primaryimage\"},\"datePublished\":\"2018-05-13T06:02:36+00:00\",\"dateModified\":\"2018-05-13T07:20:01+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/3475da6220c51c41480f337ee3a7dc6e\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Aldana, la fiscal que apres\u00f3 a un presidente en Guatemala\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/3475da6220c51c41480f337ee3a7dc6e\",\"name\":\"AP\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b8ba35da68ef10334c608dccc6dc9118?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b8ba35da68ef10334c608dccc6dc9118?s=96&d=mm&r=g\",\"caption\":\"AP\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7s\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ap\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Aldana, la fiscal que apres\u00f3 a un presidente en Guatemala - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/","og_locale":"en_US","og_type":"article","og_title":"Aldana, la fiscal que apres\u00f3 a un presidente en Guatemala - S\u00e9ptimo Sentido","og_description":"Pocos creyeron en ella en un principio. Su cercan\u00eda con el presidente Otto P\u00e9rez Molina hac\u00eda pensar en que no llevar\u00eda adelante las investigaciones en contra de \u00e9l. Pero, como ella misma destaca, hablaron las acciones. P\u00e9rez Molina acab\u00f3 tras las rejas y Aldana dejar\u00e1 su cargo el pr\u00f3ximo mi\u00e9rcoles entre elogios por su compromiso con la justicia.","og_url":"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-05-13T06:02:36+00:00","article_modified_time":"2018-05-13T07:20:01+00:00","og_image":[{"width":1920,"height":930,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7s","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"AP","Est. reading time":"8 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca.jpg","width":1920,"height":930,"caption":"Fiscal Aldana"},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/","name":"Aldana, la fiscal que apres\u00f3 a un presidente en Guatemala - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/#primaryimage"},"datePublished":"2018-05-13T06:02:36+00:00","dateModified":"2018-05-13T07:20:01+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/3475da6220c51c41480f337ee3a7dc6e"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/en\/aldana-la-fiscal-que-apreso-a-un-presidente-en-guatemala\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Aldana, la fiscal que apres\u00f3 a un presidente en Guatemala"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/3475da6220c51c41480f337ee3a7dc6e","name":"AP","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/b8ba35da68ef10334c608dccc6dc9118?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b8ba35da68ef10334c608dccc6dc9118?s=96&d=mm&r=g","caption":"AP"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7s"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ap\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018Ap7453322ca.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-Wa","jetpack-related-posts":[{"id":3294,"url":"https:\/\/7s.laprensagrafica.com\/en\/el-voto-dorado-de-las-universidades-de-carton-para-elegir-fiscal-general\/","url_meta":{"origin":3606,"position":0},"title":"El voto dorado de las universidades de cart\u00f3n  para elegir fiscal general","date":"8 April, 2018","format":false,"excerpt":"El pr\u00f3ximo lunes 16 de abril es la fecha se\u00f1alada para que el presidente de Guatemala, Jimmy Morales, anuncie a la persona que relevar\u00e1 de su cargo a la fiscal general Thelma Aldana. El primer filtro de este proceso es la comisi\u00f3n de postulaci\u00f3n integrada por los decanos de 12\u2026","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/04\/fsep07042018xxdavincie20.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3321,"url":"https:\/\/7s.laprensagrafica.com\/en\/comodin-morales-arzu-el-cang\/","url_meta":{"origin":3606,"position":1},"title":"Comod\u00edn Morales-Arz\u00fa: El CANG","date":"8 April, 2018","format":false,"excerpt":"Tener el control del Ministerio P\u00fablico (MP) de Guatemala significa controlar la investigaci\u00f3n criminal, lo que no es poco en un pa\u00eds en el que cinco de los \u00faltimos siete presidentes han sido procesados o investigados por delitos de corrupci\u00f3n. Dos de ellos est\u00e1n en prisi\u00f3n.","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/04\/fsep08042018xxjimm21.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7378,"url":"https:\/\/7s.laprensagrafica.com\/en\/narcos-centroamerica-i\/","url_meta":{"origin":3606,"position":2},"title":"Narcos Centroam\u00e9rica (I)","date":"8 March, 2020","format":false,"excerpt":"[:es]En corto: seg\u00fan la fiscal\u00eda neoyorquina, el presidente de Honduras brind\u00f3 protecci\u00f3n a un narco que ten\u00eda un laboratorio donde se produc\u00edan entre 300 y 500 kilogramos de coca\u00edna al mes.[:]","rel":"","context":"In &quot;Opini\u00f3n desde all\u00e1&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/hector-silva-avalos.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7395,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-15-marzo-2020\/","url_meta":{"origin":3606,"position":3},"title":"Carta Editorial","date":"15 March, 2020","format":false,"excerpt":"[:es]Mantener en n\u00fameros rojos a la PGR, tambi\u00e9n significa colocar como inaccesible la justicia en este pa\u00eds.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/03\/montaje2018portaditaca-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4974,"url":"https:\/\/7s.laprensagrafica.com\/en\/la-declaratoria-de-persona-non-grata-nos-tomo-de-sorpresa\/","url_meta":{"origin":3606,"position":4},"title":"&#8220;La declaratoria de persona non grata nos tom\u00f3 de sorpresa&#8221;","date":"16 December, 2018","format":false,"excerpt":"Hace un a\u00f1o el presidente guatemalteco, Jimmy Morales, declar\u00f3 \"non grato\" a Iv\u00e1n Vel\u00e1squez, el titular de la Comisi\u00f3n Internacional Contra la Impunidad en Guatemala (CICIG). Ahora, a pesar de que el comisionado a\u00fan permanece en el cargo, tiene prohibida la entrada a ese pa\u00eds. En la primera semana de\u2026","rel":"","context":"In &quot;Reportaje Nacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/12\/fsep16122018cecarl503.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2623,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-14-enero-2018\/","url_meta":{"origin":3606,"position":5},"title":"Buz\u00f3n","date":"14 January, 2018","format":false,"excerpt":"La Ley de Extinci\u00f3n de Dominio es una herramienta que desde 2013 sirve para la incautaci\u00f3n o confiscaci\u00f3n de bienes de origen il\u00edcito.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon_20180114.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3606"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=3606"}],"version-history":[{"count":3,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3606\/revisions"}],"predecessor-version":[{"id":3610,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3606\/revisions\/3610"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/3607"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=3606"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=3606"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=3606"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}