{"id":3591,"date":"2018-05-13T00:05:10","date_gmt":"2018-05-13T06:05:10","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=3591"},"modified":"2018-05-12T22:21:15","modified_gmt":"2018-05-13T04:21:15","slug":"lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/","title":{"rendered":"\u201cLo que m\u00e1s falta le hace a El Salvador es la transparencia\u201d"},"content":{"rendered":"<h4>\u00bfCu\u00e1l es el mejor recuerdo de su infancia?<\/h4>\n<p>El aire puro, los \u00e1rboles que me rodeaban, pues vengo de una zona rural de Chalchuapa, en Santa Ana. De ah\u00ed naci\u00f3 mi fascinaci\u00f3n y respeto por la naturaleza.<\/p>\n<h4>\u00bfQu\u00e9 le gustar\u00eda heredar a los futuros periodistas?<\/h4>\n<p>Una instituci\u00f3n en la que puedan creer, porque est\u00e1 integrada por ellos mismos.<\/p>\n<h4>\u00bfAd\u00f3nde va cuando quiere paz?<\/h4>\n<p>Busco la voz de mis hijas.<\/p>\n<h4>\u00bfHa existido alg\u00fan hecho que la haya hecho pensar en hacer justicia con sus propia manos?<\/h4>\n<p>S\u00ed. Vi a un hombre golpear a su mujer.<\/p>\n<h4>\u00bfQu\u00e9 opina de la burocracia?<\/h4>\n<p>Que la disfrutar\u00eda m\u00e1s si se utilizara realmente para ordenar procesos. Pero no suelo disfrutarla porque se usa m\u00e1s como una forma elegante en la que algunas instituciones p\u00fablicas nos quieren dificultar o bloquear los procesos.<\/p>\n<h4>\u00bfQu\u00e9 la saca de sus casillas?<\/h4>\n<p>El maltrato a la ni\u00f1ez.<\/p>\n<h4>\u00bfQu\u00e9 es lo que m\u00e1s falta le hace a El Salvador?<\/h4>\n<p>Transparencia.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Dalila Arriaza es la actual presidenta de la Asociaci\u00f3n de Periodistas de El Salvador (APES). Con casi 20 a\u00f1os de experiencia, ha pasado por casi todas las ramas del periodismo. Ha sido directora de radios, productora, fot\u00f3grafa. Actualmente tambi\u00e9n coordina un proyecto de capacitaci\u00f3n de acceso a la informaci\u00f3n p\u00fablica.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":3592,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-preguntas.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[6],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>\u201cLo que m\u00e1s falta le hace a El Salvador es la transparencia\u201d - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"\u201cLo que m\u00e1s falta le hace a El Salvador es la transparencia\u201d - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Dalila Arriaza es la actual presidenta de la Asociaci\u00f3n de Periodistas de El Salvador (APES). Con casi 20 a\u00f1os de experiencia, ha pasado por casi todas las ramas del periodismo. Ha sido directora de radios, productora, fot\u00f3grafa. Actualmente tambi\u00e9n coordina un proyecto de capacitaci\u00f3n de acceso a la informaci\u00f3n p\u00fablica.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-13T06:05:10+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-13T04:21:15+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018xxarr34ca.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1000\" \/>\n\t<meta property=\"og:image:height\" content=\"562\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9ptimo Sentido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018xxarr34ca.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018xxarr34ca.jpg\",\"width\":1000,\"height\":562},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/\",\"name\":\"\u201cLo que m\u00e1s falta le hace a El Salvador es la transparencia\u201d - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/#primaryimage\"},\"datePublished\":\"2018-05-13T06:05:10+00:00\",\"dateModified\":\"2018-05-13T04:21:15+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"\u201cLo que m\u00e1s falta le hace a El Salvador es la transparencia\u201d\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\",\"name\":\"S\u00e9ptimo Sentido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"caption\":\"S\u00e9ptimo Sentido\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\u201cLo que m\u00e1s falta le hace a El Salvador es la transparencia\u201d - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/","og_locale":"en_US","og_type":"article","og_title":"\u201cLo que m\u00e1s falta le hace a El Salvador es la transparencia\u201d - S\u00e9ptimo Sentido","og_description":"Dalila Arriaza es la actual presidenta de la Asociaci\u00f3n de Periodistas de El Salvador (APES). Con casi 20 a\u00f1os de experiencia, ha pasado por casi todas las ramas del periodismo. Ha sido directora de radios, productora, fot\u00f3grafa. Actualmente tambi\u00e9n coordina un proyecto de capacitaci\u00f3n de acceso a la informaci\u00f3n p\u00fablica.","og_url":"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-05-13T06:05:10+00:00","article_modified_time":"2018-05-13T04:21:15+00:00","og_image":[{"width":1000,"height":562,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018xxarr34ca.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"S\u00e9ptimo Sentido","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018xxarr34ca.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018xxarr34ca.jpg","width":1000,"height":562},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/","name":"\u201cLo que m\u00e1s falta le hace a El Salvador es la transparencia\u201d - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/#primaryimage"},"datePublished":"2018-05-13T06:05:10+00:00","dateModified":"2018-05-13T04:21:15+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/en\/lo-que-mas-falta-le-hace-a-el-salvador-es-la-transparencia\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"\u201cLo que m\u00e1s falta le hace a El Salvador es la transparencia\u201d"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b","name":"S\u00e9ptimo Sentido","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","caption":"S\u00e9ptimo Sentido"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/fsep13052018xxarr34ca.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-VV","jetpack-related-posts":[{"id":6852,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-15-diciembre-2019\/","url_meta":{"origin":3591,"position":0},"title":"Carta Editorial","date":"15 December, 2019","format":false,"excerpt":"La m\u00e1s reciente intervenci\u00f3n de Melgar est\u00e1 en la Universidad Centroamericana Jos\u00e9 Sime\u00f3n Ca\u00f1as (UCA).","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/12\/montaje2018portaditaca-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8111,"url":"https:\/\/7s.laprensagrafica.com\/en\/tenemos-que-asumirnos-como-una-region-desaparecida-del-mapa-cultural\/","url_meta":{"origin":3591,"position":1},"title":"Tenemos que asumirnos como una regi\u00f3n desaparecida del mapa cultural","date":"16 August, 2020","format":false,"excerpt":"[:es]Jorgelina Cerritos es una dramaturga y actriz salvadore\u00f1a consagrada. En 2010, gan\u00f3 el Premio Literario Casa de las Am\u00e9ricas, en la rama de teatro, con el que su trabajo trascendi\u00f3 las fronteras centroamericanas, una regi\u00f3n que, dice, es ajena o desconocida en el continente, en el mundo, pero desde la\u2026","rel":"","context":"In &quot;Reportaje Nacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/08\/fsep16082020corjorgelina05e.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9620,"url":"https:\/\/7s.laprensagrafica.com\/en\/tratan-a-una-mujer-peor-que-a-un-hombre-que-quizas-ha-hecho-otras-cosas\/","url_meta":{"origin":3591,"position":2},"title":"&#8220;Tratan a una mujer peor que a un hombre que, quiz\u00e1s, ha hecho otras cosas&#8221;","date":"11 July, 2021","format":false,"excerpt":"[:es]A Sara Rogel la sentenciaron a 30 a\u00f1os de c\u00e1rcel acusada por homicidio agravado. Esto sucedi\u00f3 despu\u00e9s de que buscara atenci\u00f3n m\u00e9dica luego de una ca\u00edda que le provoc\u00f3 la p\u00e9rdida de su beb\u00e9. Ocho a\u00f1os despu\u00e9s, obtuvo la libertad condicional. Rogel pas\u00f3, como muchas otras mujeres salvadore\u00f1as, por un\u2026","rel":"","context":"In &quot;Entrevista&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2021\/07\/fnac10072021mhsar05.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6115,"url":"https:\/\/7s.laprensagrafica.com\/en\/un-sector-del-poder-economico-bloquea-la-paz-en-colombia\/","url_meta":{"origin":3591,"position":3},"title":"Un sector del poder econ\u00f3mico bloquea la paz en Colombia","date":"4 August, 2019","format":false,"excerpt":"El l\u00edder de las FARC, Rodrigo Londo\u00f1o, conocido en su \u00e9poca de combatiente como \"Timochenko\", considera que un sector del poder econ\u00f3mico en Colombia bloquea la paz a la que \u00e9l condujo a la guerrilla, ahora un partido pol\u00edtico con las mismas siglas.","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/08\/fsep04082019xxlondono01.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":9273,"url":"https:\/\/7s.laprensagrafica.com\/en\/no-vamos-a-revivir-a-manuela-con-una-sentencia-de-la-cidh-pero-vamos-a-llevarle-verdad-a-su-familia\/","url_meta":{"origin":3591,"position":4},"title":"\u201cNo vamos a revivir a Manuela con una sentencia de la CIDH, pero vamos a llevarle verdad a su familia\u201d","date":"10 April, 2021","format":false,"excerpt":"[:es]Para Ang\u00e9lica Rivas, una de las abogadas defensoras del caso de Manuela, la diferencia entre una condena por aborto y una por homicidio en El Salvador se respalda en vac\u00edos en proceso legal y en el C\u00f3digo Penal.[:]","rel":"","context":"In &quot;Entrevista&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2021\/04\/fnac10042021cormujer3432713.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4672,"url":"https:\/\/7s.laprensagrafica.com\/en\/la-esquina-reencuentro-y-reconciliacion\/","url_meta":{"origin":3591,"position":5},"title":"La esquina: reencuentro y reconciliaci\u00f3n","date":"28 October, 2018","format":false,"excerpt":"No escucho a los candidatos de esta campa\u00f1a hablar de dos grandes hechos que nos han marcado como naci\u00f3n: la migraci\u00f3n y la violencia. No encuentro sus ideas sobre dos pol\u00edticas de Estado que necesita urgentemente un pa\u00eds desangrado y en di\u00e1spora: pol\u00edticas de reconciliaci\u00f3n y pol\u00edticas de reencuentro.","rel":"","context":"In &quot;Opini\u00f3n desde ac\u00e1&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/12\/marlonhernandezanzora.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3591"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=3591"}],"version-history":[{"count":1,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3591\/revisions"}],"predecessor-version":[{"id":3593,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3591\/revisions\/3593"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/3592"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=3591"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=3591"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=3591"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}