{"id":3588,"date":"2018-05-13T00:06:30","date_gmt":"2018-05-13T06:06:30","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=3588"},"modified":"2018-05-12T21:48:56","modified_gmt":"2018-05-13T03:48:56","slug":"carta-editorial-13-mayo-2018","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-13-mayo-2018\/","title":{"rendered":"Carta Editorial"},"content":{"rendered":"<p>El campo se nos muere. Y no es una exageraci\u00f3n. La edad promedio de las personas que trabajan la tierra en El Salvador ronda los 60 a\u00f1os. Este es un dato que revela una gran cantidad de injusticias, entre las m\u00e1s graves est\u00e1 que el campo lo trabajan personas que ya deber\u00edan estar disfrutando de la jubilaci\u00f3n. Y este acceso a una pensi\u00f3n digna despu\u00e9s de una vida entera de trabajo duro sigue siendo una deuda que el pa\u00eds mantiene con quienes juegan un papel fundamental.<\/p>\n<p>Los servicios a los que tiene acceso el agricultor cerca de su lugar de trabajo no son los mejores. All\u00e1, en donde se podr\u00eda garantizar la seguridad alimentaria y reducir la desigualdad, la gente tiene las escuelas m\u00e1s desprovistas, los servicios de salud m\u00e1s precarios y es en donde los indicadores de acceso a agua potable bajan de forma considerable.<\/p>\n<p>No es raro que uno de los problemas m\u00e1s graves de la agricultura salvadore\u00f1a sea la falta de tecnolog\u00eda y actualizaci\u00f3n. En general, los procesos se siguen ejecutando como hace d\u00e9cadas, lo que compromete la productividad y hace de esta una actividad demasiado sacrificada en comparaci\u00f3n con los resultados. Para los j\u00f3venes que proceden de familias dedicadas a trabajar la tierra, la migraci\u00f3n se convierte en una opci\u00f3n mucho m\u00e1s atractiva. El campo se pone viejo.<\/p>\n<p>El texto que el periodista Mois\u00e9s Alvarado ha escrito para esta edici\u00f3n desnuda una preocupaci\u00f3n que no se conjuga en futuro, sino que en presente. Lejos de mejorar las condiciones para que la agricultura sea una opci\u00f3n para aprovechar las tierras, para generar ingresos, para reducir el desempleo, para generar arraigo, para garantizar alimentos, para reducir la concentraci\u00f3n prejudicial en las ciudades y para evitar elevados gastos en transporte, se le est\u00e1 dejando a su suerte en una a\u00f1eja agon\u00eda con la que perdemos todos.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Para los j\u00f3venes que proceden de familias dedicadas a trabajar la tierra, la migraci\u00f3n se convierte en una opci\u00f3n mucho m\u00e1s atractiva.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":3589,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-carta.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carta Editorial - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta Editorial - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Para los j\u00f3venes que proceden de familias dedicadas a trabajar la tierra, la migraci\u00f3n se convierte en una opci\u00f3n mucho m\u00e1s atractiva.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-05-13T06:06:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-05-13T03:48:56+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/Septimo-Sentido_001.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"740\" \/>\n\t<meta property=\"og:image:height\" content=\"937\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Glenda Gir\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/Septimo-Sentido_001.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/Septimo-Sentido_001.jpg\",\"width\":740,\"height\":937},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/\",\"name\":\"Carta Editorial - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/#primaryimage\"},\"datePublished\":\"2018-05-13T06:06:30+00:00\",\"dateModified\":\"2018-05-13T03:48:56+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta Editorial\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\",\"name\":\"Glenda Gir\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"caption\":\"Glenda Gir\u00f3n\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta Editorial - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/","og_locale":"en_US","og_type":"article","og_title":"Carta Editorial - S\u00e9ptimo Sentido","og_description":"Para los j\u00f3venes que proceden de familias dedicadas a trabajar la tierra, la migraci\u00f3n se convierte en una opci\u00f3n mucho m\u00e1s atractiva.","og_url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-05-13T06:06:30+00:00","article_modified_time":"2018-05-13T03:48:56+00:00","og_image":[{"width":740,"height":937,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/Septimo-Sentido_001.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"Glenda Gir\u00f3n","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/Septimo-Sentido_001.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/Septimo-Sentido_001.jpg","width":740,"height":937},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/","name":"Carta Editorial - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/#primaryimage"},"datePublished":"2018-05-13T06:06:30+00:00","dateModified":"2018-05-13T03:48:56+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-13-mayo-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Carta Editorial"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c","name":"Glenda Gir\u00f3n","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","caption":"Glenda Gir\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/Septimo-Sentido_001.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-VS","jetpack-related-posts":[{"id":7395,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-15-marzo-2020\/","url_meta":{"origin":3588,"position":0},"title":"Carta Editorial","date":"15 March, 2020","format":false,"excerpt":"[:es]Mantener en n\u00fameros rojos a la PGR, tambi\u00e9n significa colocar como inaccesible la justicia en este pa\u00eds.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/03\/montaje2018portaditaca-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3373,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-15-abril-2018\/","url_meta":{"origin":3588,"position":1},"title":"Carta editorial","date":"15 April, 2018","format":false,"excerpt":"Que ahora el agua fluya por las tuber\u00edas deber\u00eda ser un ep\u00edlogo feliz; pero esto es El Salvador. Y ac\u00e1, el acceso a los derechos b\u00e1sicos est\u00e1 atravesado por las violencias.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/04\/Ssen_001.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7198,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-02-febrero-2020\/","url_meta":{"origin":3588,"position":2},"title":"Carta Editorial","date":"2 February, 2020","format":false,"excerpt":"[:es]En los 21 mil kil\u00f3metros que forman El Salvador, hay zonas a las que el sistema p\u00fablico de salud no se ha podido instalar.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/02\/montaje2018portaditaca.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7740,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-17-mayo-2020\/","url_meta":{"origin":3588,"position":3},"title":"Carta Editorial","date":"17 May, 2020","format":false,"excerpt":"[:es]A lo largo de nuestra historia como pa\u00eds, el silencio se ha convertido en una infecci\u00f3n que ha mantenido las heridas abiertas.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/05\/montaje2018portaditaca-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5726,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-19-mayo-2019\/","url_meta":{"origin":3588,"position":4},"title":"Carta Editorial","date":"19 May, 2019","format":false,"excerpt":"Como si se tratara de algo accesorio, el acceso a servicios de salud mental se ha dejado tradicionalmente fuera de las prioridades.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/05\/montaje2018portaditaca-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":8542,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-29-noviembre-2020\/","url_meta":{"origin":3588,"position":5},"title":"Carta Editorial","date":"29 November, 2020","format":false,"excerpt":"[:es]Hemos escuchado a cinco mujeres cuyo trabajo en la comunidad es insustituible: Lucy Luna, de ASAPROSAR; Ana Castillo, de Soleterre; Carmen Garc\u00eda, docente; Kara Garc\u00eda, de Proyecto Red y ahora es el turno de Laura Ar\u00e9valo, de Fundaci\u00f3n Contin\u00faa.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/11\/montaje2018portaditaca-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3588"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=3588"}],"version-history":[{"count":1,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3588\/revisions"}],"predecessor-version":[{"id":3590,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3588\/revisions\/3590"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/3589"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=3588"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=3588"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=3588"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}