{"id":3168,"date":"2018-03-25T00:04:31","date_gmt":"2018-03-25T06:04:31","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=3168"},"modified":"2018-03-25T23:37:13","modified_gmt":"2018-03-26T05:37:13","slug":"buzon-25-marzo-2018","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/","title":{"rendered":"Buz\u00f3n"},"content":{"rendered":"<figure id=\"attachment_3189\" style=\"width: 1474px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"3189\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/septimo-sentido-general-18_03_2018-18\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18.jpg\" data-orig-size=\"1474,935\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Septimo Sentido General 18_03_2018 18\" data-image-description=\"&lt;p&gt;Buz\u00f3n&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Buz\u00f3n&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18-300x190.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18-1024x650.jpg\" loading=\"lazy\" class=\"size-full wp-image-3189\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18.jpg\" alt=\"\" width=\"1474\" height=\"935\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18.jpg 1474w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18-300x190.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18-768x487.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18-1024x650.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18-1200x761.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18-500x317.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18-1000x634.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18-700x444.jpg 700w\" sizes=\"(max-width: 1474px) 100vw, 1474px\" \/><figcaption class=\"wp-caption-text\">Buz\u00f3n<\/figcaption><\/figure>\n<h1>Rumores hacia las vacunas<\/h1>\n<p>Fue muy interesante el art\u00edculo de la AP en 7S sobre la desconfianza que los brasile\u00f1os tienen hacia las vacunas contra la fiebre amarilla. Estos rumores se han dado desde hace mucho tiempo hacia estas campa\u00f1as que buscan evitar enfermedades end\u00e9micas. Y esta desconfianza hacia las vacunas tiene razones hist\u00f3ricas, como lo que ocurri\u00f3 en Guatemala entre 1946 y 1948, cuando 1,500 guatemaltecos, sin ellos saberlo, fueron inoculados con s\u00edfilis, gonorrea y otras enfermedades de transmisi\u00f3n sexual, como parte de experimentos m\u00e9dicos patrocinados por Estados Unidos. Al respecto, en 2010, el presidente Obama expres\u00f3 telef\u00f3nicamente sus disculpas al presidente guatemalteco, a quien le dijo que \u201ces algo chocante y condenable. Es tr\u00e1gico y Estados Unidos, desde luego, se disculpa ante todos aquellos afectados por esto\u201d. Cient\u00edficos de la \u00e9poca reclamaron que negros, latinos, indios, asi\u00e1ticos, mulatos, mestizos se convierten en instrumentos de laboratorios, dirigidos y financiados por instituciones m\u00e9dicas de pa\u00edses poderosos econ\u00f3micamente. Durante el nazismo muchos m\u00e9dicos y cient\u00edficos estuvieron involucrados en experimentos llevados a cabo utilizando seres humanos para sus investigaciones. Adem\u00e1s de vacunas, los nazis investigaron, por ejemplo, cu\u00e1nto tiempo tardaba un cuerpo en congelarse hasta la muerte. Para ello, a las v\u00edctimas se les colocaba en una tina con agua helada, desnudos, y a la intemperie a temperaturas menores de cero grados cent\u00edgrados. Mor\u00edan inevitablemente. Un cient\u00edfico nazi inyect\u00f3 a un grupo de prisioneros la bacteria que causa la tuberculosis, con el objeto de encontrar un ant\u00eddoto para la enfermedad. En muchos casos se mutilaba a un preso para trasplantar sus extremidades a otro. La idea era saber si se pod\u00eda trasplantar extremidades, pero se hizo de forma tan cruel que muchas personas murieron o quedaron inv\u00e1lidas.<br \/>\nExperimentaban con humanos prisioneros lo que se les ocurr\u00eda, como buscar una forma de hacer bebible el agua de mar, por lo que se priv\u00f3 de comida y agua fresca a los gitanos y se les oblig\u00f3 a beber solo agua de mar. Muchos desarrollaron graves enfermedades.<br \/>\nAnte el rechazo de algunas personas a las vacunas, recordemos que los rumores son informaciones parciales, falsas o poco contrastadas que se difunden r\u00e1pidamente en un determinado grupo o sociedad. Son muy frecuentes en las situaciones de peligro, y pueden minar el comportamiento de las personas y el funcionamiento del grupo.<\/p>\n<p><strong>Ren\u00e9 Alberto Calles<\/strong><br \/>\nreneca4020@gmail.com<\/p>\n<hr \/>\n<h1>Corrupci\u00f3n, tema de portada<\/h1>\n<p>Si algo nos ense\u00f1a el mapa de la corrupci\u00f3n en cualquier parte y \u00e9poca es que solo liderazgos valientes y resueltos pueden terminar con ese azote. \u201cUna naci\u00f3n comienza a corromperse cuando se corrompe su sintaxis\u201d, ha dicho Octavio Paz. Es b\u00e1sica una buena gobernabilidad como estrategia frontal derivada de la acci\u00f3n coordinada de instituciones de control que reduzcan los espacios para la putrefacci\u00f3n. Esa gobernabilidad dotar\u00e1 a las instituciones de la autoridad necesaria para reflejar no solo la apariencia de legalidad, sino la firmeza \u00e9tica que nunca va a doblegarse ante funcionarios venales de la corrupci\u00f3n p\u00fablica o privada, celando adem\u00e1s que las instituciones no sirvan de trampol\u00edn para el lavado de activos procedentes de sectores oscuros que subvierten las leyes.<br \/>\nSin \u00e9tica no hay democracia y las entidades estatales no deben permitir la colusi\u00f3n de infiltrados en las decisiones de pa\u00eds. Elegir la \u00e9tica como punto de honor y castigar la podredumbre debe ser la consigna de un Estado que ahora es un hu\u00e9rfano de honradez. Las penas deben cumplirse lo mismo para ladrones con fuero, saco y corbata que para empleados de bajo nivel, no es posible seguir con \u201cla justicia que persigue a los peque\u00f1os\u201d, como reclama el reportaje de Mois\u00e9s Alvarado. En una sociedad altamente polarizada resulta bien f\u00e1cil ver la corrupci\u00f3n en los otros, pero lo que veo a mi lado no lo es, postura que solo eleva los niveles de tolerancia, abriendo las puertas para que funcionarios de alta jerarqu\u00eda derrochen las esperanzas de los m\u00e1s necesitados; arremeter sin tregua implica un \u00f3rgano judicial fuerte, independiente e inamovible, lo que por hoy estamos lejos de tener. Cierto es que corrupci\u00f3n hay por todos lados del planeta, pero lo que nos diferencia es la impunidad que se expresa con el velo de la indolencia y el pesimismo para atrapar a los que parecen inasibles. En El Salvador la corrupci\u00f3n no se castiga ni con las leyes ni en las urnas, resulta una paradoja entre \u201cpopularidad\u201d de pol\u00edticos corruptos y repudio por ese flagelo, pero ah\u00ed est\u00e1n de nuevo los imputados reelegidos por los mismos que hacen se\u00f1alamientos. La ruta del escape a la impunidad solo ser\u00e1 posible, como queda dicho antes, con un sistema judicial despolitizado, competente y responsable, y no putrefacto como el que tenemos. De otra manera, seguiremos cargando la verg\u00fcenza de ese lugar 112, hiriendo la dignidad del salvadore\u00f1o \u00edntegro.<\/p>\n<p><strong>Julio Roberto Maga\u00f1a<\/strong><br \/>\njrobertomasa@hotmail.com<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Fue muy interesante el art\u00edculo de la AP en 7S sobre la desconfianza que los brasile\u00f1os tienen hacia las vacunas contra la fiebre amarilla. <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":3189,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-buzon.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Buz\u00f3n - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buz\u00f3n - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Fue muy interesante el art\u00edculo de la AP en 7S sobre la desconfianza que los brasile\u00f1os tienen hacia las vacunas contra la fiebre amarilla.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-25T06:04:31+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-26T05:37:13+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1474\" \/>\n\t<meta property=\"og:image:height\" content=\"935\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9ptimo Sentido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"4 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18.jpg\",\"width\":1474,\"height\":935,\"caption\":\"Buz\u00f3n\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/\",\"name\":\"Buz\u00f3n - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/#primaryimage\"},\"datePublished\":\"2018-03-25T06:04:31+00:00\",\"dateModified\":\"2018-03-26T05:37:13+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buz\u00f3n\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\",\"name\":\"S\u00e9ptimo Sentido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"caption\":\"S\u00e9ptimo Sentido\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buz\u00f3n - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/","og_locale":"en_US","og_type":"article","og_title":"Buz\u00f3n - S\u00e9ptimo Sentido","og_description":"Fue muy interesante el art\u00edculo de la AP en 7S sobre la desconfianza que los brasile\u00f1os tienen hacia las vacunas contra la fiebre amarilla.","og_url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-03-25T06:04:31+00:00","article_modified_time":"2018-03-26T05:37:13+00:00","og_image":[{"width":1474,"height":935,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"S\u00e9ptimo Sentido","Est. reading time":"4 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18.jpg","width":1474,"height":935,"caption":"Buz\u00f3n"},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/","name":"Buz\u00f3n - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/#primaryimage"},"datePublished":"2018-03-25T06:04:31+00:00","dateModified":"2018-03-26T05:37:13+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Buz\u00f3n"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b","name":"S\u00e9ptimo Sentido","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","caption":"S\u00e9ptimo Sentido"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-P6","jetpack-related-posts":[{"id":3127,"url":"https:\/\/7s.laprensagrafica.com\/en\/brasil-mira-con-desconfianza-a-la-vacuna-de-la-fiebre-amarilla\/","url_meta":{"origin":3168,"position":0},"title":"Brasil mira con desconfianza a la vacuna  de la fiebre amarilla","date":"18 March, 2018","format":false,"excerpt":"En este brote ya hay 846 casos confirmados, incluidos 260 pacientes fallecidos. Pero la vacunaci\u00f3n contra la fiebre amarilla apenas llega al 76 %, cuando la meta era de 95 %. En redes de mensajer\u00eda circulan rumores sobre su efectividad que hacen que las comunidades lleguen menos a los centros\u2026","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/fsep18032018Ap7277262.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3595,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-13-mayo-2018\/","url_meta":{"origin":3168,"position":1},"title":"Buz\u00f3n","date":"13 May, 2018","format":false,"excerpt":"Se le denomina albergue temporal al lugar para alojamiento de personas afectadas por un desastre.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":104,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-2\/","url_meta":{"origin":3168,"position":2},"title":"BUZ\u00d3N","date":"26 March, 2017","format":false,"excerpt":"La otra mitad de la salud Julio Roberto Maga\u00f1a jrobertomasa@hotmail.com En nuestro atribulado pa\u00eds a cualquier centro hospitalario al que acudamos siempre lo encontramos repleto de gente que busca paliar sus dolencias f\u00edsicas, nos hemos acostumbrado a atender las enfermedades som\u00e1ticas, pero la otra mitad de salud que reviste de\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/7s19principal.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7589,"url":"https:\/\/7s.laprensagrafica.com\/en\/la-naturaleza-no-se-domina-con-tanques-y-aviones\/","url_meta":{"origin":3168,"position":3},"title":"La naturaleza no se domina con tanques y aviones","date":"19 April, 2020","format":false,"excerpt":"[:es]Mariano Esteban forma parte de un grupo de invstigadores que trata de encontrar una vacuna contra el covid-19. Sin ninguna duda, se\u00f1ala que es el turno de la ciencia para salvar a la humanidad.[:]","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/04\/fsep19042020cormariano1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2995,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-04-marzo-2018\/","url_meta":{"origin":3168,"position":4},"title":"Buz\u00f3n","date":"4 March, 2018","format":false,"excerpt":"Los adultos mayores en nuestro pa\u00eds demandan cuidos especiales debido a la edad. La mayor\u00eda de este nicho adolece de un seguro de salud y algunos viven de la caridad p\u00fablica.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/buzon-04-marzo-2018.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1562,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-01-octubre-2017\/","url_meta":{"origin":3168,"position":5},"title":"Buz\u00f3n","date":"1 October, 2017","format":false,"excerpt":"\u00c1ngel guardi\u00e1n del enfermo Cuando ya se ha superado el golpe emocional del diagn\u00f3stico, atender al enfermo en su casa supone un verdadero reto para la familia, lo que sigue es el acomodo de espacios en el hogar para ofrecerle al infortunado el mejor confort. Sin embargo, por varias razones\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/09\/buzon-el-ocaso-de-ana.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3168"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=3168"}],"version-history":[{"count":3,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3168\/revisions"}],"predecessor-version":[{"id":3191,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3168\/revisions\/3191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/3189"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=3168"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=3168"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=3168"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}