{"id":3162,"date":"2018-03-25T00:06:54","date_gmt":"2018-03-25T06:06:54","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=3162"},"modified":"2018-03-24T14:42:21","modified_gmt":"2018-03-24T20:42:21","slug":"carta-editorial-25-marzo-2018","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-25-marzo-2018\/","title":{"rendered":"Carta Editorial"},"content":{"rendered":"<p>En esta edici\u00f3n se nos juntan violencias. Las vemos como la nota roja a la que todo mundo le voltea la cara por \u201cirrespetuosa\u201d de la \u201cdignidad\u201d humana. La vemos como una de las tantas formas que inventamos para separarnos por clases. Y la vemos como la raz\u00f3n por la que se llegan a negar incluso los servicios de educaci\u00f3n y salud. Las violencias quitan la vida de diferentes y creativas maneras.<br \/>\nFernanda Melchor es escritora y es de Veracruz, M\u00e9xico. Su origen es indispensable para entrar a consumir su obra. Ella, que creci\u00f3 en Veracruz cuando era un lugar tranquilo, aprendi\u00f3 a ver las muertes violentas que inundaron el lugar desde otro punto de vista. Aprendi\u00f3 que era necesario ver esos cuerpos maltratados porque, de lo contrario, el riesgo de que no importen se vuelve mayor.<br \/>\nAlejandro Gutman es argentino, y es un convencido de que para poder plantear una soluci\u00f3n a largo plazo al problema de inseguridad p\u00fablica es indispensable llegar a las comunidades con una bandera de integraci\u00f3n. Sin la reparaci\u00f3n de la rota relaci\u00f3n entre las comunidades y los centros de estudio b\u00e1sicos, superiores y t\u00e9cnicos, no se puede hablar de paz y estabilidad, ambos tan necesarios para alcanzar desarrollo.<br \/>\nY a esto se suma todo el calvario que deben vivir cientos de venezolanos que se han visto sin m\u00e1s camino que migrar en las peores condiciones posibles debido a la imposibilidad de conseguir, en su pa\u00eds, un nivel de vida aceptable.<br \/>\nLa violencia no siempre es algo que pega o que abre agujeros de bala. Tambi\u00e9n es decidir ignorar algo que da\u00f1a al pr\u00f3jimo, es negarse a abrir las puertas necesarias para que todos tengamos oportunidad de mejorarnos la vida, es desesperar, segregar, expulsar y limitar.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Aprendi\u00f3 que era necesario ver esos cuerpos maltratados porque, de lo contrario, el riesgo de que no importen se vuelve mayor.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":3163,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-carta.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carta Editorial - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta Editorial - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Aprendi\u00f3 que era necesario ver esos cuerpos maltratados porque, de lo contrario, el riesgo de que no importen se vuelve mayor.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-25T06:06:54+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-24T20:42:21+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/portada_Ssen03252018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"948\" \/>\n\t<meta property=\"og:image:height\" content=\"742\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Glenda Gir\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/portada_Ssen03252018.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/portada_Ssen03252018.jpg\",\"width\":948,\"height\":742,\"caption\":\"Foto de portada\/AP. Sin opci\u00f3n. Las condiciones se han deteriorado tanto en Venezuela que cientos de miles de personas cruzan la frontera hacia Colombia y Brasil, y dicen que no tienen qu\u00e9 comer.\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/\",\"name\":\"Carta Editorial - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/#primaryimage\"},\"datePublished\":\"2018-03-25T06:06:54+00:00\",\"dateModified\":\"2018-03-24T20:42:21+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta Editorial\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\",\"name\":\"Glenda Gir\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"caption\":\"Glenda Gir\u00f3n\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta Editorial - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/","og_locale":"en_US","og_type":"article","og_title":"Carta Editorial - S\u00e9ptimo Sentido","og_description":"Aprendi\u00f3 que era necesario ver esos cuerpos maltratados porque, de lo contrario, el riesgo de que no importen se vuelve mayor.","og_url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-03-25T06:06:54+00:00","article_modified_time":"2018-03-24T20:42:21+00:00","og_image":[{"width":948,"height":742,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/portada_Ssen03252018.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"Glenda Gir\u00f3n","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/portada_Ssen03252018.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/portada_Ssen03252018.jpg","width":948,"height":742,"caption":"Foto de portada\/AP. Sin opci\u00f3n. Las condiciones se han deteriorado tanto en Venezuela que cientos de miles de personas cruzan la frontera hacia Colombia y Brasil, y dicen que no tienen qu\u00e9 comer."},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/","name":"Carta Editorial - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/#primaryimage"},"datePublished":"2018-03-25T06:06:54+00:00","dateModified":"2018-03-24T20:42:21+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-25-marzo-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Carta Editorial"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c","name":"Glenda Gir\u00f3n","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","caption":"Glenda Gir\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/portada_Ssen03252018.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-P0","jetpack-related-posts":[{"id":5641,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-05-mayo-2019\/","url_meta":{"origin":3162,"position":0},"title":"Carta Editorial","date":"5 May, 2019","format":false,"excerpt":"Ma\u00f1ana, otros cientos se van a tener que ir por razones casi id\u00e9nticas a las que, hace 10 a\u00f1os, dieron los que en ese momento se fueron.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/05\/montaje2018portaditaca.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":400,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-7\/","url_meta":{"origin":3162,"position":1},"title":"Carta Editorial","date":"9 April, 2017","format":false,"excerpt":"Esto es lo que nos ha venido haciendo tanta falta como sociedad. No hemos naturalizado el cambio constante. Solo nos definimos en funci\u00f3n de ese a quien creemos opuesto.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/1usa.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1566,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-01-octubre-de-2017\/","url_meta":{"origin":3162,"position":2},"title":"Carta Editorial","date":"1 October, 2017","format":false,"excerpt":"En medio de esta situaci\u00f3n alterada, la preocupaci\u00f3n es otra manera de mostrar afecto.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/Ssen_001.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4744,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-11-noviembre-2018\/","url_meta":{"origin":3162,"position":3},"title":"Carta Editorial","date":"11 November, 2018","format":false,"excerpt":"Estos cuatro empleados no se encargan de labores de seguridad, y aun as\u00ed han tenido que mirar a la cara a gente que, arma en mano, les exige que se vayan.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/montaje11118.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6069,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-28-julio-2019\/","url_meta":{"origin":3162,"position":4},"title":"Carta Editorial","date":"28 July, 2019","format":false,"excerpt":"\u201cCada persona cuenta\u201d, pregona hoy la Fiscal\u00eda General de la Rep\u00fablica y, en eso, tiene toda la raz\u00f3n. Cada persona cuenta.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/07\/montaje2018portaditaca-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7940,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-28-junio-2020\/","url_meta":{"origin":3162,"position":5},"title":"Carta Editorial","date":"28 June, 2020","format":false,"excerpt":"[:es]Porque el virus nos ha obligado a estar en una constante despedida. Le hemos dicho adi\u00f3s a cada plan y a casi todo lo que conoc\u00edamos como vida. Se nos interrumpi\u00f3 la l\u00ednea de progreso.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/06\/PORTADASsen06282020001.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3162"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=3162"}],"version-history":[{"count":2,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3162\/revisions"}],"predecessor-version":[{"id":3165,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3162\/revisions\/3165"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/3163"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=3162"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=3162"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=3162"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}