{"id":3114,"date":"2018-03-18T00:04:30","date_gmt":"2018-03-18T06:04:30","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=3114"},"modified":"2018-03-16T20:11:48","modified_gmt":"2018-03-17T02:11:48","slug":"buzon-18-de-marzo-2018","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/","title":{"rendered":"Buz\u00f3n"},"content":{"rendered":"<figure id=\"attachment_3116\" style=\"width: 1476px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"3116\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/septimo-sentido-11_03_2018\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018.jpg\" data-orig-size=\"1476,937\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"Septimo-Sentido- 11_03_2018\" data-image-description=\"&lt;p&gt;Buz\u00f3n&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Buz\u00f3n&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018-300x190.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018-1024x650.jpg\" loading=\"lazy\" class=\"size-full wp-image-3116\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018.jpg\" alt=\"\" width=\"1476\" height=\"937\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018.jpg 1476w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018-300x190.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018-768x488.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018-1024x650.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018-1200x762.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018-500x317.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018-1000x635.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018-700x444.jpg 700w\" sizes=\"(max-width: 1476px) 100vw, 1476px\" \/><figcaption class=\"wp-caption-text\">Buz\u00f3n<\/figcaption><\/figure>\n<h1>Recordar a un santo<\/h1>\n<p>Consecuente con el art\u00edculo \u201cLa voz de un santo\u201d, publicado el domingo pasado por H\u00e9ctor Silva \u00c1valos, en 7S, recuerdo de uno de sus escritos titulado \u201cOraci\u00f3n de solidaridad: Felices los que dan la vida por los dem\u00e1s. Los que trabajan duro por la justicia anhelada. Los que construyen el Reino desde lugares remotos. Los que, an\u00f3nimos y sin primeras planas, entregan su vida para que otros vivan m\u00e1s y mejor\u201d. Recordemos que la conversi\u00f3n de Monse\u00f1or Romero fue un proceso gradual que para \u00e9l signific\u00f3 ser abierto a conocer la realidad y su sensibilidad al sufrimiento de la gente. Sus bi\u00f3grafos dicen que en 1977 fue nombrado arzobispo y tom\u00f3 posesi\u00f3n ante la algarab\u00eda de las clases adineradas y la desilusi\u00f3n de los pobres. Pero los cuerpos de seguridad generalizaron la represi\u00f3n, al grado que tiempo despu\u00e9s asesinaron a su mejor amigo: el padre Rutilio Grande. De ah\u00ed en adelante se fue produciendo un giro en Monse\u00f1or Romero, porque no solo asesinaron al sacerdote, sino tambi\u00e9n a catequistas, curas, obreros, campesinos. Todos recordamos c\u00f3mo nuestro santo se dirig\u00eda a la poblaci\u00f3n por intermedio de homil\u00edas, que predicaba todos los domingos en la misa de Catedral. Nos dej\u00f3 un legado de casi 200 homil\u00edas dominicales. Esa es su forma de alabar a Dios, de denunciar el sufrimiento de quienes acud\u00edan a \u00e9l para contarle su desgracia al ser perseguidos por las autoridades de la \u00e9poca. En cierta ocasi\u00f3n dijo entre aplausos: \u201cAhora la iglesia no se apoya en ning\u00fan dinero. Hoy la iglesia es pobre. Hoy la iglesia sabe que los poderosos la rechazan, pero que la aman quienes sienten en Dios su confianza\u201d. Ante una iglesia perseguida por las autoridades de esos tiempos crueles vividos por el pa\u00eds, Monse\u00f1or Romero apunt\u00f3 que \u201cla persecuci\u00f3n es algo necesario en la iglesia. \u00bfSaben por qu\u00e9? Porque la verdad siempre es perseguida. Jesucristo lo dijo: \u2018Si a m\u00ed me persiguieron, tambi\u00e9n os perseguir\u00e1n a vosotros\u2019\u201d. Calificado como la voz de los sin voz, Monse\u00f1or Romero dijo en una de sus homil\u00edas que quer\u00eda ser la voz de los que no tienen voz para gritar tanto atropello contra los derechos humanos. Pidi\u00f3 que se hiciera justicia, que no se queden atr\u00e1s cr\u00edmenes manchando a la patria, al tiempo que exigi\u00f3 que se diera justa indemnizaci\u00f3n a las familias que quedaron desamparadas. Supimos que en vida, Monse\u00f1or Romero no fue bien visto por, en general, la jerarqu\u00eda eclesi\u00e1stica. Fue atacado por todos los obispos salvadore\u00f1os, algo que puede hoy parecer sorprendente y desconcertante, pero en realidad ocurri\u00f3. En el Vaticano las cosas no fueron muy diferentes. Se pens\u00f3 en destituirlo, dej\u00e1ndolo como figura decorativa. La primera visita a Juan Pablo II fue dolorosa, pues el papa no pareci\u00f3 apreciar la gravedad de la persecuci\u00f3n de la iglesia. Pero al final de cuentas, esperamos con gran alegr\u00eda su santificaci\u00f3n en octubre.<\/p>\n<p><strong>Ren\u00e9 Alberto Calles<\/strong><br \/>\nreneca4020@gmail.com<\/p>\n<hr \/>\n<h1>Equidad<\/h1>\n<p>En nuestro pa\u00eds, alg\u00fan sector de mujeres no tiene acceso de dar a conocer su realidad familiar, social o laboral para expresar lo que les preocupa y les gusta. Adem\u00e1s, tienen que definir los valores y las habilidades que necesitan para su crecimiento. Nuestra sociedad debe conocer qu\u00e9 es lo que ella necesitan y quiere. Sumar los retos y logros obtenidos con base en el pensamiento y la pasi\u00f3n por el rol que desempe\u00f1an ahora se les reconoce el 8 de marzo como D\u00eda Internacional de la Mujer, instaurado por la ONU desde 1975. Anteriormente pasaba desapercibido ese d\u00eda y es de mencionar que el sector rural es el que se encuentra abandonado y las mujeres rurales son la fuerza motriz contra el hambre y la pobreza, y son la columna vertebral en sus comunidades debido a que ellas producen, procesan y preparan los alimentos por ser pilares fundamentales de sus familias y comunidades, y por esta raz\u00f3n mejoran la condici\u00f3n social y econ\u00f3mica de su entorno, debido a que tienen buen control para gastar m\u00e1s en alimentos, salud, ropa y educaci\u00f3n.<br \/>\nLa igualdad de g\u00e9nero es esencial para lograr seguridad alimentaria a trav\u00e9s de la capacitaci\u00f3n para mejorar su bienestar en los hogares y comunidades, lo que, a su vez, contribuye al crecimiento social y econ\u00f3mico a corto, mediano y largo plazo.<br \/>\nEn el reportaje \u201cLa marcha de las ausentes\u201d de la periodista Valeria Guzm\u00e1n, nos muestra una forma de denunciar la violencia por medio de una marcha y, a la vez, un reclamo para las autoridades: \u00bfpor qu\u00e9 hay tanta mujer desaparecida? Es necesario exigir salarios justos y condiciones dignas de trabajo. No todas las mujeres pueden marchar durante el d\u00eda debido a que no pueden abandonar sus puestos de trabajo. Como sociedad, estamos en deuda con este conglomerado y debemos unir esfuerzos para bien com\u00fan en una sociedad justa y equitativa sin ning\u00fan sector excluido.<\/p>\n<p><strong>Rutilio L\u00f3pez Cortez<\/strong><br \/>\nrutilio_lopezcortez@outlook.com<\/p>\n<hr \/>\n<h1>Beatleman\u00edaco<\/h1>\n<p>Estimada Evelyn Galindo, me dio gran placer leer su escrito \u201cHermana lejana playlist\u201d en S\u00e9ptimo Sentido de LA PRENSA GR\u00c1FICA, domingo 4 de marzo. Comparto su gusto por las canciones \u201cRocket Man\u201d de Elton John, \u201cVagabundear\u201d de Joan Manuel Serrat, \u201cLike a Rolling Stone\u201d de Bob Dylan y \u201cMagical Mystery Tour\u201d de The Beatles. Respecto de la \u00faltima, no est\u00e1 incluida en el \u00e1lbum \u201cSgt. Pepper&#8217;s Lonely Hearts Club Band\u201d, publicado en Inglaterra el 1.\u00ba de junio de 1967, sino en el \u00e1lbum \u201cMagical Mystery Tour\u201d, publicado en Estados Unidos de Am\u00e9rica el 27 de noviembre del mismo a\u00f1o.<br \/>\nIncluyo en mi lista de canciones alusivas al sentimiento por desplazamiento geogr\u00e1fico o conflicto de identidad cultural: \u201cNowhere Man\u201d de The Beatles, \u201cPeople Are Strange\u201d de The Doors, \u201cI Am I Said\u201d de Neil Diamond, \u201cCantares\u201d de Joan Manuel Serrat y \u201cChe sar\u00e1?\u201d (\u201c\u00bfQu\u00e9 ser\u00e1?\u201d) de Jimmy Fontana y Franco Migliacci.<\/p>\n<p><strong>Eduardo Carbone<\/strong><br \/>\neducar64@hotmail.com<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Consecuente con el art\u00edculo \u201cLa voz de un santo\u201d, publicado el domingo pasado por H\u00e9ctor Silva \u00c1valos, en 7S, recuerdo de uno de sus escritos titulado \u201cOraci\u00f3n de solidaridad: Felices los que dan la vida por los dem\u00e1s.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":3116,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-buzon.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Buz\u00f3n - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buz\u00f3n - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Consecuente con el art\u00edculo \u201cLa voz de un santo\u201d, publicado el domingo pasado por H\u00e9ctor Silva \u00c1valos, en 7S, recuerdo de uno de sus escritos titulado \u201cOraci\u00f3n de solidaridad: Felices los que dan la vida por los dem\u00e1s.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-18T06:04:30+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-17T02:11:48+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1476\" \/>\n\t<meta property=\"og:image:height\" content=\"937\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9ptimo Sentido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018.jpg\",\"width\":1476,\"height\":937,\"caption\":\"Buz\u00f3n\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/\",\"name\":\"Buz\u00f3n - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/#primaryimage\"},\"datePublished\":\"2018-03-18T06:04:30+00:00\",\"dateModified\":\"2018-03-17T02:11:48+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buz\u00f3n\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\",\"name\":\"S\u00e9ptimo Sentido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"caption\":\"S\u00e9ptimo Sentido\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buz\u00f3n - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/","og_locale":"en_US","og_type":"article","og_title":"Buz\u00f3n - S\u00e9ptimo Sentido","og_description":"Consecuente con el art\u00edculo \u201cLa voz de un santo\u201d, publicado el domingo pasado por H\u00e9ctor Silva \u00c1valos, en 7S, recuerdo de uno de sus escritos titulado \u201cOraci\u00f3n de solidaridad: Felices los que dan la vida por los dem\u00e1s.","og_url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-03-18T06:04:30+00:00","article_modified_time":"2018-03-17T02:11:48+00:00","og_image":[{"width":1476,"height":937,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"S\u00e9ptimo Sentido","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018.jpg","width":1476,"height":937,"caption":"Buz\u00f3n"},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/","name":"Buz\u00f3n - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/#primaryimage"},"datePublished":"2018-03-18T06:04:30+00:00","dateModified":"2018-03-17T02:11:48+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-18-de-marzo-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Buz\u00f3n"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b","name":"S\u00e9ptimo Sentido","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","caption":"S\u00e9ptimo Sentido"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-11_03_2018.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-Oe","jetpack-related-posts":[{"id":4151,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-julio-2018\/","url_meta":{"origin":3114,"position":0},"title":"Buz\u00f3n","date":"29 July, 2018","format":false,"excerpt":"La necesidad de contar con m\u00e1s bibliotecas en el sistema educativo de El Salvador Es muy preocupante la situaci\u00f3n de las escuelas que no tienen bibliotecas. De esta manera se nota lo poco que al Ministerio de Educaci\u00f3n le ha importado la instrucci\u00f3n que se da a los ni\u00f1os. Esta\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep22072018agbib08.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1052,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-06-agosto-2017\/","url_meta":{"origin":3114,"position":1},"title":"Buz\u00f3n","date":"6 August, 2017","format":false,"excerpt":"Captores de sucesos Es alentador que SECULTURA por fin haya tomado en cuenta para el Premio Nacional de Cultura a los profesionales del fotoperiodismo que nos ofrecen escenas con mucha riqueza en contenido de lo que pasa en el pa\u00eds. Los reporteros gr\u00e1ficos siempre han estado marginados, a pesar de\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"Buz\u00f3n","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/08\/buzon-6.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3798,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-10-junio-2018\/","url_meta":{"origin":3114,"position":2},"title":"Buz\u00f3n","date":"10 June, 2018","format":false,"excerpt":"Una avalancha de riesgos y peligros enfrentan los inmigrantes en el trayecto que enrumba la b\u00fasqueda de la ruta hacia el Norte.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/fsep03062018arcsep99.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":721,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-09-julio-2017\/","url_meta":{"origin":3114,"position":3},"title":"Buz\u00f3n","date":"9 July, 2017","format":false,"excerpt":"Los animales de los zool\u00f3gicos precisan cuidados especiales y mantenimiento \u00f3ptimo que les permitan una vida lo m\u00e1s saludable posible en cautiverio, para ese prop\u00f3sito deben haber normativas de protecci\u00f3n para brindarles alimentaci\u00f3n nutritiva, aseo de \u00e1reas, personal capacitado y toda clase de atenciones como si se tratara de humanos.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/07\/zoo-reportaje.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2928,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-febrero-2018\/","url_meta":{"origin":3114,"position":4},"title":"Buz\u00f3n","date":"25 February, 2018","format":false,"excerpt":"Acusaciones Al parecer, la alta jerarqu\u00eda del Arzobispado de San Salvador duda de la autenticidad de la acusaci\u00f3n de pederastia de un ciudadano de Panchimalco hacia un sacerdote de la misma ciudad. Un miembro de esa autoridad de la Iglesia salvadore\u00f1a acaba de afirmar que ya trabajan en la restituci\u00f3n\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/02\/Septimo_Sentido_doble.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1342,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-03-septiembre-2017\/","url_meta":{"origin":3114,"position":5},"title":"Buz\u00f3n","date":"3 September, 2017","format":false,"excerpt":"De in\u00fatiles cambios de nombres Interesante relato que hace Jacinta Escudos en la edici\u00f3n dominical de S\u00e9ptimo Sentido en torno de las pretensiones de cambiarle nombre a lugares de nuestro territorio, espec\u00edficamente se refiere a la Puerta del Diablo, pero adem\u00e1s prolonga su compendio hasta los corazones fermentados que originan\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"Buz\u00f3n","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/09\/buzon-03-septiembre-2017.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3114"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=3114"}],"version-history":[{"count":3,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3114\/revisions"}],"predecessor-version":[{"id":3117,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3114\/revisions\/3117"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/3116"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=3114"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=3114"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=3114"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}