{"id":3043,"date":"2018-03-11T00:06:44","date_gmt":"2018-03-11T06:06:44","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=3043"},"modified":"2018-03-09T20:42:32","modified_gmt":"2018-03-10T02:42:32","slug":"carta-editorial-11-marzo-2018","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-11-marzo-2018\/","title":{"rendered":"Carta Editorial"},"content":{"rendered":"<p>En el texto que abre esta edici\u00f3n hay una medida de tiempo que duele. Es la que va desde Katya Miranda hasta Carla Ayala. Duele porque si preguntamos qu\u00e9 ha cambiado entre estos dos cr\u00edmenes y c\u00f3mo el sistema absorbe los delitos contra las mujeres, la respuesta es que muy poco o casi nada. Y entre estos dos casos hay, adem\u00e1s, un innegable involucramiento de miembros de la corporaci\u00f3n policial que lejos de ser un aliciente para que los casos, por cercan\u00eda, se resuelvan con m\u00e1s celeridad que la media, el efecto es todo lo contrario. El peso de los azules los hunde mucho m\u00e1s r\u00e1pido en el pantano de la impunidad.<br \/>\nY lo que simboliza es grave. El nombre de los buenos elementos de la Polic\u00eda Nacional Civil se pierde entre la cada vez m\u00e1s larga lista de evidencias de abusos de autoridad o de negligencia. Las delegaciones est\u00e1n llenas de historias de acoso y abusos. Tambi\u00e9n est\u00e1n plagadas de tratos indignos que se les dan a quienes en un completo estado de vulnerabilidad llegan a colocar denuncias para salvar de la invisibilidad las violencias dom\u00e9sticas.<\/p>\n<p>Las del 7 y 8 de marzo han sido en El Salvador marchas que se han impuesto a la tradici\u00f3n de no hacer nada. De esa ma\u00f1a de indignarse ante la \u00faltima que muri\u00f3 vapuleada, pero no mover un dedo para evitar que otra llegue hasta esa consecuencia. Lejos de ser solo tr\u00e1fico, las marchas educan, porque en un pa\u00eds tan negado a abrir las puertas hacia una educaci\u00f3n libre e inclusiva, queda eso: gritar en la calle para que lo escuchen tantas como se pueda.<br \/>\nUn cambio institucional y de maneras de pensar como el que se necesita en El Salvador no puede ser sosegado ni t\u00edmido. No es tiempo de callar.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Lejos de ser solo tr\u00e1fico, las marchas educan, porque en un pa\u00eds tan negado a abrir las puertas hacia una educaci\u00f3n libre e inclusiva, queda eso: gritar en la calle para que lo escuchen tantas como se pueda.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":3044,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-carta.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carta Editorial - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta Editorial - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Lejos de ser solo tr\u00e1fico, las marchas educan, porque en un pa\u00eds tan negado a abrir las puertas hacia una educaci\u00f3n libre e inclusiva, queda eso: gritar en la calle para que lo escuchen tantas como se pueda.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-03-11T06:06:44+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-03-10T02:42:32+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/portada_Ssen_11marzo_2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"736\" \/>\n\t<meta property=\"og:image:height\" content=\"937\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Glenda Gir\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/portada_Ssen_11marzo_2018.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/portada_Ssen_11marzo_2018.jpg\",\"width\":736,\"height\":937},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/\",\"name\":\"Carta Editorial - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/#primaryimage\"},\"datePublished\":\"2018-03-11T06:06:44+00:00\",\"dateModified\":\"2018-03-10T02:42:32+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta Editorial\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\",\"name\":\"Glenda Gir\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"caption\":\"Glenda Gir\u00f3n\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta Editorial - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/","og_locale":"en_US","og_type":"article","og_title":"Carta Editorial - S\u00e9ptimo Sentido","og_description":"Lejos de ser solo tr\u00e1fico, las marchas educan, porque en un pa\u00eds tan negado a abrir las puertas hacia una educaci\u00f3n libre e inclusiva, queda eso: gritar en la calle para que lo escuchen tantas como se pueda.","og_url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-03-11T06:06:44+00:00","article_modified_time":"2018-03-10T02:42:32+00:00","og_image":[{"width":736,"height":937,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/portada_Ssen_11marzo_2018.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"Glenda Gir\u00f3n","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/portada_Ssen_11marzo_2018.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/portada_Ssen_11marzo_2018.jpg","width":736,"height":937},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/","name":"Carta Editorial - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/#primaryimage"},"datePublished":"2018-03-11T06:06:44+00:00","dateModified":"2018-03-10T02:42:32+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-11-marzo-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Carta Editorial"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c","name":"Glenda Gir\u00f3n","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","caption":"Glenda Gir\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/portada_Ssen_11marzo_2018.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-N5","jetpack-related-posts":[{"id":5525,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-14-abril-2019\/","url_meta":{"origin":3043,"position":0},"title":"Carta Editorial","date":"14 April, 2019","format":false,"excerpt":"La denuncia se convierte en un reto m\u00e1s grande cuando el abuso se ha cometido en casa. Es ir en contra de todo lo que se conoce en la vida.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/04\/montaje2018portaditaca-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7940,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-28-junio-2020\/","url_meta":{"origin":3043,"position":1},"title":"Carta Editorial","date":"28 June, 2020","format":false,"excerpt":"[:es]Porque el virus nos ha obligado a estar en una constante despedida. Le hemos dicho adi\u00f3s a cada plan y a casi todo lo que conoc\u00edamos como vida. Se nos interrumpi\u00f3 la l\u00ednea de progreso.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/06\/PORTADASsen06282020001.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":6069,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-28-julio-2019\/","url_meta":{"origin":3043,"position":2},"title":"Carta Editorial","date":"28 July, 2019","format":false,"excerpt":"\u201cCada persona cuenta\u201d, pregona hoy la Fiscal\u00eda General de la Rep\u00fablica y, en eso, tiene toda la raz\u00f3n. Cada persona cuenta.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/07\/montaje2018portaditaca-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3875,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-24-junio-2018\/","url_meta":{"origin":3043,"position":3},"title":"Carta Editorial","date":"24 June, 2018","format":false,"excerpt":"A menor edad de la v\u00edctima, mayor es el porcentaje de violencias sexuales que se comenten en entornos cercanos, como la casa, la escuela, la iglesia, la comunidad.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/06\/portada_septimo.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7777,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-24-mayo-2020\/","url_meta":{"origin":3043,"position":4},"title":"Carta Editorial","date":"24 May, 2020","format":false,"excerpt":"[:es]Crear y mantener abiertas unidades de atenci\u00f3n especializada no es solo un paso burocr\u00e1tico. Sirve para institucionalizar el inter\u00e9s de un gobierno por ser inclusivo.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/05\/montaje2018portaditaca-3.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4936,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-9-diciembre-2018\/","url_meta":{"origin":3043,"position":5},"title":"Carta Editorial","date":"9 December, 2018","format":false,"excerpt":"Cuando se habla de educaci\u00f3n en sexualidad, en El Salvador hace falta partir de que en la ni\u00f1ez y en la adolescencia hay un d\u00e9ficit de informaci\u00f3n.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/12\/montaje0912portadita.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3043"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=3043"}],"version-history":[{"count":1,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3043\/revisions"}],"predecessor-version":[{"id":3045,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/3043\/revisions\/3045"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/3044"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=3043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=3043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=3043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}