{"id":2659,"date":"2018-01-21T00:04:23","date_gmt":"2018-01-21T06:04:23","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=2659"},"modified":"2018-01-19T20:39:27","modified_gmt":"2018-01-20T02:39:27","slug":"buzon-21-enero-2018","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/","title":{"rendered":"Buz\u00f3n"},"content":{"rendered":"<figure id=\"attachment_2695\" style=\"width: 1538px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"2695\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/buzon-21-enero-2018-2\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018.jpg\" data-orig-size=\"1538,935\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"buzon-21-enero-2018\" data-image-description=\"&lt;p&gt;Buz\u00f3n&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Buz\u00f3n&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018-300x182.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018-1024x623.jpg\" loading=\"lazy\" class=\"size-full wp-image-2695\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018.jpg\" alt=\"\" width=\"1538\" height=\"935\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018.jpg 1538w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018-300x182.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018-768x467.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018-1024x623.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018-1200x730.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018-500x304.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018-1000x608.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018-700x426.jpg 700w\" sizes=\"(max-width: 1538px) 100vw, 1538px\" \/><figcaption class=\"wp-caption-text\">Buz\u00f3n<\/figcaption><\/figure>\n<h1>Cuentas claras<\/h1>\n<p>La corrupci\u00f3n es una enfermedad terminal que condena a las sociedades que la toleran a vivir pobres, disminuidas, subdesarrolladas, estancadas. El Salvador, por desgracia, marcado hist\u00f3ricamente por la desigualdad socioecon\u00f3mica, padece ese mal desde siempre, volvi\u00e9ndose intenso y palmario en las \u00faltimas d\u00e9cadas, diezmando as\u00ed los ya magros recursos dedicados a la inversi\u00f3n p\u00fablica para paliar las necesidades de la poblaci\u00f3n.<\/p>\n<p>Mois\u00e9s Alvarado, con sus pesquisas en torno del tema, revela esta vez en \u201cLas millonarias empresas que cambian en una oficina\u201d los \u201cpara\u00edsos fiscales intramuros\u201d que han formado argollas sedientas del tesoro p\u00fablico. Algunos de nuestros gobernantes han sido h\u00e1biles, menos estadistas, para depredar erarios, lo demuestran las artima\u00f1as en la desviaci\u00f3n de fondos que se le investiga al expresidente Saca, quien articul\u00f3 una cadena de la maldad entre sus mismos funcionarios y allegados. Es evidente que no solo en movimientos indebidos de fondos hay corrupci\u00f3n, tambi\u00e9n existe en funcionarios que los utilizan para viajar, pagarse campa\u00f1as electoreras o congraciarse con criminales. Las mismas tretas est\u00e1n presentes entre algunos empresarios que las utilizan para evadir o eludir el pago de impuestos al fisco dejando las finanzas del pa\u00eds en n\u00fameros rojos, la violaci\u00f3n de leyes laborales, la venta de productos vencidos y otros mecanismos fraudulentos.<\/p>\n<p>Los mandos medios y las instancias de m\u00e1s abajo tambi\u00e9n han aprendido esos malabarismos vergonzosos, de esa manera no hay dinero que alcance al pa\u00eds para salir adelante. El fen\u00f3meno de la corrupci\u00f3n constituye una vulneraci\u00f3n a los derechos humanos por cuanto que generalmente entra\u00f1a una violaci\u00f3n del derecho a la igualdad ante la ley y, por supuesto, a los m\u00e1s elementales postulados de una incipiente democracia como la nuestra. Hay instituciones como Corte de Cuentas de la Rep\u00fablica y el Tribunal de \u00c9tica Gubernamental que no contribuyen al combate del flagelo que ya se percibe institucionalizado, pues en vez de revelar, esconden, y en vez de investigar, protegen. Con ese l\u00e1tigo a las finanzas oficiales, el pa\u00eds ha ido bajando en la calificaci\u00f3n, quedando varios puntos abajo en el ranking evaluativo, alejado de los pa\u00edses donde hay menos percepci\u00f3n de corrupci\u00f3n y m\u00e1s cercano con los que se colocan como m\u00e1s corruptos. Al final, la mala administraci\u00f3n de los recursos de un pa\u00eds es el aspecto principal tomado en cuenta por los cooperantes internacionales. Solo con cuentas claras y ciudadanos satisfechos podemos caminar hacia la paz y la democracia.<\/p>\n<p><strong>Julio Roberto Maga\u00f1a<\/strong><br \/>\njrobertomasa@hotmail.com<\/p>\n<hr \/>\n<h1>No se vale<\/h1>\n<p>A uno le gustar\u00eda pensar que de verdad el tiempo de desfalcar el erario p\u00fablico se les acab\u00f3 a los pol\u00edticos de turno, porque en eso se puede pensar al leer el tema de la semana pasada sobre la investigaci\u00f3n de las empresas que estaban todas en una sola oficina. Pero al mismo tiempo, uno se acuerda de que ya ha habido otros casos en los que la raz\u00f3n y la l\u00f3gica han asistido a la Fiscal\u00eda General de la Rep\u00fablica e igual ha perdido los casos.<\/p>\n<p>Entonces, hay alguna esperanza y alguna compensaci\u00f3n en el hecho de que los acusados est\u00e1n ya en la c\u00e1rcel, detenidos, y aunque salgan con alguna sentencia favorable, ya pasaron un su rato all\u00e1, donde debe estar todo aquel que hace algo en contra de todos. Porque no se vale estar rob\u00e1ndole a un pa\u00eds tan sufrido y tan pobre. Encima para algo tan cutre como un tipo de enriquecimiento vulgar, lleno de lujos huecos y sin nada que aporte educaci\u00f3n o la elevaci\u00f3n del esp\u00edritu, pero claro, no se puede esperar nada m\u00e1s de las personas con tan poca conciencia que pueden robar al que no tiene.<\/p>\n<p><strong>Cristian Salazar<\/strong><br \/>\ncristiansala7812@gmail.com<\/p>\n<hr \/>\n<h1>Todos necesitamos ayuda emocional<\/h1>\n<p>Jacinta Escudos nos trae a cuenta el d\u00e9ficit que arrastramos en materia de salud mental en nuestro pa\u00eds. Si de hacer un estudio se trata, es un rubro no atendido en materia de salud. \u00bfQui\u00e9n no ha sido afectado por alguna causa? Desde la d\u00e9cada de los ochenta, damos traspi\u00e9 por toda la cadena de desgracias sufridas y a cada salvadore\u00f1o nos corresponde llevar cada uno nuestras cargas emocionales, sean familiares o laborales. Basta solo ver en la calle cuando nos trasladamos a nuestros hogares y vemos los desequilibrios en el tr\u00e1fico debido algunas veces a la recarga laboral de tareas que se ha vuelto una moda de explotaci\u00f3n moderna para generar m\u00e1s ingresos a los patronos con la consabida consigna de que lo que hacemos no es suficiente. Desde ese momento comienza una cadena de desequilibrio en que, muchas veces, los resultados son de violencia emocional que afecta en la productividad. Por esta raz\u00f3n tenemos elevados \u00edndices de violencia y agresividad que los manifestamos de diversa forma en la calle, hogar u oficina.<\/p>\n<p>Las empresas no deben subestimar al exigir a sus empleados metas dif\u00edciles de cumplir. Los polic\u00edas son los m\u00e1s afectados por las exigencias del trabajo que realizan y algunos transgreden las normas involuntariamente todo por salvaguardar su vida y la de su familia, que muchas veces reside en zonas dominadas por maras.<br \/>\nTodos necesitamos apoyo en t\u00e9rmino de salud mental por los diversos males que nos aquejan, como la injusticia laboral, impunidad de leyes y no dejar por fuera nuestra clase pol\u00edtica, que ha perdido el beneficio de servir por lo cual fue elegida.<\/p>\n<p><strong>Rutilio L\u00f3pez Cortez<\/strong><br \/>\nrutilio_lopezcortez@outlook.com<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>La corrupci\u00f3n es una enfermedad terminal que condena a las sociedades que la toleran a vivir pobres, disminuidas, subdesarrolladas, estancadas.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":2695,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-buzon.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Buz\u00f3n - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buz\u00f3n - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"La corrupci\u00f3n es una enfermedad terminal que condena a las sociedades que la toleran a vivir pobres, disminuidas, subdesarrolladas, estancadas.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2018-01-21T06:04:23+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2018-01-20T02:39:27+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1538\" \/>\n\t<meta property=\"og:image:height\" content=\"935\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9ptimo Sentido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018.jpg\",\"width\":1538,\"height\":935,\"caption\":\"Buz\u00f3n\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/\",\"name\":\"Buz\u00f3n - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/#primaryimage\"},\"datePublished\":\"2018-01-21T06:04:23+00:00\",\"dateModified\":\"2018-01-20T02:39:27+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buz\u00f3n\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\",\"name\":\"S\u00e9ptimo Sentido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"caption\":\"S\u00e9ptimo Sentido\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buz\u00f3n - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/","og_locale":"en_US","og_type":"article","og_title":"Buz\u00f3n - S\u00e9ptimo Sentido","og_description":"La corrupci\u00f3n es una enfermedad terminal que condena a las sociedades que la toleran a vivir pobres, disminuidas, subdesarrolladas, estancadas.","og_url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2018-01-21T06:04:23+00:00","article_modified_time":"2018-01-20T02:39:27+00:00","og_image":[{"width":1538,"height":935,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"S\u00e9ptimo Sentido","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018.jpg","width":1538,"height":935,"caption":"Buz\u00f3n"},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/","name":"Buz\u00f3n - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/#primaryimage"},"datePublished":"2018-01-21T06:04:23+00:00","dateModified":"2018-01-20T02:39:27+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-21-enero-2018\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Buz\u00f3n"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b","name":"S\u00e9ptimo Sentido","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","caption":"S\u00e9ptimo Sentido"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/buzon-21-enero-2018.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-GT","jetpack-related-posts":[{"id":3595,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-13-mayo-2018\/","url_meta":{"origin":2659,"position":0},"title":"Buz\u00f3n","date":"13 May, 2018","format":false,"excerpt":"Se le denomina albergue temporal al lugar para alojamiento de personas afectadas por un desastre.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/05\/buzon.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4118,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-julio-2018\/","url_meta":{"origin":2659,"position":1},"title":"Buz\u00f3n","date":"22 July, 2018","format":false,"excerpt":"Cuando era peque\u00f1a, vi partir a muchos de mis compa\u00f1eros de escuela de la misma manera en la que el joven poeta salvadore\u00f1o Javier Zamora se fue.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/buzon-22-julio-2018.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1052,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-06-agosto-2017\/","url_meta":{"origin":2659,"position":2},"title":"Buz\u00f3n","date":"6 August, 2017","format":false,"excerpt":"Captores de sucesos Es alentador que SECULTURA por fin haya tomado en cuenta para el Premio Nacional de Cultura a los profesionales del fotoperiodismo que nos ofrecen escenas con mucha riqueza en contenido de lo que pasa en el pa\u00eds. Los reporteros gr\u00e1ficos siempre han estado marginados, a pesar de\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"Buz\u00f3n","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/08\/buzon-6.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4258,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-12-agosto-2018\/","url_meta":{"origin":2659,"position":3},"title":"Buz\u00f3n","date":"12 August, 2018","format":false,"excerpt":"Siempre estoy pendiente de la revista, pero no he podido escribir por cuestiones laborales. Hace unos domingos, Mariana Belloso llev\u00f3 el tema de la educaci\u00f3n sexual de nuevo a reflexi\u00f3n.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/08\/mariana.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4067,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-08-julio-2018\/","url_meta":{"origin":2659,"position":4},"title":"Buz\u00f3n","date":"8 July, 2018","format":false,"excerpt":"Los estereotipos han estado presentes en toda sociedad y a todo nivel, el arte no escapa a esto. A ra\u00edz del surgimiento de nuevas formas de vincularnos se ha dado libertad a manifestaciones que se consideraron tab\u00fas.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/ffam27032018xxtet50.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4151,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-julio-2018\/","url_meta":{"origin":2659,"position":5},"title":"Buz\u00f3n","date":"29 July, 2018","format":false,"excerpt":"La necesidad de contar con m\u00e1s bibliotecas en el sistema educativo de El Salvador Es muy preocupante la situaci\u00f3n de las escuelas que no tienen bibliotecas. De esta manera se nota lo poco que al Ministerio de Educaci\u00f3n le ha importado la instrucci\u00f3n que se da a los ni\u00f1os. Esta\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep22072018agbib08.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/2659"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=2659"}],"version-history":[{"count":3,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/2659\/revisions"}],"predecessor-version":[{"id":2696,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/2659\/revisions\/2696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/2695"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=2659"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=2659"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=2659"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}