{"id":2197,"date":"2017-11-26T00:06:20","date_gmt":"2017-11-26T06:06:20","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=2197"},"modified":"2017-11-24T21:30:29","modified_gmt":"2017-11-25T03:30:29","slug":"carta-editorial-26-noviembre-2017","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-26-noviembre-2017\/","title":{"rendered":"Carta Editorial"},"content":{"rendered":"<p>Desde afuera se distingue perfecto. Y desde esa postura es f\u00e1cil reclamar a la v\u00edctima que por qu\u00e9 no hizo m\u00e1s por salirse y por dejar aquello que provoca da\u00f1o en tantos niveles. Desde adentro, la categorizaci\u00f3n no sale tan f\u00e1cil. Es complicado distinguir de cerca al monstruo. La violencia dom\u00e9stica es m\u00e1s que todo eso, dom\u00e9stica. Un asunto de puertas para adentro, de todos los d\u00edas, que coloca sus ra\u00edces y se mimetiza con la rutina y que, en un pa\u00eds tan violento y violentado no es sencillo identificar como delito \u2013con todas sus letras\u2013, aunque nos golpee en la cara.<\/p>\n<p>Antes de levantar cualquier tipo de cr\u00edtica hacia las v\u00edctimas, es necesario acercarse a relatos, como estos que ha escrito la periodista Valeria Guzm\u00e1n, en los que lo m\u00e1s doloroso es darse cuenta de que todas nuestras normalidades han quedado afectadas por el abuso constante. Esta es la voz de la mujer que ha sido criada en los golpes y no conoce otra vida fuera de eso. No fue educada para no querer a sus agresores. Porque sus agresores no han sido completos desconocidos en la calle; sus agresores han tenido con ella relaciones y v\u00ednculos directos de afecto. Comienza con un padre y contin\u00faa con las parejas.<\/p>\n<p>Quienes nos cuentan sus vidas en esta ocasi\u00f3n ya son mujeres; pero no quiere decir que nuestras ni\u00f1as no se est\u00e9n criando de la misma manera. Nuestras ni\u00f1as todav\u00eda crecen en hogares, escuelas, colonias, municipios, departamentos en donde la violencia es as\u00ed: dom\u00e9stica.<\/p>\n<p>Queda tanto por hacer en esto de identificar al mal y a quien lo ejecuta. Algunas de las protagonistas de estos relatos todav\u00eda creen que quienes est\u00e1n equivocadas son ellas y no quien les pega y las insulta. Quedan tantas voces por alzar en funci\u00f3n de educar para que quede claro que nada de lo que hace da\u00f1o est\u00e1 bien o se puede tolerar. La violencia no puede seguir entendi\u00e9ndose como algo \u00edntimo que afecta a una persona. Es un problema de pa\u00eds.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Lo m\u00e1s doloroso es darse cuenta de que todas nuestras normalidades han quedado afectadas por el abuso constante.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":4,"featured_media":2192,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-carta.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[4],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Carta Editorial - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Carta Editorial - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Lo m\u00e1s doloroso es darse cuenta de que todas nuestras normalidades han quedado afectadas por el abuso constante.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-26T06:06:20+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-25T03:30:29+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/portada-7s-20171126.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"757\" \/>\n\t<meta property=\"og:image:height\" content=\"985\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"Glenda Gir\u00f3n\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/portada-7s-20171126.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/portada-7s-20171126.jpg\",\"width\":757,\"height\":985},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/\",\"name\":\"Carta Editorial - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/#primaryimage\"},\"datePublished\":\"2017-11-26T06:06:20+00:00\",\"dateModified\":\"2017-11-25T03:30:29+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Carta Editorial\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c\",\"name\":\"Glenda Gir\u00f3n\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g\",\"caption\":\"Glenda Gir\u00f3n\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Carta Editorial - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/","og_locale":"en_US","og_type":"article","og_title":"Carta Editorial - S\u00e9ptimo Sentido","og_description":"Lo m\u00e1s doloroso es darse cuenta de que todas nuestras normalidades han quedado afectadas por el abuso constante.","og_url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2017-11-26T06:06:20+00:00","article_modified_time":"2017-11-25T03:30:29+00:00","og_image":[{"width":757,"height":985,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/portada-7s-20171126.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"Glenda Gir\u00f3n","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/portada-7s-20171126.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/portada-7s-20171126.jpg","width":757,"height":985},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/","name":"Carta Editorial - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/#primaryimage"},"datePublished":"2017-11-26T06:06:20+00:00","dateModified":"2017-11-25T03:30:29+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/carta-editorial-26-noviembre-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Carta Editorial"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/67583f7d4f47dafdda837ec8150b3b1c","name":"Glenda Gir\u00f3n","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b08d8a07878dbbb0f783e333027f2582?s=96&d=mm&r=g","caption":"Glenda Gir\u00f3n"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ggiron\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/portada-7s-20171126.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-zr","jetpack-related-posts":[{"id":4825,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-25-noviembre-2018\/","url_meta":{"origin":2197,"position":0},"title":"Carta Editorial","date":"25 November, 2018","format":false,"excerpt":"Es necesario decirnos a nosotras y decirles a nuestros ni\u00f1os que ning\u00fan nombre, sentimiento, reputaci\u00f3n o cargo vale la integridad f\u00edsica y emocional de una persona. Ninguno.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/11\/montaje112518portadita.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7602,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-19-abril-2020\/","url_meta":{"origin":2197,"position":1},"title":"Carta Editorial","date":"19 April, 2020","format":false,"excerpt":"[:es]Una potencial v\u00edctima no solo tiene derecho a tener al alcance informaci\u00f3n acerca de c\u00f3mo pedir auxilio y c\u00f3mo denunciar, tambi\u00e9n tiene que saber c\u00f3mo lo puede hacer en confidencialidad, sin alertar a la fuente de las agresiones.[:]","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/04\/montaje2018portaditaca-2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":157,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-3\/","url_meta":{"origin":2197,"position":2},"title":"Carta Editorial","date":"19 March, 2017","format":false,"excerpt":"C\u00e1lculos de instituciones como la Organizaci\u00f3n Panamericana de la Salud indican que la cantidad de mujeres afectadas por trastornos mentales duplica a la de hombres. Esto sin tomar en cuenta otros factores particulares del pa\u00eds que acaban reduciendo m\u00e1s las oportunidades para la poblaci\u00f3n femenina, como la discriminaci\u00f3n, la brecha\u2026","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"Ocultos. Los indicadores de prevalencia de trastornos mentales avalados por la OPS permiten reconocer que en el pa\u00eds no hay recursos para detectar a todas las personas que urgen ayuda de este tipo.","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/Ilustracion2.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4059,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-08-julio-2018\/","url_meta":{"origin":2197,"position":3},"title":"Carta Editorial","date":"8 July, 2018","format":false,"excerpt":"En las protestas en contra del gobierno de Daniel Ortega y de Rosario Murillo ya han muerto m\u00e1s de 200 personas en dos meses y medio.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/portada_s7.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1413,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-10-septiembre-2017\/","url_meta":{"origin":2197,"position":4},"title":"Carta editorial","date":"10 September, 2017","format":false,"excerpt":"Se hace indispensable la mirada hacia adentro para poder encontrar en este proceso de introspecci\u00f3n, tantas veces aplazado, una salida al espiral de deshumanizaci\u00f3n en la que el pa\u00eds lleva rato navegando.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/09\/portada-septimo-sentido-10-sept-2017.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1175,"url":"https:\/\/7s.laprensagrafica.com\/en\/carta-editorial-20-agosto-2017\/","url_meta":{"origin":2197,"position":5},"title":"Carta Editorial","date":"20 August, 2017","format":false,"excerpt":"Hay en el camino demasiados factores que reducen las oportunidades de una persona para alcanzar una vida plena. La primera de todas, el acceso a la educaci\u00f3n.","rel":"","context":"In &quot;Carta Editorial&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/08\/portada-carta-editorial.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/2197"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/4"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=2197"}],"version-history":[{"count":1,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/2197\/revisions"}],"predecessor-version":[{"id":2198,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/2197\/revisions\/2198"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/2192"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=2197"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=2197"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=2197"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}