{"id":2082,"date":"2017-11-12T00:01:39","date_gmt":"2017-11-12T06:01:39","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=2082"},"modified":"2017-11-10T21:35:34","modified_gmt":"2017-11-11T03:35:34","slug":"informe-dice-nisman-lo-asesinaron","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/informe-dice-nisman-lo-asesinaron\/","title":{"rendered":"El informe que dice que a Nisman lo asesinaron"},"content":{"rendered":"<figure id=\"attachment_2086\" style=\"width: 1920px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"2086\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/informe-dice-nisman-lo-asesinaron\/fsep12112017arcalb022-min\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min.jpg\" data-orig-size=\"1920,1280\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep12112017arcalb022-min\" data-image-description=\"&lt;p&gt;Fotograf\u00eda de Archivo&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Fotograf\u00eda de Archivo&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min-300x200.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min-1024x683.jpg\" loading=\"lazy\" class=\"size-full wp-image-2086\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min.jpg\" alt=\"\" width=\"1920\" height=\"1280\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min.jpg 1920w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min-300x200.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min-768x512.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min-1024x683.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min-1900x1267.jpg 1900w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min-1200x800.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min-500x333.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min-1000x667.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min-700x467.jpg 700w\" sizes=\"(max-width: 1920px) 100vw, 1920px\" \/><figcaption class=\"wp-caption-text\"><strong>Fotograf\u00eda de Archivo<\/strong><\/figcaption><\/figure>\n<p>Uno de los dos agresores agarr\u00f3 del cabello a Alberto Nisman en el ba\u00f1o de su apartamento en Buenos Aires, le puso la pistola en su cr\u00e1neo y le descerraj\u00f3 un tiro. Para peritos de la Polic\u00eda de Fronteras as\u00ed fue como muri\u00f3 el conocido fiscal argentino, una conclusi\u00f3n que supone un dr\u00e1stico giro respecto de la hip\u00f3tesis de suicidio a la que hab\u00edan apuntado otros expertos.<\/p>\n<p>El fiscal federal Eduardo Taiano deber\u00e1 decidir si avala las conclusiones del peritaje de la Gendarmer\u00eda en torno a uno de los casos criminales que m\u00e1s ha sacudido a Argentina en la historia reciente y que ha sido utilizado por sectores pol\u00edticos contrarios para atacarse.<br \/>\nNisman, a cargo de investigar el atentado terrorista de 1994 contra un centro jud\u00edo en Buenos Aires, fue hallado muerto el 18 de enero de 2015 en su ba\u00f1o. En el lugar encontraron una pistola calibre 22.<\/p>\n<p>Su muerte ocurri\u00f3 cuatro d\u00edas despu\u00e9s de denunciar a la entonces presidenta Cristina Fern\u00e1ndez de encubrir a los iran\u00edes acusados del ataque que dej\u00f3 85 muertos. La hoy senadora considera un disparate la denuncia en su contra.<\/p>\n<p>Tambi\u00e9n niega que su gobierno tuviera que ver con la muerte del fiscal y afirma que la entonces oposici\u00f3n \u201cech\u00f3 sospechas\u201d infundadas en su contra.<br \/>\nEl misterioso caso dividi\u00f3 a los argentinos entre los que pensaban que Nisman fue asesinado vilmente y los que cre\u00edan que se quit\u00f3 la vida, quiz\u00e1 acorralado por el temor de no poder sustentar su denuncia contra Fern\u00e1ndez. Hoy sigue generando todo tipo de conjeturas.<\/p>\n<figure id=\"attachment_2084\" style=\"width: 1020px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"2084\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/informe-dice-nisman-lo-asesinaron\/fsep12112017ap6856891-min\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856891-min.jpg\" data-orig-size=\"1020,680\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep12112017Ap6856891-min\" data-image-description=\"&lt;p&gt;Nuevos caminos. Este informe de la Gendarmer\u00eda apunta a que Nisman estaba drogado y que as\u00ed fue m\u00e1s f\u00e1cil para los \u201cvictimarios\u201d someterlo. El caso dividi\u00f3 a los argentinos entre acusaciones que rayaban en lo pol\u00edtico.&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Nuevos caminos. Este informe de la Gendarmer\u00eda apunta a que Nisman estaba drogado y que as\u00ed fue m\u00e1s f\u00e1cil para los \u201cvictimarios\u201d someterlo. El caso dividi\u00f3 a los argentinos entre acusaciones que rayaban en lo pol\u00edtico.&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856891-min-300x200.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856891-min.jpg\" loading=\"lazy\" class=\"size-full wp-image-2084\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856891-min.jpg\" alt=\"\" width=\"1020\" height=\"680\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856891-min.jpg 1020w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856891-min-300x200.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856891-min-768x512.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856891-min-500x333.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856891-min-1000x667.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856891-min-700x467.jpg 700w\" sizes=\"(max-width: 1020px) 100vw, 1020px\" \/><figcaption class=\"wp-caption-text\"><strong>Nuevos caminos<\/strong>. Este informe de la Gendarmer\u00eda apunta a que Nisman estaba drogado y que as\u00ed fue m\u00e1s f\u00e1cil para los \u201cvictimarios\u201d someterlo. El caso dividi\u00f3 a los argentinos entre acusaciones que rayaban en lo pol\u00edtico.<\/figcaption><\/figure>\n<p>En las conclusiones de la Gendarmer\u00eda, una veintena de expertos afirm\u00f3 que en la madrugada de aquel 18 de enero, Nisman fue golpeado por dos personas que lo drogaron y pusieron frente a la ba\u00f1era de su departamento en la capital argentina.<\/p>\n<p>Nisman, seg\u00fan el relato pericial, estaba con \u201cel torso erguido\u201d y con una de sus rodillas apoyada sobre el suelo, mientras uno de los \u201cvictimarios\u201d lo sujetaba por debajo de las axilas \u201ca modo de abrazo\u201d. En esa posici\u00f3n, el otro agresor se ubic\u00f3 detr\u00e1s y le apoy\u00f3 el arma en el lado derecho de la cabeza para despu\u00e9s apretar el gatillo. Eran aproximadamente las 2:46 horas de ese domingo.<br \/>\nLos gendarmes dicen haber descubierto elementos nuevos que sorprendentemente no hab\u00edan sido percibidos por otros peritos a lo largo de la investigaci\u00f3n. Por ejemplo, el m\u00e1s reciente an\u00e1lisis dice que ten\u00eda el tabique nasal roto, un golpe en la zona de la cadera y residuos en el cuerpo de ketamina, una droga con fuerte poder anest\u00e9sico. Nada de eso fue detectado en la autopsia, ni en los peritajes hechos en 2015 por la Polic\u00eda Federal y el prestigioso Cuerpo M\u00e9dico Forense.<\/p>\n<p>El m\u00e1s reciente estudio de la gendarmer\u00eda ha hecho cuestionarse a varios sobre si es m\u00e1s confiable que los anteriores. Eso tendr\u00e1 que determinarlo el fiscal Taiano.<\/p>\n<p>El fiscal dijo que la muerte de su colega es el caso de criminal\u00edstica \u201cm\u00e1s complicado\u201d de su carrera. La investigaci\u00f3n est\u00e1 considerada hasta ahora como el de una \u201cmuerte dudosa\u201d y lleg\u00f3 en 2016 a manos de Taiano tras haber quedado empantanada por meses en un fuero distinto al federal.<\/p>\n<h4>Los gendarmes dicen haber descubierto elementos nuevos que sorprendentemente no hab\u00edan sido percibidos por otros peritos a lo largo de la investigaci\u00f3n. Por ejemplo, el m\u00e1s reciente an\u00e1lisis dice que ten\u00eda el tabique nasal roto, un golpe en la zona de la cadera y residuos en el cuerpo de ketamina, una droga con fuerte poder anest\u00e9sico. Nada de eso fue detectado en la autopsia, ni en los peritajes hechos en 2015 por la Polic\u00eda Federal y el prestigioso Cuerpo M\u00e9dico Forense.<\/h4>\n<p>Dispuesto a empezar de cero, Taiano orden\u00f3 la conformaci\u00f3n de una \u201cjunta multidisciplinar\u201d de Gendarmer\u00eda para que diera su opini\u00f3n. Para el investigador, es una fuerza que no ha sido \u201ccuestionada\u201d, al contrario que la polic\u00eda federal, varios de cuyos miembros son investigados en el marco de la causa.<\/p>\n<p>Taiano tiene que comparar este \u00faltimo informe con los que lo contradicen. Y deber\u00e1 inclinarse sobre una de estas hip\u00f3tesis: asesinato, suicidio voluntario o suicidio inducido. Su conclusi\u00f3n ser\u00e1 elevada al juez de la causa, quien fijar\u00e1 la l\u00ednea de investigaci\u00f3n a seguir.<\/p>\n<figure id=\"attachment_2085\" style=\"width: 640px\"  class=\"wp-caption alignright\"><img data-attachment-id=\"2085\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/informe-dice-nisman-lo-asesinaron\/fsep12112017ap6856893-min\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856893-min.jpg\" data-orig-size=\"1020,680\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep12112017Ap6856893-min\" data-image-description=\"\" data-image-caption=\"&lt;p&gt;Fotograf\u00edas de Archivo&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856893-min-300x200.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856893-min.jpg\" loading=\"lazy\" class=\"size-card-home-second-row wp-image-2085\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856893-min-1000x667.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856893-min-1000x667.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856893-min-300x200.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856893-min-768x512.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856893-min-500x333.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856893-min-700x467.jpg 700w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6856893-min.jpg 1020w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-caption-text\">Fotograf\u00edas de Archivo<\/figcaption><\/figure>\n<p>Los gendarmes agitaron de nuevo las aguas del caso. Concluyeron que la ketamina aboli\u00f3 la voluntad de Nisman, pero permiti\u00f3 la conservaci\u00f3n de su \u201ctono muscular\u201d para posicionarlo dentro del ba\u00f1o. Nisman no se dispar\u00f3 porque en sus manos no hab\u00eda los componentes que detectan la p\u00f3lvora y los victimarios colocaron el cad\u00e1ver de tal manera que simularon un suicidio, agregaron.<br \/>\nConclusiones tan distintas sobre la muerte de Nisman abren el interrogante de si peritos de uno y otro lado actuaron con negligencia, inoperancia o mala fe.<\/p>\n<p>\u201cEn lo de la fractura del tabique nasal tienes una contradicci\u00f3n grave&#8230; tienes que ver qui\u00e9n dice la verdad y qui\u00e9n no\u201d, dijo Olga Fern\u00e1ndez, experta en criminal\u00edstica.<br \/>\nPara Fern\u00e1ndez, no es tan raro que en Argentina informes periciales sobre un mismo hecho sean dis\u00edmiles. \u201cDesgraciadamente con estos casos es que te presionan para que los resultados se obtengan m\u00e1s r\u00e1pido, lo cual puede dificultar que los resultados sean exhaustivos&#8230; tambi\u00e9n hay presiones para que los resultados salgan en un sentido u otro\u201d, dijo.<br \/>\nLa familia de Nisman tambi\u00e9n considera que se trat\u00f3 de un homicidio. Sin embargo, a partir de informaci\u00f3n de peritos que contrataron, una sola persona lo habr\u00eda asesinado, sujetando con su mano derecha la del fiscal para apretar el gatillo.<\/p>\n<p>El disparo que mat\u00f3 a Nisman sali\u00f3 de una pistola calibre 22 que le hab\u00eda prestado el t\u00e9cnico inform\u00e1tico Diego Lagomarsino, su asistente y hasta ahora el \u00fanico imputado en la causa.<\/p>\n<p>El t\u00e9cnico aleg\u00f3 que el fiscal le hab\u00eda pedido el arma el d\u00eda antes de su muerte porque tem\u00eda por la seguridad de sus hijas. La familia de Nisman, sin embargo, lo considera el principal sospechoso.<br \/>\nLos peritos aportados por Lagomarsino afirmaron que Nisman se infringi\u00f3 el disparo parado frente al espejo, seg\u00fan el informe.<\/p>\n<p>Se\u00f1alaron que la lesi\u00f3n sobre la cadera izquierda y la que se encuentra por encima del tobillo izquierdo de Nisman son de horas antes a su muerte. Y afirmaron que el tipo de salpicadura de sangre en ambas manos obedece a que el fiscal se hab\u00eda infringido el tiro empu\u00f1ando el arma con ambas manos.<\/p>\n<p>Respecto de la herida que ten\u00eda en el labio inferior se\u00f1alaron que se habr\u00eda producido durante el traslado del cad\u00e1ver.<\/p>\n<p>Por otro lado, situaron la muerte a una hora muy distinta: entre las 8 y 12 horas del 18 de enero.<\/p>\n<figure id=\"attachment_2083\" style=\"width: 640px\"  class=\"wp-caption alignleft\"><img data-attachment-id=\"2083\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/informe-dice-nisman-lo-asesinaron\/fsep12112017ap6847415-min\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6847415-min.jpg\" data-orig-size=\"1020,680\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"fsep12112017Ap6847415-min\" data-image-description=\"&lt;p&gt;Fotograf\u00edas de Archivo&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Fotograf\u00edas de Archivo&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6847415-min-300x200.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6847415-min.jpg\" loading=\"lazy\" class=\"size-card-home-second-row wp-image-2083\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6847415-min-1000x667.jpg\" alt=\"\" width=\"640\" height=\"427\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6847415-min-1000x667.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6847415-min-300x200.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6847415-min-768x512.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6847415-min-500x333.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6847415-min-700x467.jpg 700w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017Ap6847415-min.jpg 1020w\" sizes=\"(max-width: 640px) 100vw, 640px\" \/><figcaption class=\"wp-caption-text\">Fotograf\u00edas de Archivo<\/figcaption><\/figure>\n<p>Expertos del prestigioso Cuerpo M\u00e9dico Forense, dependiente de la Corte Suprema, concluyeron en 2015 que no hab\u00eda elementos para sostener que la muerte de Nisman fuera un asesinato.<br \/>\nMientras, en el peritaje de la Polic\u00eda Federal se determin\u00f3 que el fiscal se dispar\u00f3 con el arma frente al espejo del ba\u00f1o.<\/p>\n<p>Taiano dice que una dificultad de la investigaci\u00f3n es que la escena de la muerte no se preserv\u00f3 correctamente. Por ejemplo, unas 60 personas habr\u00edan caminado sin ning\u00fan cuidado por el apartamento de Nisman durante varias horas luego de que su cad\u00e1ver fue hallado por su madre y sus custodios. Adem\u00e1s, datos de su tel\u00e9fono celular y sus computadoras fueron eliminados.<br \/>\nLas c\u00e1maras de seguridad del edificio donde resid\u00eda Nisman no funcionaban desde d\u00edas antes de su muerte y polic\u00edas federales que custodiaban al fiscal son investigados.<br \/>\n\u201cEl desaf\u00edo es muy complejo\u201d, reconoci\u00f3 Taiano.<\/p>\n<p>\u201cSi el caso hubiera estado (investigado) de entrada de otra manera, hubiera sido otra cosa\u201d, se lament\u00f3 el fiscal, consciente de que la causa siempre provocar\u00e1 opiniones encontradas sin importar las conclusiones a las que se lleguen.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>A Nisman, fiscal a cargo de investigar el atentado terrorista de 1994 contra un centro jud\u00edo en Buenos Aires, lo encontraron muerto en su ba\u00f1o el 18 de enero de 2015. \u201cSuicidio\u201d, catalogaron las voces oficiales en aquel momento. Sin embargo, peritos de la Polic\u00eda de Fronteras ahora dicen que fue alguien m\u00e1s quien oblig\u00f3 al fiscal a apretar el gatillo.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":2,"featured_media":2086,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[9],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>El informe que dice que a Nisman lo asesinaron - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"El informe que dice que a Nisman lo asesinaron - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"A Nisman, fiscal a cargo de investigar el atentado terrorista de 1994 contra un centro jud\u00edo en Buenos Aires, lo encontraron muerto en su ba\u00f1o el 18 de enero de 2015. \u201cSuicidio\u201d, catalogaron las voces oficiales en aquel momento. Sin embargo, peritos de la Polic\u00eda de Fronteras ahora dicen que fue alguien m\u00e1s quien oblig\u00f3 al fiscal a apretar el gatillo.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-11-12T06:01:39+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-11T03:35:34+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1920\" \/>\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7s\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"AP\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min.jpg\",\"width\":1920,\"height\":1280,\"caption\":\"Fotograf\u00eda de Archivo\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/\",\"name\":\"El informe que dice que a Nisman lo asesinaron - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/#primaryimage\"},\"datePublished\":\"2017-11-12T06:01:39+00:00\",\"dateModified\":\"2017-11-11T03:35:34+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/3475da6220c51c41480f337ee3a7dc6e\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"El informe que dice que a Nisman lo asesinaron\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/3475da6220c51c41480f337ee3a7dc6e\",\"name\":\"AP\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/b8ba35da68ef10334c608dccc6dc9118?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/b8ba35da68ef10334c608dccc6dc9118?s=96&d=mm&r=g\",\"caption\":\"AP\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7s\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ap\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"El informe que dice que a Nisman lo asesinaron - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/","og_locale":"en_US","og_type":"article","og_title":"El informe que dice que a Nisman lo asesinaron - S\u00e9ptimo Sentido","og_description":"A Nisman, fiscal a cargo de investigar el atentado terrorista de 1994 contra un centro jud\u00edo en Buenos Aires, lo encontraron muerto en su ba\u00f1o el 18 de enero de 2015. \u201cSuicidio\u201d, catalogaron las voces oficiales en aquel momento. Sin embargo, peritos de la Polic\u00eda de Fronteras ahora dicen que fue alguien m\u00e1s quien oblig\u00f3 al fiscal a apretar el gatillo.","og_url":"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2017-11-12T06:01:39+00:00","article_modified_time":"2017-11-11T03:35:34+00:00","og_image":[{"width":1920,"height":1280,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7s","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"AP","Est. reading time":"7 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min.jpg","width":1920,"height":1280,"caption":"Fotograf\u00eda de Archivo"},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/","name":"El informe que dice que a Nisman lo asesinaron - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/#primaryimage"},"datePublished":"2017-11-12T06:01:39+00:00","dateModified":"2017-11-11T03:35:34+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/3475da6220c51c41480f337ee3a7dc6e"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/informe-dice-nisman-lo-asesinaron\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"El informe que dice que a Nisman lo asesinaron"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/3475da6220c51c41480f337ee3a7dc6e","name":"AP","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/b8ba35da68ef10334c608dccc6dc9118?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/b8ba35da68ef10334c608dccc6dc9118?s=96&d=mm&r=g","caption":"AP"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7s"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ap\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/fsep12112017arcalb022-min.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-xA","jetpack-related-posts":[{"id":3477,"url":"https:\/\/7s.laprensagrafica.com\/en\/abuso-de-menores-en-clubes-de-futbol-sacude-a-argentina\/","url_meta":{"origin":2082,"position":0},"title":"Abuso de menores en clubes de f\u00fatbol sacude a Argentina","date":"29 April, 2018","format":false,"excerpt":"La mayor\u00eda eran pobres y estaban lejos de sus familias. So\u00f1aban con triunfar en el f\u00fatbol. Pero las vidas de varios chicos que se alojaban en pensiones de dos de los principales clubes de Argentina se transformaron en una pesadilla cuando cayeron en una red de prostituci\u00f3n infantil.","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/04\/fsep29042018Ap7411479.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1809,"url":"https:\/\/7s.laprensagrafica.com\/en\/macri-logra-poder-reformar-argentina\/","url_meta":{"origin":2082,"position":1},"title":"Macri logra todo el poder para reformar Argentina","date":"29 October, 2017","format":false,"excerpt":"El l\u00edder de Propuesta Republicana (PRO) se convierte en el presidente m\u00e1s reforzado de Am\u00e9rica Latina.","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/macri-01.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4399,"url":"https:\/\/7s.laprensagrafica.com\/en\/nueve-expresidentes-de-america-latina-son-investigados-por-el-caso-odebrecht\/","url_meta":{"origin":2082,"position":2},"title":"Nueve expresidentes de Am\u00e9rica Latina son investigados por el caso Odebrecht","date":"9 September, 2018","format":false,"excerpt":"Las denuncias de Odebrecht implicaron a todos los expresidentes vivos de Brasil. Y no solo a ellos, en Latinoam\u00e9rica tambi\u00e9n est\u00e1n regados los sobornos de esta firma, de acuerdo con las declaraciones que el patriarca, Emilio, ha dado a las autoridades. Manuel Santos, de Colombia; y Mauricio Funes, en El\u2026","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/09\/fsep09092018shupre02.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5391,"url":"https:\/\/7s.laprensagrafica.com\/en\/vamos-por-un-gobiernoabierto\/","url_meta":{"origin":2082,"position":3},"title":"\u00bfVamos por un #GobiernoAbierto?","date":"17 March, 2019","format":false,"excerpt":"Nuestros compromisos como El Salvador en el Plan de Gobierno Abierto son cinco, divididos por cuatro \u00e1reas de trabajo.","rel":"","context":"In &quot;Opini\u00f3n desde ac\u00e1&quot;","img":{"alt_text":"Margarita Marroqu\u00edn","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/10\/margarita-marroquin-2018.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5414,"url":"https:\/\/7s.laprensagrafica.com\/en\/tribu-amazonica-acusa-de-atrocidades-al-ejercito-de-brasil\/","url_meta":{"origin":2082,"position":4},"title":"Tribu amaz\u00f3nica acusa de atrocidades al Ej\u00e9rcito de Brasil","date":"17 March, 2019","format":false,"excerpt":"Primero llegaron los helic\u00f3pteros lanzando bombas qu\u00edmicas. Luego vinieron hombres armados con uniformes verdes que procedieron a asesinar a miembros de una tribu del Amazonas para dar paso a un camino importante.","rel":"","context":"In &quot;Reportaje Internacional&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/03\/tribu-amazonas.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2735,"url":"https:\/\/7s.laprensagrafica.com\/en\/nadie-le-importo\/","url_meta":{"origin":2082,"position":5},"title":"A nadie le import\u00f3","date":"28 January, 2018","format":false,"excerpt":"En la \u00faltima d\u00e9cada, los cr\u00edmenes contra miembros de la comunidad LGBT aumentaron en 10 pa\u00edses de Am\u00e9rica Latina. En Brasil hubo 958 cr\u00edmenes en tres a\u00f1os y en Colombia 142 fueron masacrados en medio del conflicto armado.","rel":"","context":"In &quot;Reportaje&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/fnac28012018homlgbti2.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/2082"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=2082"}],"version-history":[{"count":1,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/2082\/revisions"}],"predecessor-version":[{"id":2087,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/2082\/revisions\/2087"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/2086"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=2082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=2082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=2082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}