{"id":1800,"date":"2017-10-29T00:04:18","date_gmt":"2017-10-29T06:04:18","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=1800"},"modified":"2017-10-27T20:45:49","modified_gmt":"2017-10-28T02:45:49","slug":"buzon-29-octubre-2017","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/","title":{"rendered":"Buz\u00f3n"},"content":{"rendered":"<figure id=\"attachment_1831\" style=\"width: 1600px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"1831\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/buzon-29-octubre-2017-2\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017.jpg\" data-orig-size=\"1600,965\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"buzon-29-octubre-2017\" data-image-description=\"&lt;p&gt;Buz\u00f3n&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Buz\u00f3n&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017-300x181.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017-1024x618.jpg\" loading=\"lazy\" class=\"size-full wp-image-1831\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017.jpg\" alt=\"\" width=\"1600\" height=\"965\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017.jpg 1600w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017-300x181.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017-768x463.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017-1024x618.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017-1200x724.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017-500x302.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017-1000x603.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017-700x422.jpg 700w\" sizes=\"(max-width: 1600px) 100vw, 1600px\" \/><figcaption class=\"wp-caption-text\">Buz\u00f3n<\/figcaption><\/figure>\n<h1>La discriminaci\u00f3n silenciosa<\/h1>\n<p>Jacinta Escudos siempre aborda esos temas tan sensibles, tan necesarios, tan vitales\u2026 Al leer su escrito revolotean en mi cabeza dos\u00a0 personajes que con la madurez de sus a\u00f1os, su conocimiento, su aporte, nos brindan una gran lecci\u00f3n de vida. Una de ellas es la doctora Mar\u00eda Isabel Rodr\u00edguez, ex ministra de Salud. Tengo el honor de visitarla en su lugar de residencia.\u00a0 Me dedico a la promoci\u00f3n y difusi\u00f3n de libros, motivo por el que le llevo las nuevas producciones literarias. La doctora es una persona que vive actualiz\u00e1ndose.<\/p>\n<p>Quisiera imitar su ejemplo, maravillarme al encanto de nuevos conocimientos. A pesar de que su entorno son libros (a veces pienso que se ha le\u00eddo casi todo en la vida) en su casa se respira el\u00a0 arte, la cultura, la ciencia. Ella siempre sabe sorprenderse al encuentro de nuevos saberes. En lo personal, al llegar a esa etapa de vida, quisiera tener su vitalidad. Pienso tambi\u00e9n en Jos\u00e9 Saramago, quien a sus 76 a\u00f1os obtuvo el premio Nobel de Literatura. Eso nos demuestra que conjuga los a\u00f1os recorridos para compartir la experiencia acumulada. A ambos deber\u00edamos considerarlos una fuente de inspiraci\u00f3n\u00a0 para imitar su ejemplo. Pero, \u00bfcu\u00e1ntos estar\u00e1n en el anonimato? y les condenamos a ese silencio estremecedor que menciona Jacinta.<\/p>\n<p><strong>Karina Amaya<\/strong><br \/>\nscoutkarina@gmail.com<\/p>\n<hr \/>\n<h1>La sempiterna brecha<\/h1>\n<p>No resulta ajeno a ning\u00fan pertinaz observador los esquemas mentales afincados en nuestra cultura que discriminan sin reparo a la mujer y que hace imposible alcanzar una igualdad total. En el reportaje \u201cEl espejismo femenino del poder pol\u00edtico\u201d de Valeria Guzm\u00e1n, se presentan los recuentos de la realidad pol\u00edtica de nuestro pa\u00eds que alimenta la sempiterna brecha de exclusi\u00f3n para optar a cargos p\u00fablicos y de elecci\u00f3n popular, uno de los irrefutables frentes de desigualdad entre hombres y mujeres. Las mujeres que incursionan las esferas de la pol\u00edtica tropiezan con muchas dificultades para su desarrollo y en no pocos casos con la oposici\u00f3n abierta de los hombres. Se ha quedado en el imaginario la at\u00e1vica divisi\u00f3n sexual del trabajo que socialmente asigna las labores p\u00fablicas a los hombres y los quehaceres dom\u00e9sticos a las mujeres, a veces en m\u00faltiples jornadas, a tal grado que se considera a la mujer como objeto y no como sujeto, ninguna ley contempla inhabilidad para las mujeres para ninguna actividad, por el contrario les oferta la oportunidad, pero los dirigentes ven esos derechos s\u00f3lo como parte del decorado de la legislaci\u00f3n.<\/p>\n<p>En la convenci\u00f3n sobre los derechos pol\u00edticos de la mujer aprobado por las Naciones Unidas se establece, m\u00e1s all\u00e1 del derecho pasivo al voto, que las mujeres tienen derecho a ser elegidas para cargos p\u00fablicos de elecci\u00f3n en igualdad de condiciones que los hombres y sin discriminaci\u00f3n, lo mismo que ejercer en toda la funci\u00f3n p\u00fablica. Y es que la protecci\u00f3n de los derechos de las mujeres en el ordenamiento jur\u00eddico internacional aparece desde 1948 cuando arranca la Declaraci\u00f3n Universal de los Derechos Humanos.<\/p>\n<p>Otro elemento importante es que si bien las mujeres son m\u00e1s, pero tambi\u00e9n son m\u00e1s las que desconocen sus derechos. Aunque hay una percepci\u00f3n en el aumento en las oportunidades a las mujeres salvadore\u00f1as, \u00e9stas no parecen estar incidiendo lo suficiente en su desarrollo; estudios recientes se\u00f1alan que una mayor igualdad en el hogar, donde los pap\u00e1s participen en el cuido, educaci\u00f3n y tareas dom\u00e9sticas favorecen las relaciones de familia, logrando un mejor equilibrio entre hombres y mujeres en el trabajo en general; dejar atr\u00e1s todas las formas de discriminaci\u00f3n contra la mujer, libre de subordinaci\u00f3n, nos beneficia a todos como sociedad. El hombre por su parte debe aprender a compartir responsabilidades hogare\u00f1as, abandonando esas im\u00e1genes machistas que a veces han sido inspiradas en contextos ancestrales.<\/p>\n<p><strong>Julio Roberto<\/strong><br \/>\nMaga\u00f1ajrobertomasa@hotmail.com<\/p>\n<hr \/>\n<h1>Discriminaci\u00f3n etaria<\/h1>\n<p>Este domingo Jacinta Escudos\u00a0 hizo un se\u00f1alamiento\u00a0 en su columna &#8220;La discriminaci\u00f3n\u00a0 silenciosa&#8221; en la cual, los empleados que pasamos de loS cincuenta a\u00f1os sufrimos de exclusi\u00f3n por parte de las empresas\u00a0 por ser un n\u00famero m\u00e1s en su engranaje, m\u00e1s si estamos por jubilarnos. Cada d\u00eda crece la tendencia en este pa\u00eds a promover la discriminaci\u00f3n etaria en la fuerza laboral en edad madura, implementando el desempleo masivo. Hoy en d\u00eda los patronos que solicitan empleados no aceptan a los que ofrecen madurez, estabilidad y experiencia por causa de la edad. Para muestra solo basta leer los anuncios de solicitud de nuevo personal\u00a0 donde proclaman los l\u00edmites m\u00e1ximos de edad y adoptan pol\u00edticas que promueven encubiertamente la discriminaci\u00f3n laboral por raz\u00f3n de la edad y este criterio es demasiado arbitrario para ser importante y lo aplican tambi\u00e9n en los procesos de promoci\u00f3n y ascensos.<\/p>\n<p>Hay empresas en los que los empleados de mayor edad experimentan una discriminaci\u00f3n encubierta como prescindir de ellos al momento de un ascenso y se les cede o presiona para que se jubilen anticipadamente para hacerle sitio a personal m\u00e1s joven que no les exija sus derechos laborales. Los se\u00f1alamientos que arguyen los empleadores para los empleados viejos\u00a0 son: que no son capaces de soportar el agotamiento f\u00edsico o mental, que no son adaptables a las pol\u00edticas explotadoras y que un empleado viejo es menos flexible y que por consecuencia menos eficiente y productivo, tienen m\u00e1s ausencias por causas de enfermedades y accidentes y, por \u00faltimo, no capacitan a un empleado viejo que solo servir\u00e1 a la empresa unos pocos a\u00f1os antes de su retiro. Algunos argumentos esgrimidos son m\u00e1s que mentiras. Lo que pudiera faltarle al trabajador maduro lo compensa con su experiencia.<\/p>\n<p>Tampoco es cierto que se ausente m\u00e1s del trabajo que el empleado joven ya que tiene la probabilidad que llegue m\u00e1s temprano o se quede m\u00e1s tiempo en sus labores. La actitud de un empleado, su experiencia, estabilidad, entusiasmo y habilidad no dependen necesariamente de la edad. Adem\u00e1s, posee m\u00e1s juicio, lealtad y menores posibilidades de irse de la empresa, aprovecha mejor el tiempo y esfuerzo que los empleados j\u00f3venes e infunden un mayor respeto. En nuestro pa\u00eds debemos romper paradigmas para que las leyes protejan a las personas que pasamos la edad que\u00a0 los empresarios llaman &#8220;el l\u00edmite de edad productiva&#8221;.<\/p>\n<p><strong>Rutilio L\u00f3pez Cortez<\/strong><br \/>\nrutilio_lopezcortez@outlook.com<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Jacinta Escudos siempre aborda esos temas tan sensibles, tan necesarios, tan vitales\u2026 Al leer su escrito revolotean en mi cabeza dos\u00a0 personajes que con la madurez de sus a\u00f1os, su conocimiento, su aporte, nos brindan una gran lecci\u00f3n de vida.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":1831,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-buzon.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Buz\u00f3n - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buz\u00f3n - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Jacinta Escudos siempre aborda esos temas tan sensibles, tan necesarios, tan vitales\u2026 Al leer su escrito revolotean en mi cabeza dos\u00a0 personajes que con la madurez de sus a\u00f1os, su conocimiento, su aporte, nos brindan una gran lecci\u00f3n de vida.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-29T06:04:18+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-28T02:45:49+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1600\" \/>\n\t<meta property=\"og:image:height\" content=\"965\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9ptimo Sentido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017.jpg\",\"width\":1600,\"height\":965,\"caption\":\"Buz\u00f3n\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/\",\"name\":\"Buz\u00f3n - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/#primaryimage\"},\"datePublished\":\"2017-10-29T06:04:18+00:00\",\"dateModified\":\"2017-10-28T02:45:49+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buz\u00f3n\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\",\"name\":\"S\u00e9ptimo Sentido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"caption\":\"S\u00e9ptimo Sentido\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buz\u00f3n - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/","og_locale":"en_US","og_type":"article","og_title":"Buz\u00f3n - S\u00e9ptimo Sentido","og_description":"Jacinta Escudos siempre aborda esos temas tan sensibles, tan necesarios, tan vitales\u2026 Al leer su escrito revolotean en mi cabeza dos\u00a0 personajes que con la madurez de sus a\u00f1os, su conocimiento, su aporte, nos brindan una gran lecci\u00f3n de vida.","og_url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2017-10-29T06:04:18+00:00","article_modified_time":"2017-10-28T02:45:49+00:00","og_image":[{"width":1600,"height":965,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"S\u00e9ptimo Sentido","Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017.jpg","width":1600,"height":965,"caption":"Buz\u00f3n"},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/","name":"Buz\u00f3n - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/#primaryimage"},"datePublished":"2017-10-29T06:04:18+00:00","dateModified":"2017-10-28T02:45:49+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-octubre-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Buz\u00f3n"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b","name":"S\u00e9ptimo Sentido","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","caption":"S\u00e9ptimo Sentido"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-29-octubre-2017.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-t2","jetpack-related-posts":[{"id":873,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-30-julio-2017\/","url_meta":{"origin":1800,"position":0},"title":"Buz\u00f3n","date":"30 July, 2017","format":false,"excerpt":"Nuevamente tengo el privilegio y la oportunidad de agradecerle al autor de la p\u00e1gina Escribiviendo por conducirme por los senderos hist\u00f3ricos que evoca en m\u00ed la lectura \u201cRecuerdos de un pasado presente\u201d.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/07\/buzon002-1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2566,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-07-enero-2018\/","url_meta":{"origin":1800,"position":1},"title":"Buz\u00f3n","date":"7 January, 2018","format":false,"excerpt":"Qu\u00e9 grato es leer sobre mujeres que est\u00e1n por encima de un amplio sector de la poblaci\u00f3n, cada una en su campo han sabido destacar con solvencia.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/01\/Septimo-Sentido-General-31_12_2017-10.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4258,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-12-agosto-2018\/","url_meta":{"origin":1800,"position":2},"title":"Buz\u00f3n","date":"12 August, 2018","format":false,"excerpt":"Siempre estoy pendiente de la revista, pero no he podido escribir por cuestiones laborales. Hace unos domingos, Mariana Belloso llev\u00f3 el tema de la educaci\u00f3n sexual de nuevo a reflexi\u00f3n.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/08\/mariana.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":114,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-3\/","url_meta":{"origin":1800,"position":3},"title":"BUZ\u00d3N","date":"12 March, 2017","format":false,"excerpt":"Julio Roberto Maga\u00f1a robertomasa@hotmail.com El milagro de nacer La maravilla de un embarazo planeado es un evento que debe considerarse como un prodigio sin parang\u00f3n. Ese ciclo de hospedaje \u00edntimo que la mujer provee durante la gestaci\u00f3n requiere una esmerada atenci\u00f3n incluida la educaci\u00f3n. Lamentable es ese 28% de partos\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/06\/fsep12032017arcpdf01.pdf.png?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2417,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-17-diciembre-2017\/","url_meta":{"origin":1800,"position":4},"title":"Buz\u00f3n","date":"17 December, 2017","format":false,"excerpt":"El mundo se divide entre quienes leen y los que no leen. El amor por los libros debe cimentarse en el mejor de los casos en compa\u00f1\u00eda de la leche materna; un h\u00e1bito cari\u00f1oso a temperatura temprana en el mundo de la palabra.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/12\/buzon-17-diciembre-2017.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":4151,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-29-julio-2018\/","url_meta":{"origin":1800,"position":5},"title":"Buz\u00f3n","date":"29 July, 2018","format":false,"excerpt":"La necesidad de contar con m\u00e1s bibliotecas en el sistema educativo de El Salvador Es muy preocupante la situaci\u00f3n de las escuelas que no tienen bibliotecas. De esta manera se nota lo poco que al Ministerio de Educaci\u00f3n le ha importado la instrucci\u00f3n que se da a los ni\u00f1os. Esta\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/07\/fsep22072018agbib08.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/1800"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=1800"}],"version-history":[{"count":2,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/1800\/revisions"}],"predecessor-version":[{"id":1832,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/1800\/revisions\/1832"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/1831"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=1800"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=1800"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=1800"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}