{"id":1753,"date":"2017-10-22T00:04:16","date_gmt":"2017-10-22T06:04:16","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=1753"},"modified":"2017-10-21T20:20:31","modified_gmt":"2017-10-22T02:20:31","slug":"buzon-22-octubre-2017","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/","title":{"rendered":"Buz\u00f3n"},"content":{"rendered":"<figure id=\"attachment_1781\" style=\"width: 1476px\"  class=\"wp-caption aligncenter\"><img data-attachment-id=\"1781\" data-permalink=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/buzon-22-octubre-2017-2\/\" data-orig-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017.jpg\" data-orig-size=\"1476,888\" data-comments-opened=\"1\" data-image-meta=\"{&quot;aperture&quot;:&quot;0&quot;,&quot;credit&quot;:&quot;&quot;,&quot;camera&quot;:&quot;&quot;,&quot;caption&quot;:&quot;&quot;,&quot;created_timestamp&quot;:&quot;0&quot;,&quot;copyright&quot;:&quot;&quot;,&quot;focal_length&quot;:&quot;0&quot;,&quot;iso&quot;:&quot;0&quot;,&quot;shutter_speed&quot;:&quot;0&quot;,&quot;title&quot;:&quot;&quot;,&quot;orientation&quot;:&quot;0&quot;}\" data-image-title=\"buzon-22-octubre-2017\" data-image-description=\"&lt;p&gt;Buz\u00f3n&lt;\/p&gt;\n\" data-image-caption=\"&lt;p&gt;Buz\u00f3n&lt;\/p&gt;\n\" data-medium-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017-300x180.jpg\" data-large-file=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017-1024x616.jpg\" loading=\"lazy\" class=\"img-responsive wp-image-1781 size-full\" src=\"http:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017.jpg\" alt=\"\" width=\"1476\" height=\"888\" srcset=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017.jpg 1476w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017-300x180.jpg 300w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017-768x462.jpg 768w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017-1024x616.jpg 1024w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017-1200x722.jpg 1200w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017-500x301.jpg 500w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017-1000x602.jpg 1000w, https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017-700x421.jpg 700w\" sizes=\"(max-width: 1476px) 100vw, 1476px\" \/><figcaption class=\"wp-caption-text\">Buz\u00f3n<\/figcaption><\/figure>\n<h1>Vil negocio<\/h1>\n<p>El lavado de dinero es una actividad delictiva que tiene impactos letales en la vida econ\u00f3mica de los pa\u00edses donde pernocta; vil negocio que pasa casi inadvertido por mucha gente. La legitimaci\u00f3n de activos originados en movimientos il\u00edcitos con su alto poder corruptor impacta la institucionalidad de un Estado. Los delitos que preceden al lavado crean redes de procesos y empresas que corrompen una diversidad de instituciones p\u00fablicas y privadas; lo que ser\u00eda suficiente para hacer los m\u00e1ximos esfuerzos para fortalecer la prevenci\u00f3n y persecuci\u00f3n de ese ignominioso monstruo, m\u00e1s cuando se trata de entidades fr\u00e1giles como las nuestras que sufren toda clase de drenajes de los recursos p\u00fablicos. Aunque la experiencia muestra que no siempre va a ser dinero lo que se derive de esos blanqueos delictivos.<\/p>\n<p>El lavador trata de desprenderse de las cuantiosas sumas en efectivo, desliga los fondos il\u00edcitos de su origen y procura la integraci\u00f3n final de su riqueza obtenida por medios il\u00edcitos a las esferas econ\u00f3micas oficiales. De esa manera, ese brote agresivo se vuelve espinoso desaf\u00edo para las autoridades competentes, porque a ese nivel es m\u00e1s complicado diferenciar el origen de los capitales obtenidos il\u00edcitamente de los de origen legal, salvo que se tenga un historial exhaustivo del recorrido indebido del billete.<\/p>\n<p>La compraventa de inmuebles con testaferros o familiares es uno de los artificios habituales, y se puede llegar hasta sofisticadas argucias donde las inversiones son parte de una estrategia m\u00e1s amplia en la que se involucran compa\u00f1\u00edas y empresas \u201cpantalla\u201d, y pr\u00e9stamos simulados donde el delincuente se presta a s\u00ed mismo, por ah\u00ed enrumban los para\u00edsos fiscales.<\/p>\n<p>En su entrega dominical \u201cLas reformas que buscan cercar el lavado de dinero\u201d, Mois\u00e9s Alvarado relaciona el impulso creciente que va conquistando el crimen organizado, tal vez m\u00e1s organizado que el mismo Estado, con la participaci\u00f3n de funcionarios que han ca\u00eddo en las tentaciones que quebrantan el orden jur\u00eddico, social y moral. Basta caminar por pueblos y ciudades donde de la noche a la ma\u00f1ana aparecen inmensas construcciones con enormes negocios con propietarios que nunca han sido acomodados. En las fronteras hay propiedades compradas con el dinero del mal que involucra a dos pa\u00edses, y sus due\u00f1os se desplazan con toda libertad por esos linderos a la luz de los uniformes, que supuestamente custodian esos confines. El grado de posicionamiento es asombroso, ya que mutan en sus estrategias y burlan la enclenque legislaci\u00f3n vigente.<\/p>\n<p><strong>Julio Roberto Maga\u00f1a Salinas<\/strong><br \/>\njrobertomasa@hotmail.com<\/p>\n<hr \/>\n<h1>Argelia: Amada Libertad, mujer solidaria<\/h1>\n<p>Como ya es habitual, las ma\u00f1anas de domingo son especiales. Como rutina que se vuelve h\u00e1bito, espero LA PRENSA GR\u00c1FICA, en especial S\u00e9ptimo Sentido, el que colecciono y pasa a formar parte de mi biblioteca personal. Esta vez, mi lectura se centr\u00f3 en una amiga, Argelia Quintana.<br \/>\nConoc\u00ed a Argelia por el a\u00f1o 2000, hab\u00eda decidido irme de casa, necesitaba abrir camino, estudiar, buscar un trabajo&#8230; Argelia adem\u00e1s de ser una mujer persistente, decidida y con un entra\u00f1able amor por su hija, que conocemos a trav\u00e9s de ella, \u2014Leyla, su amada libertad\u2014, es una mujer solidaria, para m\u00ed fue de esos \u00e1ngeles que encontr\u00e9 a mi paso, se convirti\u00f3 en un pelda\u00f1o, cuando me abri\u00f3 las puertas de su casa, de su amistad. Conozco de su lucha constante, de su amor por la vida, de su perseverancia. Infinitas gracias, Argelia, por compartirnos tu testimonio y tu ejemplo.<\/p>\n<p><strong>Karina Amaya<\/strong><br \/>\nscoutkarina@gmail.com<\/p>\n<hr \/>\n<h1>Divididos por categor\u00edas<\/h1>\n<p>En nuestro pa\u00eds, todos estamos ubicados en una estratificaci\u00f3n social, que es la desigualdad que nos estructura entre distintos agrupamientos de individuos donde nos ubican. El sistema pol\u00edtico y social permite que seamos reconocidos de acuerdo con diferentes criterios de categorizaci\u00f3n de poder, prestigio, propiedad o ingreso. Por esta raz\u00f3n, basados en una de las caracter\u00edsticas universales de la sociedad humana: la diferenciaci\u00f3n social, es como en nuestro pa\u00eds existen estratos en la educaci\u00f3n, la salud y el trabajo.<\/p>\n<p>La estratificaci\u00f3n social es un estimulante para las personas calificadas, que posibilita el buen funcionamiento de la sociedad, en la cual los miembros tienen la sensaci\u00f3n de que se ha hecho justicia con ellos cuando se les valora como superiores o inferiores de acuerdo con las normas valorativas de su entorno. Si no existe ese sentimiento de justicia cumplida, sobreviene la apat\u00eda de los mejores, como sucede en algunos centros de trabajo. La columna del periodista Sigfredo Ram\u00edrez, \u201cDe cuarta categor\u00eda\u201d, viene como anillo al dedo. Dada las diversas circunstancias que todos vivimos, somos nosotros los que permitimos que nos ubiquen, como en algunos bancos que tienen una base de datos y que al realizar una transacci\u00f3n atienden primero al que les genera m\u00e1s ingresos; y permitimos esa desigualdad para que no se cumpla el art\u00edculo 3 de nuestra Constituci\u00f3n.<\/p>\n<p>Hace falta una reflexi\u00f3n sobre el trabajo, los derechos humanos y el resto de nuestro entorno, que mejore los m\u00e9todos de aproximaci\u00f3n a la realidad que vivimos. Por esta raz\u00f3n agradezco que S\u00e9ptimo Sentido nos abra un espacio para un encuentro de investigaci\u00f3n y de herramientas conceptuales que pueden generar buenos resultados en un futuro pr\u00f3ximo.<\/p>\n<p><strong>Rutilio L\u00f3pez Cortez<\/strong><br \/>\nrutilio_lopezcortez@outlook.com<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>El lavado de dinero es una actividad delictiva que tiene impactos letales en la vida econ\u00f3mica de los pa\u00edses donde pernocta; vil negocio que pasa casi inadvertido por mucha gente.<!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":1781,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-buzon.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[5],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Buz\u00f3n - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Buz\u00f3n - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"El lavado de dinero es una actividad delictiva que tiene impactos letales en la vida econ\u00f3mica de los pa\u00edses donde pernocta; vil negocio que pasa casi inadvertido por mucha gente.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-10-22T06:04:16+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-10-22T02:20:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1476\" \/>\n\t<meta property=\"og:image:height\" content=\"888\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9ptimo Sentido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"5 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017.jpg\",\"width\":1476,\"height\":888,\"caption\":\"Buz\u00f3n\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/\",\"name\":\"Buz\u00f3n - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/#primaryimage\"},\"datePublished\":\"2017-10-22T06:04:16+00:00\",\"dateModified\":\"2017-10-22T02:20:31+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Buz\u00f3n\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\",\"name\":\"S\u00e9ptimo Sentido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"caption\":\"S\u00e9ptimo Sentido\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Buz\u00f3n - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/","og_locale":"en_US","og_type":"article","og_title":"Buz\u00f3n - S\u00e9ptimo Sentido","og_description":"El lavado de dinero es una actividad delictiva que tiene impactos letales en la vida econ\u00f3mica de los pa\u00edses donde pernocta; vil negocio que pasa casi inadvertido por mucha gente.","og_url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2017-10-22T06:04:16+00:00","article_modified_time":"2017-10-22T02:20:31+00:00","og_image":[{"width":1476,"height":888,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"S\u00e9ptimo Sentido","Est. reading time":"5 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017.jpg","width":1476,"height":888,"caption":"Buz\u00f3n"},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/","name":"Buz\u00f3n - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/#primaryimage"},"datePublished":"2017-10-22T06:04:16+00:00","dateModified":"2017-10-22T02:20:31+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/en\/buzon-22-octubre-2017\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"Buz\u00f3n"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b","name":"S\u00e9ptimo Sentido","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","caption":"S\u00e9ptimo Sentido"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/10\/buzon-22-octubre-2017.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-sh","jetpack-related-posts":[{"id":1562,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-01-octubre-2017\/","url_meta":{"origin":1753,"position":0},"title":"Buz\u00f3n","date":"1 October, 2017","format":false,"excerpt":"\u00c1ngel guardi\u00e1n del enfermo Cuando ya se ha superado el golpe emocional del diagn\u00f3stico, atender al enfermo en su casa supone un verdadero reto para la familia, lo que sigue es el acomodo de espacios en el hogar para ofrecerle al infortunado el mejor confort. Sin embargo, por varias razones\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/09\/buzon-el-ocaso-de-ana.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1458,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-17-septiembre-2017\/","url_meta":{"origin":1753,"position":1},"title":"Buz\u00f3n","date":"17 September, 2017","format":false,"excerpt":"Pap\u00e1 perdi\u00f3 el olfato y mi rinitis fue provocada por el aserr\u00edn de la madera de su taller. Lo veo aserruchar los perfumados laureles, los pinos, los conacastes, los cen\u00edceros y lijar los bellos caobas: todo ese aserr\u00edn lo llevo almacenado en el coraz\u00f3n.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/09\/el-llamado-de-la-poesia.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1166,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-20-agosto-2017\/","url_meta":{"origin":1753,"position":2},"title":"Buz\u00f3n","date":"20 August, 2017","format":false,"excerpt":"Extorsi\u00f3n e impunidad Deseo felicitar a Mois\u00e9s Alvarado por su investigaci\u00f3n period\u00edstica sobre el delito de extorsi\u00f3n, as\u00ed como a los investigadores policiales que diligente y exitosamente culminaron sus averiguaciones sobre los casos abordados. Ciertamente admiro a los investigadores que profundizan en su trabajo y merecen los cr\u00e9ditos respectivos. Desafortunadamente\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"Buz\u00f3n","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/08\/buzon-20-agosto-2017.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":1052,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-06-agosto-2017\/","url_meta":{"origin":1753,"position":3},"title":"Buz\u00f3n","date":"6 August, 2017","format":false,"excerpt":"Captores de sucesos Es alentador que SECULTURA por fin haya tomado en cuenta para el Premio Nacional de Cultura a los profesionales del fotoperiodismo que nos ofrecen escenas con mucha riqueza en contenido de lo que pasa en el pa\u00eds. Los reporteros gr\u00e1ficos siempre han estado marginados, a pesar de\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"Buz\u00f3n","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/08\/buzon-6.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2100,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-12-noviembre-2017\/","url_meta":{"origin":1753,"position":4},"title":"Buz\u00f3n","date":"12 November, 2017","format":false,"excerpt":"Ya se ha repetido tantas veces que la violencia en El Salvador es un problema complejo que debe ser abordado alejado de an\u00e1lisis simplistas y de emociones partidarias, pues estamos en una sociedad condensada en blanco y negro en donde se pierde con facilidad la riqueza de una reflexi\u00f3n que\u2026","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/11\/buzon-12-nov-2017.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":3168,"url":"https:\/\/7s.laprensagrafica.com\/en\/buzon-25-marzo-2018\/","url_meta":{"origin":1753,"position":5},"title":"Buz\u00f3n","date":"25 March, 2018","format":false,"excerpt":"Fue muy interesante el art\u00edculo de la AP en 7S sobre la desconfianza que los brasile\u00f1os tienen hacia las vacunas contra la fiebre amarilla.","rel":"","context":"In &quot;Buz\u00f3n&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2018\/03\/Septimo-Sentido-General-18_03_2018-18.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/1753"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=1753"}],"version-history":[{"count":3,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/1753\/revisions"}],"predecessor-version":[{"id":1783,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/1753\/revisions\/1783"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/1781"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=1753"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=1753"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=1753"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}