{"id":1047,"date":"2017-08-06T00:05:04","date_gmt":"2017-08-06T06:05:04","guid":{"rendered":"http:\/\/7s.laprensagrafica.com\/?p=1047"},"modified":"2017-08-05T17:00:31","modified_gmt":"2017-08-05T23:00:31","slug":"costo-no-lo-estamos-mas-alto-hacerlo","status":"publish","type":"post","link":"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/","title":{"rendered":"&#8220;El costo de no hacer lo que estamos haciendo es m\u00e1s alto que hacerlo&#8221;"},"content":{"rendered":"<h4>\u00bfHay algo que de tener m\u00e1s\/menos marcar\u00eda alguna diferencia en tu vida?<\/h4>\n<p>Tener internet 24 horas disponible. Dejo de hacer tantas cosas por no tenerlo que a veces el tiempo me parece lastimosamente desperdiciado.<\/p>\n<h4>\u00bfQu\u00e9 est\u00e1s soportando o tolerando actualmente que no te haga feliz?<\/h4>\n<p>El miedo inducido a cosas que no deber\u00edan asustar. Y el malabarismo de argumentos que integran eso que se ha dado en llamar la \u201cpostverdad\u201d, los \u201calternative facts\u201d, que es mentir por omisi\u00f3n y no es solo un fen\u00f3meno de Donald Trump o pol\u00edticos capitalistas\u2026<\/p>\n<h4>\u00bfQu\u00e9 es lo que tiene m\u00e1s valor de tu situaci\u00f3n actual?<\/h4>\n<p>En oposici\u00f3n a lo anterior, la valent\u00eda de mis colegas. Aquellos que han comprendido que el costo de no hacer lo que estamos haciendo es m\u00e1s alto que hacerlo. Ellos son los que me inspiran y me hacen sentir que estoy impulsando un cambio que llegar\u00e1 m\u00e1s temprano que tarde.<\/p>\n<h4>\u00bfCu\u00e1l ha sido el mayor atrevimiento de tu vida?<\/h4>\n<p>Quedarme en Cuba a pesar de que toda mi familia se fue.<\/p>\n<h4>\u00bfPeriodismo en Cuba es sin\u00f3nimo de utop\u00eda?<\/h4>\n<p>No. Es un oficio hermoso y necesario, que ha atra\u00eddo a gente con talento y compromiso social y empieza a mostrar sus resultados. Por eso le temen tanto aquellos que acumulan cuotas de poder.<\/p>\n<h4>\u00bfHar\u00edas periodismo en otro pa\u00eds?<\/h4>\n<p>Por supuesto que s\u00ed, y con mucha humildad, tratando de ofrecer con mi mirada de extranjero una luz fresca sobre cosas que de tan sumidos en su cotidianidad no vean los locales. Lo har\u00eda (es m\u00e1s, espero hacerlo alguna vez) porque lo considero un ejercicio necesario de entrenamiento y adquisici\u00f3n de \u201cknow how\u201d para luego aplicarlo en Cuba.<\/p>\n<h4>\u00bfCu\u00e1nto impacto puede generar un medio como El Toque en la Cuba actual?<\/h4>\n<p>Menos del que quisi\u00e9ramos, pero con el alcance que hemos sido capaces de crear, empezamos a ver la satisfacci\u00f3n en la audiencia por encontrarse contenidos que nadie les ofrece o les sirven para tomar decisiones en su vida.<\/p>\n<!-- AddThis Advanced Settings generic via filter on the_content --><!-- AddThis Share Buttons generic via filter on the_content -->","protected":false},"excerpt":{"rendered":"<p>Jos\u00e9 Jas\u00e1n Nieves es un periodista cubano nacido en 1987. Es el coordinador de la plataforma El Toque (eltoque.com), uno de los medios alternativos que han aparecido en Cuba en los \u00faltimos a\u00f1os (como El Estornudo y Periodismo de Barrio) gracias a la apertura de internet en la isla, que ofrecen historias sobre la cotidianidad de una naci\u00f3n que apenas ahora ha comenzado a abrirse al mundo. Jos\u00e9 se define a s\u00ed mismo como \u201cperiodista y conversador a tiempo completo\u201d.  <!-- AddThis Advanced Settings generic via filter on get_the_excerpt --><!-- AddThis Share Buttons generic via filter on get_the_excerpt --><\/p>\n","protected":false},"author":6,"featured_media":1048,"comment_status":"open","ping_status":"open","sticky":false,"template":"single-preguntas.php","format":"standard","meta":{"spay_email":"","jetpack_publicize_message":"","jetpack_is_tweetstorm":false,"jetpack_publicize_feature_enabled":true},"categories":[6],"tags":[34],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v18.1 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>&quot;El costo de no hacer lo que estamos haciendo es m\u00e1s alto que hacerlo&quot; - S\u00e9ptimo Sentido<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"&quot;El costo de no hacer lo que estamos haciendo es m\u00e1s alto que hacerlo&quot; - S\u00e9ptimo Sentido\" \/>\n<meta property=\"og:description\" content=\"Jos\u00e9 Jas\u00e1n Nieves es un periodista cubano nacido en 1987. Es el coordinador de la plataforma El Toque (eltoque.com), uno de los medios alternativos que han aparecido en Cuba en los \u00faltimos a\u00f1os (como El Estornudo y Periodismo de Barrio) gracias a la apertura de internet en la isla, que ofrecen historias sobre la cotidianidad de una naci\u00f3n que apenas ahora ha comenzado a abrirse al mundo. Jos\u00e9 se define a s\u00ed mismo como \u201cperiodista y conversador a tiempo completo\u201d.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/\" \/>\n<meta property=\"og:site_name\" content=\"S\u00e9ptimo Sentido\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:author\" content=\"https:\/\/www.facebook.com\/revista7S\/\" \/>\n<meta property=\"article:published_time\" content=\"2017-08-06T06:05:04+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2017-08-05T23:00:31+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/08\/Sietepreguntas.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"1200\" \/>\n\t<meta property=\"og:image:height\" content=\"800\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@revista7S\" \/>\n<meta name=\"twitter:site\" content=\"@sept_sentido\" \/>\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"S\u00e9ptimo Sentido\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\",\"url\":\"http:\/\/7s.laprensagrafica.com\/\",\"name\":\"S\u00e9ptimo Sentido\",\"description\":\"Un revista de La Prensa Gr\u00e1fica\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"en-US\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/#primaryimage\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/08\/Sietepreguntas.jpg\",\"contentUrl\":\"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/08\/Sietepreguntas.jpg\",\"width\":1200,\"height\":800},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/#webpage\",\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/\",\"name\":\"\\\"El costo de no hacer lo que estamos haciendo es m\u00e1s alto que hacerlo\\\" - S\u00e9ptimo Sentido\",\"isPartOf\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/#primaryimage\"},\"datePublished\":\"2017-08-06T06:05:04+00:00\",\"dateModified\":\"2017-08-05T23:00:31+00:00\",\"author\":{\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\"},\"breadcrumb\":{\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"http:\/\/7s.laprensagrafica.com\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"&#8220;El costo de no hacer lo que estamos haciendo es m\u00e1s alto que hacerlo&#8221;\"}]},{\"@type\":\"Person\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b\",\"name\":\"S\u00e9ptimo Sentido\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"http:\/\/7s.laprensagrafica.com\/#personlogo\",\"inLanguage\":\"en-US\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g\",\"caption\":\"S\u00e9ptimo Sentido\"},\"sameAs\":[\"https:\/\/www.facebook.com\/revista7S\/\",\"https:\/\/twitter.com\/revista7S\"],\"url\":\"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"\"El costo de no hacer lo que estamos haciendo es m\u00e1s alto que hacerlo\" - S\u00e9ptimo Sentido","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/","og_locale":"en_US","og_type":"article","og_title":"\"El costo de no hacer lo que estamos haciendo es m\u00e1s alto que hacerlo\" - S\u00e9ptimo Sentido","og_description":"Jos\u00e9 Jas\u00e1n Nieves es un periodista cubano nacido en 1987. Es el coordinador de la plataforma El Toque (eltoque.com), uno de los medios alternativos que han aparecido en Cuba en los \u00faltimos a\u00f1os (como El Estornudo y Periodismo de Barrio) gracias a la apertura de internet en la isla, que ofrecen historias sobre la cotidianidad de una naci\u00f3n que apenas ahora ha comenzado a abrirse al mundo. Jos\u00e9 se define a s\u00ed mismo como \u201cperiodista y conversador a tiempo completo\u201d.","og_url":"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/","og_site_name":"S\u00e9ptimo Sentido","article_publisher":"https:\/\/www.facebook.com\/revista7S\/","article_author":"https:\/\/www.facebook.com\/revista7S\/","article_published_time":"2017-08-06T06:05:04+00:00","article_modified_time":"2017-08-05T23:00:31+00:00","og_image":[{"width":1200,"height":800,"url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/08\/Sietepreguntas.jpg","type":"image\/jpeg"}],"twitter_card":"summary_large_image","twitter_creator":"@revista7S","twitter_site":"@sept_sentido","twitter_misc":{"Written by":"S\u00e9ptimo Sentido","Est. reading time":"2 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebSite","@id":"http:\/\/7s.laprensagrafica.com\/#website","url":"http:\/\/7s.laprensagrafica.com\/","name":"S\u00e9ptimo Sentido","description":"Un revista de La Prensa Gr\u00e1fica","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/7s.laprensagrafica.com\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"en-US"},{"@type":"ImageObject","@id":"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/#primaryimage","inLanguage":"en-US","url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/08\/Sietepreguntas.jpg","contentUrl":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/08\/Sietepreguntas.jpg","width":1200,"height":800},{"@type":"WebPage","@id":"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/#webpage","url":"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/","name":"\"El costo de no hacer lo que estamos haciendo es m\u00e1s alto que hacerlo\" - S\u00e9ptimo Sentido","isPartOf":{"@id":"http:\/\/7s.laprensagrafica.com\/#website"},"primaryImageOfPage":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/#primaryimage"},"datePublished":"2017-08-06T06:05:04+00:00","dateModified":"2017-08-05T23:00:31+00:00","author":{"@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b"},"breadcrumb":{"@id":"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/7s.laprensagrafica.com\/en\/costo-no-lo-estamos-mas-alto-hacerlo\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"http:\/\/7s.laprensagrafica.com\/"},{"@type":"ListItem","position":2,"name":"&#8220;El costo de no hacer lo que estamos haciendo es m\u00e1s alto que hacerlo&#8221;"}]},{"@type":"Person","@id":"http:\/\/7s.laprensagrafica.com\/#\/schema\/person\/68b391fa96170e0239c5d23872dd612b","name":"S\u00e9ptimo Sentido","image":{"@type":"ImageObject","@id":"http:\/\/7s.laprensagrafica.com\/#personlogo","inLanguage":"en-US","url":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/201f507f5a747415a203d69aebc6fb2d?s=96&d=mm&r=g","caption":"S\u00e9ptimo Sentido"},"sameAs":["https:\/\/www.facebook.com\/revista7S\/","https:\/\/twitter.com\/revista7S"],"url":"https:\/\/7s.laprensagrafica.com\/en\/author\/ssentido\/"}]}},"jetpack_featured_media_url":"https:\/\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/08\/Sietepreguntas.jpg","jetpack_publicize_connections":[],"jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p91Eoh-gT","jetpack-related-posts":[{"id":6078,"url":"https:\/\/7s.laprensagrafica.com\/en\/liderar-una-orquesta-no-habia-estado-en-mi-lista-de-propositos-para-el-futuro\/","url_meta":{"origin":1047,"position":0},"title":"&#8220;Liderar una orquesta no hab\u00eda estado en mi lista de prop\u00f3sitos para el futuro&#8221;","date":"28 July, 2019","format":false,"excerpt":"Es el coordinador general de la Orquesta Mar\u00eda de Baratta y exintegrante de la Orquesta Sinf\u00f3nica Juvenil de El Salvador, donde por ocho a\u00f1os interpret\u00f3 la viola. Este a\u00f1o viaj\u00f3 a Costa Rica para ser parte del Primer Simposio de Maestros, M\u00fasicos y Gestores Culturales de Iberoam\u00e9rica, coordinado por la\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/07\/fsep27072019xxfabricio1.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":5095,"url":"https:\/\/7s.laprensagrafica.com\/en\/es-un-derecho-sentirnos-seguros-en-nuestra-propia-tierra\/","url_meta":{"origin":1047,"position":1},"title":"\u201cEs un derecho sentirnos seguros en nuestra propia tierra\u201d","date":"13 January, 2019","format":false,"excerpt":"Es bailarina, maestra y core\u00f3grafa de danzas urbanas. Inici\u00f3 su formaci\u00f3n art\u00edstica hace nueve a\u00f1os en El Salvador, Costa Rica y Estados Unidos. En 2015 se especializ\u00f3 en estilo urbano Waacking y se gradu\u00f3 de la Licenciatura en Mercadeo. Ha participado representando a El Salvador en competencias internacionales de hip\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2019\/01\/fsep10012019corbai33.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7195,"url":"https:\/\/7s.laprensagrafica.com\/en\/el-docente-debe-investigar-ir-a-la-vanguardia\/","url_meta":{"origin":1047,"position":2},"title":"&#8220;El docente debe investigar, ir a la vanguardia&#8221;","date":"2 February, 2020","format":false,"excerpt":"[:es]Sey Najarro es licenciada para la Ense\u00f1anza del Idioma Ingl\u00e9s. Cuando termin\u00f3 su bachillerato, Najarro quer\u00eda estudiar pediatr\u00eda, pero no pod\u00eda costearse los estudios, as\u00ed que opt\u00f3 por los idiomas, otra de sus pasiones, que la ha llevado a dedicarse por completo a la ense\u00f1anza del ingl\u00e9s. Actualmente es coordinadora\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/02\/fsep02022020arcmae02.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":2502,"url":"https:\/\/7s.laprensagrafica.com\/en\/la-fe-transformar-una-sociedad\/","url_meta":{"origin":1047,"position":3},"title":"\u201cLa fe debe transformar una sociedad\u201d","date":"31 December, 2017","format":false,"excerpt":"Sime\u00f3n Reyes es un sacerdote salvadore\u00f1o nacido en Tepecoyo, La Libertad, hace 38 a\u00f1os. Actualmente es el vicario de Comunicaciones del Arzobispado de San Salvador. Tambi\u00e9n es el director de Radio Paz y del semanario Orientaci\u00f3n. Ordenado sacerdote en 2006, tiene a su cargo la iglesia El Calvario, de Cojutepeque,\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2017\/12\/fsep31122017xxcuest33.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7831,"url":"https:\/\/7s.laprensagrafica.com\/en\/la-vida-no-es-una-dicotomia\/","url_meta":{"origin":1047,"position":4},"title":"&#8220;La vida no es una dicotom\u00eda&#8221;","date":"31 May, 2020","format":false,"excerpt":"[:es]Eduardo Salazar es un comunicador salvadore\u00f1o. Actualmente trabaja como gestor de campa\u00f1as publicitarias de compra program\u00e1tica en AKQA, una agencia digital internacional con presencia en El Salvador. Es graduado de la licenciatura en Ciencias de la Comunicaci\u00f3n de la Universidad Dr. Jos\u00e9 Mat\u00edas Delgado.[:]","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/05\/fsep31052020corcuest92.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]},{"id":7716,"url":"https:\/\/7s.laprensagrafica.com\/en\/mi-miedo-mas-grande-es-al-fracaso\/","url_meta":{"origin":1047,"position":5},"title":"&#8220;Mi miedo m\u00e1s grande es al fracaso&#8221;","date":"10 May, 2020","format":false,"excerpt":"[:es]Manuel Cortez es un salvadore\u00f1o que se especializa en la Medicina Veterinaria y Zoot\u00e9cnica. El joven cuenta con diplomados sobre la fauna silvestre y ha trabajado en el Programa de Conservaci\u00f3n de Murci\u00e9lagos de El Salvador y la Fundaci\u00f3n Zool\u00f3gica de El Salvador (FUNZEL). En 2017, Cortez viaj\u00f3 a Costa\u2026","rel":"","context":"In &quot;Siete Preguntas&quot;","img":{"alt_text":"","src":"https:\/\/i0.wp.com\/7s.laprensagrafica.com\/wp-content\/uploads\/2020\/05\/fsep10052020xxcuest01ca.jpg?resize=350%2C200&ssl=1","width":350,"height":200},"classes":[]}],"_links":{"self":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/1047"}],"collection":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/comments?post=1047"}],"version-history":[{"count":3,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/1047\/revisions"}],"predecessor-version":[{"id":1051,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/posts\/1047\/revisions\/1051"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media\/1048"}],"wp:attachment":[{"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/media?parent=1047"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/categories?post=1047"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/7s.laprensagrafica.com\/en\/wp-json\/wp\/v2\/tags?post=1047"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}